{"id":36855,"date":"2022-11-08T11:16:52","date_gmt":"2022-11-08T16:16:52","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=36855"},"modified":"2022-11-20T08:59:44","modified_gmt":"2022-11-20T13:59:44","slug":"as-mulheres-guerreiras-de-dahomey","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/","title":{"rendered":"As Mulheres Guerreiras De Dahomey"},"content":{"rendered":"<p>EQUIPA DA ADF<\/p>\n<p>Em<span class=\"Apple-converted-space\">\u00a0<\/span>1861, 3.000 mulheres-soldado, com armamento pesado, vieram contra uma muralha espinhosa durante uma demonstra\u00e7\u00e3o de habilidades.<\/p>\n<p>Rei Glele, o seu chefe em Dahomey, uma regi\u00e3o que agora faz parte do Benin, estava ansioso por demonstrar a ferocidade e habilidade dos seus guerreiros. A muralha de 400 metros, foi refor\u00e7ada com ramos de ac\u00e1cia, bem afiados, com 5 cm de comprimento.<\/p>\n<p>As mulheres estavam descal\u00e7as, armadas com paus e facas. Algumas delas \u2013 \u201cReappers\u201d (as Ceifeiras) \u2013 tinham navalhas de 1 metro de comprimento que, disse o rei, podiam ser utilizadas para cortar um homem pela metade.<\/p>\n<p>As guerreiras vieram contra a muralha, ignorando ferimentos enormes causados pelos espinhos. Elas seguiram para o topo, simulando um combate de corpo a corpo com um inimigo invis\u00edvel. Desceram e voltaram a subir a muralha, desta vez, salvando um grupo de alde\u00f5es que agiam como prisioneiros.<\/p>\n<p>A demonstra\u00e7\u00e3o provou aos visitantes que as mulheres n\u00e3o eram figuras meramente cerimoniais. Elas, na verdade, eram os \u00fanicos soldados do destacamento feminino do mundo na altura em que estavam a servir em combate.<\/p>\n<p>As mulheres guerreiras de Dahomey provavelmente tiveram a sua origem no S\u00e9culo XVII. Uma teoria afirma que elas come\u00e7aram como ca\u00e7adoras da tribo Fon. Contudo, Stanley Alpern, um especialista renomado em mat\u00e9ria de guerreiros, escreveu no seu livro de 1998, intitulado \u201cAmazons of Black Sparta,\u201d que elas provavelmente come\u00e7aram como guardas do pal\u00e1cio na d\u00e9cada de 1720. Vieram depois a ser conhecidas como as \u201cMino,\u201d que significa \u201cNossas M\u00e3es,\u201d na l\u00edngua Fon.<\/p>\n<p>As mulheres de Dahomey lutaram em grandes batalhas. Alpern disse que nas quatro grandes campanhas, nos finais do S\u00e9culo XIX, pelo menos 6.000 ou mesmo 15.000 morreram em batalha.<\/p>\n<p>Existem v\u00e1rias teorias sobre como as guerreiras de Dahomey vieram a existir, mas muitos acreditam que foi uma quest\u00e3o de necessidade \u2014 os homens Fon, como resultado de guerras e de com\u00e9rcio de escravos, estavam em desvantagem num\u00e9rica de 10 para 1 em rela\u00e7\u00e3o aos seus rivais da tribo Yoruba. Como resultado, as mulheres Fon foram recrutadas para combater.<\/p>\n<p>Apenas existiam cerca de 600 mulheres guerreiras dahomianas at\u00e9 meados do S\u00e9culo XIX, quando o rei Ghezo aumentou o seu n\u00famero para cerca de 6.000. Ele foi capaz de recrutar muitas mulheres para viverem como guerreiras, porque as mulheres de Dahomey daquele tempo viviam na pobreza e, muitas vezes, n\u00e3o recebiam um bom tratamento.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Como guerreiras, as mulheres viviam no acampamento do rei. O explorador Sir Richard Burton reportou que as mulheres recebiam alimentos, tabaco, bebidas alco\u00f3licas e escravos.<\/p>\n<p>As guerreiras eram exaustivamente treinadas para lutar, para resistir a grande dor e para sobreviver. Observadores afirmam que, apesar de elas n\u00e3o serem boas em rela\u00e7\u00e3o ao uso de arma de fogo, eram especialistas em termos de combate corpo a corpo e no uso de facas.<\/p>\n<p>At\u00e9 princ\u00edpios do S\u00e9culo XX, as mulheres estavam num estado de constante guerra sob o comando de reis ambiciosos. Mas quando a Fran\u00e7a invadiu com armas modernas, as mulheres foram derrotadas e as suas fileiras foram desmanteladas.<\/p>\n<p>A sua bravura \u00e9 resumida num credo que as mulheres alegadamente repetiam para demonstrar o seu esp\u00edrito: \u201cAqueles que voltam da guerra sem terem conquistado devem morrer. Se recuarmos, a nossa vida fica \u00e0 merc\u00ea do rei. Qualquer que seja a cidade que for atacada, devemos venc\u00ea-la ou enterramo-nos nas suas ru\u00ednas.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF Em\u00a01861, 3.000 mulheres-soldado, com armamento pesado, vieram contra uma muralha espinhosa durante uma demonstra\u00e7\u00e3o de habilidades. Rei Glele, o seu chefe em Dahomey, uma regi\u00e3o que agora faz parte do Benin, estava ansioso por demonstrar a ferocidade e habilidade dos seus guerreiros. A muralha de 400 metros, foi refor\u00e7ada com ramos de<\/p>\n","protected":false},"author":1,"featured_media":36373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[335,344],"tags":[],"class_list":{"0":"post-36855","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colunas","8":"category-retrospectiva"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As Mulheres Guerreiras De Dahomey - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As Mulheres Guerreiras De Dahomey - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF Em\u00a01861, 3.000 mulheres-soldado, com armamento pesado, vieram contra uma muralha espinhosa durante uma demonstra\u00e7\u00e3o de habilidades. Rei Glele, o seu chefe em Dahomey, uma regi\u00e3o que agora faz parte do Benin, estava ansioso por demonstrar a ferocidade e habilidade dos seus guerreiros. A muralha de 400 metros, foi refor\u00e7ada com ramos de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-08T16:16:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-20T13:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"As Mulheres Guerreiras De Dahomey\",\"datePublished\":\"2022-11-08T16:16:52+00:00\",\"dateModified\":\"2022-11-20T13:59:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/\"},\"wordCount\":577,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Flashback_CMYK.jpg\",\"articleSection\":[\"Colunas\",\"Retrospectiva\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/\",\"name\":\"As Mulheres Guerreiras De Dahomey - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Flashback_CMYK.jpg\",\"datePublished\":\"2022-11-08T16:16:52+00:00\",\"dateModified\":\"2022-11-20T13:59:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Flashback_CMYK.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Flashback_CMYK.jpg\",\"width\":1080,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/11\\\/as-mulheres-guerreiras-de-dahomey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As Mulheres Guerreiras De Dahomey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As Mulheres Guerreiras De Dahomey - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/","og_locale":"pt_PT","og_type":"article","og_title":"As Mulheres Guerreiras De Dahomey - Africa Defense Forum","og_description":"EQUIPA DA ADF Em\u00a01861, 3.000 mulheres-soldado, com armamento pesado, vieram contra uma muralha espinhosa durante uma demonstra\u00e7\u00e3o de habilidades. Rei Glele, o seu chefe em Dahomey, uma regi\u00e3o que agora faz parte do Benin, estava ansioso por demonstrar a ferocidade e habilidade dos seus guerreiros. A muralha de 400 metros, foi refor\u00e7ada com ramos de","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2022-11-08T16:16:52+00:00","article_modified_time":"2022-11-20T13:59:44+00:00","og_image":[{"width":1080,"height":774,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"As Mulheres Guerreiras De Dahomey","datePublished":"2022-11-08T16:16:52+00:00","dateModified":"2022-11-20T13:59:44+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/"},"wordCount":577,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg","articleSection":["Colunas","Retrospectiva"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/","name":"As Mulheres Guerreiras De Dahomey - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg","datePublished":"2022-11-08T16:16:52+00:00","dateModified":"2022-11-20T13:59:44+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/10\/Flashback_CMYK.jpg","width":1080,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/11\/as-mulheres-guerreiras-de-dahomey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"As Mulheres Guerreiras De Dahomey"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/36855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=36855"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/36855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/36373"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=36855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=36855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=36855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}