{"id":31074,"date":"2022-03-15T14:43:29","date_gmt":"2022-03-15T18:43:29","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=31074"},"modified":"2022-03-15T14:45:00","modified_gmt":"2022-03-15T18:45:00","slug":"estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/","title":{"rendered":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central"},"content":{"rendered":"<div>\n<p><span lang=\"PT\">EQUIPA DA ADF<br \/>\n<\/span><span lang=\"PT\"><br \/>\nAs frotas de pesca em \u00e1guas long\u00ednquas (PAL) da China tiveram como alvo as \u00e1guas do Golfo da Guin\u00e9, na \u00c1frica Ocidental e Central, durante d\u00e9cadas. Agora, a regi\u00e3o est\u00e1 rapidamente a ficar sem peixe, causando inseguran\u00e7a alimentar e perda de receitas para milhares de pessoas que trabalham na ind\u00fastria de pescas.<\/span><\/p>\n<p>Um estudo recente feito pela Hoover Institution, um grupo de reflex\u00e3o da Universidade de Stanford, examinou os efeitos que a PAL da China teve nos <span lang=\"PT\">Camar\u00f5es, na Rep\u00fablica do Congo, no Gab\u00e3o e na Nig\u00e9ria, onde os arrast\u00f5es chineses notoriamente envolvem-se na pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN). Em toda a regi\u00e3o, <em>40<\/em>% a 60% do <em>peixe <\/em>\u00e9 <em>pescado de forma ilegal, afirmam os analistas.<\/em><\/span><em><span lang=\"PT\"><br \/>\n<\/span><\/em><span lang=\"PT\"><br \/>\nA presen\u00e7a da PAL da China \u2014 a maior do mundo \u2014 obriga os pescadores artesanais a aventurarem-se para mais distante no mar, muitas vezes, regressando com pouco ou sem nenhum peixe, Agnes Ebo\u2019o, uma especialista em mat\u00e9rias de pesca em \u00e1guas long\u00ednquas, que foi a autora do estudo, disse numa reportagem do jornal nigeriano Premium Times. A China tamb\u00e9m possui o pior registo de pesca INN do mundo, de acordo com o \u00cdndice de Pesca INN.<\/span><\/p>\n<\/div>\n<div>\n<p><span lang=\"PT\">\u201cA pesca em \u00e1guas long\u00ednquas por si s\u00f3 n\u00e3o \u00e9 ilegal e tem sido praticada durante s\u00e9culos,\u201d disse Ebo\u2019o no relat\u00f3rio.&#8221;Contudo, as empresas de pesca da vanguarda est\u00e3o a ter a tend\u00eancia de inclinar-se para a criminalidade, notavelmente atrav\u00e9s de fraudes fiscais, corrup\u00e7\u00e3o e outros crimes econ\u00f3micos associados \u00e0 pesca INN.&#8221;<\/span><\/p>\n<p>Uma falta de embarca\u00e7\u00f5es de patrulha e de sistema de vigil\u00e2ncia faz com que seja dif\u00edcil para as autoridades fazerem a monitoria da totalidade da linha da costa do Golfo da Guin\u00e9 de mais de 6.000 quil\u00f3metros. Na Rep\u00fablica do Congo, por exemplo, a Divis\u00e3o da Direc\u00e7\u00e3o de Inspec\u00e7\u00e3o de Pescas de Kouilou possui apenas duas embarca\u00e7\u00f5es de patrulha, de acordo com Ebo\u2019o. Ela observou que as embarca\u00e7\u00f5es de pesca chinesas perfazem quase a totalidade das frotas de pesca industrial nas \u00e1guas daquele pa\u00eds.<\/p>\n<p>A fraca governa\u00e7\u00e3o, a falta de mecanismos de transpar\u00eancia e estruturas administrativas e jur\u00eddicas limitadas para lidar com a pesca INN tamb\u00e9m acrescentam os desafios mar\u00edtimos na regi\u00e3o, escreveu Ebo\u2019o. Os resultados s\u00e3o dispendiosos.<\/p>\n<p>O com\u00e9rcio mar\u00edtimo ilegal lesa a \u00c1frica Ocidental em cerca de 1,95 bilh\u00f5es de d\u00f3lares em toda a cadeia de valores pesqueiros e 593 milh\u00f5es de d\u00f3lares por ano em rendimento dos agregados familiares. A pesca INN tamb\u00e9m causa a inseguran\u00e7a alimentar, uma vez que dizima as unidades populacionais de peixe, destr\u00f3i os ecossistemas e tem estado ligada \u00e0 pirataria, raptos e ao tr\u00e1fico de drogas.<\/p>\n<p>Em 2021, a Uni\u00e3o Europeia (UE) emitiu um &#8220;cart\u00e3o amarelo&#8221; contra os Camar\u00f5es pela sua resposta inadequada \u00e0 pesca INN. Um cart\u00e3o amarelo \u00e9 um alerta que indica que san\u00e7\u00f5es podem ser impostas caso o pa\u00eds n\u00e3o melhore os seus esfor\u00e7os para acabar com a pesca INN.<\/p>\n<p><em>\u201c\u00c9 lament\u00e1vel que os Camar\u00f5es n\u00e3o tenham sido capazes de garantir um controlo adequado das actividades pesqueiras que ocorrem debaixo da sua bandeira,&#8221; <\/em>Virginijus Sinkevi\u010dius, comiss\u00e1rio da Uni\u00e3o Europeia para o meio ambiente, oceanos e locais de pesca, disse num comunicado. \u201c<em>A comiss\u00e3o est\u00e1 pronta para trabalhar e cooperar com os Camar\u00f5es para implementar as reformas necess\u00e1rias.\u201d<\/em><\/p>\n<p>De acordo com a Funda\u00e7\u00e3o para a Justi\u00e7a Ambiental, os Camar\u00f5es s\u00e3o conhecidos por oferecer &#8220;bandeiras de conveni\u00eancia&#8221; para as embarca\u00e7\u00f5es de pesca operarem de forma ilegal, com pouca monitoria e pouco cumprimento da lei. Uma bandeira de conveni\u00eancia refere-se a uma empresa que paga para que as suas embarca\u00e7\u00f5es de pesca utilizem a bandeira de um determinado pa\u00eds, embora os benefici\u00e1rios efectivos estejam localizados em outros lugares.<\/p>\n<p>A C\u00e2mara dos Deputados da Nig\u00e9ria indicou, em 2021, que aquele pa\u00eds perde 70 milh\u00f5es de d\u00f3lares por ano devido \u00e0 pesca INN, incluindo perda de taxas de licen\u00e7as, rendimentos de impostos e dinheiro que poderia ter sido feito por pescadores artesanais.<\/p>\n<p>Os pa\u00edses do Golfo da Guin\u00e9 continuam a favorecer sistemas de licenciamento de rendas ou a fazer acordos bilaterais com empresas de pesca industriais e semi-industriais, embora esta abordagem beneficie os pescadores de \u00e1guas long\u00ednquas e os pa\u00edses ricos em pesca mais do que os pa\u00edses anfitri\u00f5es, escreveu Ebo\u2019o.<\/p>\n<p>Observando que os pa\u00edses individualmente s\u00e3o respons\u00e1veis por manter pescas sustent\u00e1veis e garantir que os recursos marinhos n\u00e3o sejam explorados, os pa\u00edses da \u00c1frica Ocidental e Central &#8220;deviam desenvolver estrat\u00e9gias para proteger os seus dom\u00ednios mar\u00edtimos de pr\u00e1ticas predat\u00f3rias como a PAL sem \u00e9tica atrav\u00e9s da criminaliza\u00e7\u00e3o e imposi\u00e7\u00e3o de san\u00e7\u00f5es de forma eficaz contra pr\u00e1ticas ilegais,\u201d acrescentou Ebo\u2019o.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF As frotas de pesca em \u00e1guas long\u00ednquas (PAL) da China tiveram como alvo as \u00e1guas do Golfo da Guin\u00e9, na \u00c1frica Ocidental e Central, durante d\u00e9cadas. Agora, a regi\u00e3o est\u00e1 rapidamente a ficar sem peixe, causando inseguran\u00e7a alimentar e perda de receitas para milhares de pessoas que trabalham na ind\u00fastria de pescas.<\/p>\n","protected":false},"author":1,"featured_media":31072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[],"class_list":{"0":"post-31074","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF As frotas de pesca em \u00e1guas long\u00ednquas (PAL) da China tiveram como alvo as \u00e1guas do Golfo da Guin\u00e9, na \u00c1frica Ocidental e Central, durante d\u00e9cadas. Agora, a regi\u00e3o est\u00e1 rapidamente a ficar sem peixe, causando inseguran\u00e7a alimentar e perda de receitas para milhares de pessoas que trabalham na ind\u00fastria de pescas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-15T18:43:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T18:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central\",\"datePublished\":\"2022-03-15T18:43:29+00:00\",\"dateModified\":\"2022-03-15T18:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/\"},\"wordCount\":866,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DOMINATION-I.jpg\",\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/\",\"name\":\"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DOMINATION-I.jpg\",\"datePublished\":\"2022-03-15T18:43:29+00:00\",\"dateModified\":\"2022-03-15T18:45:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DOMINATION-I.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DOMINATION-I.jpg\",\"width\":1080,\"height\":721,\"caption\":\"Autoridades de pesca inspeccionam um arrast\u00e3o chin\u00eas, na Serra Leoa. \u00a9 PIERRE GLEIZES\\\/GREENPEACE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2022\\\/03\\\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/","og_locale":"pt_PT","og_type":"article","og_title":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum","og_description":"EQUIPA DA ADF As frotas de pesca em \u00e1guas long\u00ednquas (PAL) da China tiveram como alvo as \u00e1guas do Golfo da Guin\u00e9, na \u00c1frica Ocidental e Central, durante d\u00e9cadas. Agora, a regi\u00e3o est\u00e1 rapidamente a ficar sem peixe, causando inseguran\u00e7a alimentar e perda de receitas para milhares de pessoas que trabalham na ind\u00fastria de pescas.","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2022-03-15T18:43:29+00:00","article_modified_time":"2022-03-15T18:45:00+00:00","og_image":[{"width":1080,"height":721,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central","datePublished":"2022-03-15T18:43:29+00:00","dateModified":"2022-03-15T18:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/"},"wordCount":866,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg","articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/","name":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg","datePublished":"2022-03-15T18:43:29+00:00","dateModified":"2022-03-15T18:45:00+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2022\/03\/DOMINATION-I.jpg","width":1080,"height":721,"caption":"Autoridades de pesca inspeccionam um arrast\u00e3o chin\u00eas, na Serra Leoa. \u00a9 PIERRE GLEIZES\/GREENPEACE"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2022\/03\/estudo-frotas-chinesas-dizimam-locais-de-pesca-da-africa-ocidental-e-central\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Estudo: Frotas Chinesas Dizimam Locais de Pesca da \u00c1frica Ocidental e Central"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/31074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=31074"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/31074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/31072"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=31074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=31074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=31074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}