{"id":133927,"date":"2026-02-03T13:43:00","date_gmt":"2026-02-03T18:43:00","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=133927"},"modified":"2026-02-03T13:43:19","modified_gmt":"2026-02-03T18:43:19","slug":"mineiros-chineses-pilham-os-recursos-da-nigeria","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2026\/02\/mineiros-chineses-pilham-os-recursos-da-nigeria\/","title":{"rendered":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria"},"content":{"rendered":"<p style=\"font-weight: 400;\">A minera\u00e7\u00e3o ilegal praticada por empresas chinesas na Nig\u00e9ria est\u00e1 a prejudicar a economia do pa\u00eds, degradando o ambiente e expulsando os residentes das suas resid\u00eancias, em parte, devido \u00e0 explora\u00e7\u00e3o de regulamenta\u00e7\u00f5es fracas e for\u00e7as de seguran\u00e7a corruptas, de acordo com uma nova an\u00e1lise.<\/p>\n<p style=\"font-weight: 400;\">O relat\u00f3rio da Renevlyn Development Initiative (RDI), uma organiza\u00e7\u00e3o n\u00e3o-governamental nigeriana, intitulado \u201cConquista Silenciosa: A Infiltra\u00e7\u00e3o Chinesa no Sector de Minerais S\u00f3lidos da Nig\u00e9ria,\u201d centra-se na minera\u00e7\u00e3o entre 2018 e 2025. Ele d\u00e1 aten\u00e7\u00e3o especial ao per\u00edodo desde 2022, quando a Nig\u00e9ria passou a dar mais \u00eanfase \u00e0 minera\u00e7\u00e3o de minerais para diversificar uma economia dominada pelo petr\u00f3leo e pelo g\u00e1s natural.<\/p>\n<p style=\"font-weight: 400;\">Os pesquisadores estudaram Estados ricos em minerais \u2014 Kogi, Kwara, Nasarawa, N\u00edger, Osun, Plateau e Zamfara \u2014 onde a minera\u00e7\u00e3o ilegal e o envolvimento estrangeiro de empresas chinesas s\u00e3o predominantes.<\/p>\n<p style=\"font-weight: 400;\">\u201cEm muitas comunidades anfitri\u00e3s, as opera\u00e7\u00f5es ilegais transformaram terras agr\u00edcolas, florestas e leitos de rios em campos de extrac\u00e7\u00e3o n\u00e3o regulamentados, causando degrada\u00e7\u00e3o ambiental, aumentando a tens\u00e3o social e privando o governo de receitas substanciais,\u201d afirma o relat\u00f3rio.<\/p>\n<p style=\"font-weight: 400;\">A falta de fiscaliza\u00e7\u00e3o eficaz por parte do governo permite que as mineradoras estrangeiras operem sem levar em conta as normas ou o bem-estar da comunidade, de acordo com a RDI.<\/p>\n<p style=\"font-weight: 400;\">\u201cA implica\u00e7\u00e3o mais ampla \u00e9 que o controlo da Nig\u00e9ria sobre os seus recursos minerais estrat\u00e9gicos est\u00e1 a ser corro\u00eddo por dentro,\u201d l\u00ea-se no relat\u00f3rio.<\/p>\n<p style=\"font-weight: 400;\">As minas da Nig\u00e9ria produzem uma variedade de minerais valiosos, como l\u00edtio, fluorite, estanho, tit\u00e2nio e chumbo, bem como minerais raros como c\u00e9rio, lant\u00e2nio e t\u00f3rio, utilizados na tecnologia moderna. A RDI observa que os recursos minerais do pa\u00eds representam um recurso econ\u00f3mico amplamente inexplorado, estimado em 700 bilh\u00f5es de d\u00f3lares. No entanto, a minera\u00e7\u00e3o contribui com menos de 1% para o produto interno bruto da Nig\u00e9ria. Em compara\u00e7\u00e3o, o petr\u00f3leo e o g\u00e1s fornecem 90% do PIB da Nig\u00e9ria.<\/p>\n<p style=\"font-weight: 400;\">\u201cApesar do seu potencial para impulsionar o crescimento econ\u00f3mico e diversificar as fontes de receita da Nig\u00e9ria para al\u00e9m do petr\u00f3leo e do g\u00e1s, o sector enfrenta amea\u00e7as significativas das opera\u00e7\u00f5es de minera\u00e7\u00e3o ilegal,\u201d l\u00ea-se no relat\u00f3rio.<\/p>\n<p style=\"font-weight: 400;\">Nos \u00faltimos anos, as autoridades nigerianas realizaram v\u00e1rias deten\u00e7\u00f5es de cidad\u00e3os chineses envolvidos na minera\u00e7\u00e3o ilegal. Em Julho de 2025, as autoridades prenderam sete cidad\u00e3os chineses por minera\u00e7\u00e3o sem licen\u00e7a no Estado de Akwa Ibom, na costa atl\u00e2ntica. Outros foram detidos nos Estados de Nasarawa e Plateau. Muitos desses cidad\u00e3os chineses entraram na Nig\u00e9ria com vistos de turista antes de trabalhar ilegalmente no sector mineiro.<\/p>\n<p style=\"font-weight: 400;\">O perigo da minera\u00e7\u00e3o ilegal praticada por empresas chinesas vai al\u00e9m dos danos econ\u00f3micos, de acordo com a RDI. Tamb\u00e9m alimenta a inseguran\u00e7a ao fortalecer grupos criminosos, criar rotas de tr\u00e1fico e desestabilizar partes das regi\u00f5es noroeste e centro-norte da Nig\u00e9ria, escreveram os analistas.<\/p>\n<p style=\"font-weight: 400;\">\u201cEste padr\u00e3o ressalta a necessidade urgente de reformas decisivas na gest\u00e3o e nos mecanismos de supervis\u00e3o mais fortes para evitar que o sector de minerais s\u00f3lidos se torne mais um cap\u00edtulo na longa hist\u00f3ria de m\u00e1 gest\u00e3o de recursos da Nig\u00e9ria,\u201d observou o relat\u00f3rio.<\/p>\n<p style=\"font-weight: 400;\">De acordo com os pesquisadores do projecto ENACT, o envolvimento de grupos armados na minera\u00e7\u00e3o ilegal na Nig\u00e9ria agrava o contrabando de armas e os conflitos violentos em todo o pa\u00eds e na regi\u00e3o mais ampla do Sahel. Isso tamb\u00e9m leva a um aumento no sequestro de mulheres e meninas para trabalho for\u00e7ado nas minas.<\/p>\n<p style=\"font-weight: 400;\">Analistas da RDI instaram as autoridades governamentais em Julho a fortalecer o controlo do pa\u00eds sobre o sector de minera\u00e7\u00e3o. Eles repetem esse apelo no seu relat\u00f3rio mais recente, instando o governo a adoptar uma postura mais agressiva em rela\u00e7\u00e3o \u00e0 minera\u00e7\u00e3o ilegal, prendendo os condenados e confiscando tanto os equipamentos de minera\u00e7\u00e3o quanto os materiais extra\u00eddos.<\/p>\n<p style=\"font-weight: 400;\">Entre outras mudan\u00e7as, a RDI recomenda:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">Garantir que as empresas de minera\u00e7\u00e3o chinesas e outras empresas estrangeiras tenham as licen\u00e7as adequadas e sejam penalizadas por infringir a lei.<\/li>\n<li style=\"font-weight: 400;\">Impor rigor na emiss\u00e3o de vistos de turista a cidad\u00e3os chineses para limitar a sua capacidade de trabalhar no sector mineiro e permanecer no pa\u00eds ap\u00f3s o vencimento dos vistos.<\/li>\n<li style=\"font-weight: 400;\">Refor\u00e7ar a capacidade da Ag\u00eancia Nacional de Aplica\u00e7\u00e3o das Normas e Regulamentos Ambientais para responsabilizar os mineiros ilegais pelos danos ambientais.<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u201cSem uma ac\u00e7\u00e3o governamental firme e coordenada, o sector corre o risco de cair ainda mais nas m\u00e3os de actores n\u00e3o regulamentados que prejudicam a seguran\u00e7a nacional e privam o pa\u00eds de receitas significativas,\u201d escreveram os analistas da RDI.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A minera\u00e7\u00e3o ilegal praticada por empresas chinesas na Nig\u00e9ria est\u00e1 a prejudicar a economia do pa\u00eds, degradando o ambiente e expulsando os residentes das suas resid\u00eancias, em parte, devido \u00e0 explora\u00e7\u00e3o de regulamenta\u00e7\u00f5es fracas e for\u00e7as de seguran\u00e7a corruptas, de acordo com uma nova an\u00e1lise. O relat\u00f3rio da Renevlyn Development Initiative (RDI), uma organiza\u00e7\u00e3o n\u00e3o-governamental<\/p>\n","protected":false},"author":1,"featured_media":133925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[546,944,453,1018],"class_list":{"0":"post-133927","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-china-pt-pt","9":"tag-mineracao","10":"tag-nigeria-pt-pt","11":"tag-seguranca-nacional"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/?p=133929\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"A minera\u00e7\u00e3o ilegal praticada por empresas chinesas na Nig\u00e9ria est\u00e1 a prejudicar a economia do pa\u00eds, degradando o ambiente e expulsando os residentes das suas resid\u00eancias, em parte, devido \u00e0 explora\u00e7\u00e3o de regulamenta\u00e7\u00f5es fracas e for\u00e7as de seguran\u00e7a corruptas, de acordo com uma nova an\u00e1lise. O relat\u00f3rio da Renevlyn Development Initiative (RDI), uma organiza\u00e7\u00e3o n\u00e3o-governamental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/?p=133929\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T18:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T18:43:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria\",\"datePublished\":\"2026-02-03T18:43:00+00:00\",\"dateModified\":\"2026-02-03T18:43:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929\"},\"wordCount\":847,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/REVENUE-LOSS-1_EFCC.jpg\",\"keywords\":[\"China\",\"Minera\u00e7\u00e3o\",\"Nigeria\",\"seguran\u00e7a nacional\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929\",\"name\":\"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/REVENUE-LOSS-1_EFCC.jpg\",\"datePublished\":\"2026-02-03T18:43:00+00:00\",\"dateModified\":\"2026-02-03T18:43:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/REVENUE-LOSS-1_EFCC.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/REVENUE-LOSS-1_EFCC.jpg\",\"width\":1080,\"height\":810,\"caption\":\"As autoridades nigerianas prenderam dezenas de cidad\u00e3os chineses por acusa\u00e7\u00f5es de minera\u00e7\u00e3o ilegal nos \u00faltimos anos. A fiscaliza\u00e7\u00e3o melhorou desde 2022, quando o governo passou a dar mais \u00eanfase \u00e0 minera\u00e7\u00e3o como forma de diversificar uma economia dominada pelo petr\u00f3leo e pelo g\u00e1s natural. COMISS\u00c3O DE CRIMES ECON\u00d3MICOS E FINANCEIROS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/?p=133929#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/?p=133929","og_locale":"pt_PT","og_type":"article","og_title":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum","og_description":"A minera\u00e7\u00e3o ilegal praticada por empresas chinesas na Nig\u00e9ria est\u00e1 a prejudicar a economia do pa\u00eds, degradando o ambiente e expulsando os residentes das suas resid\u00eancias, em parte, devido \u00e0 explora\u00e7\u00e3o de regulamenta\u00e7\u00f5es fracas e for\u00e7as de seguran\u00e7a corruptas, de acordo com uma nova an\u00e1lise. O relat\u00f3rio da Renevlyn Development Initiative (RDI), uma organiza\u00e7\u00e3o n\u00e3o-governamental","og_url":"https:\/\/adf-magazine.com\/fr\/?p=133929","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2026-02-03T18:43:00+00:00","article_modified_time":"2026-02-03T18:43:19+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria","datePublished":"2026-02-03T18:43:00+00:00","dateModified":"2026-02-03T18:43:19+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929"},"wordCount":847,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg","keywords":["China","Minera\u00e7\u00e3o","Nigeria","seguran\u00e7a nacional"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/?p=133929#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/?p=133929","url":"https:\/\/adf-magazine.com\/fr\/?p=133929","name":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg","datePublished":"2026-02-03T18:43:00+00:00","dateModified":"2026-02-03T18:43:19+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/?p=133929"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2026\/02\/REVENUE-LOSS-1_EFCC.jpg","width":1080,"height":810,"caption":"As autoridades nigerianas prenderam dezenas de cidad\u00e3os chineses por acusa\u00e7\u00f5es de minera\u00e7\u00e3o ilegal nos \u00faltimos anos. A fiscaliza\u00e7\u00e3o melhorou desde 2022, quando o governo passou a dar mais \u00eanfase \u00e0 minera\u00e7\u00e3o como forma de diversificar uma economia dominada pelo petr\u00f3leo e pelo g\u00e1s natural. COMISS\u00c3O DE CRIMES ECON\u00d3MICOS E FINANCEIROS"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/?p=133929#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Mineiros Chineses \u2018Pilham\u2019 os Recursos da Nig\u00e9ria"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/133927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=133927"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/133927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/133925"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=133927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=133927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=133927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}