{"id":132976,"date":"2025-12-23T12:48:10","date_gmt":"2025-12-23T17:48:10","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=132976"},"modified":"2025-12-23T12:48:25","modified_gmt":"2025-12-23T17:48:25","slug":"trafico-de-animais-selvagens-prospera-na-internet","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/","title":{"rendered":"Tr\u00e1fico de Animais Selvagens Prospera na Internet"},"content":{"rendered":"<p style=\"font-weight: 400;\">Numa quarta-feira recente, num cremat\u00f3rio de animais de estima\u00e7\u00e3o nos arredores de Joanesburgo, as autoridades sul-africanas destru\u00edram quase uma tonelada m\u00e9trica de ossos de le\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">A destrui\u00e7\u00e3o dos restos confiscados fazia parte do esfor\u00e7o da \u00c1frica do Sul para acabar com a cria\u00e7\u00e3o de le\u00f5es em cativeiro e o tr\u00e1fico dos seus ossos para uso na medicina tradicional chinesa (MTC).<\/p>\n<p style=\"font-weight: 400;\">A \u00c1frica do Sul proibiu efectivamente a exporta\u00e7\u00e3o de ossos de le\u00e3o este ano, estabelecendo uma quota de exporta\u00e7\u00e3o igual a zero. A \u00c1frica do Sul conta com cerca de 12.000 le\u00f5es criados em fazendas para serem ca\u00e7ados, em compara\u00e7\u00e3o com uma popula\u00e7\u00e3o selvagem de cerca de 3.000. Os le\u00f5es mortos durante as ca\u00e7adas s\u00e3o abatidos e as suas partes traficadas, muitas vezes, em substitui\u00e7\u00e3o aos ossos de tigre usados nas formula\u00e7\u00f5es da MTC.<\/p>\n<p style=\"font-weight: 400;\">A \u00c1frica do Sul tem sido h\u00e1 muito tempo um centro de com\u00e9rcio il\u00edcito de ossos de le\u00e3o, chifres de rinoceronte, marfim de elefante e outras partes e produtos de animais, muitos deles enviados para os mercados asi\u00e1ticos para uso na MTC.<\/p>\n<p style=\"font-weight: 400;\">O governo sul-africano proibiu a exporta\u00e7\u00e3o de ossos de le\u00e3o em 2019 e anunciou em 2024 que iria encerrar as fazendas de le\u00f5es do pa\u00eds, citando as condi\u00e7\u00f5es insalubres em que a maioria dos animais vive. No entanto, n\u00e3o foi definido um prazo firme para o encerramento das fazendas. As autoridades afirmaram na altura que a ca\u00e7a aos trof\u00e9us continuaria por um per\u00edodo indeterminado.<\/p>\n<p style=\"font-weight: 400;\">Num novo relat\u00f3rio, investigadores da Iniciativa Global contra o Crime Organizado Transnacional (GI-TOC) trabalharam com organiza\u00e7\u00f5es de monitoriza\u00e7\u00e3o da vida selvagem em todo o mundo para examinar as formas como o com\u00e9rcio ilegal da vida selvagem transporta animais e partes de animais por todo o mundo, com grande parte desse tr\u00e1fego centrado na China.<\/p>\n<p style=\"font-weight: 400;\">O estudo abrangeu o per\u00edodo de Abril de 2024 a Agosto de 2025 e incluiu tr\u00eas pa\u00edses africanos: Camar\u00f5es, Nig\u00e9ria e \u00c1frica do Sul.<\/p>\n<p style=\"font-weight: 400;\">Grande parte do com\u00e9rcio ilegal de animais selvagens ocorre abertamente online, com o Facebook a veicular a maior parte da publicidade que promove animais vivos (normalmente aves) e partes de animais (normalmente de mam\u00edferos).<\/p>\n<p style=\"font-weight: 400;\">O estudo da GI-TOC descobriu que o Facebook era respons\u00e1vel por quase 84% dos mais de 13.200 an\u00fancios analisados em todo o mundo. Isso representa uma queda em rela\u00e7\u00e3o aos 95% registados h\u00e1 alguns anos. Dois ter\u00e7os desses an\u00fancios promoviam partes de animais, 84% dos quais eram animais protegidos pela Conven\u00e7\u00e3o das Na\u00e7\u00f5es Unidas sobre o Com\u00e9rcio Internacional de Esp\u00e9cies Amea\u00e7adas de Extin\u00e7\u00e3o (CITES).<\/p>\n<p style=\"font-weight: 400;\">\u201cIsso destaca a centralidade cont\u00ednua do Facebook nos esfor\u00e7os de monitoriza\u00e7\u00e3o e aplica\u00e7\u00e3o de interven\u00e7\u00f5es regulat\u00f3rias,\u201d escreveram os investigadores da GI-TOC.<\/p>\n<p style=\"font-weight: 400;\">Em alguns casos, os anunciantes usam emojis codificados para identificar secretamente os produtos da vida selvagem que est\u00e3o a oferecer.<\/p>\n<p style=\"font-weight: 400;\">Os investigadores da GI-TOC recomendam que o Facebook e outras redes sociais ou sites de com\u00e9rcio electr\u00f3nico tornem mais r\u00edgidas as suas pr\u00f3prias regras para a publicidade de produtos da vida selvagem, exigindo documenta\u00e7\u00e3o que comprove que os produtos est\u00e3o isentos de proibi\u00e7\u00f5es comerciais.<\/p>\n<p style=\"font-weight: 400;\">Em Agosto, a \u00c1frica do Sul indiciou seis pessoas sob a acusa\u00e7\u00e3o de traficar quase 1.000 chifres de rinoceronte para mercados asi\u00e1ticos usando documentos falsificados. As autoridades afirmaram que os traficantes alegavam estar a vender os chifres no mercado interno, quando na verdade os estavam a enviar para o exterior.<\/p>\n<p style=\"font-weight: 400;\">O tr\u00e1fico il\u00edcito de animais selvagens, muitas vezes, envolve organiza\u00e7\u00f5es criminosas transnacionais. Os lucros crescentes em cada etapa do processo de tr\u00e1fico tornam a actividade atraente para os envolvidos. O estudo usa o caso da Coreia do Norte, que vende produtos da medicina tradicional chinesa com quantidades min\u00fasculas de chifre de rinoceronte para evitar san\u00e7\u00f5es internacionais e gerar receita em moeda forte.<\/p>\n<p style=\"font-weight: 400;\">Os investigadores da GI-TOC observam que a Coreia do Norte tem usado o tr\u00e1fico ilegal de animais selvagens para gerar receitas h\u00e1 muitos anos. Uma investiga\u00e7\u00e3o das Na\u00e7\u00f5es Unidas sugere que diplomatas norte-coreanos est\u00e3o no centro do contrabando de chifres de rinoceronte e outros materiais ilegais de animais selvagens. Um diplomata \u00e9 acusado de tentar traficar 65 milh\u00f5es de d\u00f3lares em chifres de rinoceronte para a China via Mo\u00e7ambique.<\/p>\n<p style=\"font-weight: 400;\">O chifre de rinoceronte comprado a traficantes \u00e9 vendido como Angong Niuhuang Wan (ANW) com uma margem de lucro de 30 a 40 vezes o valor do chifre utilizado.<\/p>\n<p style=\"font-weight: 400;\">Um \u00fanico quilograma il\u00edcito de chifre de rinoceronte traficado, comprado por 22.300 d\u00f3lares no Vietname, pode render ao pa\u00eds cerca de 830.000 d\u00f3lares em receitas no mercado chin\u00eas e noutros mercados asi\u00e1ticos.<\/p>\n<p><span style=\"font-weight: 400;\">\u201cIsso torna o ANW altamente lucrativo para os traficantes e refor\u00e7a o incentivo para continuar a adquirir chifre de rinoceronte,\u201d escreveram os investigadores da GI-TOC. \u201cO papel da Coreia do Norte no tr\u00e1fico de chifres de rinoceronte eleva a situa\u00e7\u00e3o de um desafio de conserva\u00e7\u00e3o para uma preocupa\u00e7\u00e3o de seguran\u00e7a internacional.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa quarta-feira recente, num cremat\u00f3rio de animais de estima\u00e7\u00e3o nos arredores de Joanesburgo, as autoridades sul-africanas destru\u00edram quase uma tonelada m\u00e9trica de ossos de le\u00e3o. A destrui\u00e7\u00e3o dos restos confiscados fazia parte do esfor\u00e7o da \u00c1frica do Sul para acabar com a cria\u00e7\u00e3o de le\u00f5es em cativeiro e o tr\u00e1fico dos seus ossos para uso<\/p>\n","protected":false},"author":1,"featured_media":132974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[403,446,546,453,654],"class_list":{"0":"post-132976","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-africa-do-sul","9":"tag-camaroes","10":"tag-china-pt-pt","11":"tag-nigeria-pt-pt","12":"tag-trafico-de-animais-selvagens"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Numa quarta-feira recente, num cremat\u00f3rio de animais de estima\u00e7\u00e3o nos arredores de Joanesburgo, as autoridades sul-africanas destru\u00edram quase uma tonelada m\u00e9trica de ossos de le\u00e3o. A destrui\u00e7\u00e3o dos restos confiscados fazia parte do esfor\u00e7o da \u00c1frica do Sul para acabar com a cria\u00e7\u00e3o de le\u00f5es em cativeiro e o tr\u00e1fico dos seus ossos para uso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T17:48:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-23T17:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Tr\u00e1fico de Animais Selvagens Prospera na Internet\",\"datePublished\":\"2025-12-23T17:48:10+00:00\",\"dateModified\":\"2025-12-23T17:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/\"},\"wordCount\":883,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GettyImages-154120328.jpg\",\"keywords\":[\"\u00c1frica do Sul\",\"Camar\u00f5es\",\"China\",\"Nigeria\",\"tr\u00e1fico de animais selvagens\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/\",\"name\":\"Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GettyImages-154120328.jpg\",\"datePublished\":\"2025-12-23T17:48:10+00:00\",\"dateModified\":\"2025-12-23T17:48:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GettyImages-154120328.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GettyImages-154120328.jpg\",\"width\":1024,\"height\":526,\"caption\":\"O tr\u00e1fico il\u00edcito de animais e partes de animais selvagens, como le\u00f5es criados para a ca\u00e7a de trof\u00e9us na \u00c1frica do Sul, \u00e9 impulsionado pela publicidade online atrav\u00e9s das redes sociais e sites de com\u00e9rcio electr\u00f3nico, de acordo com a Iniciativa Global contra o Crime Organizado Transnacional. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/12\\\/trafico-de-animais-selvagens-prospera-na-internet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1fico de Animais Selvagens Prospera na Internet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/","og_locale":"pt_PT","og_type":"article","og_title":"Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum","og_description":"Numa quarta-feira recente, num cremat\u00f3rio de animais de estima\u00e7\u00e3o nos arredores de Joanesburgo, as autoridades sul-africanas destru\u00edram quase uma tonelada m\u00e9trica de ossos de le\u00e3o. A destrui\u00e7\u00e3o dos restos confiscados fazia parte do esfor\u00e7o da \u00c1frica do Sul para acabar com a cria\u00e7\u00e3o de le\u00f5es em cativeiro e o tr\u00e1fico dos seus ossos para uso","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-12-23T17:48:10+00:00","article_modified_time":"2025-12-23T17:48:25+00:00","og_image":[{"width":1024,"height":526,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Tr\u00e1fico de Animais Selvagens Prospera na Internet","datePublished":"2025-12-23T17:48:10+00:00","dateModified":"2025-12-23T17:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/"},"wordCount":883,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg","keywords":["\u00c1frica do Sul","Camar\u00f5es","China","Nigeria","tr\u00e1fico de animais selvagens"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/","name":"Tr\u00e1fico de Animais Selvagens Prospera na Internet - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg","datePublished":"2025-12-23T17:48:10+00:00","dateModified":"2025-12-23T17:48:25+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/12\/GettyImages-154120328.jpg","width":1024,"height":526,"caption":"O tr\u00e1fico il\u00edcito de animais e partes de animais selvagens, como le\u00f5es criados para a ca\u00e7a de trof\u00e9us na \u00c1frica do Sul, \u00e9 impulsionado pela publicidade online atrav\u00e9s das redes sociais e sites de com\u00e9rcio electr\u00f3nico, de acordo com a Iniciativa Global contra o Crime Organizado Transnacional. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/12\/trafico-de-animais-selvagens-prospera-na-internet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1fico de Animais Selvagens Prospera na Internet"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=132976"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/132974"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=132976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=132976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=132976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}