{"id":132266,"date":"2025-11-07T08:59:30","date_gmt":"2025-11-07T13:59:30","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=132266"},"modified":"2025-11-17T08:57:47","modified_gmt":"2025-11-17T13:57:47","slug":"uma-abordagem-simples","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/","title":{"rendered":"\u2018Uma Abordagem Simples\u2019"},"content":{"rendered":"<p>\u00c1frica perde cerca de 11,2 bilh\u00f5es de d\u00f3lares em receitas anuais devido \u00e0 pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN). O desafio \u00e9 particularmente grave na \u00c1frica Ocidental, que perde cerca de 9,4 bilh\u00f5es de d\u00f3lares com este flagelo.<\/p>\n<p>A pesca ilegal praticada por arrast\u00f5es industriais e semi-industriais estrangeiros, particularmente da China, tem causado inseguran\u00e7a alimentar e amea\u00e7ado os empregos de mais de 10 milh\u00f5es de homens e mulheres que trabalham na pesca artesanal em \u00c1frica.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Os profissionais de seguran\u00e7a reconhecem a amea\u00e7a. O Coronel Roland T. Bai Murphy, comandante da 23.\u00aa Brigada de Infantaria das For\u00e7as Armadas da Lib\u00e9ria, viu em primeira m\u00e3o os efeitos da pesca INN nos pescadores artesanais do seu pa\u00eds. A Lib\u00e9ria perde 75 milh\u00f5es de d\u00f3lares anualmente devido \u00e0 pesca ilegal.<\/p>\n<p>\u201cA pesca INN \u00e9 grave, porque a maior parte da nossa popula\u00e7\u00e3o que vive ao longo da costa \u00e9 composta por pescadores artesanais,\u201d Murphy disse \u00e0 ADF durante a Cimeira das For\u00e7as Terrestres Africanas em Acra, Gana, em Abril de 2025. \u201cPortanto, quando temos estes arrast\u00f5es vindos de pa\u00edses asi\u00e1ticos e de alguns pa\u00edses europeus a pescar ilegalmente de forma agressiva nas nossas \u00e1guas, isso priva os pescadores artesanais locais do seu sustento.\u201d<\/p>\n<p>Na Lib\u00e9ria, cerca de 37.000 pessoas trabalham a tempo inteiro ou parcial na ind\u00fastria pesqueira e 80% da popula\u00e7\u00e3o depende do peixe como fonte de prote\u00edna. Mas os \u201csuper arrast\u00f5es\u201d industriais est\u00e3o a p\u00f4r em risco este modo de vida, deslocando os pescadores artesanais e dizimando o ecossistema oce\u00e2nico.<\/p>\n<figure id=\"attachment_131766\" aria-describedby=\"caption-attachment-131766\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-131766\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double.jpg\" alt=\"\" width=\"1080\" height=\"706\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double-300x196.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double-1024x669.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double-768x502.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double-150x98.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-double-450x294.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-131766\" class=\"wp-caption-text\">Um marinheiro da Costa do Marfim guarnece dois arrast\u00f5es chineses detidos por pesca ilegal. AFP\/GETTY IMAGES<\/figcaption><\/figure>\n<p>\u201cExistem esses grandes arrast\u00f5es, alguns com redes de mais de um quil\u00f3metro e meio, que arrastam o fundo do mar, danificando os recifes de coral de tal forma que, na Lib\u00e9ria, come\u00e7aram a aparecer recifes de coral levados pela mar\u00e9,\u201d revelou Murphy.<\/p>\n<p>V\u00e1rios pa\u00edses do Golfo da Guin\u00e9 implementaram um conjunto de iniciativas para combater a pesca ilegal, mas, muitas vezes, elas n\u00e3o s\u00e3o aplicadas nem integradas devido \u00e0 fraca gest\u00e3o, aos recursos limitados para fiscaliza\u00e7\u00e3o e \u00e0 corrup\u00e7\u00e3o.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Gareth Johnstone \u00e9 director-executivo da Trygg Mat Tracking (TMT), uma organiza\u00e7\u00e3o sem fins lucrativos que fornece informa\u00e7\u00f5es sobre a pesca a pa\u00edses e organiza\u00e7\u00f5es. Ele defende que a coopera\u00e7\u00e3o e a colabora\u00e7\u00e3o regionais s\u00e3o imperativas na luta contra a pesca ilegal.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u201c\u00c9 uma abordagem simples de nos unirmos,\u201d Johnstone disse \u00e0 ADF. \u201cIsso significa que se come\u00e7a a partilhar informa\u00e7\u00f5es. Come\u00e7a-se a partilhar recursos. Assim, h\u00e1 mais olhos postos no problema. Isso tamb\u00e9m aumenta a transpar\u00eancia. \u00c9 poss\u00edvel ver o que consta da lista de licen\u00e7as [de pesca do seu pa\u00eds], pelo que, quando os navios s\u00e3o apreendidos, podemos verificar se t\u00eam licen\u00e7a legal ou n\u00e3o. A regionaliza\u00e7\u00e3o \u00e9 realmente uma escolha \u00f3bvia.\u201d<\/p>\n<p>H\u00e1 avan\u00e7os nessa direc\u00e7\u00e3o. Em 2022, o Comit\u00e9 das Pescas do Centro-Oeste do Golfo da Guin\u00e9 e a Comiss\u00e3o Sub-Regional das Pescas assinaram um memorando de entendimento com a Comunidade Econ\u00f3mica dos Estados da \u00c1frica Ocidental que estabeleceu um quadro de colabora\u00e7\u00e3o, parceria e coopera\u00e7\u00e3o.<\/p>\n<p>Atrav\u00e9s deste quadro, o Centro Regional de Monitoria, Controlo e Vigil\u00e2ncia em Tema, no Gana, faz parte de um esfor\u00e7o para combater a pesca ilegal, melhorar a supervis\u00e3o da pesca e a aplica\u00e7\u00e3o da legisla\u00e7\u00e3o em mat\u00e9ria de pesca, aumentar a partilha de informa\u00e7\u00f5es e reduzir os custos para os Estados-membros. A TMT ajuda o centro a identificar embarca\u00e7\u00f5es de pesca ilegais, a rastrear as suas actividades e a analisar as suas liga\u00e7\u00f5es a outros crimes.<\/p>\n<figure id=\"attachment_131770\" aria-describedby=\"caption-attachment-131770\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet.jpg\"><img decoding=\"async\" class=\"size-full wp-image-131770\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet.jpg\" alt=\"\" width=\"1080\" height=\"676\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet-300x188.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet-1024x641.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet-768x481.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet-150x94.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-fleet-450x282.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-131770\" class=\"wp-caption-text\">Arrast\u00f5es de pesca atracados no porto chin\u00eas de Zhoushan. O pa\u00eds comanda a maior frota de pesca em \u00e1guas long\u00ednquas do mundo. REUTERS<\/figcaption><\/figure>\n<p><strong>O Caso do Nova Zeelandia<\/strong><\/p>\n<p>Em Mar\u00e7o de 2023, as autoridades de Tema demonstraram o valor do interc\u00e2mbio bem-sucedido de informa\u00e7\u00f5es e da colabora\u00e7\u00e3o transfronteiri\u00e7a quando o navio holand\u00eas Nova Zeelandia entrou no porto. N\u00e3o havia ind\u00edcios imediatos de que o navio operasse ilegalmente, mas uma avalia\u00e7\u00e3o retrospectiva de monitoria, controlo e vigil\u00e2ncia identificou lacunas na utiliza\u00e7\u00e3o do sistema de identifica\u00e7\u00e3o autom\u00e1tica do navio, uma pr\u00e1tica conhecida como desligamento.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Muitas vezes, os barcos fazem isso para ocultar opera\u00e7\u00f5es ilegais.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Uma investiga\u00e7\u00e3o revelou que o navio tinha operado com navios doadores com bandeira dos Camar\u00f5es para transbordar ilegalmente peixe no mar. Os Camar\u00f5es s\u00e3o um Estado de bandeira sancionado pela Uni\u00e3o Europeia por viola\u00e7\u00f5es das regras de pesca. Ap\u00f3s an\u00e1lise, o Gana contactou Angola atrav\u00e9s do Centro de Coordena\u00e7\u00e3o de Monitoria, Controlo e Vigil\u00e2ncia da Comunidade para o Desenvolvimento da \u00c1frica Austral (SADC) e confirmou que o navio tamb\u00e9m tinha transbordado ilegalmente peixe no mar, uma pr\u00e1tica conhecida como saiko, juntamente com os outros quatro navios. Os documentos do Nova Zeelandia tamb\u00e9m eram falsos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Durante a investiga\u00e7\u00e3o, a plataforma de comunica\u00e7\u00e3o regional da For\u00e7a-Tarefa da \u00c1frica Ocidental organizou uma colabora\u00e7\u00e3o em tempo real com Angola, Benin, Costa do Marfim e Gana, todas as \u00e1reas por onde o navio navegou. Isso levou Angola a abrir um processo judicial contra o Nova Zeelandia e os outros navios envolvidos na saiko. Em 2024, o Nova Zeelandia foi proibido de continuar a operar em Angola. Os Camar\u00f5es multaram cada propriet\u00e1rio de navio por incumprimento das leis nacionais de pesca.<\/p>\n<p>\u201cO caso Nova Zeelandia serve de modelo para futuros esfor\u00e7os de aplica\u00e7\u00e3o da lei multirregionais, mostrando como a implementa\u00e7\u00e3o robusta do PSMA [Acordo sobre Medidas do Estado do Porto] e a aplica\u00e7\u00e3o da lei baseada em informa\u00e7\u00f5es podem encerrar redes de pesca INN,\u201d Johnstone escreveu num relat\u00f3rio da TMT.<\/p>\n<p><strong>Protegendo as \u00c1guas da \u00c1frica Austral<\/strong><\/p>\n<p>Dentro da SADC, o Madag\u00e1scar \u00e9 visto como promotor da transpar\u00eancia e da coopera\u00e7\u00e3o regional nos esfor\u00e7os para combater os crimes mar\u00edtimos e melhorar a economia azul.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>O Centro Regional de Fus\u00e3o de Informa\u00e7\u00f5es Mar\u00edtimas do Madag\u00e1scar ajuda a identificar embarca\u00e7\u00f5es suspeitas. A monitoria constante pela sala de vigil\u00e2ncia do centro ajuda a alertar as ag\u00eancias regionais de fiscaliza\u00e7\u00e3o da lei mar\u00edtima sobre amea\u00e7as em tempo \u00fatil.<\/p>\n<figure id=\"attachment_131762\" aria-describedby=\"caption-attachment-131762\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg\"><img decoding=\"async\" class=\"size-full wp-image-131762\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg\" alt=\"\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket-1024x683.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket-150x100.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket-450x300.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-131762\" class=\"wp-caption-text\">Um homem trabalha num mercado de peixe em Conacri, na Guin\u00e9. GETTY IMAGES<\/figcaption><\/figure>\n<p>O centro do Madag\u00e1scar partilha informa\u00e7\u00f5es com a sua opera\u00e7\u00e3o irm\u00e3, o Centro Regional de Coordena\u00e7\u00e3o Operacional das Seychelles, e com qualquer pa\u00eds que enfrente uma amea\u00e7a mar\u00edtima. O centro das Seychelles realiza principalmente ac\u00e7\u00f5es conjuntas de fiscaliza\u00e7\u00e3o da lei no mar.<\/p>\n<p>Os analistas recomendaram que todos os pa\u00edses da regi\u00e3o se juntem \u00e0 arquitectura do Programa de Seguran\u00e7a Mar\u00edtima para que possam receber informa\u00e7\u00f5es dos centros regionais. Comores, Djibouti, Fran\u00e7a em nome da Ilha Reuni\u00e3o, Qu\u00e9nia, Madag\u00e1scar, Maur\u00edcias, Seychelles e Tanz\u00e2nia s\u00e3o os actuais membros do programa.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Em Abril de 2025, o Centro de Coordena\u00e7\u00e3o de Monitoria, Controlo e Vigil\u00e2ncia da SADC; o centro do Madag\u00e1scar; Stop Illegal Fishing; TMT; o Fundo Mundial para a Natureza; e Fitsinjo, um observat\u00f3rio local de pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada; participaram num workshop de quatro dias com o objectivo de estabelecer um registo regional de embarca\u00e7\u00f5es de pesca. Eles apresentaram aos inspectores de pesca de seis portos do Madag\u00e1scar as ferramentas e a metodologia promovidas pelo centro da SADC para avaliar os riscos dos navios de pesca e refor\u00e7ar os processos de tomada de decis\u00e3o para lidar com actividades suspeitas.<\/p>\n<p>Em Agosto de 2024, o Madag\u00e1scar revelou um plano quinquenal para implementar quotas de pesca, criar \u00e1reas marinhas protegidas e diversificar as fontes de rendimento das comunidades pesqueiras.<\/p>\n<p>\u201cAo capacitar os pescadores, atrav\u00e9s de forma\u00e7\u00e3o e educa\u00e7\u00e3o, pretendemos garantir que a pesca em pequena escala continue a ser uma actividade vi\u00e1vel e sustent\u00e1vel para as gera\u00e7\u00f5es futuras,\u201d Paubert Mahatante, Ministro das Pescas e da Economia Azul do Madag\u00e1scar, disse \u00e0 SeafoodSource. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<hr \/>\n<h3 id=\"malignos\"><strong>Os M\u00e9todos Malignos da China<\/strong><\/h3>\n<p>A China, que possui a maior frota de pesca em \u00e1guas long\u00ednquas do mundo, tem o pior hist\u00f3rico de pesca ilegal do mundo, de acordo com o \u00cdndice de Risco de Pesca INN. Entre as principais 10 empresas envolvidas na pesca ilegal, a n\u00edvel mundial, oito s\u00e3o provenientes da China. Os arrast\u00f5es de Pequim podem capturar cinco vezes mais peixes num dia do que uma pequena frota de uma aldeia num ano.<\/p>\n<p>Os arrast\u00f5es chineses s\u00e3o conhecidos por praticarem o \u201cflagging in\u201d em pa\u00edses africanos, o que significa que usam e abusam dos regulamentos locais para atribuir bandeira a uma embarca\u00e7\u00e3o de propriet\u00e1rios e operada por estrangeiros, colocando-a num registo africano, para pescar em \u00e1guas locais. O flagging in \u00e9 um sinal comum de que os navios est\u00e3o a pescar ilegalmente. Entre os m\u00e9todos de pesca ilegal mais destrutivos praticados pela frota chinesa est\u00e1 a pesca de arrasto de fundo. Em toda a \u00c1frica, a frota de arrasto de fundo da China captura cerca de 2,35 milh\u00f5es de toneladas de peixe por ano, estimadas em mais de 5 bilh\u00f5es de d\u00f3lares, de acordo com a Funda\u00e7\u00e3o para a Justi\u00e7a Ambiental. Al\u00e9m de roubar alimentos e rendimentos ao continente, a pesca de arrasto de fundo destr\u00f3i ecossistemas de que os peixes precisam para sobreviver e captura indiscriminadamente todo o tipo de vida marinha.<\/p>\n<p>Outros m\u00e9todos ilegais empregues pelos arrast\u00f5es chineses incluem a pesca com explosivos, a pesca com luzes potentes \u00e0 noite, a pesca em \u00e1reas proibidas, como a zona econ\u00f3mica exclusiva de um pa\u00eds, e a \u201csaiko,\u201d o transbordo ilegal de peixe no mar. Na saiko, as capturas s\u00e3o transferidas de um arrast\u00e3o para uma grande canoa capaz de transportar cerca de 450 vezes mais peixe do que uma canoa de pesca artesanal. Os arrast\u00f5es de Pequim tamb\u00e9m s\u00e3o conhecidos por destruir artes de pesca utilizadas pelos pescadores locais e virar as suas canoas, causando por vezes mortes.<\/p>\n<p>Em Abril de 2025, o Minist\u00e9rio das Pescas e Aquicultura do Gana e a Comiss\u00e3o das Pescas suspenderam por 12 meses as licen\u00e7as de pesca de quatro arrast\u00f5es chineses por praticarem a saiko, despejarem peixe indesejado, pescarem em zonas restritas e capturarem peixes juvenis. A pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada custa ao pa\u00eds entre 14,4 e 23,7 milh\u00f5es de d\u00f3lares anualmente.<\/p>\n<p>\u201cA saiko est\u00e1 a precipitar o colapso das unidades populacionais de peixes b\u00e1sicos do Gana e, com isso, a pobreza e a fome do seu povo,\u201d Steve Trent, director-executivo da Funda\u00e7\u00e3o para a Justi\u00e7a Ambiental, disse numa reportagem da Dialogue Earth. \u201cOs arrast\u00f5es chineses est\u00e3o a ganhar milh\u00f5es de d\u00f3lares num com\u00e9rcio ilegal que representa mais da metade dos peixes capturados por barcos industriais no Gana.\u201d<\/p>\n<p>Os arrast\u00f5es Meng Xin 10, Florence 2, Long Xiang 607 e Long Xiang 608 estavam registados no Gana, mas s\u00e3o propriedade de tr\u00eas empresas chinesas, informou o Ghana Business News.<\/p>\n<p>A frota Meng Xin, propriedade da Dalian Mengxin Ocean Fishery Co., est\u00e1 ligada ao desaparecimento, em 2019, do observador de pesca gan\u00eas, Emmanuel Essien. Ele desapareceu do arrast\u00e3o Meng Xin 15 depois de filmar a tripula\u00e7\u00e3o a descartar ilegalmente peixe no mar e apresentar uma den\u00fancia \u00e0 Comiss\u00e3o das Pescas do pa\u00eds. E jamais foi encontrado.<\/p>\n<hr \/>\n<h4><strong>Em Termos Num\u00e9ricos<\/strong><\/h4>\n<p>A pesca ilegal rouba receitas ao continente, amea\u00e7a o sustento de milh\u00f5es de trabalhadores e provoca a inseguran\u00e7a alimentar h\u00e1 d\u00e9cadas. Estes n\u00fameros ilustram a dimens\u00e3o do problema:<\/p>\n<ul>\n<li><b>O continente perde <\/b>11,2 BILH\u00d5ES DE D\u00d3LARES <b>por ano devido \u00e0 pesca ilegal.<\/b><\/li>\n<li>9,4 BILH\u00d5ES DE D\u00d3LARES<b> s\u00e3o perdidos s\u00f3 na \u00c1frica Ocidental devido \u00e0 pesca ilegal.<\/b><\/li>\n<li>40% <b>dos arrast\u00f5es ilegais do mundo pescam na \u00c1frica Ocidental.<\/b><\/li>\n<li>7 MILH\u00d5ES<b> de pessoas na \u00c1frica Ocidental dependem <\/b><b>do peixe para alimenta\u00e7\u00e3o e emprego.<\/b><\/li>\n<li><b>Na Costa do Marfim, a captura total anual <\/b>CAIU QUASE 40%<b> entre 2003 e 2020, em grande parte devido \u00e0 pesca ilegal.<\/b><\/li>\n<li><b>O potencial m\u00e1ximo de captura para a <\/b><b>Costa do Marfim, o Gana e a Nig\u00e9ria poder\u00e1 <\/b>CAIR CERCA DE 50%<b> at\u00e9 meados do s\u00e9culo.<\/b><\/li>\n<li><b>No Gana, o total da captura de pequenos peixes <\/b><b>pel\u00e1gicos, um alimento b\u00e1sico da dieta nacional, <\/b>CAIU 59%<b> entre 1993 e 2019.<\/b><\/li>\n<li><b>Das <\/b>10 MAIORES<b> empresas envolvidas na pesca ilegal a n\u00edvel mundial, oito s\u00e3o <\/b>CHINESAS<b>.<\/b><\/li>\n<li><b>A frota de arrasto de fundo da China captura cerca de <\/b>2,35 MILH\u00d5ES<b> de toneladas de peixe por ano em todo o continente, avaliadas em mais de<\/b> 5 BILH\u00d5ES de d\u00f3lares<b>.<\/b><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1frica perde cerca de 11,2 bilh\u00f5es de d\u00f3lares em receitas anuais devido \u00e0 pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN). O desafio \u00e9 particularmente grave na \u00c1frica Ocidental, que perde cerca de 9,4 bilh\u00f5es de d\u00f3lares com este flagelo. A pesca ilegal praticada por arrast\u00f5es industriais e semi-industriais estrangeiros, particularmente da China, tem causado<\/p>\n","protected":false},"author":1,"featured_media":131774,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[334],"tags":[636,669,820],"class_list":["post-132266","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportagens","tag-cedeao","tag-liberia-pt-pt","tag-sadc-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"\u00c1frica perde cerca de 11,2 bilh\u00f5es de d\u00f3lares em receitas anuais devido \u00e0 pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN). O desafio \u00e9 particularmente grave na \u00c1frica Ocidental, que perde cerca de 9,4 bilh\u00f5es de d\u00f3lares com este flagelo. A pesca ilegal praticada por arrast\u00f5es industriais e semi-industriais estrangeiros, particularmente da China, tem causado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T13:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T13:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"\u2018Uma Abordagem Simples\u2019\",\"datePublished\":\"2025-11-07T13:59:30+00:00\",\"dateModified\":\"2025-11-17T13:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/\"},\"wordCount\":2207,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/iuu-intro.jpg\",\"keywords\":[\"CEDEAO\",\"Liberia\",\"SADC\"],\"articleSection\":[\"Reportagens\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/\",\"name\":\"\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/iuu-intro.jpg\",\"datePublished\":\"2025-11-07T13:59:30+00:00\",\"dateModified\":\"2025-11-17T13:57:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/iuu-intro.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/iuu-intro.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Um pescador artesanal do Senegal usa uma linha de m\u00e3o perto de dois arrast\u00f5es chineses. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-abordagem-simples\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Uma Abordagem Simples\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/","og_locale":"pt_PT","og_type":"article","og_title":"\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum","og_description":"\u00c1frica perde cerca de 11,2 bilh\u00f5es de d\u00f3lares em receitas anuais devido \u00e0 pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN). O desafio \u00e9 particularmente grave na \u00c1frica Ocidental, que perde cerca de 9,4 bilh\u00f5es de d\u00f3lares com este flagelo. A pesca ilegal praticada por arrast\u00f5es industriais e semi-industriais estrangeiros, particularmente da China, tem causado","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-11-07T13:59:30+00:00","article_modified_time":"2025-11-17T13:57:47+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_image":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-bucket.jpg","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"\u2018Uma Abordagem Simples\u2019","datePublished":"2025-11-07T13:59:30+00:00","dateModified":"2025-11-17T13:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/"},"wordCount":2207,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-intro.jpg","keywords":["CEDEAO","Liberia","SADC"],"articleSection":["Reportagens"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/","name":"\u2018Uma Abordagem Simples\u2019 - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-intro.jpg","datePublished":"2025-11-07T13:59:30+00:00","dateModified":"2025-11-17T13:57:47+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-intro.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/iuu-intro.jpg","width":1080,"height":720,"caption":"Um pescador artesanal do Senegal usa uma linha de m\u00e3o perto de dois arrast\u00f5es chineses. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-abordagem-simples\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"\u2018Uma Abordagem Simples\u2019"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=132266"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/131774"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=132266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=132266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=132266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}