{"id":132251,"date":"2025-11-06T15:46:17","date_gmt":"2025-11-06T20:46:17","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=132251"},"modified":"2025-11-17T08:58:52","modified_gmt":"2025-11-17T13:58:52","slug":"uma-serie-de-desafios","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/","title":{"rendered":"Uma S\u00e9rie de Desafios"},"content":{"rendered":"<p><strong><i><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/ADF_V18N3_ENG_Rampersad-Sooroojebally.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-132245\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/ADF_V18N3_ENG_Rampersad-Sooroojebally.jpg\" alt=\"\" width=\"180\" height=\"180\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/ADF_V18N3_ENG_Rampersad-Sooroojebally.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/ADF_V18N3_ENG_Rampersad-Sooroojebally-150x150.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/ADF_V18N3_ENG_Rampersad-Sooroojebally-70x70.jpg 70w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a>Rampersad Sooroojebally \u00e9 um veterano da Pol\u00edcia das Maur\u00edcias, tendo-se alistado em 1971. Antes de ser nomeado comiss\u00e1rio a 15 de Novembro de 2024, desempenhou um papel fundamental na reestrutura\u00e7\u00e3o da Unidade Antidroga e Contrabando da for\u00e7a policial. Ele tamb\u00e9m projectou e liderou a Unidade Antiterrorismo do pa\u00eds, que colecta e analisa informa\u00e7\u00f5es antes de dissemin\u00e1-las \u00e0s autoridades policiais. Os seus coment\u00e1rios foram editados por quest\u00f5es de espa\u00e7o e clareza.<\/i><\/strong><\/p>\n<p><b>ADF: <\/b>Apesar da sua pequena extens\u00e3o, as Maur\u00edcias patrulham uma zona econ\u00f3mica exclusiva (ZEE) que se estende por 2,3 milh\u00f5es de quil\u00f3metros quadrados, aproximadamente o mesmo tamanho do maior pa\u00eds da \u00c1frica, a Arg\u00e9lia. Pode descrever a estrat\u00e9gia geral do seu pa\u00eds para maximizar os recursos destinados a monitorar e proteger essa \u00e1rea?<\/p>\n<p><b>Sooroojebally: <\/b>Como disse, as Maur\u00edcias t\u00eam uma ZEE muito grande, cerca de 1.200 vezes a nossa massa terrestre. Isso apresenta uma s\u00e9rie de desafios. A Guarda Costeira Nacional (NCG), que \u00e9 o bra\u00e7o mar\u00edtimo da Pol\u00edcia das Maur\u00edcias, tem a responsabilidade de proteger estas zonas mar\u00edtimas. A NCG concentra-se em v\u00e1rias \u00e1reas-chave, tais como capacidades de recolha de informa\u00e7\u00f5es, promo\u00e7\u00e3o da colabora\u00e7\u00e3o e refor\u00e7o das capacidades. A nossa capacidade de monitorar e analisar as actividades mar\u00edtimas foi refor\u00e7ada para garantir que as opera\u00e7\u00f5es s\u00e3o orientadas pela intelig\u00eancia e pela informa\u00e7\u00e3o.<\/p>\n<p>Em colabora\u00e7\u00e3o, a NCG coopera activamente com ag\u00eancias de seguran\u00e7a mar\u00edtima nacionais, regionais e internacionais para partilhar informa\u00e7\u00f5es e coordenar esfor\u00e7os. A n\u00edvel interno, coopera estreitamente com unidades da Pol\u00edcia das Maur\u00edcias, tais como a Unidade Antidroga e Contrabando e o Servi\u00e7o de Passaportes e Imigra\u00e7\u00e3o, bem como com organiza\u00e7\u00f5es externas, como a Sec\u00e7\u00e3o Antinarc\u00f3ticos das Alf\u00e2ndegas, a Autoridade das Pescas, a Autoridade do Turismo e a Autoridade Mar\u00edtima e Portu\u00e1ria. A NCG tamb\u00e9m colabora activamente com for\u00e7as mar\u00edtimas de pa\u00edses com ideias semelhantes, bem como com organiza\u00e7\u00f5es multilaterais para detectar e impedir actividades mar\u00edtimas il\u00edcitas.<\/p>\n<p>O investimento cont\u00ednuo em tecnologia e equipamentos modernos para a NCG tem sido um foco do governo. Ao longo dos anos, adquirimos novos navios, aeronaves, barcos de alta velocidade, sistemas de vigil\u00e2ncia e software, que aumentaram a nossa capacidade de vigiar e conduzir opera\u00e7\u00f5es de forma eficaz. Estamos tamb\u00e9m a actualizar muitos destes sistemas tecnol\u00f3gicos em r\u00e1pida evolu\u00e7\u00e3o, tais como o sistema de vigil\u00e2ncia por radar costeiro.<\/p>\n<figure id=\"attachment_131818\" aria-describedby=\"caption-attachment-131818\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-131818\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit.jpg\" alt=\"\" width=\"1080\" height=\"727\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit-300x202.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit-1024x689.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit-768x517.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit-150x101.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/RC2LBDAAD4YD_edit-450x303.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-131818\" class=\"wp-caption-text\">Membros da Pol\u00edcia das Maur\u00edcias marcham durante a celebra\u00e7\u00e3o do 57.\u00ba Dia Nacional do pa\u00eds no hip\u00f3dromo Champ de Mars, Port Louis, Maur\u00edcias, no dia 12 de Mar\u00e7o de 2025. REUTERS<\/figcaption><\/figure>\n<p><b>ADF: <\/b>Como \u00e9 que estes sistemas tecnol\u00f3gicos protegem as vossas \u00e1guas?<\/p>\n<p><b>Sooroojebally: <\/b>Desempenham um papel fundamental na vigil\u00e2ncia da nossa vasta ZEE e no refor\u00e7o da nossa conscientiza\u00e7\u00e3o do dom\u00ednio mar\u00edtimo. A NCG utiliza v\u00e1rias ferramentas e software para rastrear e monitorar navios mercantes, navios de pesca e outras embarca\u00e7\u00f5es de interesse na nossa zona mar\u00edtima. A NCG tem uma abordagem de vigil\u00e2ncia em v\u00e1rias camadas que inclui um sistema de radar de vigil\u00e2ncia costeira, um sistema de identifica\u00e7\u00e3o autom\u00e1tica, ou AIS, aeronaves de vigil\u00e2ncia, navios e mecanismos de partilha de informa\u00e7\u00f5es para monitorar os movimentos das embarca\u00e7\u00f5es em tempo real.<\/p>\n<p>Estamos tamb\u00e9m a criar um Centro Nacional de Partilha de Informa\u00e7\u00f5es Mar\u00edtimas para melhor aproveitar a tecnologia e agilizar o fluxo de informa\u00e7\u00f5es entre v\u00e1rias partes interessadas internas e externas, a fim de refor\u00e7ar a nossa capacidade de monitorar as nossas zonas mar\u00edtimas. A adop\u00e7\u00e3o e absor\u00e7\u00e3o de tecnologia \u00e9 um processo cont\u00ednuo, e continuamos a adquirir e integrar essas ferramentas para fortalecer as nossas capacidades de vigil\u00e2ncia e interven\u00e7\u00e3o.<\/p>\n<p><b>ADF: <\/b>O crime organizado, como o tr\u00e1fico de drogas, armas e seres humanos, \u00e9 predominante no Oceano \u00cdndico e no Canal de Mo\u00e7ambique. Que tipos de actividades mar\u00edtimas ilegais a sua for\u00e7a enfrenta?<\/p>\n<p><b>Sooroojebally: <\/b>Enfrentamos desafios significativos, incluindo actividades mar\u00edtimas il\u00edcitas que amea\u00e7am a nossa seguran\u00e7a, a nossa economia e a nossa ecologia. Entre elas, o tr\u00e1fico de drogas continua a ser uma das preocupa\u00e7\u00f5es mais prementes para o pa\u00eds. Os efeitos nocivos do tr\u00e1fico de drogas v\u00e3o muito al\u00e9m do seu impacto imediato, contribuindo para o aumento de actividades il\u00edcitas associadas que prejudicam o bem-estar da sociedade. Os oceanos continuam a servir como canal para o contrabando de drogas, e tem sido nosso esfor\u00e7o constante implementar medidas robustas para combater essa amea\u00e7a.<\/p>\n<p>A pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada [INN] \u00e9 uma outra grande amea\u00e7a. A regi\u00e3o do Oceano \u00cdndico abriga algumas das pescarias mais importantes do mundo, que sustentam milh\u00f5es de meios de subsist\u00eancia e desempenham um papel fundamental na seguran\u00e7a alimentar global. A pesca excessiva e n\u00e3o regulamentada pode perturbar os ecossistemas marinhos, esgotar os recursos pesqueiros e criar desequil\u00edbrios ecol\u00f3gicos a longo prazo. \u00c9 uma grande prioridade e trabalhamos arduamente para proteger os nossos recursos marinhos e promover pr\u00e1ticas sustent\u00e1veis.<\/p>\n<p>Outras actividades mar\u00edtimas ilegais, como o tr\u00e1fico de seres humanos e a imigra\u00e7\u00e3o ilegal, tamb\u00e9m representam desafios significativos. Essas actividades n\u00e3o s\u00f3 violam as leis nacionais e internacionais, mas tamb\u00e9m colocam em risco vidas humanas e prejudicam a estabilidade regional.<\/p>\n<p>O ambiente \u00e9 outra quest\u00e3o importante devido ao turismo. Precisamos que as pessoas venham para as Maur\u00edcias. N\u00e3o h\u00e1 d\u00favida disso. Coordenamos e auxiliamos o governo a evitar desastres ambientais.<\/p>\n<p><b>ADF: <\/b>Descreva a rela\u00e7\u00e3o das Maur\u00edcias com a \u00cdndia em mat\u00e9ria de seguran\u00e7a mar\u00edtima e como essa parceria ganhou import\u00e2ncia nos \u00faltimos anos.<\/p>\n<p><b>Sooroojebally: <\/b>A nossa rela\u00e7\u00e3o \u00e9 profunda e baseada em la\u00e7os culturais, hist\u00f3ricos, lingu\u00edsticos e diplom\u00e1ticos fortes. Isso tamb\u00e9m refor\u00e7ou a parceria em seguran\u00e7a mar\u00edtima entre os dois pa\u00edses. Ao longo dos anos, o interesse comum em garantir a seguran\u00e7a e a estabilidade da regi\u00e3o do Oceano \u00cdndico refor\u00e7ou ainda mais a nossa coopera\u00e7\u00e3o e rela\u00e7\u00e3o. As iniciativas da \u00cdndia, como as iniciativas SAGAR [Seguran\u00e7a e Crescimento para Todos na Regi\u00e3o] e MAHASAGAR [Avan\u00e7o M\u00fatuo e Hol\u00edstico da Seguran\u00e7a e do Crescimento para Todos na Regi\u00e3o], que promovem a seguran\u00e7a cooperativa e o desenvolvimento mar\u00edtimo sustent\u00e1vel, est\u00e3o alinhadas com os interesses das Maur\u00edcias, e esperamos fortalecer ainda mais esta coopera\u00e7\u00e3o para um Oceano \u00cdndico seguro, protegido e est\u00e1vel.<\/p>\n<figure id=\"attachment_131626\" aria-describedby=\"caption-attachment-131626\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg\"><img decoding=\"async\" class=\"size-full wp-image-131626\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg\" alt=\"\" width=\"1080\" height=\"728\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit-300x202.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit-1024x690.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit-768x518.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit-150x101.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit-450x303.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-131626\" class=\"wp-caption-text\">Membros da Guarda Costeira Nacional das Maur\u00edcias realizam treino de visita, abordagem, busca e apreens\u00e3o durante o Exerc\u00edcio Cutlass Express em Port Louis, no dia 20 de Fevereiro de 2025. Suboficial de 2.\u00aa Classe NATALIA KAI\/MARINHA DOS EUA<\/figcaption><\/figure>\n<p><b>ADF: <\/b>Qual \u00e9 a sua preocupa\u00e7\u00e3o com as perdas financeiras anuais de milh\u00f5es de d\u00f3lares causadas pela pesca ilegal, n\u00e3o declarada e n\u00e3o regulamentada (INN) e qual \u00e9 o impacto disso na economia das Maur\u00edcias?<\/p>\n<p><b>Sooroojebally: <\/b>A pesca INN \u00e9 uma amea\u00e7a significativa para as Maur\u00edcias. Ela esgota os recursos pesqueiros, afectando a capacidade dos pescadores legais de capturar e vender peixe. Distorce os pre\u00e7os de mercado. Amea\u00e7a os meios de subsist\u00eancia e tamb\u00e9m compromete a seguran\u00e7a alimentar.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>O sector das pescas emprega mais de 20.000 pessoas, sendo que s\u00f3 a ind\u00fastria do atum emprega mais de 7.000 pessoas. O esgotamento dos recursos pesqueiros devido \u00e0s actividades INN compromete a nossa ind\u00fastria de exporta\u00e7\u00e3o de frutos do mar e prejudica o crescimento econ\u00f3mico. Para combater isso, as Maur\u00edcias tomaram medidas en\u00e9rgicas, incluindo a ratifica\u00e7\u00e3o do Acordo sobre Medidas do Estado do Porto para impedir a entrada de peixes capturados ilegalmente nos nossos portos. Tamb\u00e9m estamos a refor\u00e7ar as nossas capacidades de vigil\u00e2ncia e a melhorar a coopera\u00e7\u00e3o regional para combater a pesca INN. A economia azul surgiu como um pilar da nossa prosperidade e desenvolvimento econ\u00f3micos. Abordar a quest\u00e3o da pesca INN \u00e9 crucial para garantir a prosperidade a longo prazo da economia das Maur\u00edcias.<\/p>\n<p><b>ADF: <\/b>O que \u00e9 necess\u00e1rio fazer para identificar e impedir os navios de pesca INN? Quais s\u00e3o as estrat\u00e9gias mais eficazes no combate \u00e0 pesca INN e a outros crimes mar\u00edtimos nas \u00e1guas da \u00c1frica Oriental?<\/p>\n<p><b>Sooroojebally: <\/b>Na luta contra a pesca ilegal, a NCG coordena com o Departamento das Pescas a monitoriza\u00e7\u00e3o das nossas \u00e1guas. Realizamos uma vigil\u00e2ncia a\u00e9rea e mar\u00edtima extensiva, juntamente com patrulhas costeiras, para coibir a pesca ilegal na \u00e1rea. Os esfor\u00e7os da NCG tamb\u00e9m levaram \u00e0 detec\u00e7\u00e3o e preven\u00e7\u00e3o da pesca ilegal em \u00e1reas costeiras e resultaram na confisca\u00e7\u00e3o de redes de pesca ilegais que se estendiam por quase 6 quil\u00f3metros. Este tipo de ac\u00e7\u00e3o tem sido fundamental para proteger os nossos recursos marinhos e garantir a sustentabilidade das nossas pescas. O refor\u00e7o da coopera\u00e7\u00e3o regional com outros pa\u00edses da regi\u00e3o que tamb\u00e9m s\u00e3o afectados por problemas semelhantes torna, sem d\u00favida, mais eficazes os esfor\u00e7os contra a pesca INN. Acordo sobre Medidas do Estado do Porto tem sido crucial para impedir que o peixe capturado ilegalmente entre nos portos.<\/p>\n<p><b>ADF: <\/b>Qu\u00e3o ben\u00e9ficas t\u00eam sido as organiza\u00e7\u00f5es regionais, como o Centro de Coordena\u00e7\u00e3o Regional de Opera\u00e7\u00f5es das Seychelles e o Centro Regional de Fus\u00e3o de Informa\u00e7\u00f5es Mar\u00edtimas de Madag\u00e1scar, para o seu trabalho nas Maur\u00edcias? Como gostaria que este tipo de parcerias evolu\u00edsse e se expandisse?<\/p>\n<p><b>Sooroojebally: <\/b>Elas t\u00eam sido vitais para garantir a colabora\u00e7\u00e3o com os pa\u00edses da regi\u00e3o na luta contra as actividades mar\u00edtimas ilegais. Elas t\u00eam sido capazes de fornecer informa\u00e7\u00f5es, melhorar a consci\u00eancia situacional e permitir respostas regionais coordenadas a amea\u00e7as como a pesca INN e o tr\u00e1fico. Essas parcerias fortalecem a nossa capacidade colectiva de monitorar e proteger as nossas vastas zonas mar\u00edtimas. No futuro, vemos grande valor em continuar essas colabora\u00e7\u00f5es por meio de um maior interc\u00e2mbio de informa\u00e7\u00f5es e da inclus\u00e3o de mais parceiros regionais. \u00c0 medida que as amea\u00e7as mar\u00edtimas se tornam cada vez mais complexas, este tipo de esfor\u00e7os coordenados e baseados em informa\u00e7\u00f5es s\u00e3o essenciais para garantir a seguran\u00e7a e a estabilidade colectivas no Oceano \u00cdndico Ocidental.<\/p>\n<p><b>ADF: <\/b>As Maur\u00edcias acolheram um grande grupo de l\u00edderes seniores na Cimeira das For\u00e7as Mar\u00edtimas Africanas, em Junho de 2025. O que faz com que encontros como este sejam \u00fateis?<\/p>\n<p><b>Sooroojebally: <\/b>Todos queremos construir um ambiente mar\u00edtimo mais seguro e est\u00e1vel, por isso, encontros como a Cimeira das For\u00e7as Mar\u00edtimas Africanas e o Simp\u00f3sio de L\u00edderes da Infantaria Naval de \u00c1frica s\u00e3o inestim\u00e1veis para promover a colabora\u00e7\u00e3o, partilhar as melhores pr\u00e1ticas e refor\u00e7ar a seguran\u00e7a mar\u00edtima regional. Estes eventos re\u00fanem l\u00edderes seniores, decisores e especialistas. Eles proporcionam uma plataforma para discutir amea\u00e7as mar\u00edtimas emergentes, como a pirataria, a pesca ilegal e o tr\u00e1fico, que afectam v\u00e1rios pa\u00edses. H\u00e1 uma troca maravilhosa de ideias sobre novas tecnologias, estrat\u00e9gias e quadros operacionais. Ao criar um espa\u00e7o para o di\u00e1logo aberto, constru\u00edmos confian\u00e7a e melhoramos a coordena\u00e7\u00e3o entre as for\u00e7as mar\u00edtimas africanas, e garantimos que as nossas respostas \u00e0s amea\u00e7as \u00e0 seguran\u00e7a mar\u00edtima sejam mais eficazes.<span class=\"Apple-converted-space\"> \u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rampersad Sooroojebally \u00e9 um veterano da Pol\u00edcia das Maur\u00edcias, tendo-se alistado em 1971. Antes de ser nomeado comiss\u00e1rio a 15 de Novembro de 2024, desempenhou um papel fundamental na reestrutura\u00e7\u00e3o da Unidade Antidroga e Contrabando da for\u00e7a policial. Ele tamb\u00e9m projectou e liderou a Unidade Antiterrorismo do pa\u00eds, que colecta e analisa informa\u00e7\u00f5es antes de<\/p>\n","protected":false},"author":1,"featured_media":131802,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[334],"tags":[1009,545,998],"class_list":["post-132251","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportagens","tag-lideranca","tag-maritimo","tag-perguntas-e-respostas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma S\u00e9rie de Desafios - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma S\u00e9rie de Desafios - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Rampersad Sooroojebally \u00e9 um veterano da Pol\u00edcia das Maur\u00edcias, tendo-se alistado em 1971. Antes de ser nomeado comiss\u00e1rio a 15 de Novembro de 2024, desempenhou um papel fundamental na reestrutura\u00e7\u00e3o da Unidade Antidroga e Contrabando da for\u00e7a policial. Ele tamb\u00e9m projectou e liderou a Unidade Antiterrorismo do pa\u00eds, que colecta e analisa informa\u00e7\u00f5es antes de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T20:46:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T13:58:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Uma S\u00e9rie de Desafios\",\"datePublished\":\"2025-11-06T20:46:17+00:00\",\"dateModified\":\"2025-11-17T13:58:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/\"},\"wordCount\":2020,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mauritius-Police-rev.jpg\",\"keywords\":[\"lideran\u00e7a\",\"mar\u00edtimo\",\"Perguntas e Respostas\"],\"articleSection\":[\"Reportagens\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/\",\"name\":\"Uma S\u00e9rie de Desafios - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mauritius-Police-rev.jpg\",\"datePublished\":\"2025-11-06T20:46:17+00:00\",\"dateModified\":\"2025-11-17T13:58:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mauritius-Police-rev.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mauritius-Police-rev.jpg\",\"width\":886,\"height\":734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/11\\\/uma-serie-de-desafios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma S\u00e9rie de Desafios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma S\u00e9rie de Desafios - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/","og_locale":"pt_PT","og_type":"article","og_title":"Uma S\u00e9rie de Desafios - Africa Defense Forum","og_description":"Rampersad Sooroojebally \u00e9 um veterano da Pol\u00edcia das Maur\u00edcias, tendo-se alistado em 1971. Antes de ser nomeado comiss\u00e1rio a 15 de Novembro de 2024, desempenhou um papel fundamental na reestrutura\u00e7\u00e3o da Unidade Antidroga e Contrabando da for\u00e7a policial. Ele tamb\u00e9m projectou e liderou a Unidade Antiterrorismo do pa\u00eds, que colecta e analisa informa\u00e7\u00f5es antes de","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-11-06T20:46:17+00:00","article_modified_time":"2025-11-17T13:58:52+00:00","og_image":[{"width":1080,"height":728,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_image":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/CE25VBSS1_edit.jpg","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Uma S\u00e9rie de Desafios","datePublished":"2025-11-06T20:46:17+00:00","dateModified":"2025-11-17T13:58:52+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/"},"wordCount":2020,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/Mauritius-Police-rev.jpg","keywords":["lideran\u00e7a","mar\u00edtimo","Perguntas e Respostas"],"articleSection":["Reportagens"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/","name":"Uma S\u00e9rie de Desafios - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/Mauritius-Police-rev.jpg","datePublished":"2025-11-06T20:46:17+00:00","dateModified":"2025-11-17T13:58:52+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/Mauritius-Police-rev.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/Mauritius-Police-rev.jpg","width":886,"height":734},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/11\/uma-serie-de-desafios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Uma S\u00e9rie de Desafios"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=132251"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/132251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/131802"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=132251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=132251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=132251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}