{"id":122894,"date":"2025-01-28T15:18:44","date_gmt":"2025-01-28T20:18:44","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=122894"},"modified":"2025-01-28T15:19:03","modified_gmt":"2025-01-28T20:19:03","slug":"forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/","title":{"rendered":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico"},"content":{"rendered":"<p style=\"font-weight: 400;\">EQUIPA DA ADF<\/p>\n<p style=\"font-weight: 400;\">As for\u00e7as de seguran\u00e7a da regi\u00e3o de Puntl\u00e2ndia, na Som\u00e1lia, destru\u00edram recentemente v\u00e1rias bases operacionais do Estado Isl\u00e2mico (EI-Som\u00e1lia) nas montanhas de Cal Miskaad, no extremo norte do pa\u00eds.<\/p>\n<p style=\"font-weight: 400;\">As montanhas tornaram-se um ref\u00fagio para o EI-Som\u00e1lia e um \u00edman para os combatentes estrangeiros que se deslocam para a Som\u00e1lia a partir dos pa\u00edses africanos vizinhos e do M\u00e9dio Oriente atrav\u00e9s do Golfo de \u00c1den. As for\u00e7as de seguran\u00e7a encontraram um passaporte saudita entre os objectos capturados na rusga, de acordo com a Ag\u00eancia Nacional de Not\u00edcias da Som\u00e1lia.<\/p>\n<p style=\"font-weight: 400;\">Os ataques na regi\u00e3o de Cal Miskaad fazem parte de uma estrat\u00e9gia mais alargada das autoridades da Puntl\u00e2ndia para envolver os cl\u00e3s \u00e9tnicos da regi\u00e3o na luta contra o EI-Som\u00e1lia. As autoridades pediram ajuda especificamente aos cl\u00e3s que vivem perto das montanhas Cal Miskaad.<\/p>\n<p style=\"font-weight: 400;\">\u201cA luta n\u00e3o pode ser ganha apenas pelas for\u00e7as de seguran\u00e7a,\u201d o primeiro vice-presidente do parlamento da Puntl\u00e2ndia, Mohamed Bari Shire, disse num comunicado. \u201cPrecisamos da coragem e da coopera\u00e7\u00e3o das pessoas para proteger as nossas comunidades.\u201d<\/p>\n<p style=\"font-weight: 400;\">O EI-Som\u00e1lia encontra-se activo na Puntl\u00e2ndia desde 2015, quando um grupo de combatentes do al-Shabaab se separou e trocou a alian\u00e7a com a al-Qaeda pelo grupo Estado Isl\u00e2mico. Nos anos que se seguiram, o EI-Som\u00e1lia tem-se dedicado a assassinatos e atentados bombistas na Puntl\u00e2ndia.<\/p>\n<p style=\"font-weight: 400;\">Bari est\u00e1 a liderar a campanha para controlar o EI-Som\u00e1lia depois de o grupo terrorista ter atacado uma base das for\u00e7as antiterroristas da Puntl\u00e2ndia em Dharjaale, no dia 31 de Dezembro.<\/p>\n<p style=\"font-weight: 400;\">O ataque das 4 da manh\u00e3 incluiu dois ve\u00edculos-bomba e quatro combatentes com coletes-bomba. Mais de 20 soldados morreram nos combates antes de as for\u00e7as de seguran\u00e7a terem conseguido repelir o ataque. Uma d\u00fazia de terroristas morreram.<\/p>\n<p style=\"font-weight: 400;\">No dia seguinte, em comunicado, o EI-Som\u00e1lia afirmou que os 12 terroristas mortos eram provenientes de sete pa\u00edses: Arg\u00e9lia, Eti\u00f3pia, L\u00edbia, Marrocos, Tanz\u00e2nia, Tun\u00edsia e I\u00e9men. A composi\u00e7\u00e3o cada vez mais internacional do EI-Som\u00e1lia aumenta o risco de o grupo promover ataques para al\u00e9m da Puntl\u00e2ndia, segundo o analista Liam Kerr, do Instituto para o Estudo da Guerra.<\/p>\n<p style=\"font-weight: 400;\">A localiza\u00e7\u00e3o de Puntl\u00e2ndia e a sua paisagem acidentada fazem dela um campo de batalha fundamental para o EI-Som\u00e1lia, que tem refor\u00e7ado as suas fileiras com combatentes estrangeiros e receitas de extors\u00e3o, segundo os especialistas. Ao longo do \u00faltimo ano, o EI-Som\u00e1lia assumiu em grande medida o controlo da regi\u00e3o de Cal Miskaad, facto que as autoridades somalis confirmaram ao The Somali Digest em Abril de 2024. Segundo o The Somali Digest, o governo de Puntl\u00e2ndia mant\u00e9m a autoridade sobre as comunidades dispersas e as estradas da regi\u00e3o pouco povoada. Tanto o al-Shabaab como o EI-Som\u00e1lia infiltraram-se na regi\u00e3o a p\u00e9 para evitar as for\u00e7as de seguran\u00e7a.<\/p>\n<p style=\"font-weight: 400;\">As autoridades da Puntl\u00e2ndia acreditam que o EI-Som\u00e1lia \u00e9 constitu\u00eddo por 200 a 300 combatentes. A maior parte dos combatentes prov\u00e9m da vizinha Eti\u00f3pia, sendo os restantes provenientes de outros pa\u00edses.<\/p>\n<p style=\"font-weight: 400;\">Ao envolver os cl\u00e3s da Puntl\u00e2ndia na persegui\u00e7\u00e3o dos combatentes do EI-Som\u00e1lia, as autoridades podem evitar os erros que permitiram que os bombistas suicidas de Dharjaale passassem por v\u00e1rias comunidades entre Cal Miskaad e a base militar sem darem o alerta.<\/p>\n<p style=\"font-weight: 400;\">As autoridades da Puntl\u00e2ndia consideram este acontecimento como uma falha importante do seu sistema de informa\u00e7\u00f5es. Embora os residentes locais se sintam intimidados pelos combatentes do EI-Som\u00e1lia, os l\u00edderes da Puntl\u00e2ndia v\u00eaem esses mesmos residentes como uma componente fundamental para seguir os movimentos dos terroristas nos vastos espa\u00e7os abertos da regi\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">O Presidente da Puntl\u00e2ndia, Said Abdullahi Deni, anunciou recentemente a Opera\u00e7\u00e3o Hillaac, uma campanha antiterrorista em grande escala para erradicar os esconderijos de militantes no terreno montanhoso da Puntl\u00e2ndia.<\/p>\n<p style=\"font-weight: 400;\">A opera\u00e7\u00e3o \u00e9 inteiramente planeada e executada pelas autoridades da Puntl\u00e2ndia. Envolve as For\u00e7as de Defesa da Puntl\u00e2ndia, a For\u00e7a de Pol\u00edcia Mar\u00edtima da Puntl\u00e2ndia e a Pol\u00edcia Antiterrorista.<\/p>\n<p><span style=\"font-weight: 400;\">\u201cEsta \u00e9 uma luta pela sobreviv\u00eancia e estabilidade da Puntl\u00e2ndia e da Som\u00e1lia,\u201d Deni disse num comunicado.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF As for\u00e7as de seguran\u00e7a da regi\u00e3o de Puntl\u00e2ndia, na Som\u00e1lia, destru\u00edram recentemente v\u00e1rias bases operacionais do Estado Isl\u00e2mico (EI-Som\u00e1lia) nas montanhas de Cal Miskaad, no extremo norte do pa\u00eds. As montanhas tornaram-se um ref\u00fagio para o EI-Som\u00e1lia e um \u00edman para os combatentes estrangeiros que se deslocam para a Som\u00e1lia a partir<\/p>\n","protected":false},"author":1,"featured_media":122892,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[1207,535,1139],"class_list":{"0":"post-122894","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-estado-islamico","9":"tag-somalia-pt-pt","10":"tag-terrorism-pt-pt"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF As for\u00e7as de seguran\u00e7a da regi\u00e3o de Puntl\u00e2ndia, na Som\u00e1lia, destru\u00edram recentemente v\u00e1rias bases operacionais do Estado Isl\u00e2mico (EI-Som\u00e1lia) nas montanhas de Cal Miskaad, no extremo norte do pa\u00eds. As montanhas tornaram-se um ref\u00fagio para o EI-Som\u00e1lia e um \u00edman para os combatentes estrangeiros que se deslocam para a Som\u00e1lia a partir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T20:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T20:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico\",\"datePublished\":\"2025-01-28T20:18:44+00:00\",\"dateModified\":\"2025-01-28T20:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/\"},\"wordCount\":764,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PUNTLAND-CLANS-1.jpg\",\"keywords\":[\"Estado Isl\u00e2mico\",\"Somalia\",\"Terrorism\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/\",\"name\":\"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PUNTLAND-CLANS-1.jpg\",\"datePublished\":\"2025-01-28T20:18:44+00:00\",\"dateModified\":\"2025-01-28T20:19:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PUNTLAND-CLANS-1.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PUNTLAND-CLANS-1.jpg\",\"width\":860,\"height\":657,\"caption\":\"For\u00e7as da Puntl\u00e2ndia participam numa opera\u00e7\u00e3o para afastar os terroristas do Estado Isl\u00e2mico das montanhas de Al-Miskaad. AG\u00caNCIA NOTICIOSA NACIONAL DA SOM\u00c1LIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2025\\\/01\\\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/","og_locale":"pt_PT","og_type":"article","og_title":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum","og_description":"EQUIPA DA ADF As for\u00e7as de seguran\u00e7a da regi\u00e3o de Puntl\u00e2ndia, na Som\u00e1lia, destru\u00edram recentemente v\u00e1rias bases operacionais do Estado Isl\u00e2mico (EI-Som\u00e1lia) nas montanhas de Cal Miskaad, no extremo norte do pa\u00eds. As montanhas tornaram-se um ref\u00fagio para o EI-Som\u00e1lia e um \u00edman para os combatentes estrangeiros que se deslocam para a Som\u00e1lia a partir","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-01-28T20:18:44+00:00","article_modified_time":"2025-01-28T20:19:03+00:00","og_image":[{"width":860,"height":657,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico","datePublished":"2025-01-28T20:18:44+00:00","dateModified":"2025-01-28T20:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/"},"wordCount":764,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg","keywords":["Estado Isl\u00e2mico","Somalia","Terrorism"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/","name":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg","datePublished":"2025-01-28T20:18:44+00:00","dateModified":"2025-01-28T20:19:03+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/01\/PUNTLAND-CLANS-1.jpg","width":860,"height":657,"caption":"For\u00e7as da Puntl\u00e2ndia participam numa opera\u00e7\u00e3o para afastar os terroristas do Estado Isl\u00e2mico das montanhas de Al-Miskaad. AG\u00caNCIA NOTICIOSA NACIONAL DA SOM\u00c1LIA"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2025\/01\/forcas-de-seguranca-da-puntlandia-recrutam-clas-para-a-luta-contra-os-terroristas-do-estado-islamico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"For\u00e7as de Seguran\u00e7a da Puntl\u00e2ndia Recrutam Cl\u00e3s para a Luta Contra os Terroristas do Estado Isl\u00e2mico"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/122894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=122894"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/122894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/122892"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=122894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=122894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=122894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}