{"id":119251,"date":"2024-10-18T10:41:35","date_gmt":"2024-10-18T14:41:35","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=119251"},"modified":"2024-10-18T10:41:35","modified_gmt":"2024-10-18T14:41:35","slug":"criminosos-ciberneticos-veem-africa-como-campo-de-ensaio","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/","title":{"rendered":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio"},"content":{"rendered":"<p>EQUIPA DA ADF<\/p>\n<p>Um v\u00edrus de ransomware que infecta sistemas inform\u00e1ticos em \u00c1frica \u00e9 a mais recente prova de que os criminosos est\u00e3o a utilizar o continente como campo de ensaio para novos ataques.<\/p>\n<p>O v\u00edrus Medusa visa empresas e ag\u00eancias governamentais, bloqueando os utilizadores do sistema e amea\u00e7ando expor informa\u00e7\u00f5es sens\u00edveis se n\u00e3o for pago um resgate.<\/p>\n<p>O mesmo atingiu a Autoridade Aeroportu\u00e1ria do Qu\u00e9nia, bancos da \u00c1frica do Sul e outras empresas e organiza\u00e7\u00f5es. A empresa de seguran\u00e7a cibern\u00e9tica Performanta, sediada em Londres, estudou os ataques e descobriu o que parece ser uma estrat\u00e9gia para se concentrar inicialmente em organiza\u00e7\u00f5es de pa\u00edses com pouca experi\u00eancia em defesa cibern\u00e9tica, incluindo pa\u00edses de \u00c1frica.<\/p>\n<p>\u201cPara conseguirmos um ambiente mais seguro em termos de seguran\u00e7a cibern\u00e9tica para todas as organiza\u00e7\u00f5es a n\u00edvel mundial, temos de aumentar a sensibiliza\u00e7\u00e3o para este problema crescente,\u201d afirmou Guy Golan, Director-Executivo da Performanta, segundo a p\u00e1gina da internet de not\u00edcias sobre seguran\u00e7a cibern\u00e9tica Dark Reading. \u201cS\u00f3 compreendendo as tend\u00eancias e os padr\u00f5es da guerra cibern\u00e9tica geopol\u00edtica \u00e9 que poderemos clarificar o panorama global das amea\u00e7as.\u201d<\/p>\n<figure id=\"attachment_118591\" aria-describedby=\"caption-attachment-118591\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-118591\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit.jpg\" alt=\"\" width=\"1080\" height=\"764\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit-300x212.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit-1024x724.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit-768x543.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit-150x106.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/iStock-1017628288_edit-450x318.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-118591\" class=\"wp-caption-text\">\u00c0 medida que as fam\u00edlias em toda a \u00c1frica passam tempo online, enfrentam novas amea\u00e7as cibern\u00e9ticas.<\/figcaption><\/figure>\n<p>O Dr. Robinson Sibe, director-executivo da empresa de seguran\u00e7a cibern\u00e9tica Digital Footprints, com sede na Nig\u00e9ria, afirma que, embora o \u201cr\u00e1pido crescimento da conectividade\u201d em \u00c1frica tenha sido positivo do ponto de vista do desenvolvimento, \u201ctamb\u00e9m se traduz num aumento s\u00fabito de utilizadores vulner\u00e1veis e numa superf\u00edcie de ataque alargada.\u201d Por correio electr\u00f3nico, Sibe disse \u00e0 ADF que os criminosos cibern\u00e9ticos \u201csimplesmente aproveitam-se da baixa prepara\u00e7\u00e3o e maturidade das institui\u00e7\u00f5es do continente africano em termos de seguran\u00e7a cibern\u00e9tica.\u201d<\/p>\n<p>\u201cMuitas das institui\u00e7\u00f5es de \u00c1frica, tanto p\u00fablicas como privadas, t\u00eam um n\u00edvel muito baixo de prepara\u00e7\u00e3o para a seguran\u00e7a cibern\u00e9tica e s\u00e3o, por isso, vulner\u00e1veis,\u201d escreveu. \u201cO criminoso cibern\u00e9tico estar\u00e1 mais motivado para visar um alvo vulner\u00e1vel.\u201d<\/p>\n<p>A criminalidade cibern\u00e9tica assume muitas formas. A Universidade de Norwich observa que os criminosos que se infiltram em computadores e redes desenvolveram software malicioso e t\u00e9cnicas de engenharia social para cometer diferentes tipos de crime cibern\u00e9tico. A universidade divide o crime cibern\u00e9tico em cinco categorias:<\/p>\n<ul>\n<li>A pirataria inform\u00e1tica \u00e9 o acto de obter acesso n\u00e3o autorizado a dados de um computador ou de uma rede. Os piratas inform\u00e1ticos exploram as fraquezas dos sistemas para roubar dados que v\u00e3o desde informa\u00e7\u00f5es pessoais e segredos empresariais a informa\u00e7\u00f5es governamentais. Os piratas inform\u00e1ticos tamb\u00e9m penetram nas redes para perturbar as opera\u00e7\u00f5es governamentais e comerciais. As autoridades afirmam que este tipo de pirataria custa bilh\u00f5es de d\u00f3lares por ano.<\/li>\n<li>Malware, ou software malicioso, refere-se a qualquer programa\u00e7\u00e3o concebida para interferir com o funcionamento normal de um computador ou para cometer um crime cibern\u00e9tico. O malware existe desde que os computadores se tornaram amplamente dispon\u00edveis, com toda uma ind\u00fastria dedicada ao seu bloqueio. Os tipos comuns de malware incluem v\u00edrus, worms, trojans invasivos e v\u00e1rios programas h\u00edbridos. Os subconjuntos de malware incluem adware, spyware e ransomware. \u201cBloqueando ficheiros digitais valiosos e exigindo um resgate para a sua liberta\u00e7\u00e3o, os ataques de ransomware s\u00e3o normalmente executados com recurso a um trojan \u2014 malware que disfar\u00e7a a sua verdadeira inten\u00e7\u00e3o,\u201d refere a Norwich. \u201cO ransomware infiltra-se normalmente atrav\u00e9s de e-mail, levando o utilizador a clicar num anexo ou a visitar um site que infecta o computador com c\u00f3digo malicioso.\u201d Os alvos do ransomware incluem servi\u00e7os p\u00fablicos, hospitais, escolas, governos estatais e locais, ag\u00eancias de lei e empresas.<\/li>\n<li>Quando algu\u00e9m obt\u00e9m ilegalmente as informa\u00e7\u00f5es pessoais de outra pessoa e as utiliza para cometer um roubo ou fraude, trata-se de roubo de identidade. Nem todos os roubos de identidade resultam de ataques cibern\u00e9ticos, mas o malware, como os trojans e o spyware, \u00e9 frequentemente utilizado para roubar informa\u00e7\u00f5es pessoais. O phishing, a pr\u00e1tica fraudulenta de enviar mensagens de e-mail ou outras mensagens que se fazem passar por empresas id\u00f3neas para obter informa\u00e7\u00f5es pessoais, como palavras-passe e n\u00fameros de cart\u00f5es de cr\u00e9dito, \u00e9 uma forma de roubo de identidade. Os ataques de phishing a empresas t\u00eam agora o seu pr\u00f3prio nome: compromisso do e-mail comercial.<\/li>\n<li>A engenharia social \u00e9 a manipula\u00e7\u00e3o psicol\u00f3gica de pessoas para que realizem ac\u00e7\u00f5es ou divulguem informa\u00e7\u00f5es confidenciais. Os criminosos cibern\u00e9ticos utilizam a engenharia social para cometer fraudes online. Os sites de namoro online podem proporcionar oportunidades para iniciar conversas com potenciais v\u00edtimas com o objectivo de as enganar e tirar-lhes o seu dinheiro.<\/li>\n<li>A pirataria de software \u00e9 a reprodu\u00e7\u00e3o, distribui\u00e7\u00e3o e utiliza\u00e7\u00e3o n\u00e3o autorizadas de software. Nos prim\u00f3rdios da tecnologia pessoal nos pa\u00edses africanos, os computadores eram normalmente carregados com software pirata contendo v\u00edrus. O software pirata assume a forma de produtos comerciais contrafeitos, incluindo sistemas operativos e software de escrit\u00f3rio. O grupo comercial BSA estima que 37% do software instalado em computadores pessoais a n\u00edvel mundial n\u00e3o est\u00e1 licenciado. Os criminosos cibern\u00e9ticos adicionam frequentemente malware ao software pirateado.<\/li>\n<\/ul>\n<p>O advento e o aperfei\u00e7oamento da intelig\u00eancia artificial acrescentar\u00e3o um novo n\u00edvel de complexidade \u00e0 luta contra a criminalidade cibern\u00e9tica. O X-Force Threat Intelligence Index 2024, compilado por uma equipa de piratas inform\u00e1ticos, respons\u00e1veis, investigadores e analistas, observou que a intelig\u00eancia artificial generativa, que utiliza modelos de aprendizagem profunda para criar novos conte\u00fados, incluindo texto, imagens, m\u00fasica, \u00e1udio e v\u00eddeos, obrigar\u00e1 todos a rever a forma como definem e respondem \u00e0s amea\u00e7as cibern\u00e9ticas.<\/p>\n<p>\u201cOs decisores pol\u00edticos, os executivos de empresas e os profissionais de seguran\u00e7a cibern\u00e9tica est\u00e3o todos a sentir a press\u00e3o para adoptar a IA nas suas opera\u00e7\u00f5es,\u201d observou o \u00edndice, conforme relatado pela Business Insider Africa. \u201cE a pressa em adoptar a IA [generativa] est\u00e1 actualmente a ultrapassar a capacidade da ind\u00fastria para compreender os riscos de seguran\u00e7a que estas novas capacidades ir\u00e3o introduzir.\u201d<\/p>\n<figure id=\"attachment_118467\" aria-describedby=\"caption-attachment-118467\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit.jpg\"><img decoding=\"async\" class=\"size-full wp-image-118467\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit.jpg\" alt=\"\" width=\"1080\" height=\"559\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit-300x155.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit-1024x530.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit-768x398.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit-150x78.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cyber-Organized-Crime-in-West-Africa_edit-450x233.jpg 450w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-118467\" class=\"wp-caption-text\">Funcion\u00e1rios discutem sobre o crime cibern\u00e9tico e as respostas eficazes durante um workshop regional sobre o Crime Organizado Cibern\u00e9tico na \u00c1frica Ocidental em Abidjan, Costa do Marfim. NA\u00c7\u00d5ES UNIDAS<\/figcaption><\/figure>\n<p><strong>A PRAGA DO RANSOMWARE<\/strong><\/p>\n<p>O ransomware data de 1989 e tornou-se uma for\u00e7a destrutiva em quase todos os locais onde os computadores s\u00e3o utilizados. As v\u00edtimas recusam-se frequentemente a revelar se pagaram resgates e, em caso afirmativo, o montante pago. No seu relat\u00f3rio anual sobre crimes, a empresa de rastreamento de criptomoedas Chainalysis calculou que os pagamentos de ransomware ultrapassaram 1,1 bilh\u00f5es de d\u00f3lares em 2023, com base no rastreamento desses pagamentos em blockchains. Foi o n\u00famero mais elevado alguma vez medido pela empresa num \u00fanico ano e quase o dobro do ano anterior.<\/p>\n<p>O Dr. Nate Allen, professor associado do Centro de Estudos Estrat\u00e9gicos de \u00c1frica, afirma que os pa\u00edses e as empresas africanas se tornaram alvos de ransomware.<\/p>\n<p>\u201cO ransomware \u00e9 uma grande amea\u00e7a, em parte, porque, por vezes, o ransomware atinge elementos-chave de infra-estruturas cr\u00edticas, como portos, redes el\u00e9ctricas ou servi\u00e7os governamentais,\u201d afirmou num e-mail enviado \u00e0 ADF. \u201cTodos foram desactivados por ransomware em v\u00e1rias partes de \u00c1frica nos \u00faltimos anos. E este \u00e9 um desafio particular para \u00c1frica porque, embora os pa\u00edses africanos n\u00e3o tenham o mesmo grau de infra-estruturas cr\u00edticas dependentes da tecnologia que os pa\u00edses ocidentais, as que t\u00eam servem, muitas vezes, uma parte significativa da popula\u00e7\u00e3o e podem funcionar com software desactualizado, o que as torna um alvo apetec\u00edvel.\u201d<\/p>\n<p>Sibe e Allen concordam que o compromisso de e-mail comercial, ou BEC, se tornou uma enorme fraude em \u00c1frica e resultar\u00e1 em ataques sofisticados de phishing contra utilizadores desprevenidos.<\/p>\n<p>\u201cDe acordo com as estimativas do FBI, os actores do BEC foram respons\u00e1veis por dezenas de bilh\u00f5es de d\u00f3lares de perdas,\u201d Allen disse \u00e0 ADF. \u201cEstavam entre os grupos mais prol\u00edficos de piratas inform\u00e1ticos que cometeram fraudes em mat\u00e9ria de seguros e presta\u00e7\u00f5es sociais durante a pandemia da COVID-19, roubando centenas de milh\u00f5es, se n\u00e3o bilh\u00f5es, de d\u00f3lares em ajudas destinadas a pessoas que perderam o emprego ou tiveram de suspender as suas vidas devido \u00e0 pandemia.\u201d<\/p>\n<p>Num relat\u00f3rio de 2023, a empresa de consultoria Control Risk referiu que as quest\u00f5es relacionadas com o crime cibern\u00e9tico tornar-se-\u00e3o provavelmente \u201ccada vez mais relevantes\u201d em \u00c1frica, \u00e0 medida que os criminosos cibern\u00e9ticos se tornam mais sofisticados. O relat\u00f3rio afirma que as empresas que operam em \u00c1frica e as empresas africanas que pretendem expandir-se para fora do continente \u201cter\u00e3o cada vez mais de considerar a seguran\u00e7a cibern\u00e9tica a par da seguran\u00e7a f\u00edsica no seu planeamento.\u201d As empresas que operam em \u00c1frica s\u00e3o suscept\u00edveis de enfrentar amea\u00e7as de seguran\u00e7a cibern\u00e9tica cada vez mais sofisticadas e uma exposi\u00e7\u00e3o crescente a quest\u00f5es f\u00edsicas, como a concorr\u00eancia geopol\u00edtica ou a criminalidade, que se tornam mais proeminentes no espa\u00e7o cibern\u00e9tico, segundo o relat\u00f3rio.<\/p>\n<figure id=\"attachment_118443\" aria-describedby=\"caption-attachment-118443\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit.jpg\"><img decoding=\"async\" class=\"size-full wp-image-118443\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit.jpg\" alt=\"\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-1024x683.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-150x100.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-450x300.jpg 450w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Africa-Cyber-Defense-Forum-2023_edit-272x182.jpg 272w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-118443\" class=\"wp-caption-text\">O Ruanda acolheu o F\u00f3rum Africano de Defesa Cibern\u00e9tica de 2023, uma confer\u00eancia anual que re\u00fane os principais especialistas mundiais em seguran\u00e7a cibern\u00e9tica e l\u00edderes governamentais. AUTORIDADE NACIONAL DE SEGURAN\u00c7A CIBERN\u00c9TICA DO RUANDA<\/figcaption><\/figure>\n<p><strong>PIRATAS INFORM\u00c1TICOS EXTERNOS<\/strong><\/p>\n<p>Estudos mostram que uma parte da criminalidade cibern\u00e9tica em \u00c1frica \u00e9 de origem interna. No entanto, Sibe observou que existem \u201cfontes abundantes\u201d que mostram que muitos ataques cibern\u00e9ticos em \u00c1frica prov\u00eam de maus actores em pa\u00edses fora do continente.<\/p>\n<p>\u201cHouve v\u00e1rios relatos de ataques cibern\u00e9ticos em \u00c1frica, ligados a agentes de amea\u00e7as russos e aos seus representantes no espa\u00e7o africano,\u201d escreveu. \u201cAl\u00e9m disso, no ano passado, durante as elei\u00e7\u00f5es na Nig\u00e9ria, o Ministro das Comunica\u00e7\u00f5es e da Economia Digital anunciou milh\u00f5es de ataques cibern\u00e9ticos contra as infra-estruturas eleitorais do pa\u00eds. De acordo com o comunicado, a maior parte delas teve origem fora do pa\u00eds (e do continente).<\/p>\n<p>\u201cNuma das elei\u00e7\u00f5es estatais anteriores, alguns dos ataques ter\u00e3o tido origem na \u00c1sia. Em 2021, a Equipa Nigeriana de Resposta a Emerg\u00eancias Inform\u00e1ticas emitiu um aviso de que um grupo de piratas inform\u00e1ticos iraniano conhecido como Lyceum estava a visar empresas de telecomunica\u00e7\u00f5es e Minist\u00e9rios dos Neg\u00f3cios Estrangeiros, na Nig\u00e9ria e noutros pa\u00edses africanos.\u201d<\/p>\n<p>Sibe observou tamb\u00e9m que, em 2022, os criminosos cibern\u00e9ticos russos foram responsabilizados por ataques a sites de apostas populares na Nig\u00e9ria e noutros pa\u00edses. Observou que, em 2023, houve relatos de grupos de amea\u00e7as patrocinados pelo Estado chin\u00eas que efectuaram ataques sustentados contra empresas de telecomunica\u00e7\u00f5es e institui\u00e7\u00f5es governamentais em pa\u00edses africanos.<\/p>\n<p><strong>FALTA DE SENSIBILIZA\u00c7\u00c3O<\/strong><\/p>\n<p>Sibe afirma que um dos principais problemas de muitos pa\u00edses africanos \u00e9 a falta de sensibiliza\u00e7\u00e3o sobre o crime cibern\u00e9tico.<\/p>\n<p>\u201cComo se costuma dizer, o utilizador \u00e9, muitas vezes, o elo mais fraco de uma implementa\u00e7\u00e3o de seguran\u00e7a,\u201d Sibe disse \u00e0 ADF. \u201cIndependentemente das implementa\u00e7\u00f5es de seguran\u00e7a, sem um utilizador capaz, haver\u00e1 sempre desafios. Dito isto, as institui\u00e7\u00f5es e os pa\u00edses africanos precisam de investir na seguran\u00e7a cibern\u00e9tica para melhorar a sua resili\u00eancia e prontid\u00e3o. A maioria das institui\u00e7\u00f5es tem pouco ou nenhum or\u00e7amento para a seguran\u00e7a cibern\u00e9tica. As organiza\u00e7\u00f5es precisam de refor\u00e7ar a sua resili\u00eancia cibern\u00e9tica atrav\u00e9s de melhores infra-estruturas, processos e forma\u00e7\u00e3o regular do pessoal.\u201d<\/p>\n<p>Acrescentou que \u00e9 necess\u00e1ria uma colabora\u00e7\u00e3o mais estreita entre as institui\u00e7\u00f5es p\u00fablicas e privadas, bem como um melhor acompanhamento dos processos de criminalidade cibern\u00e9tica. Observou que existe legisla\u00e7\u00e3o espec\u00edfica sobre o crime cibern\u00e9tico na maioria dos pa\u00edses africanos, mas a menos que os sistemas de justi\u00e7a e as autoridades policiais estejam \u201cjuridicamente preparados,\u201d os criminosos cibern\u00e9ticos sempre aproveitar-se-\u00e3o das lacunas na ac\u00e7\u00e3o penal.<\/p>\n<p>\u201cAl\u00e9m disso, a \u00c1frica tem um dos n\u00fameros mais baixos de especialistas em seguran\u00e7a cibern\u00e9tica do mundo,\u201d afirmou. \u201cN\u00e3o se pode travar uma guerra formid\u00e1vel contra os criminosos cibern\u00e9ticos sem pessoal competente. Para resolver este problema de forma sustent\u00e1vel, os governos t\u00eam de refor\u00e7ar estrategicamente as institui\u00e7\u00f5es de ensino. A ideia \u00e9 aumentar as compet\u00eancias para colmatar o d\u00e9fice crescente de talentos no dom\u00ednio da seguran\u00e7a cibern\u00e9tica.\u201d<\/p>\n<p>Allen disse que a luta contra o crime cibern\u00e9tico \u00e9 complicada pelo facto de ser um termo demasiado restrito para o que est\u00e1 a acontecer em \u00c1frica.<\/p>\n<p>Isso deve-se ao facto de haver cada vez mais um elemento \u201ccibern\u00e9tico\u201d em quase tudo o que fazemos, incluindo no dom\u00ednio da seguran\u00e7a,\u201d afirmou. A utiliza\u00e7\u00e3o abusiva dos recursos cibern\u00e9ticos pode incluir a espionagem e a vigil\u00e2ncia patrocinadas pelo Estado; a subvers\u00e3o cibern\u00e9tica ou a chantagem dirigida a institui\u00e7\u00f5es ou indiv\u00edduos importantes; e a crescente depend\u00eancia dos sistemas militares, incluindo os que est\u00e3o a ser implantados em \u00c1frica, numa s\u00e9rie de tecnologias digitais.<\/p>\n<p>Allen observou que o crescimento econ\u00f3mico de \u00c1frica depender\u00e1, em grande medida, da forma como as na\u00e7\u00f5es lidam com os crimes cibern\u00e9ticos.<\/p>\n<p>\u201cO crescimento econ\u00f3mico em \u00c1frica e em todo o mundo est\u00e1 cada vez mais ligado ao crescimento digital,\u201d escreveu. \u201cEstudos estimam, por exemplo, que, por cada aumento de 10% na conectividade em \u00c1frica, obt\u00e9m-se um aumento de 2,5% no produto interno bruto. Ao mesmo tempo, o crime cibern\u00e9tico est\u00e1 a caminho de tornar-se uma ind\u00fastria de 10 trilh\u00f5es de d\u00f3lares at\u00e9 2025. A quest\u00e3o \u00e9 que n\u00e3o se pode ter um crescimento digital sem sistemas digitais seguros e, na medida em que os sistemas em \u00c1frica s\u00e3o particularmente vulner\u00e1veis \u00e0s amea\u00e7as cibern\u00e9ticas, isso ser\u00e1 um entrave \u00e0 prosperidade econ\u00f3mica.\u201d<span class=\"Apple-converted-space\"> \u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF Um v\u00edrus de ransomware que infecta sistemas inform\u00e1ticos em \u00c1frica \u00e9 a mais recente prova de que os criminosos est\u00e3o a utilizar o continente como campo de ensaio para novos ataques. O v\u00edrus Medusa visa empresas e ag\u00eancias governamentais, bloqueando os utilizadores do sistema e amea\u00e7ando expor informa\u00e7\u00f5es sens\u00edveis se n\u00e3o for<\/p>\n","protected":false},"author":1,"featured_media":118471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[334],"tags":[857,1448],"class_list":{"0":"post-119251","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-reportagens","8":"tag-ciberseguranca","9":"tag-ciberseguranca-pt-pt"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF Um v\u00edrus de ransomware que infecta sistemas inform\u00e1ticos em \u00c1frica \u00e9 a mais recente prova de que os criminosos est\u00e3o a utilizar o continente como campo de ensaio para novos ataques. O v\u00edrus Medusa visa empresas e ag\u00eancias governamentais, bloqueando os utilizadores do sistema e amea\u00e7ando expor informa\u00e7\u00f5es sens\u00edveis se n\u00e3o for\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T14:41:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio\",\"datePublished\":\"2024-10-18T14:41:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/\"},\"wordCount\":2444,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Cybercriminals.jpg\",\"keywords\":[\"ciberseguran\u00e7a\",\"ciberseguran\u00e7a\"],\"articleSection\":[\"Reportagens\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/\",\"name\":\"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Cybercriminals.jpg\",\"datePublished\":\"2024-10-18T14:41:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Cybercriminals.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Cybercriminals.jpg\",\"width\":1080,\"height\":849},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/10\\\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/","og_locale":"pt_PT","og_type":"article","og_title":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum","og_description":"EQUIPA DA ADF Um v\u00edrus de ransomware que infecta sistemas inform\u00e1ticos em \u00c1frica \u00e9 a mais recente prova de que os criminosos est\u00e3o a utilizar o continente como campo de ensaio para novos ataques. O v\u00edrus Medusa visa empresas e ag\u00eancias governamentais, bloqueando os utilizadores do sistema e amea\u00e7ando expor informa\u00e7\u00f5es sens\u00edveis se n\u00e3o for","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-10-18T14:41:35+00:00","og_image":[{"width":1080,"height":849,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio","datePublished":"2024-10-18T14:41:35+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/"},"wordCount":2444,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg","keywords":["ciberseguran\u00e7a","ciberseguran\u00e7a"],"articleSection":["Reportagens"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/","name":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg","datePublished":"2024-10-18T14:41:35+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/Cybercriminals.jpg","width":1080,"height":849},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/10\/criminosos-ciberneticos-veem-africa-como-campo-de-ensaio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Criminosos Cibern\u00e9ticos V\u00eaem \u00c1frica Como Campo De Ensaio"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/119251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=119251"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/119251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/118471"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=119251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=119251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=119251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}