{"id":113937,"date":"2024-04-05T13:13:33","date_gmt":"2024-04-05T17:13:33","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=113937"},"modified":"2024-04-08T10:07:30","modified_gmt":"2024-04-08T14:07:30","slug":"pontos-de-vista-15","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/","title":{"rendered":"Pontos de Vista"},"content":{"rendered":"<p>Muitos pa\u00edses africanos est\u00e3o a lutar contra o flagelo do tr\u00e1fico il\u00edcito. O com\u00e9rcio ilegal de drogas, armas, minerais e vida selvagem alimenta a instabilidade. Al\u00e9m disso, priva os Estados de receitas fiscais e destr\u00f3i recursos naturais insubstitu\u00edveis.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>As redes est\u00e3o espalhadas por todo o mundo. Os traficantes de droga sul-americanos utilizam a \u00c1frica Ocidental como rota para transportar os estupefacientes para a Europa e a \u00c1sia. As organiza\u00e7\u00f5es mafiosas chinesas transportam a madeira, a vida selvagem e os minerais de \u00c1frica para os mercados asi\u00e1ticos. O Grupo Wagner, da R\u00fassia, tem negociado acordos com os governos dos pa\u00edses anfitri\u00f5es para permitir a explora\u00e7\u00e3o de recursos naturais em troca de promessas de seguran\u00e7a.<\/p>\n<p>Um relat\u00f3rio da organiza\u00e7\u00e3o de investiga\u00e7\u00e3o sobre o crime transnacional ENACT concluiu que 61% das pessoas em \u00c1frica vivem num pa\u00eds com elevados n\u00edveis de crime organizado.<\/p>\n<p>O problema est\u00e1 a aumentar. No seu relat\u00f3rio de 2021, o projecto ENACT estudou 10 crimes, incluindo o tr\u00e1fico de seres humanos, de armas e de droga, bem como o roubo de minerais, da fauna e da flora selvagens. Concluiu que todos os crimes, excepto um \u2014 o tr\u00e1fico de hero\u00edna \u2014 estavam a aumentar.<\/p>\n<p>O tr\u00e1fico concentra-se em pa\u00edses com seguran\u00e7a limitada nas fronteiras e corrup\u00e7\u00e3o end\u00e9mica. A \u00c1frica Central, onde a guerra deixou vastas \u00e1reas efectivamente sem lei, \u00e9 a regi\u00e3o com o maior crescimento do tr\u00e1fico il\u00edcito.<\/p>\n<p>\u201cO conflito proporciona um terreno f\u00e9rtil onde a criminalidade prospera,\u201d escreveram os investigadores do ENACT.<\/p>\n<p>O custo \u00e9 enorme. Os fluxos financeiros il\u00edcitos custam aos pa\u00edses africanos 50 bilh\u00f5es de d\u00f3lares por ano, de acordo com um relat\u00f3rio da Uni\u00e3o Africana. Os autores do relat\u00f3rio admitiram que o total estimado \u00e9 provavelmente baixo.<\/p>\n<p>Mas o preju\u00edzo vai muito para al\u00e9m da perda de receitas. As redes criminosas provocaram um aumento das taxas de toxicodepend\u00eancia e de explora\u00e7\u00e3o dos jovens. Nalguns casos, traficantes poderosos cooptaram funcion\u00e1rios p\u00fablicos, num processo conhecido como \u201ccaptura do Estado.\u201d<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Nenhum pa\u00eds pode enfrentar estas amea\u00e7as sozinho. Os pa\u00edses devem partilhar informa\u00e7\u00f5es e cooperar na aplica\u00e7\u00e3o da lei. As organiza\u00e7\u00f5es internacionais de policiamento, Interpol e Afripol, coordenam esfor\u00e7os para ajudar a lan\u00e7ar uma rede alargada e apanhar os traficantes. Os programas destinados a melhorar a seguran\u00e7a dos portos mar\u00edtimos, aeroportos e fronteiras dificultam o transporte de mercadorias pelos criminosos sem serem detectadas. As medidas de combate \u00e0 corrup\u00e7\u00e3o garantem que os funcion\u00e1rios p\u00fablicos e os profissionais da seguran\u00e7a sirvam as pessoas e n\u00e3o os traficantes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Atrav\u00e9s de uma coopera\u00e7\u00e3o eficaz, os profissionais da seguran\u00e7a podem ajudar a garantir a circula\u00e7\u00e3o segura e legal de pessoas e bens, proteger os recursos naturais e reduzir a criminalidade transfronteiri\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muitos pa\u00edses africanos est\u00e3o a lutar contra o flagelo do tr\u00e1fico il\u00edcito. O com\u00e9rcio ilegal de drogas, armas, minerais e vida selvagem alimenta a instabilidade. Al\u00e9m disso, priva os Estados de receitas fiscais e destr\u00f3i recursos naturais insubstitu\u00edveis.\u00a0 As redes est\u00e3o espalhadas por todo o mundo. Os traficantes de droga sul-americanos utilizam a \u00c1frica Ocidental<\/p>\n","protected":false},"author":1,"featured_media":113598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[335,336],"tags":[],"class_list":{"0":"post-113937","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colunas","8":"category-pontos-de-vista"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pontos de Vista - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pontos de Vista - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Muitos pa\u00edses africanos est\u00e3o a lutar contra o flagelo do tr\u00e1fico il\u00edcito. O com\u00e9rcio ilegal de drogas, armas, minerais e vida selvagem alimenta a instabilidade. Al\u00e9m disso, priva os Estados de receitas fiscais e destr\u00f3i recursos naturais insubstitu\u00edveis.\u00a0 As redes est\u00e3o espalhadas por todo o mundo. Os traficantes de droga sul-americanos utilizam a \u00c1frica Ocidental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T17:13:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T14:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Pontos de Vista\",\"datePublished\":\"2024-04-05T17:13:33+00:00\",\"dateModified\":\"2024-04-08T14:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/\"},\"wordCount\":499,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Viewpoint_1074431044_CMYK.jpg\",\"articleSection\":[\"Colunas\",\"Pontos de Vista\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/\",\"name\":\"Pontos de Vista - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Viewpoint_1074431044_CMYK.jpg\",\"datePublished\":\"2024-04-05T17:13:33+00:00\",\"dateModified\":\"2024-04-08T14:07:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Viewpoint_1074431044_CMYK.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Viewpoint_1074431044_CMYK.jpg\",\"width\":1080,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/04\\\/pontos-de-vista-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pontos de Vista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pontos de Vista - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/","og_locale":"pt_PT","og_type":"article","og_title":"Pontos de Vista - Africa Defense Forum","og_description":"Muitos pa\u00edses africanos est\u00e3o a lutar contra o flagelo do tr\u00e1fico il\u00edcito. O com\u00e9rcio ilegal de drogas, armas, minerais e vida selvagem alimenta a instabilidade. Al\u00e9m disso, priva os Estados de receitas fiscais e destr\u00f3i recursos naturais insubstitu\u00edveis.\u00a0 As redes est\u00e3o espalhadas por todo o mundo. Os traficantes de droga sul-americanos utilizam a \u00c1frica Ocidental","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-04-05T17:13:33+00:00","article_modified_time":"2024-04-08T14:07:30+00:00","og_image":[{"width":1080,"height":721,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Pontos de Vista","datePublished":"2024-04-05T17:13:33+00:00","dateModified":"2024-04-08T14:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/"},"wordCount":499,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg","articleSection":["Colunas","Pontos de Vista"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/","name":"Pontos de Vista - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg","datePublished":"2024-04-05T17:13:33+00:00","dateModified":"2024-04-08T14:07:30+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/04\/Viewpoint_1074431044_CMYK.jpg","width":1080,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/04\/pontos-de-vista-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Pontos de Vista"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/113937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=113937"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/113937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/113598"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=113937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=113937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=113937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}