{"id":113173,"date":"2024-03-26T14:33:16","date_gmt":"2024-03-26T18:33:16","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=113173"},"modified":"2024-03-26T14:33:16","modified_gmt":"2024-03-26T18:33:16","slug":"nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/","title":{"rendered":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">EQUIPA DA ADF<br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\nNove membros da tripula\u00e7\u00e3o de um navio-tanque de produtos qu\u00edmicos que se dirigia da Costa do Marfim para os Camar\u00f5es foram raptados por piratas em Janeiro, quando o navio navegava perto da Guin\u00e9 Equatorial.<\/p>\n<p>A pirataria \u00e9 um dos muitos crimes mar\u00edtimos que prevalecem no Golfo da Guin\u00e9, e os observadores dizem que as tecnologias emergentes podem beneficiar os pa\u00edses que lutam para proteger as suas \u00e1guas.<\/p>\n<p>A Nig\u00e9ria, por exemplo, j\u00e1 foi designada como um foco de pirataria pelo Gabinete Mar\u00edtimo Internacional (IMB). No entanto, o investimento do pa\u00eds em infra-estruturas de base tecnol\u00f3gica ajudou-o a combater a pirataria, a pesca ilegal, o roubo de petr\u00f3leo, o tr\u00e1fico de droga e de armas e outros crimes.<br \/>\n\u201cA Marinha Nigeriana adquiriu continuamente novos activos e melhorou ainda mais as suas capacidades para manter uma grande frota e operar muito para al\u00e9m das suas \u00e1guas territoriais,\u201d o ent\u00e3o Chefe do Estado-Maior da Marinha, Vice-Almirante Awwal Gambo, disse numa reportagem de 2022 do The Guardian.<\/p>\n<p>Nos \u00faltimos tr\u00eas anos, a Nig\u00e9ria implantou o sistema Regional Maritime Awareness Capability (RMAC) e o sistema Falcon Eye de conscientiza\u00e7\u00e3o do dom\u00ednio mar\u00edtimo.<\/p>\n<p>O RMAC recebe, integra, visualiza, regista e distribui dados de sensores e sistemas, incluindo radares de vigil\u00e2ncia mar\u00edtima e a\u00e9rea, sistemas de posicionamento global (GPS), o sistema de identifica\u00e7\u00e3o autom\u00e1tica (AIS), c\u00e2maras e tecnologia de transmiss\u00e3o autom\u00e1tica de vigil\u00e2ncia dependente. Outras ferramentas podem incluir drones e dados de localiza\u00e7\u00e3o por sat\u00e9lite.<\/p>\n<p>O Falcon Eye utiliza uma s\u00e9rie de radares, sistemas electro\u00f3pticos e c\u00e2maras operadas a partir de um centro de comando para monitorizar as \u00e1guas do pa\u00eds e seguir os movimentos dos navios na regi\u00e3o. O antigo vice-presidente da Nig\u00e9ria, Yemi Osinbajo, encomendou o Falcon Eye em 2021.<\/p>\n<p>O sistema \u201cpermitir\u00e1 \u00e0 Marinha Nigeriana gerar um quadro abrangente de informa\u00e7\u00f5es sobre as actividades no nosso ambiente mar\u00edtimo para an\u00e1lise posterior antes de, em casos apropriados, enviar um navio da Marinha Nigeriana para interdi\u00e7\u00e3o, investiga\u00e7\u00e3o e\/ou subsequente deten\u00e7\u00e3o de embarca\u00e7\u00f5es suspeitas,\u201d disse Osinbajo numa reportagem da defenceWeb. \u201cTamb\u00e9m permitir\u00e1 \u00e0 Marinha Nigeriana combater eficazmente quaisquer crimes mar\u00edtimos que possam perturbar a condu\u00e7\u00e3o do com\u00e9rcio mar\u00edtimo.\u201d<\/p>\n<p>Escrevendo no The Conversation, Ifesinachi Okafor-Yarwood, professor da Universidade de St. Louis Andrews, no Reino Unido, destacou o lan\u00e7amento em 2022 do Projecto Deep Blue da Nig\u00e9ria, uma abordagem multifacetada para enfrentar a pirataria. O projecto de 195 milh\u00f5es de d\u00f3lares re\u00fane uma mistura de navios, avi\u00f5es e drones para patrulhar as movimentadas rotas mar\u00edtimas ao largo da costa da Nig\u00e9ria.<\/p>\n<p>Outras tecnologias que est\u00e3o a ser utilizadas para combater os crimes mar\u00edtimos na regi\u00e3o incluem:<\/p>\n<p>* O Sistema de Informa\u00e7\u00e3o Regional da Arquitectura de Yaound\u00e9, ou <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.gogin.eu\/plateforme-yaris\/\">Yaris<\/a><\/span><span style=\"font-weight: 400;\">, uma ferramenta de monitoriza\u00e7\u00e3o digital segura desenvolvida atrav\u00e9s de parcerias com a Rede Inter-regional do Golfo da Guin\u00e9 da Uni\u00e3o Europeia, que aumenta a capacidade de interc\u00e2mbio de informa\u00e7\u00f5es sem descontinuidades.<\/p>\n<p>* <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/info.seavision.volpe.dot.gov\/\">SeaVision<\/a><\/span><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">uma ferramenta de conhecimento do dom\u00ednio mar\u00edtimo que ajuda os profissionais de um centro de opera\u00e7\u00f5es a localizar navios no mar. Criada em 2012 pelos Estados Unidos, esta ferramenta \u00e9 utilizada por cerca de 25 pa\u00edses africanos.<\/p>\n<p>* <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.skylight.global\/\">Skylight<\/a><\/span><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">uma ferramenta de monitoriza\u00e7\u00e3o mar\u00edtima que segue os navios de pesca em tempo real e alerta as autoridades sobre comportamentos suspeitos.<\/p>\n<p>* <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/globalfishingwatch.org\/\">Global Fishing Watch<\/a><\/span><span style=\"font-weight: 400;\">, uma plataforma que apresenta dados AIS e do sistema de monitoriza\u00e7\u00e3o de navios (VMS) atrav\u00e9s do seu portal de navios de transporte e de ferramentas de visualiza\u00e7\u00e3o de navios para ajudar as autoridades a identificar e analisar as opera\u00e7\u00f5es de pesca nas suas \u00e1guas.<\/p>\n<p><\/span><span style=\"font-weight: 400;\">Em muitas zonas, \u00e9 ilegal as embarca\u00e7\u00f5es desligarem o AIS, que transmite dados de identifica\u00e7\u00e3o da embarca\u00e7\u00e3o v\u00e1rias vezes por minuto, e o VMS, que localiza as embarca\u00e7\u00f5es nos sectores do transporte mar\u00edtimo e das pescas. Mas muitos navios envolvidos em actividades suspeitas desligam estes sistemas para evitar a detec\u00e7\u00e3o, uma ac\u00e7\u00e3o conhecida como \u201cficar desligado.\u201d<\/p>\n<p>Inova\u00e7\u00f5es tecnol\u00f3gicas recentes, como o radar de abertura sint\u00e9tica (SAR) e o conjunto de radi\u00f3metros de imagem por infravermelhos para navios (VIIRS), podem ajudar a iluminar a actividade obscura dos navios, como Okafor-Yarwood e outros peritos observaram na Marine Policy, uma revista que estuda as pol\u00edticas oce\u00e2nicas.<\/p>\n<p>O SAR \u00e9 uma vers\u00e3o mais avan\u00e7ada do radar tradicional e pode observar \u00e1reas em quaisquer condi\u00e7\u00f5es meteorol\u00f3gicas e a qualquer momento. Pode ser utilizado em zonas onde os navios desactivam os seus sistemas de localiza\u00e7\u00e3o.<\/p>\n<p>O VIIRS recolhe imagens no vis\u00edvel e no infravermelho e faz observa\u00e7\u00f5es globais da terra, da atmosfera e dos oceanos.Pode ajudar a identificar os navios que utilizam ilegalmente luzes para pescar \u00e0 noite.<\/p>\n<p>Okafor-Yarwood afirmou que \u00e9 do interesse dos pa\u00edses do Golfo da Guin\u00e9 cooperar e colaborar para enfrentar os desafios da seguran\u00e7a mar\u00edtima.<\/p>\n<p>\u201cA tecnologia pode desempenhar um papel fundamental neste dom\u00ednio,\u201d escreveu Okafor-Yarwood no The Conversation. \u201cMas \u00e9 vital que os pa\u00edses reforcem os conhecimentos tecnol\u00f3gicos e assegurem que os parceiros externos e as empresas utilizem os servi\u00e7os tecnol\u00f3gicos dispon\u00edveis. Este ser\u00e1 um grande passo em direc\u00e7\u00e3o a um ambiente mar\u00edtimo seguro e colaborativo.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF Nove membros da tripula\u00e7\u00e3o de um navio-tanque de produtos qu\u00edmicos que se dirigia da Costa do Marfim para os Camar\u00f5es foram raptados por piratas em Janeiro, quando o navio navegava perto da Guin\u00e9 Equatorial. A pirataria \u00e9 um dos muitos crimes mar\u00edtimos que prevalecem no Golfo da Guin\u00e9, e os observadores dizem<\/p>\n","protected":false},"author":1,"featured_media":113125,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[544,453,543,1030,1070],"class_list":{"0":"post-113173","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-golfo-da-guine","9":"tag-nigeria-pt-pt","10":"tag-pesca-ilegal","11":"tag-pirataria","12":"tag-trafico-de-armas-pt-pt"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF Nove membros da tripula\u00e7\u00e3o de um navio-tanque de produtos qu\u00edmicos que se dirigia da Costa do Marfim para os Camar\u00f5es foram raptados por piratas em Janeiro, quando o navio navegava perto da Guin\u00e9 Equatorial. A pirataria \u00e9 um dos muitos crimes mar\u00edtimos que prevalecem no Golfo da Guin\u00e9, e os observadores dizem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T18:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas\",\"datePublished\":\"2024-03-26T18:33:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/\"},\"wordCount\":930,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/MARSEC-TECH_1_sRGB.jpg\",\"keywords\":[\"Golfo da Guin\u00e9\",\"Nigeria\",\"pesca ilegal\",\"pirataria\",\"tr\u00e1fico de armas\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/\",\"name\":\"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/MARSEC-TECH_1_sRGB.jpg\",\"datePublished\":\"2024-03-26T18:33:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/MARSEC-TECH_1_sRGB.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/MARSEC-TECH_1_sRGB.jpg\",\"width\":1080,\"height\":720,\"caption\":\"O sistema de conscientiza\u00e7\u00e3o do dom\u00ednio mar\u00edtimo Falcon Eye da Nig\u00e9ria ajuda a monitorizar as \u00e1guas do pa\u00eds e a seguir os movimentos dos navios na regi\u00e3o. MARINHA NIGERIANA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/03\\\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/","og_locale":"pt_PT","og_type":"article","og_title":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum","og_description":"EQUIPA DA ADF Nove membros da tripula\u00e7\u00e3o de um navio-tanque de produtos qu\u00edmicos que se dirigia da Costa do Marfim para os Camar\u00f5es foram raptados por piratas em Janeiro, quando o navio navegava perto da Guin\u00e9 Equatorial. A pirataria \u00e9 um dos muitos crimes mar\u00edtimos que prevalecem no Golfo da Guin\u00e9, e os observadores dizem","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-03-26T18:33:16+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas","datePublished":"2024-03-26T18:33:16+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/"},"wordCount":930,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg","keywords":["Golfo da Guin\u00e9","Nigeria","pesca ilegal","pirataria","tr\u00e1fico de armas"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/","name":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg","datePublished":"2024-03-26T18:33:16+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/03\/MARSEC-TECH_1_sRGB.jpg","width":1080,"height":720,"caption":"O sistema de conscientiza\u00e7\u00e3o do dom\u00ednio mar\u00edtimo Falcon Eye da Nig\u00e9ria ajuda a monitorizar as \u00e1guas do pa\u00eds e a seguir os movimentos dos navios na regi\u00e3o. MARINHA NIGERIANA"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/03\/nigeria-mostra-que-tecnologia-emergente-pode-ajudar-a-proteger-as-aguas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Nig\u00e9ria Mostra que Tecnologia Emergente Pode Ajudar a Proteger as \u00c1guas"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/113173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=113173"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/113173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/113125"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=113173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=113173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=113173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}