{"id":112570,"date":"2024-02-20T11:56:50","date_gmt":"2024-02-20T16:56:50","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=112570"},"modified":"2024-02-20T11:57:21","modified_gmt":"2024-02-20T16:57:21","slug":"forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/","title":{"rendered":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC"},"content":{"rendered":"<p style=\"font-weight: 400;\">EQUIPA DA ADF<\/p>\n<p style=\"font-weight: 400;\">As For\u00e7as Armadas de Mo\u00e7ambique (FADM) est\u00e3o a assumir um papel mais proeminente nas opera\u00e7\u00f5es de combate ao terrorismo, numa altura em que as tropas da Miss\u00e3o da Comunidade para o Desenvolvimento da \u00c1frica Austral em Mo\u00e7ambique (SAMIM) come\u00e7am a ser retiradas.<\/p>\n<p style=\"font-weight: 400;\">A insurg\u00eancia na prov\u00edncia de Cabo Delgado, no nordeste do pa\u00eds, continua a aterrorizar os civis e a confundir as for\u00e7as de seguran\u00e7a multinacionais com a sua capacidade de resist\u00eancia.<\/p>\n<p style=\"font-weight: 400;\">As for\u00e7as do Ruanda e da SAMIM \u201creduziram significativamente\u201d o Ansar al-Sunna, um grupo extremista violento tamb\u00e9m conhecido como Estado Isl\u00e2mico de Mo\u00e7ambique (ISM). Ao fim de mais de dois anos de combates, o grupo terrorista est\u00e1 reduzido a \u201c160 a 200 combatentes em estado de alerta,\u201d de acordo com um relat\u00f3rio da equipa de monitoriza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas publicado a 29 de Janeiro.<\/p>\n<p style=\"font-weight: 400;\">A SAMIM, que foi destacada pela primeira vez para Cabo Delgado a 18 de Julho de 2021, indicou durante meses que em breve iniciaria uma retirada faseada. Um comunicado do bloco regional confirmou que a retirada est\u00e1 em curso e estar\u00e1 conclu\u00edda at\u00e9 15 de Julho.<\/p>\n<p style=\"font-weight: 400;\">\u201cA Miss\u00e3o pretende deixar um ambiente seguro e est\u00e1vel que garanta a seguran\u00e7a dos civis,\u201d declarou a SADC a 28 de Janeiro.<\/p>\n<p style=\"font-weight: 400;\">Os remanescentes do grupo insurgente est\u00e3o a deslocar-se para sul em busca de recursos e recrutas, \u00e0 medida que as for\u00e7as mo\u00e7ambicanas os expulsam dos seus redutos na floresta de Catupa.<\/p>\n<p style=\"font-weight: 400;\">\u201cDesde Fevereiro de 2023, pelo menos, o ISM tem feito um esfor\u00e7o consider\u00e1vel para construir rela\u00e7\u00f5es de apoio com as comunidades da zona costeira [do distrito de Macomia],\u201d segundo o site do observat\u00f3rio de conflitos Cabo Ligado, publicado pelo Projecto de Localiza\u00e7\u00e3o de Conflitos Armados e Dados de Eventos. \u201cIsto permitiu o estabelecimento de cadeias de abastecimento de bens b\u00e1sicos, muitas vezes, por via mar\u00edtima, e provavelmente d\u00e1 acesso a informa\u00e7\u00f5es sobre os movimentos das FADM e das tropas da SAMIM.\u201d<\/p>\n<p style=\"font-weight: 400;\">O Presidente de Mo\u00e7ambique, Filipe Nyusi, descreveu o ISM como \u201cem fuga\u201d e apelou os jovens mo\u00e7ambicanos para resistirem \u00e0s tentativas de recrutamento.<\/p>\n<p style=\"font-weight: 400;\">\u201cOs movimentos dos grupos extremistas em novos pontos de Cabo Delgado visam desviar os avan\u00e7os das for\u00e7as governamentais, que se dirigem para as principais bases terroristas,\u201d disse num discurso de 3 de Fevereiro. \u201cAs for\u00e7as de defesa e seguran\u00e7a t\u00eam como \u00faltimo objectivo impedir a penetra\u00e7\u00e3o e a mobilidade dos terroristas por mar, incluindo o seu reabastecimento a partir das ilhas adjacentes.\u201d<\/p>\n<p style=\"font-weight: 400;\">Nyusi disse que as for\u00e7as ruandesas e da SAMIM continuam a apoiar as tropas das FADM. Os especialistas dizem que ainda h\u00e1 muitos desafios para as for\u00e7as mo\u00e7ambicanas levarem a cabo efectivamente opera\u00e7\u00f5es de combate ao terrorismo sem o apoio estrangeiro.<\/p>\n<p style=\"font-weight: 400;\">\u201cO crescimento inicial do ISM e a subsequente resili\u00eancia do n\u00facleo remanescente expuseram as fraquezas estruturais das FADM, reflectidas na sua falta de sofistica\u00e7\u00e3o t\u00e1ctica e estrat\u00e9gica, na indisciplina das tropas e no equipamento obsoleto,\u201d escreveu o Cabo Ligado numa reportagem de 31 de Janeiro.<\/p>\n<p style=\"font-weight: 400;\">O jornalista do Zitamar News, Tom Gould, falou sobre as consequ\u00eancias da retirada da SAMIM, observando que as FADM ser\u00e3o empurradas para um vazio de seguran\u00e7a.<\/p>\n<p style=\"font-weight: 400;\">\u201cO seu desempenho at\u00e9 agora n\u00e3o tem sido nada encorajador,\u201d escreveu. \u201cNo dia 18 de Janeiro, as FADM abandonaram a aldeia estrat\u00e9gica de Mucojo, dando efectivamente aos insurgentes acesso livre \u00e0 costa de Macomia. Sabe-se que as for\u00e7as de seguran\u00e7a mo\u00e7ambicanas est\u00e3o a sofrer de falta de alimentos e que muitos soldados n\u00e3o s\u00e3o pagos h\u00e1 meses. Se as for\u00e7as armadas mo\u00e7ambicanas est\u00e3o a ter dificuldades em cumprir as suas responsabilidades actuais, \u00e9 dif\u00edcil imagin\u00e1-las a lidar com um papel alargado quando a SAMIM partir.\u201d<\/p>\n<p><span style=\"font-weight: 400;\">Os recentes ataques do ISM sublinham a dificuldade que Mo\u00e7ambique enfrenta na tentativa de eliminar os restantes militantes. Nyusi afirmou que a luta contra o terrorismo \u201cpode ser lenta, dolorosa e exaustiva, mas n\u00e3o temos outra alternativa sen\u00e3o derrot\u00e1-lo.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF As For\u00e7as Armadas de Mo\u00e7ambique (FADM) est\u00e3o a assumir um papel mais proeminente nas opera\u00e7\u00f5es de combate ao terrorismo, numa altura em que as tropas da Miss\u00e3o da Comunidade para o Desenvolvimento da \u00c1frica Austral em Mo\u00e7ambique (SAMIM) come\u00e7am a ser retiradas. A insurg\u00eancia na prov\u00edncia de Cabo Delgado, no nordeste do<\/p>\n","protected":false},"author":1,"featured_media":112568,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[1207,499,1020,473,820,1129,1139],"class_list":["post-112570","post","type-post","status-publish","format-standard","has-post-thumbnail","category-melhores-historias","tag-estado-islamico","tag-extremismo","tag-insurgencia","tag-mocambique","tag-sadc-pt-pt","tag-samim-pt-pt","tag-terrorism-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF As For\u00e7as Armadas de Mo\u00e7ambique (FADM) est\u00e3o a assumir um papel mais proeminente nas opera\u00e7\u00f5es de combate ao terrorismo, numa altura em que as tropas da Miss\u00e3o da Comunidade para o Desenvolvimento da \u00c1frica Austral em Mo\u00e7ambique (SAMIM) come\u00e7am a ser retiradas. A insurg\u00eancia na prov\u00edncia de Cabo Delgado, no nordeste do\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-20T16:56:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-20T16:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1065\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC\",\"datePublished\":\"2024-02-20T16:56:50+00:00\",\"dateModified\":\"2024-02-20T16:57:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/\"},\"wordCount\":710,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SAMIMEXIT1.jpg\",\"keywords\":[\"Estado Isl\u00e2mico\",\"extremismo\",\"insurg\u00eancia\",\"Mo\u00e7ambique\",\"SADC\",\"SAMIM\",\"Terrorism\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/\",\"name\":\"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SAMIMEXIT1.jpg\",\"datePublished\":\"2024-02-20T16:56:50+00:00\",\"dateModified\":\"2024-02-20T16:57:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SAMIMEXIT1.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/SAMIMEXIT1.jpg\",\"width\":1600,\"height\":1065,\"caption\":\"Elias Magosi, secret\u00e1rio-executivo da Comunidade para a Desenvolvimento da \u00c1frica Austral, ao centro, visita Pemba, Mo\u00e7ambique, a 26 de Janeiro para supervisionar a retirada das for\u00e7as regionais. SADC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2024\\\/02\\\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/","og_locale":"pt_PT","og_type":"article","og_title":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum","og_description":"EQUIPA DA ADF As For\u00e7as Armadas de Mo\u00e7ambique (FADM) est\u00e3o a assumir um papel mais proeminente nas opera\u00e7\u00f5es de combate ao terrorismo, numa altura em que as tropas da Miss\u00e3o da Comunidade para o Desenvolvimento da \u00c1frica Austral em Mo\u00e7ambique (SAMIM) come\u00e7am a ser retiradas. A insurg\u00eancia na prov\u00edncia de Cabo Delgado, no nordeste do","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-02-20T16:56:50+00:00","article_modified_time":"2024-02-20T16:57:21+00:00","og_image":[{"width":1600,"height":1065,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC","datePublished":"2024-02-20T16:56:50+00:00","dateModified":"2024-02-20T16:57:21+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/"},"wordCount":710,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg","keywords":["Estado Isl\u00e2mico","extremismo","insurg\u00eancia","Mo\u00e7ambique","SADC","SAMIM","Terrorism"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/","name":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg","datePublished":"2024-02-20T16:56:50+00:00","dateModified":"2024-02-20T16:57:21+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/02\/SAMIMEXIT1.jpg","width":1600,"height":1065,"caption":"Elias Magosi, secret\u00e1rio-executivo da Comunidade para a Desenvolvimento da \u00c1frica Austral, ao centro, visita Pemba, Mo\u00e7ambique, a 26 de Janeiro para supervisionar a retirada das for\u00e7as regionais. SADC"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2024\/02\/forcas-mocambicanas-passam-para-frente-com-a-retirada-da-sadc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"For\u00e7as Mo\u00e7ambicanas Passam para Frente Com a Retirada da SADC"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/112570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=112570"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/112570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/112568"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=112570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=112570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=112570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}