{"id":109259,"date":"2023-09-14T14:40:21","date_gmt":"2023-09-14T18:40:21","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=109259"},"modified":"2023-09-22T13:19:00","modified_gmt":"2023-09-22T17:19:00","slug":"as-fantasticas-possibilidades-dos-drones","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/","title":{"rendered":"As Fant\u00e1sticas Possibilidades Dos Drones"},"content":{"rendered":"<p>EQUIPA DA ADF<\/p>\n<p>A Nig\u00e9ria utiliza drones nos postos fronteiri\u00e7os para aumentar a seguran\u00e7a ao longo da sua fronteira porosa e para identificar potenciais amea\u00e7as quando estas ainda est\u00e3o a v\u00e1rios quil\u00f3metros de dist\u00e2ncia.<\/p>\n<p>Os drones Orion, fabricados pela empresa franco-americana Elistair, funcionam na extremidade de um cabo de Kevlar de 100 metros. O cabo fornece energia para um m\u00e1ximo de 50 horas de voo e uma comunica\u00e7\u00e3o segura e sem interfer\u00eancias com os operadores. Os drones fazem parte da frota de ve\u00edculos n\u00e3o tripulados da Nig\u00e9ria, que faz do pa\u00eds um dos principais actores do continente na tecnologia de drones.<\/p>\n<p>\u00c9 prov\u00e1vel que os terroristas que as autoridades nigerianas procuram os estejam a observar com os seus pr\u00f3prios drones. Segundo os analistas, grupos terroristas como o Boko Haram e a sua ramifica\u00e7\u00e3o, a Prov\u00edncia da \u00c1frica Ocidental do Estado Isl\u00e2mico, utilizam-nos para recolher informa\u00e7\u00f5es, ao mesmo tempo que experimentam transformar drones baratos e dispon\u00edveis no mercado em dispositivos explosivos improvisados (DEI) voadores que podem utilizar para lan\u00e7ar ataques contra alvos civis e militares.<\/p>\n<p>A Nig\u00e9ria \u00e9 representativa do continente africano em geral, uma vez que a r\u00e1pida prolifera\u00e7\u00e3o da tecnologia de drones indicia uma iminente corrida ao armamento. Os drones j\u00e1 est\u00e3o a remodelar a forma como as for\u00e7as armadas, de Marrocos \u00e0 \u00c1frica do Sul, protegem os seus cidad\u00e3os, vigiam as suas costas, combatem a ca\u00e7a furtiva de animais selvagens e muito mais.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>O crescimento da tecnologia de drones de n\u00edvel militar \u00e9 paralelo \u00e0 disponibilidade acelerada de drones comerciais de n\u00edvel civil, muitos deles fabricados e comercializados pela China, que t\u00eam o potencial de serem transformados em armas por grupos extremistas.<\/p>\n<p>\u201c\u00c9 uma tecnologia pouco sofisticada que ganha sofistica\u00e7\u00e3o rapidamente,\u201d Adam Rosman, director-geral da fabricante sul-africana de drones, Aerial Monitoring Solutions, disse \u00e0 ADF. \u201cH\u00e1 muitas possibilidades em \u00c1frica.\u201d<\/p>\n<figure id=\"attachment_108911\" aria-describedby=\"caption-attachment-108911\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-108911\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249.jpg\" alt=\"\" width=\"1080\" height=\"672\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249-300x187.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249-1024x637.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1189007249-768x478.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-108911\" class=\"wp-caption-text\">O drone Bayraktar TB2 da Turquia, que foi utilizado durante a guerra civil na L\u00edbia, atraiu o interesse de v\u00e1rios pa\u00edses africanos que pretendem acrescentar tecnologia de drones aos seus arsenais. AFP\/GETTY IMAGES<\/figcaption><\/figure>\n<p><b>QUEM TEM DRONES?<\/b><\/p>\n<p>Os primeiros drones utilizados em \u00c1frica surgiram em 1978, lan\u00e7ados pela \u00c1frica do Sul para monitorizar a guerra civil na ent\u00e3o Rod\u00e9sia. A \u00c1frica do Sul produziu os primeiros drones do continente, tamb\u00e9m conhecidos como ve\u00edculos a\u00e9reos n\u00e3o tripulados (VANT), no final da d\u00e9cada de 1980. A utiliza\u00e7\u00e3o de drones modernos come\u00e7ou em 2001, quando o Botswana encomendou uma s\u00e9rie de VANT Silver Arrow Micro-V de fabrico israelita. Desde ent\u00e3o, os drones tornaram-se cada vez mais uma tecnologia imprescind\u00edvel para os governos de todo o continente.<\/p>\n<p>Quase todos os pa\u00edses do continente utilizam drones de alguma forma. Na maioria dos casos, essas utiliza\u00e7\u00f5es s\u00e3o pac\u00edficas \u2014 desde a entrega de material de sa\u00fade a comunidades remotas at\u00e9 \u00e0 monitoriza\u00e7\u00e3o de reservas da vida selvagem amea\u00e7adas por ca\u00e7adores furtivos. A pandemia da COVID-19 chamou a aten\u00e7\u00e3o para a capacidade nascente de drones em \u00c1frica quando os pa\u00edses utilizaram drones a\u00e9reos e terrestres para fornecer informa\u00e7\u00f5es vitais de sa\u00fade p\u00fablica e para monitorizar os confinamentos.<\/p>\n<p>\u201cO continente africano est\u00e1 a tornar-se um local-chave para a adapta\u00e7\u00e3o de drones para muitos fins militares e n\u00e3o militares,\u201d Nichola Heras, director s\u00e9nior de estrat\u00e9gia e inova\u00e7\u00e3o do New Lines Institute for Strategy and Policy, disse \u00e0 ADF.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Os pa\u00edses s\u00e3o menos transparentes quanto \u00e0 utiliza\u00e7\u00e3o de drones no que respeita \u00e0s suas for\u00e7as armadas. Os cr\u00edticos afirmam que essa falta de transpar\u00eancia suscita preocupa\u00e7\u00f5es quanto ao facto de os drones estarem a ser utilizados de acordo com as normas internacionais em mat\u00e9ria de direitos humanos e com as regras tradicionais de combate.<\/p>\n<p>\u201cIsso impede debates abertos sobre a utiliza\u00e7\u00e3o militar de drones em \u00c1frica,\u201d comentou a organiza\u00e7\u00e3o de paz PAX, sediada nos Pa\u00edses Baixos, num relat\u00f3rio sobre a utiliza\u00e7\u00e3o de drones no continente. O relat\u00f3rio da PAX apresenta uma lista de 20 pa\u00edses do Norte de \u00c1frica, do Sahel e do Corno de \u00c1frica que adquiriram drones militares. O Marrocos tamb\u00e9m os fabrica.<\/p>\n<p>\u201cUm n\u00famero incont\u00e1vel de drones est\u00e1 cada vez mais a monitorizar e a afectar vidas em todo o Norte de \u00c1frica, no Sahel e no Corno de \u00c1frica,\u201d informou a PAX.<\/p>\n<p>Na \u00c1frica Subsaariana, a \u00c1frica do Sul tornou-se outro actor importante na ind\u00fastria de drones. A \u00c1frica do Sul fabrica drones para venda a outros pa\u00edses e considerou a possibilidade de os destacar ao longo dos seus 5.244 quil\u00f3metros de fronteira. A Nig\u00e9ria tamb\u00e9m fabrica os seus pr\u00f3prios drones. Os Camar\u00f5es adquiriram pequenos drones militares em 2018. O Qu\u00e9nia utiliza drones para monitorizar os insurgentes do al-Shabaab na vizinha Som\u00e1lia. A Rep\u00fablica Democr\u00e1tica do Congo e Mo\u00e7ambique tamb\u00e9m utilizaram drones em combate.<\/p>\n<p>O Botswana, a Costa do Marfim, o Sud\u00e3o e a Z\u00e2mbia acrescentaram drones t\u00e1cticos de tamanho m\u00e9dio \u00e0 sua frota militar. O sucesso dos drones turcos Bayraktar TB2 na guerra civil da L\u00edbia deu visibilidade aos drones armados, e as for\u00e7as armadas da Eti\u00f3pia, Marrocos, Ruanda, Togo e Tun\u00edsia adquiriram-nos. Angola est\u00e1 a ponderar adicion\u00e1-los tamb\u00e9m.<\/p>\n<p>\u201cA utiliza\u00e7\u00e3o de drones pela Turquia na L\u00edbia demonstrou aos pa\u00edses de rendimento m\u00e9dio e m\u00e9dio-baixo de todo o mundo que os drones lhes proporcionam uma for\u00e7a a\u00e9rea barata que pode ter um impacto devastador no campo de batalha,\u201d afirmou Heras.<\/p>\n<figure id=\"attachment_109249\" aria-describedby=\"caption-attachment-109249\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71.jpg\"><img decoding=\"async\" class=\"size-full wp-image-109249\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71.jpg\" alt=\"\" width=\"1080\" height=\"608\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71-300x169.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71-1024x576.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Nigerian-Police-uses-Elistair-Orion-UAVs-for-border-protection71-768x432.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-109249\" class=\"wp-caption-text\">L\u00edderes militares nigerianos e funcion\u00e1rios da Elistair demonstram os drones Orion que a Nig\u00e9ria utiliza para a seguran\u00e7a das fronteiras. ELISTAIR<\/figcaption><\/figure>\n<p><b>UM MULTIPLICADOR DE FOR\u00c7AS \u2014 COM LIMITA\u00c7\u00d5ES<\/b><\/p>\n<p>Quer estejam a seguir barcos de pesca ilegal no mar, a perseguir ca\u00e7adores furtivos numa reserva de vida selvagem ou a lan\u00e7ar ataques contra c\u00e9lulas terroristas, os drones tornaram-se um multiplicador de for\u00e7as para as ag\u00eancias de seguran\u00e7a de todo o continente.<\/p>\n<p>\u201cA utiliza\u00e7\u00e3o de SANT [sistemas a\u00e9reos n\u00e3o tripulados] representa uma nova itera\u00e7\u00e3o da tecnologia digital,\u201d escreveu a analista Karen Allen para o Centro de Estudos Estrat\u00e9gicos de \u00c1frica.<\/p>\n<p>O baixo custo da tecnologia de drones em rela\u00e7\u00e3o a um navio da marinha ou a um ca\u00e7a da for\u00e7a a\u00e9rea significa que as for\u00e7as armadas descapitalizadas podem aumentar capacidades gastando pouco dinheiro. Os drones com tecnologia de raios infravermelhos podem ver no escuro, uma ferramenta \u00fatil para observar os ca\u00e7adores furtivos que, muitas vezes, operam a coberto da noite. Tamb\u00e9m podem pairar sobre um alvo ou mesmo segui-lo durante um per\u00edodo prolongado. O seu perfil pequeno torna-os dif\u00edceis de detectar e de abater.<\/p>\n<p>A presen\u00e7a de drones sobre uma embarca\u00e7\u00e3o de pesca, ao longo de uma fronteira ou sobre um parque de vida selvagem tamb\u00e9m pode semear d\u00favidas na mente dos potenciais maus actores \u2014 d\u00favidas que podem lev\u00e1-los a interromper as opera\u00e7\u00f5es ilegais, segundo Rosman.<\/p>\n<p>Apesar das suas capacidades, os drones t\u00eam limita\u00e7\u00f5es. Podem ser desactivados atrav\u00e9s de interfer\u00eancia ou pirateados e virados contra os seus operadores. Podem ser imobilizados por tempestades de areia, copas de \u00e1rvores densas ou nuvens espessas, condi\u00e7\u00f5es que se encontram habitualmente em \u00c1frica.<\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<\/span>Os drones tamb\u00e9m funcionam durante um per\u00edodo de tempo limitado antes de terem de reabastecer ou recarregar. Isso pode dificultar a cobertura eficaz de grandes dist\u00e2ncias.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u201cUm drone n\u00e3o \u00e9 uma bala de prata que vai resolver todos os seus problemas,\u201d disse Rosman \u00e0 ADF. \u201c\u00c9 preciso ter pessoas no terreno.\u201d<\/p>\n<p>Essas limita\u00e7\u00f5es s\u00e3o frequentemente ignoradas a favor da m\u00edstica associada \u00e0 tecnologia de drones, acrescentou. Os l\u00edderes africanos s\u00e3o bombardeados com propostas de pa\u00edses e empresas ansiosos por lhes venderem tecnologia de drones, alguns fazendo promessas que o seu equipamento n\u00e3o consegue cumprir.<\/p>\n<p>Para al\u00e9m disso, os l\u00edderes militares esperam, por vezes, que os drones fa\u00e7am coisas de que simplesmente n\u00e3o s\u00e3o capazes, como ver o interior de um tanque.<\/p>\n<p>\u201c\u00c9 sempre poss\u00edvel saber que filmes andaram a ver,\u201d disse Rosman.<\/p>\n<p>A procura de drones mais avan\u00e7ados produziu uma mistura de tecnologia de v\u00e1rios pa\u00edses, incluindo a China, o Ir\u00e3o, Israel e a Turquia. Segundo Rosman, os utilizadores navegam numa miscel\u00e2nea de software e de l\u00ednguas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Depois de comprarem a tecnologia, alguns l\u00edderes recusam-se a gastar o dinheiro extra para formar os operadores, optando por deix\u00e1-los resolver o problema sozinhos. Esta abordagem \u201cfa\u00e7a voc\u00ea mesmo\u201d pode resultar em drones perdidos no fundo do oceano ou numa pilha de destro\u00e7os no ch\u00e3o. Outras vezes, o equipamento n\u00e3o vai a lado nenhum.<\/p>\n<p>\u201cH\u00e1 uma enorme quantidade de equipamento neste continente que n\u00e3o est\u00e1 a ser utilizado,\u201d disse Rosman.<\/p>\n<figure id=\"attachment_109253\" aria-describedby=\"caption-attachment-109253\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480.jpg\"><img decoding=\"async\" class=\"size-full wp-image-109253\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480.jpg\" alt=\"\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480-1024x683.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-611423480-272x182.jpg 272w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-109253\" class=\"wp-caption-text\">Combatentes de ambos os lados da guerra civil da L\u00edbia utilizaram drones comerciais para vigil\u00e2ncia e informa\u00e7\u00e3o e drones militares para atacar alvos. AFP\/GETTY IMAGES<\/figcaption><\/figure>\n<p><b>CORRIDA DE ARMAS DE IA<\/b><\/p>\n<p>Na sua corrida para comprar drones, os pa\u00edses africanos poder\u00e3o em breve tornar-se o campo de ensaio para o pr\u00f3ximo passo na tecnologia de drones: a intelig\u00eancia artificial.<\/p>\n<p>\u201c\u00c1frica \u00e9 um mercado emergente para esta tend\u00eancia,\u201d disse Heras \u00e0 ADF. \u201cQuando combinada com potenciais capacidades militares, pode ser um local-chave para a cria\u00e7\u00e3o de prot\u00f3tipos de drones aut\u00f3nomos em contextos militares.\u201d<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>A guerra civil na L\u00edbia pode j\u00e1 ter dado um vislumbre desse futuro. Com cerca de 1.000 ataques a\u00e9reos com drones, a L\u00edbia tornou-se uma montra da sua utiliza\u00e7\u00e3o em combate. O representante especial da ONU para a L\u00edbia, Ghassan Salame, chamou ao conflito \u201ca maior guerra de drones do mundo.\u201d<\/p>\n<p>Desse campo de batalha emergiu um relat\u00f3rio das Na\u00e7\u00f5es Unidas que sugere que um drone turco Kargu-2 equipado com IA pode ter, nas palavras do relat\u00f3rio, \u201cca\u00e7ado e combatido remotamente\u201d soldados inimigos sem ordens de operadores humanos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>O criador do Kargu-2 descreve o drone quadric\u00f3ptero como tendo sido concebido para pairar sobre um alvo com navega\u00e7\u00e3o totalmente aut\u00f3noma e capacidades de ataque de precis\u00e3o. A ac\u00e7\u00e3o de ataque requer a interven\u00e7\u00e3o de um manipulador humano, segundo o site do Kargu-2.<\/p>\n<p>No entanto, n\u00e3o est\u00e1 claro se foi assim que o ataque realmente aconteceu, de acordo com o relat\u00f3rio da ONU.<\/p>\n<p>\u201cUma vez em retirada, foram sujeitos a um ass\u00e9dio cont\u00ednuo por parte dos ve\u00edculos a\u00e9reos de combate n\u00e3o tripulados e dos sistemas de armas aut\u00f3nomas letais,\u201d escreveram os autores do relat\u00f3rio.<\/p>\n<p>Zachary Kallenborn, investigador a tempo parcial do Programa de Tecnologia Estrat\u00e9gica, do Centro de Estudos Estrat\u00e9gicos e Internacionais, que estuda os drones, disse ao The New York Times que o relat\u00f3rio sugeria que, pela primeira vez, um sistema de armas com capacidade de IA encontrou e atacou pessoas de forma independente.<\/p>\n<p>Kallenborn disse \u00e0 ADF que j\u00e1 existem todas as componentes necess\u00e1rias para criar um drone deste tipo.<\/p>\n<p><b>O FUTURO: ATAQUES EM ENXAME<\/b><\/p>\n<p>A experi\u00eancia da L\u00edbia com drones \u00e9 \u00fanica no continente, de acordo com Brendan Cannon, que estuda as implica\u00e7\u00f5es da tecnologia dos drones na Universidade Khalifa, nos Emirados \u00c1rabes Unidos. Mas esse poder\u00e1 n\u00e3o ser o caso durante muito mais tempo.<\/p>\n<p>\u201cEu diria que a corrida ao armamento est\u00e1 a acontecer, mas o seu in\u00edcio est\u00e1 a ser lento por raz\u00f5es relacionadas com as limita\u00e7\u00f5es de recursos e a disponibilidade de drones,\u201d disse Cannon \u00e0 ADF num e-mail. Quando essa corrida ao armamento come\u00e7ar, pode ser vantajosa para os grupos extremistas se os pa\u00edses n\u00e3o tiverem cuidado, acrescentou. Os drones dispon\u00edveis no mercado podem ser transformados em armas, apesar de poderem transportar apenas cargas leves.<\/p>\n<p>\u201cIsso dar-lhes-\u00e1 potencialmente uma vantagem para levarem a cabo ataques armados (ainda que em pequena escala) contra alvos suaves, mas altamente vis\u00edveis do poder do Estado, como pal\u00e1cios presidenciais ou esquadras da pol\u00edcia, devido \u00e0 inadequada ou inexistente defesa a\u00e9rea na maioria dos Estados,\u201d afirmou Cannon.<\/p>\n<p>Segundo Kallenborn, os avan\u00e7os no software podem ajudar os extremistas a combater a tecnologia de n\u00edvel militar dos governos, utilizando dezenas ou centenas de drones dispon\u00edveis no mercado para criar ataques em \u201cenxame.<\/p>\n<p>Pela primeira vez na hist\u00f3ria, a tecnologia dos drones criou a possibilidade de actores n\u00e3o estatais controlarem os c\u00e9us de uma determinada \u00e1rea, disse Kallenborn \u00e0 ADF.<\/p>\n<p>Allen sugeriu que os pa\u00edses combatam a potencial corrida \u00e0s armas de drones, monitorizando de perto e possivelmente restringindo as importa\u00e7\u00f5es de tecnologia de drones \u2014 uma t\u00e1ctica que outros analistas consideram dif\u00edcil de executar eficazmente, dadas as fronteiras porosas do continente e as muitas utiliza\u00e7\u00f5es leg\u00edtimas dos drones comerciais. Os grupos poderiam importar drones de corrida, por exemplo, e convert\u00ea-los em DEI voadores, disse Rosman.<\/p>\n<p>\u201cActualmente, n\u00e3o existe um contra-ataque eficaz \u00e0 utiliza\u00e7\u00e3o de drones desta forma,\u201d afirmou Heras. \u201cOs efeitos das for\u00e7as n\u00e3o-estatais que utilizam grandes frotas de drones comerciais pequenos, altamente m\u00f3veis e de baixo perfil contra a maioria das for\u00e7as armadas africanas devem manter os estados-maiores de todo o continente acordados \u00e0 noite.\u201d<span class=\"Apple-converted-space\"> \u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF A Nig\u00e9ria utiliza drones nos postos fronteiri\u00e7os para aumentar a seguran\u00e7a ao longo da sua fronteira porosa e para identificar potenciais amea\u00e7as quando estas ainda est\u00e3o a v\u00e1rios quil\u00f3metros de dist\u00e2ncia. Os drones Orion, fabricados pela empresa franco-americana Elistair, funcionam na extremidade de um cabo de Kevlar de 100 metros. O cabo<\/p>\n","protected":false},"author":1,"featured_media":109245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[334],"tags":[520,1678,1776,501,1589,583],"class_list":{"0":"post-109259","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-reportagens","8":"tag-libia","9":"tag-libia-pt-pt","10":"tag-sahel-pt-pt-2","11":"tag-sahel-pt-pt","12":"tag-tecnologia-pt-pt","13":"tag-tecnologia"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF A Nig\u00e9ria utiliza drones nos postos fronteiri\u00e7os para aumentar a seguran\u00e7a ao longo da sua fronteira porosa e para identificar potenciais amea\u00e7as quando estas ainda est\u00e3o a v\u00e1rios quil\u00f3metros de dist\u00e2ncia. Os drones Orion, fabricados pela empresa franco-americana Elistair, funcionam na extremidade de um cabo de Kevlar de 100 metros. O cabo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T18:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-22T17:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"As Fant\u00e1sticas Possibilidades Dos Drones\",\"datePublished\":\"2023-09-14T18:40:21+00:00\",\"dateModified\":\"2023-09-22T17:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/\"},\"wordCount\":2304,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1244138286.jpg\",\"keywords\":[\"L\u00edbia\",\"L\u00edbia\",\"Sahel\",\"Sahel\",\"tecnologia\",\"tecnologia\"],\"articleSection\":[\"Reportagens\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/\",\"name\":\"As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1244138286.jpg\",\"datePublished\":\"2023-09-14T18:40:21+00:00\",\"dateModified\":\"2023-09-22T17:19:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1244138286.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1244138286.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/09\\\/as-fantasticas-possibilidades-dos-drones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As Fant\u00e1sticas Possibilidades Dos Drones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/","og_locale":"pt_PT","og_type":"article","og_title":"As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum","og_description":"EQUIPA DA ADF A Nig\u00e9ria utiliza drones nos postos fronteiri\u00e7os para aumentar a seguran\u00e7a ao longo da sua fronteira porosa e para identificar potenciais amea\u00e7as quando estas ainda est\u00e3o a v\u00e1rios quil\u00f3metros de dist\u00e2ncia. Os drones Orion, fabricados pela empresa franco-americana Elistair, funcionam na extremidade de um cabo de Kevlar de 100 metros. O cabo","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-09-14T18:40:21+00:00","article_modified_time":"2023-09-22T17:19:00+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"As Fant\u00e1sticas Possibilidades Dos Drones","datePublished":"2023-09-14T18:40:21+00:00","dateModified":"2023-09-22T17:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/"},"wordCount":2304,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg","keywords":["L\u00edbia","L\u00edbia","Sahel","Sahel","tecnologia","tecnologia"],"articleSection":["Reportagens"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/","name":"As Fant\u00e1sticas Possibilidades Dos Drones - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg","datePublished":"2023-09-14T18:40:21+00:00","dateModified":"2023-09-22T17:19:00+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1244138286.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/09\/as-fantasticas-possibilidades-dos-drones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"As Fant\u00e1sticas Possibilidades Dos Drones"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/109259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=109259"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/109259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/109245"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=109259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=109259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=109259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}