{"id":106083,"date":"2023-05-23T13:46:35","date_gmt":"2023-05-23T17:46:35","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=106083"},"modified":"2023-05-23T13:47:37","modified_gmt":"2023-05-23T17:47:37","slug":"terroristas-declaram-guerra-a-educacao-no-sahel","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/","title":{"rendered":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel"},"content":{"rendered":"<p style=\"font-weight: 400;\">EQUIPA DA ADF<\/p>\n<p style=\"font-weight: 400;\">Por vezes, come\u00e7a com uma amea\u00e7a violenta escrita em graffiti numa parede de uma escola.<\/p>\n<p style=\"font-weight: 400;\">Quando extremistas fortemente armados chegam de motorizadas, o terror instala-se \u2014 os professores s\u00e3o baleados, raptados, violados. Alguns s\u00e3o executados \u00e0 frente das crian\u00e7as. Os edif\u00edcios escolares s\u00e3o incendiados. Alguns s\u00e3o queimados de forma irrepar\u00e1vel.<\/p>\n<p style=\"font-weight: 400;\">Os extremistas violentos do Sahel declararam guerra \u00e0 educa\u00e7\u00e3o. O seu alvo n\u00e3o s\u00e3o apenas os professores e as crian\u00e7as, mas o tecido social.<\/p>\n<p style=\"font-weight: 400;\">\u201cVisar as escolas \u00e9 uma estrat\u00e9gia fundamental para os grupos militantes extremistas, uma vez que as escolas s\u00e3o, muitas vezes, o \u00fanico s\u00edmbolo da presen\u00e7a do Estado em aldeias remotas e ensinam valores que s\u00e3o antit\u00e9ticos \u00e0 ideologia dos extremistas,\u201d escreveu a jornalista de dados, Marie Toulemonde, num artigo publicado a 4 de Maio na revista The Africa Report.<\/p>\n<p style=\"font-weight: 400;\">Entre 2020 e 2021, mais de 1.000 escolas no Mali, no Burquina Faso e no N\u00edger foram alvo de ataques armados por parte de organiza\u00e7\u00f5es extremistas violentas.<\/p>\n<p style=\"font-weight: 400;\">De acordo com a investiga\u00e7\u00e3o de Toulemonde, cerca de 9.000 escolas nos tr\u00eas pa\u00edses encerraram nos \u00faltimos quatro anos (2019-2022), afectando mais de 1,6 milh\u00f5es de crian\u00e7as.<\/p>\n<p style=\"font-weight: 400;\">O Burquina Faso foi o pa\u00eds mais atingido, com quase metade das escolas encerradas na \u00c1frica Central e Ocidental.<\/p>\n<p style=\"font-weight: 400;\">O encerramento de escolas aumentou 40% desde o final do \u00faltimo ano lectivo. Uma em cada quatro escolas fechou nos \u00faltimos quatro anos, afectando mais de um milh\u00e3o de crian\u00e7as.<\/p>\n<p style=\"font-weight: 400;\">Desde Setembro de 2022, pelo menos oito professores foram assassinados, na sua maioria em zonas rurais controladas por extremistas.<\/p>\n<p style=\"font-weight: 400;\">Na cidade bloqueada de Pama, na regi\u00e3o leste, apenas duas das oito escolas est\u00e3o a funcionar. Seis professores e um punhado de volunt\u00e1rios servem mais de 1.000 crian\u00e7as em Pama.<\/p>\n<p style=\"font-weight: 400;\">\u201cPara aqueles de n\u00f3s que ainda c\u00e1 est\u00e3o, \u00e9 uma decis\u00e3o muito pessoal ficar,\u201d disse um professor ao Conselho Noruegu\u00eas para Refugiados (NRC). \u201cA educa\u00e7\u00e3o \u00e9 um direito universal, por isso sentimos que \u00e9 nosso dever continuar. Mas o medo n\u00e3o desaparece facilmente.<\/p>\n<p style=\"font-weight: 400;\">\u201cMuitas vezes, temos de parar as aulas porque ouvimos tiros aqui ou ali. As amea\u00e7as s\u00e3o grandes e as condi\u00e7\u00f5es s\u00e3o dif\u00edceis, mas podemos e devemos ultrapassar os desafios para ajudar as crian\u00e7as que nunca quiseram ser colocadas nesta situa\u00e7\u00e3o.\u201d<\/p>\n<p style=\"font-weight: 400;\">Hassane Hamadou, o director nacional do NRC no Burquina Faso, disse que 31.000 professores foram afectados, incluindo cerca de 6.300 que foram transferidos para escolas com um grande n\u00famero de alunos deslocados internamente.<\/p>\n<p style=\"font-weight: 400;\">Mesmo as boas not\u00edcias s\u00e3o menos do que ideais, disse Hamadou. Embora cerca de 300 escolas tenham sido reabertas ou transferidas desde Janeiro, o Burquina Faso debate-se claramente com uma crise de educa\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">\u201cApenas cerca de um quarto das crian\u00e7as expulsas da escola receberam novas salas de aula,\u201d afirmou num comunicado. \u201cA maioria ficou sem acesso \u00e0 educa\u00e7\u00e3o, roubando-lhes a inf\u00e2ncia e a oportunidade de se tornarem adultos e cidad\u00e3os independentes.\u201d<\/p>\n<p style=\"font-weight: 400;\">No Mali, uma em cada cinco escolas fechou. Segundo a ONU, 1.664 escolas foram encerradas nos \u00faltimos quatro anos, deixando 500.000 alunos sem educa\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">Mais de 700 escolas foram encerradas no N\u00edger, afectando cerca de 75.000 crian\u00e7as. A maioria situa-se na regi\u00e3o de Tillab\u00e9ri, adjacente a Liptako-Gourma, ou zona da tr\u00edplice fronteira entre o N\u00edger, o Mali e o Burquina Faso, onde os combatentes do Estado Isl\u00e2mico mant\u00eam uma forte presen\u00e7a.<\/p>\n<p style=\"font-weight: 400;\">O encerramento de escolas representa uma amea\u00e7a devastadora para a regi\u00e3o do Sahel, onde, em 2020, o UNICEF informou que \u201cmais de 8 milh\u00f5es de crian\u00e7as com idades compreendidas entre os 6 e os 14 anos [n\u00e3o] frequentam a escola, ou seja, quase 55% deste grupo et\u00e1rio.\u201d<\/p>\n<p style=\"font-weight: 400;\">Os especialistas dizem que o perigo de uma gera\u00e7\u00e3o perdida no Sahel \u00e9 real e que mesmo o abandono escolar tempor\u00e1rio tem consequ\u00eancias desastrosas para o futuro das crian\u00e7as e do seu pa\u00eds.<\/p>\n<p style=\"font-weight: 400;\">A destrui\u00e7\u00e3o de escolas n\u00e3o s\u00f3 agrava os problemas econ\u00f3micos e estruturais fundamentais, como tamb\u00e9m \u00e9 um factor essencial de recrutamento para grupos terroristas.<\/p>\n<p style=\"font-weight: 400;\">\u201c\u00c0 medida que cada vez mais crian\u00e7as s\u00e3o privadas de educa\u00e7\u00e3o, n\u00e3o podem continuar a estudar para aceder a empregos est\u00e1veis e profissionais, o que as torna mais vulner\u00e1veis a serem atra\u00eddas para grupos extremistas,\u201d escreveu Toulemonde.<\/p>\n<p style=\"font-weight: 400;\">Grupos de defesa dos direitos humanos como o NRC apelam a uma ac\u00e7\u00e3o urgente.<\/p>\n<p style=\"font-weight: 400;\">\u201cQuanto mais esta situa\u00e7\u00e3o se arrastar, quanto mais grave se tornar, mais dif\u00edcil ser\u00e1 inverter esta tend\u00eancia e proteger o seu futuro,\u201d disse Hamadou.<\/p>\n<p><span style=\"font-weight: 400;\">\u201cAs autoridades do Burquina Faso, bem como as organiza\u00e7\u00f5es humanit\u00e1rias e de desenvolvimento, devem renovar urgentemente os seus esfor\u00e7os para p\u00f4r termo a esta hemorragia educativa.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF Por vezes, come\u00e7a com uma amea\u00e7a violenta escrita em graffiti numa parede de uma escola. Quando extremistas fortemente armados chegam de motorizadas, o terror instala-se \u2014 os professores s\u00e3o baleados, raptados, violados. Alguns s\u00e3o executados \u00e0 frente das crian\u00e7as. Os edif\u00edcios escolares s\u00e3o incendiados. Alguns s\u00e3o queimados de forma irrepar\u00e1vel. Os extremistas<\/p>\n","protected":false},"author":1,"featured_media":106081,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[503,748,1207,499,452,502,501,534,730],"class_list":{"0":"post-106083","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-burkina-faso-pt-pt","9":"tag-educacao","10":"tag-estado-islamico","11":"tag-extremismo","12":"tag-mali-pt-pt","13":"tag-niger-pt-pt","14":"tag-sahel-pt-pt","15":"tag-terrorismo","16":"tag-unicef-pt-pt"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF Por vezes, come\u00e7a com uma amea\u00e7a violenta escrita em graffiti numa parede de uma escola. Quando extremistas fortemente armados chegam de motorizadas, o terror instala-se \u2014 os professores s\u00e3o baleados, raptados, violados. Alguns s\u00e3o executados \u00e0 frente das crian\u00e7as. Os edif\u00edcios escolares s\u00e3o incendiados. Alguns s\u00e3o queimados de forma irrepar\u00e1vel. Os extremistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-23T17:46:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T17:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel\",\"datePublished\":\"2023-05-23T17:46:35+00:00\",\"dateModified\":\"2023-05-23T17:47:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/\"},\"wordCount\":819,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/GettyImages-1180595424.jpg\",\"keywords\":[\"Burkina Faso\",\"educa\u00e7\u00e3o\",\"Estado Isl\u00e2mico\",\"extremismo\",\"Mali\",\"Niger\",\"Sahel\",\"Terrorismo\",\"UNICEF\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/\",\"name\":\"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/GettyImages-1180595424.jpg\",\"datePublished\":\"2023-05-23T17:46:35+00:00\",\"dateModified\":\"2023-05-23T17:47:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/GettyImages-1180595424.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/GettyImages-1180595424.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Crian\u00e7as aprendem ao ar livre em Kaya, no norte do Burquina Faso. GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/05\\\/terroristas-declaram-guerra-a-educacao-no-sahel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/","og_locale":"pt_PT","og_type":"article","og_title":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum","og_description":"EQUIPA DA ADF Por vezes, come\u00e7a com uma amea\u00e7a violenta escrita em graffiti numa parede de uma escola. Quando extremistas fortemente armados chegam de motorizadas, o terror instala-se \u2014 os professores s\u00e3o baleados, raptados, violados. Alguns s\u00e3o executados \u00e0 frente das crian\u00e7as. Os edif\u00edcios escolares s\u00e3o incendiados. Alguns s\u00e3o queimados de forma irrepar\u00e1vel. Os extremistas","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-05-23T17:46:35+00:00","article_modified_time":"2023-05-23T17:47:37+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel","datePublished":"2023-05-23T17:46:35+00:00","dateModified":"2023-05-23T17:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/"},"wordCount":819,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg","keywords":["Burkina Faso","educa\u00e7\u00e3o","Estado Isl\u00e2mico","extremismo","Mali","Niger","Sahel","Terrorismo","UNICEF"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/","name":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg","datePublished":"2023-05-23T17:46:35+00:00","dateModified":"2023-05-23T17:47:37+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/05\/GettyImages-1180595424.jpg","width":1024,"height":683,"caption":"Crian\u00e7as aprendem ao ar livre em Kaya, no norte do Burquina Faso. GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/05\/terroristas-declaram-guerra-a-educacao-no-sahel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Terroristas Declaram Guerra \u00e0 Educa\u00e7\u00e3o no Sahel"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/106083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=106083"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/106083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/106081"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=106083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=106083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=106083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}