{"id":105036,"date":"2023-04-25T14:57:22","date_gmt":"2023-04-25T18:57:22","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=105036"},"modified":"2023-04-25T14:58:15","modified_gmt":"2023-04-25T18:58:15","slug":"somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/","title":{"rendered":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul"},"content":{"rendered":"<p style=\"font-weight: 400;\">EQUIPA DA ADF<\/p>\n<p style=\"font-weight: 400;\">Depois de conseguir vit\u00f3rias importantes contra o al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou a sua segunda ofensiva contra o grupo extremista, com objectivo de expuls\u00e1-lo das regi\u00f5es centro e sul daquele pa\u00eds.<\/p>\n<p style=\"font-weight: 400;\">O Presidente da Som\u00e1lia, Hassan Sheikh Mohamud, anunciou a nova ofensiva em finais de Mar\u00e7o. Os soldados da Som\u00e1lia e os seus aliados tribais ir\u00e3o utilizar a experi\u00eancia que ganharam durante a primeira ofensiva para fazer com que a segunda ronda de opera\u00e7\u00f5es seja mais bem-sucedida ainda, disse o presidente.<\/p>\n<p style=\"font-weight: 400;\">\u201cTemos mais experi\u00eancia do que quando entr\u00e1mos na guerra pela primeira vez, nos Estados de Galmudug e Hirshabelle,\u201d disse Mohamud este ano no final da primeira ofensiva. \u201cJ\u00e1 conhecemos as t\u00e1cticas do al-Shabaab. O nosso moral diz-nos que somos capazes de derrot\u00e1-los.\u201d<\/p>\n<p style=\"font-weight: 400;\">Em \u00faltima inst\u00e2ncia, a nova estrat\u00e9gia visa colocar um fim a d\u00e9cadas de viol\u00eancia que prejudicaram as vidas de gera\u00e7\u00f5es de somalis.<\/p>\n<p style=\"font-weight: 400;\">A primeira vaga de ataques contra o al-Shabaab esteve centrada nas regi\u00f5es de Middle Shabelle, nos arredores da capital nacional, Mogad\u00edscio. Durante aquela ofensiva, que decorreu de Agosto de 2022 a Janeiro de 2023, o ex\u00e9rcito da Som\u00e1lia libertou 70 comunidades, como Rage-El, uma aldeia onde os residentes juntaram-se \u00e0 luta do ex\u00e9rcito em Agosto \u00faltimo, depois de 13 anos sob o controlo do al-Shabaab.<\/p>\n<p style=\"font-weight: 400;\">\u201cA popula\u00e7\u00e3o vivia em agonia,\u201d Mohamud Adow, um residente da aldeia, de 80 anos de idade, que pegou em armas, disse \u00e0 Associated Press.<\/p>\n<p style=\"font-weight: 400;\">A primeira ofensiva libertou cerca de um ter\u00e7o do territ\u00f3rio que estava sob o controlo do al-Shabaab. Tamb\u00e9m matou mais de 3.000 combatentes do grupo e feriu mais de 3.700, de acordo com o Minist\u00e9rio da Informa\u00e7\u00e3o da Som\u00e1lia.<\/p>\n<p style=\"font-weight: 400;\">O ex\u00e9rcito da Som\u00e1lia recebeu treinos e armas de aliados internacionais, incluindo os Estados Unidos, a Turquia e ATMIS, a Miss\u00e3o de Transi\u00e7\u00e3o da Uni\u00e3o Africana na Som\u00e1lia. Contudo, os l\u00edderes somalis enfatizam que os seus soldados est\u00e3o a liderar o ataque com a ajuda de combatentes de cl\u00e3s que se viraram contra o al-Shabaab.<\/p>\n<p style=\"font-weight: 400;\">\u201c[O al-Shabaab] est\u00e1 a enfrentar a voc\u00eas, soldados da Som\u00e1lia, que est\u00e3o bem treinados e preparados para a batalha, que levaram a batalha para as linhas da frente,\u201d Kamal Dahir Hassan Gutale, conselheiro de seguran\u00e7a nacional do Primeiro-Ministro, Hamza Abdi Barre, disse \u00e0 Voz da Am\u00e9rica. \u201cO povo da Som\u00e1lia e o seu governo possibilitaram que todos aqueles sucessos fossem alcan\u00e7ados pelas nossas for\u00e7as de seguran\u00e7a em muito curto espa\u00e7o de tempo.\u201d<\/p>\n<p style=\"font-weight: 400;\">Gutale desconsiderou as afirma\u00e7\u00f5es de um l\u00edder do al-Shabaab, segundo as quais a primeira ofensiva n\u00e3o cumpriu a sua miss\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">\u201cQue ele os enfrente,\u201d disse Gutale, desafiando o l\u00edder terrorista a enfrentar os soldados da Som\u00e1lia. \u201cEles libertaram mais de 500 quil\u00f3metros das m\u00e3os do al-Shabaab e ainda est\u00e3o atr\u00e1s dele.\u201d<\/p>\n<p style=\"font-weight: 400;\">Analistas afirmam que os ganhos recentes foram devidos, em parte, \u00e0s pr\u00f3prias ac\u00e7\u00f5es do grupo extremista, que despertaram a ira da popula\u00e7\u00e3o que vive nas regi\u00f5es sob o seu controlo.<\/p>\n<p style=\"font-weight: 400;\">\u201cEnquanto a seca sem fim se intensificava, no in\u00edcio do Ver\u00e3o de 2022, o grupo ligado \u00e0 al-Qaeda, al-Shabaab, reagiu com brutalidade t\u00edpica,\u201d escreveu Vanda Felbab-Brown, da Brookings instituton. Enquanto a seca e as dificuldades econ\u00f3micas aumentavam, o al-Shabaab continuavam a pressionar a popula\u00e7\u00e3o, cobrando \u201cimpostos\u201d para apoiar as suas opera\u00e7\u00f5es.<\/p>\n<p style=\"font-weight: 400;\">Apoiado pelos cl\u00e3s e pelos aliados internacionais, a segunda ofensiva do ex\u00e9rcito da Som\u00e1lia est\u00e1 a pressionar ainda mais as fortalezas do al-Shabaab no sul, em Jubaland.<\/p>\n<p style=\"font-weight: 400;\">Enquanto a ofensiva progride, dirigida pelas for\u00e7as especiais da Som\u00e1lia, o governo fornece apoio log\u00edstico, muni\u00e7\u00f5es, produtos alimentares e evacua\u00e7\u00e3o m\u00e9dica para as mil\u00edcias dos cl\u00e3s. Os cl\u00e3s, por sua vez, ligam o ex\u00e9rcito \u00e0s popula\u00e7\u00f5es locais e demonstram que algumas por\u00e7\u00f5es das popula\u00e7\u00f5es da Som\u00e1lia viraram-se contra o al-Shabaab, de acordo com o Grupo Internacional da Crise.<\/p>\n<p><span style=\"font-weight: 400;\">Enquanto as tropas da Som\u00e1lia e os seus aliados libertam as comunidades do controlo do al-Shabaab, Mohamud enfatizou o compromisso do governo de criar e trazer servi\u00e7os p\u00fablicos para aquelas regi\u00f5es de modo a manter afastada qualquer tentativa dos extremistas de regressarem.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EQUIPA DA ADF Depois de conseguir vit\u00f3rias importantes contra o al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou a sua segunda ofensiva contra o grupo extremista, com objectivo de expuls\u00e1-lo das regi\u00f5es centro e sul daquele pa\u00eds. O Presidente da Som\u00e1lia, Hassan Sheikh Mohamud, anunciou a nova ofensiva em finais de Mar\u00e7o. Os soldados da<\/p>\n","protected":false},"author":1,"featured_media":105038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[363],"tags":[535,1139,534],"class_list":{"0":"post-105036","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-melhores-historias","8":"tag-somalia-pt-pt","9":"tag-terrorism-pt-pt","10":"tag-terrorismo"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"EQUIPA DA ADF Depois de conseguir vit\u00f3rias importantes contra o al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou a sua segunda ofensiva contra o grupo extremista, com objectivo de expuls\u00e1-lo das regi\u00f5es centro e sul daquele pa\u00eds. O Presidente da Som\u00e1lia, Hassan Sheikh Mohamud, anunciou a nova ofensiva em finais de Mar\u00e7o. Os soldados da\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-25T18:57:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-25T18:58:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul\",\"datePublished\":\"2023-04-25T18:57:22+00:00\",\"dateModified\":\"2023-04-25T18:58:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/\"},\"wordCount\":755,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/GettyImages-1247349563.jpg\",\"keywords\":[\"Somalia\",\"Terrorism\",\"Terrorismo\"],\"articleSection\":[\"Not\u00edcias diaries\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/\",\"name\":\"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/GettyImages-1247349563.jpg\",\"datePublished\":\"2023-04-25T18:57:22+00:00\",\"dateModified\":\"2023-04-25T18:58:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/GettyImages-1247349563.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/GettyImages-1247349563.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Depois de libertar 70 comunidades no centro da Som\u00e1lia, do controlo do al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou uma nova ofensiva que tem como alvo as fortalezas do grupo terrorista no sul. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/2023\\\/04\\\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/","og_locale":"pt_PT","og_type":"article","og_title":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum","og_description":"EQUIPA DA ADF Depois de conseguir vit\u00f3rias importantes contra o al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou a sua segunda ofensiva contra o grupo extremista, com objectivo de expuls\u00e1-lo das regi\u00f5es centro e sul daquele pa\u00eds. O Presidente da Som\u00e1lia, Hassan Sheikh Mohamud, anunciou a nova ofensiva em finais de Mar\u00e7o. Os soldados da","og_url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-04-25T18:57:22+00:00","article_modified_time":"2023-04-25T18:58:15+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"Escrito por":"ADF","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul","datePublished":"2023-04-25T18:57:22+00:00","dateModified":"2023-04-25T18:58:15+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/"},"wordCount":755,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg","keywords":["Somalia","Terrorism","Terrorismo"],"articleSection":["Not\u00edcias diaries"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/","url":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/","name":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg","datePublished":"2023-04-25T18:57:22+00:00","dateModified":"2023-04-25T18:58:15+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/04\/GettyImages-1247349563.jpg","width":1024,"height":683,"caption":"Depois de libertar 70 comunidades no centro da Som\u00e1lia, do controlo do al-Shabaab, em finais de 2022, a Som\u00e1lia lan\u00e7ou uma nova ofensiva que tem como alvo as fortalezas do grupo terrorista no sul. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/pt-pt\/2023\/04\/somalia-lanca-2a-ofensiva-contra-fortalezas-do-al-shabaab-no-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Som\u00e1lia Lan\u00e7a 2\u00aa Ofensiva Contra Fortalezas do al-Shabaab no Sul"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/pt-pt\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/105036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=105036"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/posts\/105036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media\/105038"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=105036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=105036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=105036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}