{"id":8944,"date":"2017-09-28T18:48:44","date_gmt":"2017-09-28T18:48:44","guid":{"rendered":"https:\/\/adf-magazine.com?p=8944"},"modified":"2017-11-16T19:16:32","modified_gmt":"2017-11-16T19:16:32","slug":"le-projet-du-nil-reliera-10-pays","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2017\/09\/le-projet-du-nil-reliera-10-pays\/","title":{"rendered":"LE PROJET DU NIL RELIERA 10 PAYS"},"content":{"rendered":"<p>PERSONNEL d\u2019<i>ADF<\/i><\/p>\n<p>Les travaux sont sur le point de commencer sur une voie commerciale de 4.000 kilom\u00e8tres qui doit relier la mer M\u00e9diterran\u00e9e au lac Victoria, promettant d\u2019am\u00e9liorer les \u00e9changes commerciaux pour 10 nations.<\/p>\n<p>Cette voie navigable, destin\u00e9e notamment \u00e0 utiliser le Nil comme route maritime commerciale, devrait \u00eatre compl\u00e9t\u00e9e d\u2019ici \u00e0 2024. Elle traversera le Burundi, l\u2019\u00c9gypte, l\u2019\u00c9thiopie, le Kenya, l\u2019Ouganda, la R\u00e9publique d\u00e9mocratique du Congo, le Rwanda, le Soudan, le Soudan du Sud et la Tanzanie. L\u2019\u00c9thiopie a accept\u00e9 tardivement ce projet, ne d\u00e9cidant de rejoindre les autres pays qu\u2019en d\u00e9but 2017.<\/p>\n<p>Le projet est destin\u00e9 aux vaisseaux commerciaux de petite et moyenne taille afin de stimuler le commerce entre les 10 pays. C\u2019est l\u2019un des \u00e9l\u00e9ments du projet de l\u2019axe routier Le Caire-Le Cap reliant l\u2019\u00c9gypte \u00e0 l\u2019Afrique du Sud et long de 10.000 kilom\u00e8tres. Le projet int\u00e9grera \u00e9galement des lignes ferroviaires. Le budget pr\u00e9vu pour cette voie de navigation serait de 10 \u00e0 12 milliards de dollars.<\/p>\n<p>Cette voie navigable est compliqu\u00e9e \u00e0 r\u00e9aliser. Il faudra construire des \u00e9cluses en raison des chutes pr\u00e9sentes sur le parcours.<\/p>\n<p>L\u2019\u00c9gypte a fait \u00e9tat de nombre de volets potentiels du projet, y compris le soutien au d\u00e9veloppement \u00e9conomique du bassin du Nil par le biais d\u2019une augmentation du niveau d\u2019\u00e9changes commerciaux et de transports de biens et de personnes, et \u00e9galement l\u2019\u00e9tablissement d\u2019un centre de formation de gestion de la navigation fluviale dans certains des \u00e9tats concern\u00e9s.<\/p>\n<p>Pendant une premi\u00e8re phase il est pr\u00e9vu de r\u00e9aliser la section reliant le lac Albert, en Ouganda, \u00e0 Khartoum, au Soudan ; un lien de Gambela, en \u00c9thiopie, au Nil blanc dans le Soudan du Sud ; et un lien de Khartoum \u00e0 Aswan, en \u00c9gypte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL d\u2019ADF Les travaux sont sur le point de commencer sur une voie commerciale de 4.000 kilom\u00e8tres qui doit relier la mer M\u00e9diterran\u00e9e au lac Victoria, promettant d\u2019am\u00e9liorer les \u00e9changes commerciaux pour 10 nations. Cette voie navigable, destin\u00e9e notamment \u00e0 utiliser le Nil comme route maritime commerciale, devrait \u00eatre compl\u00e9t\u00e9e d\u2019ici \u00e0 2024. Elle traversera<\/p>\n","protected":false},"author":1,"featured_media":8729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[44,40],"tags":[],"class_list":{"0":"post-8944","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-croissance-et-progres","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL d\u2019ADF Les travaux sont sur le point de commencer sur une voie commerciale de 4.000 kilom\u00e8tres qui doit relier la mer M\u00e9diterran\u00e9e au lac Victoria, promettant d\u2019am\u00e9liorer les \u00e9changes commerciaux pour 10 nations. Cette voie navigable, destin\u00e9e notamment \u00e0 utiliser le Nil comme route maritime commerciale, devrait \u00eatre compl\u00e9t\u00e9e d\u2019ici \u00e0 2024. Elle traversera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T18:48:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-16T19:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"LE PROJET DU NIL RELIERA 10 PAYS\",\"datePublished\":\"2017-09-28T18:48:44+00:00\",\"dateModified\":\"2017-11-16T19:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/\"},\"wordCount\":314,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/AP_17067291321081_Toned_Resized_V2.jpg\",\"articleSection\":[\"Croissance et progr\u00e8s\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/\",\"name\":\"LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/AP_17067291321081_Toned_Resized_V2.jpg\",\"datePublished\":\"2017-09-28T18:48:44+00:00\",\"dateModified\":\"2017-11-16T19:16:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/AP_17067291321081_Toned_Resized_V2.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/AP_17067291321081_Toned_Resized_V2.jpg\",\"width\":1080,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2017\\\/09\\\/nile-river-project-will-link-10-countries\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE PROJET DU NIL RELIERA 10 PAYS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/","og_locale":"fr_FR","og_type":"article","og_title":"LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum","og_description":"PERSONNEL d\u2019ADF Les travaux sont sur le point de commencer sur une voie commerciale de 4.000 kilom\u00e8tres qui doit relier la mer M\u00e9diterran\u00e9e au lac Victoria, promettant d\u2019am\u00e9liorer les \u00e9changes commerciaux pour 10 nations. Cette voie navigable, destin\u00e9e notamment \u00e0 utiliser le Nil comme route maritime commerciale, devrait \u00eatre compl\u00e9t\u00e9e d\u2019ici \u00e0 2024. Elle traversera","og_url":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2017-09-28T18:48:44+00:00","article_modified_time":"2017-11-16T19:16:32+00:00","og_image":[{"width":1080,"height":726,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"LE PROJET DU NIL RELIERA 10 PAYS","datePublished":"2017-09-28T18:48:44+00:00","dateModified":"2017-11-16T19:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/"},"wordCount":314,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg","articleSection":["Croissance et progr\u00e8s","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/","url":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/","name":"LE PROJET DU NIL RELIERA 10 PAYS - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg","datePublished":"2017-09-28T18:48:44+00:00","dateModified":"2017-11-16T19:16:32+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2017\/09\/AP_17067291321081_Toned_Resized_V2.jpg","width":1080,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2017\/09\/nile-river-project-will-link-10-countries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"LE PROJET DU NIL RELIERA 10 PAYS"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/8944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=8944"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/8944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/8729"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=8944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=8944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=8944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}