{"id":6344,"date":"2016-07-18T17:19:25","date_gmt":"2016-07-18T17:19:25","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=6344"},"modified":"2016-08-02T17:38:05","modified_gmt":"2016-08-02T17:38:05","slug":"apres-ebola","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/","title":{"rendered":"APR\u00c8S EBOLA"},"content":{"rendered":"<h3>Alors que\u00a0l\u2019Union africaine\u00a0fait le bilan des le\u00e7ons et des d\u00e9fis,\u00a0de nouvelles approches logistiques\u00a0voient le jour<\/h3>\n<p>PERSONNEL D\u2019<i>ADF<\/i><\/p>\n<p>Plus de deux ans apr\u00e8s qu\u2019Ebola a commenc\u00e9 sa progression mortelle \u00e0 travers la Guin\u00e9e, le Liberia et la Sierra Leone, faisant plus de 11.300 victimes, l\u2019Organisation mondiale de la Sant\u00e9 (OMS) a annonc\u00e9 ce qui semblait \u00eatre un miracle : l\u2019\u00e9pid\u00e9mie a pris fin.<\/p>\n<p>Le 14 janvier 2016 marque les quarante-deux jours \u00e9coul\u00e9s depuis que les derniers cas confirm\u00e9s au Liberia ont donn\u00e9 un test n\u00e9gatif. Les deux derniers patients du Liberia, le p\u00e8re et le jeune fr\u00e8re d\u2019un adolescent \u00e2g\u00e9 de 15 ans d\u00e9c\u00e9d\u00e9 du virus sont sortis de l\u2019h\u00f4pital le 3 d\u00e9cembre 2015.<\/p>\n<figure id=\"attachment_5931\" aria-describedby=\"caption-attachment-5931\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye.jpg\"><img decoding=\"async\" class=\"wp-image-5931 size-thumbnail\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye-150x150.jpg\" alt=\"Le Dr Benjamin Djoudalbaye, responsable principal de la sant\u00e9 au sein de la Commission de l\u2019Union africaine PHOTO AVEC L\u2019AIMABLE AUTORISATION DU Dr BENJAMIN DJOUDALBAYE\" width=\"150\" height=\"150\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye-150x150.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye-768x774.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye-1016x1024.jpg 1016w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/DrDjoudalbaye.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-5931\" class=\"wp-caption-text\">Le Dr Benjamin Djoudalbaye, responsable principal de la sant\u00e9 au sein de la Commission de l\u2019Union africaine<\/figcaption><\/figure>\n<p>Toutefois, les bonnes nouvelles n\u2019ont pas dur\u00e9. Le 15 janvier, la Sierra Leone a confirm\u00e9 un nouveau cas de d\u00e9c\u00e8s d\u00fb au virus Ebola. La Sierra Leone a \u00e9t\u00e9 d\u00e9clar\u00e9e exempte de la transmission du virus Ebola le 7 novembre 2015.<\/p>\n<p>Le 21 janvier, un deuxi\u00e8me cas \u00e9tait confirm\u00e9 en Sierra Leone. Un porte-parole de l\u2019OMS a annonc\u00e9 \u00e0 l\u2019Agence France-Presse qu\u2019une femme \u00e2g\u00e9e de 38 ans s\u2019\u00e9tait occup\u00e9e de sa ni\u00e8ce \u00e2g\u00e9e de 22 ans, Marie Jalloh, d\u00e9c\u00e9d\u00e9e du virus Ebola le 12 janvier. Les responsables s\u2019attendaient \u00e0 de nouveaux cas parmi les personnes ayant lav\u00e9 le corps de Marie Jalloh durant les pr\u00e9paratifs traditionnels pour son enterrement. Cette pratique a \u00e9t\u00e9 reconnue comme \u00e9tant l\u2019un des modes principaux de propagation de la maladie.<\/p>\n<p>\u00ab C\u2019est d\u00e9cevant, naturellement, \u00e9tant donn\u00e9 que plus d\u2019une centaine de jours s\u2019\u00e9taient \u00e9coul\u00e9s depuis l\u2019enregistrement du dernier cas \u00bb, a d\u00e9clar\u00e9 Sidi Yahya Tunis, le porte-parole du minist\u00e8re sierra-l\u00e9onais de la Sant\u00e9 \u00e0 l\u2019AFP, le 21 janvier.<\/p>\n<p>La d\u00e9ception des observateurs a \u00e9t\u00e9 att\u00e9nu\u00e9e par le fait que la patiente avait \u00e9t\u00e9 identifi\u00e9e comme \u00e9tant un \u00ab contact \u00e0 haut risque \u00bb, mais ils se sont demand\u00e9 pourquoi elle avait \u00e9t\u00e9 trait\u00e9e en tant que patiente externe et avait \u00e9t\u00e9 autoris\u00e9e \u00e0 entrer en contact avec 27 personnes. Il semble donc que l\u2019on continue de tirer des enseignements de la flamb\u00e9e \u00e9pid\u00e9mique et de les appliquer.<\/p>\n<p>Devant la persistance d\u2019Ebola face aux efforts de la communaut\u00e9 internationale, une chose est claire : Ebola continuera en Afrique. Il est certain qu\u2019il y aura une autre flamb\u00e9e. \u00c0 un moment donn\u00e9. Quelque part. Et il ne s\u2019agit pas de la seule pand\u00e9mie qui menace le continent. Il y a le virus Marburg, la grippe pand\u00e9mique et le chol\u00e9ra, entre autres menaces.<\/p>\n<p><b>L\u2019UA INTENSIFIE SA RIPOSTE<\/b><\/p>\n<p>Ebola a d\u00e9clench\u00e9 la mobilisation de l\u2019aide, du soutien et du personnel \u00e0 l\u2019\u00e9chelle mondiale. Les Nations Unies ont \u00e9tabli leur premi\u00e8re mission sanitaire d\u2019urgence, la Mission des Nations Unies pour l\u2019action d\u2019urgence contre l\u2019Ebola (MINUAUCE). L\u2019OMS et M\u00e9decins Sans Fronti\u00e8res ont mobilis\u00e9, parall\u00e8lement \u00e0 une force militaire am\u00e9ricaine, Operation United Assistance, qui a d\u00e9ploy\u00e9 pr\u00e8s de 3.000 soldats en Afrique de l\u2019Ouest. L\u2019Agence am\u00e9ricaine pour le d\u00e9veloppement international (USAID) a \u00e9galement r\u00e9pondu \u00e0 l\u2019appel.<\/p>\n<figure id=\"attachment_5910\" aria-describedby=\"caption-attachment-5910\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-5910\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o.jpg\" alt=\"Un ouvrier suspend des bottes protectrices en caoutchouc sur des supports en bois en d\u00e9cembre 2014 au Centre de traitement d\u2019Ebola dirig\u00e9 par l\u2019UA de Magbenteh, en Sierra Leone. MINUAUCE\/MARTINE PERRET\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640649154_2321bc275b_o-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-5910\" class=\"wp-caption-text\">Un ouvrier suspend des bottes protectrices en caoutchouc sur des supports en bois en d\u00e9cembre 2014 au Centre de traitement d\u2019Ebola dirig\u00e9 par l\u2019UA de Magbenteh, en Sierra Leone. MINUAUCE\/MARTINE PERRET<\/figcaption><\/figure>\n<p>Aux c\u00f4t\u00e9s de ces organisations, travaillant main dans la main avec tous les partenaires, se trouvait l\u2019Union africaine qui a d\u00e9ploy\u00e9 855 personnes en Guin\u00e9e, au Liberia et en Sierra Leone dans le cadre d\u2019une initiative connue sous le nom de Mission de soutien de l\u2019Union africaine pour la riposte contre l\u2019\u00e9pid\u00e9mie d\u2019Ebola en Afrique de l\u2019Ouest (ASEOWA). Cette mission, qui a officiellement pris fin le 31 d\u00e9cembre 2015, fait \u00e0 pr\u00e9sent le point sur les d\u00e9fis rencontr\u00e9s et les succ\u00e8s en mati\u00e8re de logistique, tout en se pr\u00e9parant pour la prochaine flamb\u00e9e \u00e9pid\u00e9mique en Afrique.<\/p>\n<p>En ao\u00fbt 2014, le Conseil de paix et de s\u00e9curit\u00e9 de l\u2019Union africaine a d\u00e9cid\u00e9 de d\u00e9ployer une force d\u2019intervention. Moins d\u2019un mois apr\u00e8s, les \u00e9quipes de l\u2019ASEOWA \u00e9taient sur le terrain en Afrique de l\u2019Ouest. Tr\u00e8s vite, l\u2019ASEOWA s\u2019est d\u00e9velopp\u00e9e en incorporant 855 agents. Parmi ceux-ci, on comptait 740 membres du personnel m\u00e9dical, dont des m\u00e9decins, des infirmiers et infirmi\u00e8res, des auxiliaires m\u00e9dicaux, des pharmaciens, des laborantins et des travailleurs sociaux. L\u2019ASEOWA \u00e9tait au d\u00e9part destin\u00e9e \u00e0 durer six mois, mais la mission a \u00e9t\u00e9 prolong\u00e9e \u00e0 deux reprises jusqu\u2019\u00e0 la fin 2015.<\/p>\n<p>La mise sur pied de l\u2019intervention de l\u2019ASEOWA n\u2019a pas \u00e9t\u00e9 une t\u00e2che facile, explique le Dr Benjamin Djoudalbaye, responsable principal de la sant\u00e9 aupr\u00e8s de la Commission de l\u2019UA. Le Dr Djoudalbaye, un m\u00e9decin tchadien bas\u00e9 \u00e0 Addis-Abeba, en \u00c9thiopie, a exerc\u00e9 les fonctions de directeur des op\u00e9rations de l\u2019ASEOWA jusqu\u2019en mars 2015, date \u00e0 laquelle il a \u00e9t\u00e9 d\u00e9sign\u00e9 responsable du soutien \u00e0 la mission. Il est devenu ult\u00e9rieurement chef de mission, en remplacement du g\u00e9n\u00e9ral de division ougandais Julius Oketta.<\/p>\n<p>Au fur et \u00e0 mesure de l\u2019intensification de la mission, les responsables ont \u00e9t\u00e9 confront\u00e9s \u00e0 trois probl\u00e8mes logistiques majeurs : le transport a\u00e9rien, l\u2019h\u00e9bergement du personnel et le transport terrestre dans les pays affect\u00e9s.<\/p>\n<p>\u00ab Le d\u00e9fi num\u00e9ro un \u00e9tait celui du transport \u00bb, indique le Dr Djoudalbaye. Les planificateurs ont conclu au d\u00e9part que les besoins majeurs concernaient les ressources humaines. \u00ab Une fois les personnes mobilis\u00e9es, comment allions-nous les faire venir sur place ?\u2009\u00bb<\/p>\n<p>Certains pays ayant adopt\u00e9 des mesures d\u2019interdiction de voyager dans la r\u00e9gion affect\u00e9e, l\u2019UA a fait parvenir des membres de son personnel par avion en passant par le Maroc. Les responsables ont affr\u00e9t\u00e9 des vols charters par Egyptian Airlines, Asky Airlines et Kenya Airways pour que le personnel puisse se rendre en Afrique de l\u2019Ouest.<\/p>\n<figure id=\"attachment_5913\" aria-describedby=\"caption-attachment-5913\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o.jpg\"><img decoding=\"async\" class=\"size-full wp-image-5913\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o.jpg\" alt=\"Des membres du personnel portent un \u00e9quipement de protection au Centre de traitement d\u2019Ebola de Magbenteh, en Sierra Leone. MINUAUCE\/MARTINE PERRET\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/15640651564_6dab71f190_o-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-5913\" class=\"wp-caption-text\">Des membres du personnel portent un \u00e9quipement de protection au Centre de traitement d\u2019Ebola de Magbenteh, en Sierra Leone.<br \/>MINUAUCE\/MARTINE PERRET<\/figcaption><\/figure>\n<p>\u00ab\u00a0 \u00c0 partir de l\u00e0, lorsque vous arrivez sur le terrain l\u00e0-bas, le d\u00e9fi num\u00e9ro deux est celui de l\u2019h\u00e9bergement. Il n\u2019y avait pas assez d\u2019h\u00f4tels pour loger tout notre personnel, parce qu\u2019il est n\u00e9cessaire d\u2019assurer son h\u00e9bergement dans un espace o\u00f9 sa s\u00e9curit\u00e9 est assur\u00e9e. Et l\u00e0, une fois que l\u2019h\u00e9bergement \u00e9tait arrang\u00e9, les prix \u00e9taient multipli\u00e9s par deux ou par trois. C\u2019\u00e9tait vraiment tr\u00e8s on\u00e9reux de loger notre personnel l\u00e0-bas \u00bb. Plut\u00f4t que de loger les personnes \u00e0 l\u2019h\u00f4tel, l\u2019ASEOWA a contact\u00e9 des civils qui \u00e9taient en mesure de louer des logements disponibles \u00e0 nos agents.<\/p>\n<p>Le troisi\u00e8me d\u00e9fi majeur concernait le transport terrestre une fois le personnel de l\u2019ASEOWA arriv\u00e9 en Afrique de l\u2019Ouest. Les agents avaient besoin de voitures et de v\u00e9hicules de type SUV pour effectuer le travail minutieux de \u00ab recherche des contacts \u00bb, qui consiste \u00e0 faire suivre par les agents sanitaires chaque personne avec laquelle un patient atteint du virus Ebola est entr\u00e9 en contact, \u00e0 des fins d\u2019\u00e9valuation et de quarantaine ou de traitement potentiel. Cette pratique laborieuse est essentielle \u00e0 mettre un coup d\u2019arr\u00eat \u00e0 la propagation de la maladie. Le Dr Djoudalbaye observe que la disponibilit\u00e9 des v\u00e9hicules \u00e9tait probl\u00e9matique et que les prix grimpaient en fonction de la demande. En mai 2015, la MINUAUCE a fourni certaines voitures \u00e0 l\u2019ASEOWA.<\/p>\n<p>Dans le cadre de cette op\u00e9ration sanitaire majeure, des m\u00e9dicaments et des fournitures connexes ont \u00e9t\u00e9 fournis aux agents de l\u2019ASEOWA par des organisations internationales telles que l\u2019OMS et l\u2019UNICEF. En revanche, il a \u00e9t\u00e9 plus difficile de se procurer d\u2019autres n\u00e9cessit\u00e9s, telles que des bottes en caoutchouc et des \u00e9quipements de protection individuelle. \u00ab Vous ne les trouvez pas dans les march\u00e9s locaux \u00bb, ajoute le Dr Djoudalbaye. \u00ab C\u2019\u00e9tait une difficult\u00e9 r\u00e9elle. Et \u00e9tant donn\u00e9 les interdictions de voyager mentionn\u00e9es pr\u00e9c\u00e9demment, m\u00eame si ces \u00e9quipements \u00e9taient disponibles dans les pays limitrophes, comment allions-nous nous les faire acheminer ? \u00bb Les agents sont arriv\u00e9s \u00e0 se procurer certains articles divers n\u00e9cessaires en envoyant des personnes dans les march\u00e9s locaux pour acheter tout ce qui \u00e9tait disponible. Quelquefois, ils contactaient des marchands qui avaient ferm\u00e9 boutique et les persuadaient d\u2019ouvrir et de leur vendre les articles dont ils avaient besoin.<\/p>\n<p>De septembre \u00e0 novembre 2014, les probl\u00e8mes d\u2019approvisionnement ont pris beaucoup de temps et ont \u00e9t\u00e9 difficiles \u00e0 r\u00e9soudre. C\u2019est alors que le pr\u00e9sident de la Commission de l\u2019UA a sign\u00e9 une d\u00e9rogation autorisant l\u2019ASEOWA \u00e0 acc\u00e9l\u00e9rer les achats malgr\u00e9 la stricte politique mise en place par l\u2019UA en mati\u00e8re d\u2019approvisionnement. Cette d\u00e9rogation a facilit\u00e9 la capacit\u00e9 d\u2019obtenir des fournitures ainsi que de recruter du personnel. Le Dr Djoudalbaye convient qu\u2019une flamb\u00e9e ne laissait pas le temps d\u2019\u00eatre entrav\u00e9 par une bureaucratie tatillonne.<\/p>\n<p><b>DANS LA PERSPECTIVE\u00a0<\/b><b>DE FUTURES FLAMB\u00c9ES \u00c9PID\u00c9MIQUES<\/b><\/p>\n<p>L\u2019UA et l\u2019OMS mettent \u00e0 ex\u00e9cution des plans visant \u00e0 se pr\u00e9parer pour la prochaine et in\u00e9vitable flamb\u00e9e, quelle qu\u2019elle soit, n\u2019importe quand et n\u2019importe o\u00f9. Beaucoup de choses peuvent se produire. L\u2019OMS indique qu\u2019environ 100 \u00ab \u00e9v\u00e9nements aigus de sant\u00e9 publique \u00bb sont signal\u00e9s \u00e0 son Bureau r\u00e9gional africain chaque ann\u00e9e. Ceux qui sont les plus fr\u00e9quemment signal\u00e9s sont le chol\u00e9ra, la dengue, la rougeole, la m\u00e9ningite, la peste et les fi\u00e8vres h\u00e9morragiques virales telles qu\u2019Ebola.<\/p>\n<p>L\u2019OMS, \u00ab reconnaissant le r\u00f4le crucial et l\u2019importance de la logistique pour la pr\u00e9paration et la riposte \u00e0 une flamb\u00e9e \u00e9pid\u00e9mique \u00bb a \u00e9tabli en 2015 un \u00ab Plan strat\u00e9gique r\u00e9gional de logistique 2015-2018 \u00bb, en collaboration avec d\u2019autres partenaires, y compris l\u2019USAID et les Centres am\u00e9ricains pour le contr\u00f4le et la pr\u00e9vention des maladies.<\/p>\n<figure id=\"attachment_5955\" aria-describedby=\"caption-attachment-5955\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5955\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit.jpg\" alt=\"Un homme re\u00e7oit un certificat de sant\u00e9 de la clinique Elwa, un centre de traitement d\u2019Ebola de Monrovia, au Liberia, en juillet 2015. AFP\/GETTY IMAGES\" width=\"1080\" height=\"709\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit-300x197.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit-768x504.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-481472688_edit-1024x672.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-5955\" class=\"wp-caption-text\">Un homme re\u00e7oit un certificat de sant\u00e9 de la clinique Elwa, un centre de traitement d\u2019Ebola de Monrovia, au Liberia, en juillet 2015. AFP\/GETTY IMAGES<\/figcaption><\/figure>\n<p>Le plan de l\u2019OMS indique \u00ab qu\u2019au cours des derni\u00e8res ann\u00e9es, l\u2019importance de la logistique pendant la pr\u00e9paration et la riposte aux flamb\u00e9es a \u00e9t\u00e9 cruciale pour s\u2019assurer que les fournitures essentielles et les r\u00e9actifs sont pr\u00e9positionn\u00e9s et d\u00e9ploy\u00e9s rapidement sur le terrain dans le cadre du soutien op\u00e9rationnel dans la lutte contre l\u2019\u00e9pid\u00e9mie. L\u2019importance de ce pr\u00e9positionnement est soulign\u00e9e dans le Cadre d\u2019action d\u2019urgence de l\u2019OMS qui pr\u00e9cise que la fourniture d\u2019un appui administratif et logistique est une exigence essentielle pour assurer un syst\u00e8me efficace d\u2019intervention rapide \u00bb.<\/p>\n<p>Parmi les six objectifs sp\u00e9cifiques de l\u2019OMS figure le pr\u00e9positionnement des fournitures et des \u00e9quipements utilis\u00e9s pour la lutte contre la flamb\u00e9e, afin qu\u2019ils soient pr\u00eats \u00e0 \u00eatre achemin\u00e9s lorsque cela est n\u00e9cessaire. Pour accomplir cela, le plan recommande entre autres mesures le d\u00e9veloppement de sites de stockage, d\u2019entrep\u00f4ts et d\u2019un syst\u00e8me de gestion des stocks.<\/p>\n<p>Le Dr Djoudalbaye ajoute que le pr\u00e9positionnement des fournitures en vue d\u2019une utilisation future est \u00e9galement une priorit\u00e9 essentielle de l\u2019UA. \u00ab Pour nous, c\u2019est une question simple \u00bb, observe-t-il. \u00ab Nous avons aujourd\u2019hui la possibilit\u00e9 de disposer d\u2019une base logistique continentale \u00e0 Douala, au Cameroun. Aussi essayons-nous \u00e0 pr\u00e9sent d\u2019avoir, par exemple, des arrangements \u00e0 l\u2019avance avec des fournisseurs, dans le but de pr\u00e9positionner notre mat\u00e9riel logistique \u00bb.<\/p>\n<p>L\u2019UA projette d\u2019entreposer \u00e0 Douala des v\u00e9hicules et des habitations mobiles fournies par des donateurs. Lorsqu\u2019il s\u2019agit d\u2019\u00e9quipement \u00e9lectronique, tel que des ordinateurs portables et des tablettes, au lieu de faire des achats en gros et d\u2019entreposer les \u00e9quipements pendant une dur\u00e9e ind\u00e9termin\u00e9e, les responsables concluront des ententes pr\u00e9alables avec les fabricants dans l\u2019espoir de se procurer ce mat\u00e9riel dans les 48 \u00e0 72 heures, comme l\u2019explique le Dr Djoudalbaye. \u00ab De telle sorte que s\u2019il y a un besoin, nous pourrons leur demander de faire leur possible pour livrer 1.000 ordinateurs portables dans cette zone \u00bb, ajoute-t-il. \u00ab Ce sont des choses que nous essayons de mettre en place \u00e0 pr\u00e9sent\u2026 afin que nous disposions \u00e0 l\u2019avance d\u2019un plan de pr\u00e9paration, y compris en cas d\u2019urgence, de fa\u00e7on \u00e0 ce que si demain il y a une crise\u2026 nous puissions \u00eatre en mesure de surmonter les difficult\u00e9s auxquelles nous avons d\u00fb faire face dans le cadre de l\u2019ASEOWA \u00bb.<\/p>\n<p><b>LE CDC AFRICAIN<\/b><\/p>\n<p>La flamb\u00e9e d\u2019Ebola a \u00e9galement donn\u00e9 l\u2019occasion d\u2019acc\u00e9l\u00e9rer des plans visant \u00e0 \u00e9tablir des Centres pour le contr\u00f4le et la pr\u00e9vention des maladies africains (CDC africains). Un centre de coordination sera \u00e9tabli \u00e0 Addis-Abeba, en \u00c9thiopie, et il y aura cinq centres r\u00e9gionaux, r\u00e9partis entre l\u2019Afrique centrale, l\u2019Afrique de l\u2019Est, l\u2019Afrique du Nord, l\u2019Afrique du Sud et l\u2019Afrique de l\u2019Ouest.<\/p>\n<p>Les CDC africains aideront les autorit\u00e9s \u00e0 acc\u00e9l\u00e9rer la d\u00e9tection, la pr\u00e9paration et la riposte \u00e0 des flamb\u00e9es. Ebola a s\u00e9vi en Afrique de l\u2019Ouest des mois avant que les autorit\u00e9s n\u2019aient reconnu qu\u2019il s\u2019agissait d\u2019un probl\u00e8me sanitaire mondial. Avec des centres r\u00e9gionaux, les capacit\u00e9s de ressources et de d\u00e9tection seront plus proches lors de la survenance d\u2019une flamb\u00e9e, quelle que soit la r\u00e9gion.<\/p>\n<figure id=\"attachment_5952\" aria-describedby=\"caption-attachment-5952\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5952\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit.jpg\" alt=\"Une infirmi\u00e8re administre une injection en f\u00e9vrier 2015 le premier jour d\u2019une \u00e9tude sur le vaccin du virus Ebola r\u00e9alis\u00e9e \u00e0 Monrovia, au Liberia. GETTY IMAGES\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/GettyImages-462658366_edit-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-5952\" class=\"wp-caption-text\">Une infirmi\u00e8re administre une injection en f\u00e9vrier 2015 le premier jour d\u2019une \u00e9tude sur le vaccin du virus Ebola r\u00e9alis\u00e9e \u00e0 Monrovia, au Liberia. GETTY IMAGES<\/figcaption><\/figure>\n<p>Chaque zone proposera pour le centre r\u00e9gional un pays h\u00f4te, qui sera alors \u00e9valu\u00e9 par des \u00e9quipes d\u2019autres CDC du monde entier. Les candidatures pour les centres r\u00e9gionaux devront avoir \u00e9t\u00e9 pr\u00e9sent\u00e9es au plus tard le 31 d\u00e9cembre 2015. Les op\u00e9rations seront supervis\u00e9es par un conseil de direction compos\u00e9 de deux responsables des minist\u00e8res de la Sant\u00e9 des pays de chaque r\u00e9gion et d\u2019un groupe consultatif de partenaires techniques. L\u2019objectif \u00e0 long terme pour chaque pays est d\u2019avoir des centres nationaux disposant de capacit\u00e9s similaires.<\/p>\n<p>Les responsables esp\u00e8rent que le centre de coordination sera ouvert au premier trimestre 2016. L\u2019ouverture des centres r\u00e9gionaux est pr\u00e9vue \u00e0 une date ult\u00e9rieure.<\/p>\n<p><b>LE CORPS DES VOLONTAIRES AFRICAINS POUR LA SANT\u00c9<\/b><\/p>\n<p>Le CDC africain constitue une structure r\u00e9gionalis\u00e9e permanente con\u00e7ue pour riposter aux flamb\u00e9es \u00e9pid\u00e9miques dans l\u2019ensemble du continent. Toutefois, l\u2019UA travaille \u00e9galement sur une autre strate de capacit\u00e9s qui am\u00e9liorera l\u2019aptitude \u00e0 une riposte rapide durant les urgences sanitaires. En juin 2015, la Conf\u00e9rence des chefs d\u2019\u00c9tat et de gouvernement de l\u2019UA a demand\u00e9 \u00e0 la Commission de l\u2019UA de collaborer avec les partenaires de d\u00e9veloppement et les \u00c9tats membres en vue d\u2019\u00e9tablir un Corps des volontaires africains pour la sant\u00e9 (AVoHC).<\/p>\n<p>En octobre 2015, \u00e0 Mah\u00e9, aux Seychelles, les responsables ont pr\u00e9sent\u00e9 et examin\u00e9 un avant-projet de proposition d\u2019un Corps des volontaires africains pour la sant\u00e9 (AVoHC) au cours de l\u2019Atelier d\u2019\u00e9valuation de la Mission de soutien de l\u2019Union africaine \u00e0 la lutte contre l\u2019\u00e9pid\u00e9mie d\u2019Ebola en Afrique de l\u2019Ouest. L\u2019AVoHC contribuera \u00e0 combler les lacunes en mati\u00e8re de ressources humaines pour faire en sorte que les \u00e9pid\u00e9mies et les urgences de sant\u00e9 publique fassent l\u2019objet d\u2019une riposte en temps voulu et efficace, en employant des personnes issues de divers domaines d\u2019expertise.<\/p>\n<p>\u00ab L\u2019id\u00e9e est d\u2019avoir une sorte d\u2019effectif en attente pouvant \u00eatre mobilis\u00e9 \u00e0 tout moment \u00bb, indique le Dr Djoudalbaye. \u00ab Nous allons \u00e9tablir une liste de personnes que nous contacterons pour qu\u2019elles re\u00e7oivent une formation peut-\u00eatre une ou deux fois par an. Toutefois, la mission du Corps des volontaires africains pour la sant\u00e9 sera de r\u00e9pondre aux pr\u00e9occupations prioritaires en mati\u00e8re de sant\u00e9 publique en Afrique par le biais de la pr\u00e9vention, de la d\u00e9tection et de la riposte appropri\u00e9e \u00bb.<\/p>\n<p>L\u2019ensemble de ces d\u00e9veloppements, qu\u2019ils soient inspir\u00e9s ou acc\u00e9l\u00e9r\u00e9s par la flamb\u00e9e d\u2019Ebola en Afrique de l\u2019Ouest, servira \u00e0 rapprocher de chaque zone du continent les ressources appropri\u00e9es et les personnels comp\u00e9tents, pr\u00eats \u00e0 la riposte d\u00e8s l\u2019\u00e9mergence d\u2019un probl\u00e8me sanitaire.<\/p>\n<p>\u00ab Notre devise est d\u00e9sormais \u2018Plus t\u00f4t, plus vite, plus souplement et plus intelligemment\u2019 \u00bb, conclut le Dr Djoudalbaye. \u00ab Nous avons besoin d\u2019une d\u00e9tection plus pr\u00e9coce, d\u2019une r\u00e9action plus rapide, d\u2019une coordination plus souple et d\u2019une riposte plus intelligente. C\u2019est donc l\u00e0-dessus que nous allons travailler \u00bb.<\/p>\n<hr \/>\n<h4>L\u2019AFRIQUE DE L\u2019EST\u00a0<b>LANCE UN PROGRAMME DE PR\u00c9VENTION ET DE CONTR\u00d4LE DES PAND\u00c9MIES<\/b><\/h4>\n<p>VOICE OF AMERICA<\/p>\n<figure id=\"attachment_6042\" aria-describedby=\"caption-attachment-6042\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6042\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit.jpg\" alt=\"Etienne Ouamouno, p\u00e8re du premier enfant atteint du virus Ebola, le \u00ab patient z\u00e9ro \u00bb se tient pr\u00e8s du kapokier o\u00f9, selon des scientifiques, \u00c9mile, son fils \u00e2g\u00e9 de 2 ans, pourrait avoir contract\u00e9 le virus Ebola transmis par des chauves-souris \u00e0 Meliandou, en Guin\u00e9e. REUTERS\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/RTR4RX96_edit-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-6042\" class=\"wp-caption-text\">Etienne Ouamouno, p\u00e8re du premier enfant atteint du virus Ebola, le \u00ab patient z\u00e9ro \u00bb se tient pr\u00e8s du kapokier o\u00f9, selon des scientifiques, \u00c9mile, son fils \u00e2g\u00e9 de 2 ans, pourrait avoir contract\u00e9 le virus Ebola transmis par des chauves-souris \u00e0 Meliandou, en Guin\u00e9e. REUTERS<\/figcaption><\/figure>\n<p>Ebola n\u2019est pas la premi\u00e8re \u00e9pid\u00e9mie caus\u00e9e par la transmission de microbes entre animaux et humains. \u00c0 mesure que la population mondiale continue de cro\u00eetre, parall\u00e8lement \u00e0 la demande de produits alimentaires, des menaces similaires sont susceptibles de se produire.<\/p>\n<p>En janvier 2016, dans un h\u00f4tel de Nairobi, au Kenya, L\u2019Organisation des Nations Unies pour l\u2019alimentation et l\u2019agriculture (FAO) et l\u2019Agence am\u00e9ricaine pour le d\u00e9veloppement international (USAID) ont lanc\u00e9 la composante est-africaine du programme Menaces pand\u00e9miques \u00e9mergentes (EPT-2) de la FAO. Il est destin\u00e9 \u00e0 aider \u00e0 d\u00e9tecter, pr\u00e9venir et contr\u00f4ler de nouvelles maladies dites \u00ab zoonotiques \u00bb, qui peuvent \u00eatre transmises entre l\u2019animal et l\u2019homme.<\/p>\n<p>Subhash Morzaria, coordinateur mondial du programme EPT-2, explique que ces maladies peuvent \u00eatre transmises par l\u2019air ou par le toucher de fluides ou de mati\u00e8res infect\u00e9es. \u00ab Quel que soit le mode de transmission&#8230; si ces maladies infectieuses persistent dans nos populations animales, alors nous sommes en pr\u00e9sence d\u2019un risque constant que cette maladie soit susceptible de devenir pand\u00e9mique et de causer des flamb\u00e9es, une morbidit\u00e9 et une mortalit\u00e9 tout \u00e0 fait consid\u00e9rables chez l\u2019homme et aussi chez l\u2019animal \u00bb, pr\u00e9cise-t-il.<\/p>\n<p>Parmi les maladies zoonotiques, mentionnons le VIH\/SIDA, la grippe, y compris celle qui est couramment appel\u00e9e la grippe aviaire et la grippe porcine, ainsi que le syndrome respiratoire aigu s\u00e9v\u00e8re (SARS), le syndrome respiratoire du Moyen-Orient (MERS-CoV), la maladie \u00e0 virus de Marburg et l\u2019infection \u00e0 virus Nipah. On estime que sur 10 maladies infectieuses existant chez l\u2019homme, six sont transmises par les animaux, selon les Centres am\u00e9ricains pour la pr\u00e9vention et le contr\u00f4le des maladies.<\/p>\n<p>Les Nations Unies pr\u00e9voient une croissance de la population mondiale qui passera du chiffre actuel de 7,3 milliards d\u2019habitants \u00e0 9,7 milliards d\u2019habitants en 2050. Cette augmentation rapide signifie une augmentation parall\u00e8le de la demande alimentaire.<\/p>\n<p>\u00ab Ceci \u00e9tant dit, ces syst\u00e8mes de production \u00e9volueront tr\u00e8s rapidement pour r\u00e9pondre \u00e0 cette demande, et il est possible que certaines pratiques \u00e0 haut risque soient utilis\u00e9es dans l\u2019\u00e9levage de b\u00e9tail, et que ces pratiques risqu\u00e9es puissent cr\u00e9er un environnement propice \u00e0 l\u2019\u00e9volution et \u00e0 la propagation de nouveaux agents pathog\u00e8nes \u00bb, poursuit Subhash Morzaria.<\/p>\n<p>Le directeur des services v\u00e9t\u00e9rinaires du Kenya, le Dr Kisa Juma Ngeiywa, pr\u00e9cise que les nouveaux agents pathog\u00e8nes peuvent se propager plus loin que jamais auparavant dans le contexte de la mobilit\u00e9 sociale d\u2019aujourd\u2019hui.<\/p>\n<p>\u00ab Consid\u00e9rons la grippe H7N9, qui se propageait en Chine \u00bb, explique le Dr Kisa Juma Ngeiywa \u00e0 propos de la souche de la grippe aviaire. \u00ab Maintenant, si vous prenez en compte les avions, de Kenya Airways, Ethiopian Airlines et d\u2019autres compagnies a\u00e9riennes, vous savez qu\u2019ils vont en Chine et qu\u2019ils reviennent au Kenya, chaque jour. Donc, \u00e0 cause de cela, il y a l\u00e0 une vuln\u00e9rabilit\u00e9 de taille, \u00e0 moins que nous ne mettions des mesures [en place] pour \u00eatre \u00e0 m\u00eame de faire en sorte d\u2019arr\u00eater la diss\u00e9mination \u00bb.<\/p>\n<p>Subhash Morzaria affirme que nous sommes tous partie prenante dans ce processus.<\/p>\n<p>\u00ab Tout le monde est menac\u00e9 \u00bb, a-t-il d\u00e9clar\u00e9. \u00ab Le virus ne fait pas de distinction entre une personne pauvre ou une personne riche. S\u2019il est hautement infectieux et pathog\u00e8ne, alors il arrive, il infecte et il tue cette personne. Aussi je pense qu\u2019il s\u2019agit d\u2019une pr\u00e9occupation mondiale \u00bb.<\/p>\n<p>En octobre 2015, l\u2019USAID a annonc\u00e9 un nouveau financement pour ce programme, \u00e0 hauteur de 87 millions de dollars. Les fonds seront utilis\u00e9s pour aider les pouvoirs publics et les services v\u00e9t\u00e9rinaires \u00e0 mieux comprendre les syst\u00e8mes d\u2019\u00e9levage et pour aider \u00e0 effectuer une surveillance et \u00e0 identifier les agents pathog\u00e8nes actuels et potentiels.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6345\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time.jpg\" alt=\"ADF_V9N2_Fre_54Time\" width=\"1237\" height=\"534\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time.jpg 1237w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time-300x130.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time-768x332.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time-1024x442.jpg 1024w\" sizes=\"(max-width: 1237px) 100vw, 1237px\" \/><\/a><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6348\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2.jpg\" alt=\"ADF_V9N2_Fre_54Time2\" width=\"1237\" height=\"534\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2.jpg 1237w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2-300x130.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2-768x332.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time2-1024x442.jpg 1024w\" sizes=\"(max-width: 1237px) 100vw, 1237px\" \/><\/a><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6351\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3.jpg\" alt=\"ADF_V9N2_Fre_54Time3\" width=\"1237\" height=\"534\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3.jpg 1237w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3-300x130.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3-768x332.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time3-1024x442.jpg 1024w\" sizes=\"(max-width: 1237px) 100vw, 1237px\" \/><\/a><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6354\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4.jpg\" alt=\"ADF_V9N2_Fre_54Time4\" width=\"1237\" height=\"534\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4.jpg 1237w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4-300x130.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4-768x332.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/07\/ADF_V9N2_Fre_54Time4-1024x442.jpg 1024w\" sizes=\"(max-width: 1237px) 100vw, 1237px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que\u00a0l\u2019Union africaine\u00a0fait le bilan des le\u00e7ons et des d\u00e9fis,\u00a0de nouvelles approches logistiques\u00a0voient le jour PERSONNEL D\u2019ADF Plus de deux ans apr\u00e8s qu\u2019Ebola a commenc\u00e9 sa progression mortelle \u00e0 travers la Guin\u00e9e, le Liberia et la Sierra Leone, faisant plus de 11.300 victimes, l\u2019Organisation mondiale de la Sant\u00e9 (OMS) a annonc\u00e9 ce qui semblait \u00eatre<\/p>\n","protected":false},"author":1,"featured_media":5935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[],"class_list":{"0":"post-6344","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articles"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>APR\u00c8S EBOLA - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"APR\u00c8S EBOLA - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Alors que\u00a0l\u2019Union africaine\u00a0fait le bilan des le\u00e7ons et des d\u00e9fis,\u00a0de nouvelles approches logistiques\u00a0voient le jour PERSONNEL D\u2019ADF Plus de deux ans apr\u00e8s qu\u2019Ebola a commenc\u00e9 sa progression mortelle \u00e0 travers la Guin\u00e9e, le Liberia et la Sierra Leone, faisant plus de 11.300 victimes, l\u2019Organisation mondiale de la Sant\u00e9 (OMS) a annonc\u00e9 ce qui semblait \u00eatre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-18T17:19:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-02T17:38:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"APR\u00c8S EBOLA\",\"datePublished\":\"2016-07-18T17:19:25+00:00\",\"dateModified\":\"2016-08-02T17:38:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/\"},\"wordCount\":3674,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/EBOLA_ReplacementPhoto.jpg\",\"articleSection\":[\"articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/\",\"name\":\"APR\u00c8S EBOLA - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/EBOLA_ReplacementPhoto.jpg\",\"datePublished\":\"2016-07-18T17:19:25+00:00\",\"dateModified\":\"2016-08-02T17:38:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/EBOLA_ReplacementPhoto.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/EBOLA_ReplacementPhoto.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2016\\\/07\\\/apres-ebola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"APR\u00c8S EBOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"APR\u00c8S EBOLA - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/","og_locale":"fr_FR","og_type":"article","og_title":"APR\u00c8S EBOLA - Africa Defense Forum","og_description":"Alors que\u00a0l\u2019Union africaine\u00a0fait le bilan des le\u00e7ons et des d\u00e9fis,\u00a0de nouvelles approches logistiques\u00a0voient le jour PERSONNEL D\u2019ADF Plus de deux ans apr\u00e8s qu\u2019Ebola a commenc\u00e9 sa progression mortelle \u00e0 travers la Guin\u00e9e, le Liberia et la Sierra Leone, faisant plus de 11.300 victimes, l\u2019Organisation mondiale de la Sant\u00e9 (OMS) a annonc\u00e9 ce qui semblait \u00eatre","og_url":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2016-07-18T17:19:25+00:00","article_modified_time":"2016-08-02T17:38:05+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"APR\u00c8S EBOLA","datePublished":"2016-07-18T17:19:25+00:00","dateModified":"2016-08-02T17:38:05+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/"},"wordCount":3674,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg","articleSection":["articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/","url":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/","name":"APR\u00c8S EBOLA - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg","datePublished":"2016-07-18T17:19:25+00:00","dateModified":"2016-08-02T17:38:05+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2016\/06\/EBOLA_ReplacementPhoto.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2016\/07\/apres-ebola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"APR\u00c8S EBOLA"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/6344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=6344"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/6344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/5935"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=6344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=6344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=6344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}