{"id":5328,"date":"2015-12-21T16:45:36","date_gmt":"2015-12-21T16:45:36","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=5328"},"modified":"2016-01-20T17:50:47","modified_gmt":"2016-01-20T17:50:47","slug":"la-profession-des-armes","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2015\/12\/la-profession-des-armes\/","title":{"rendered":"La Profession des Armes"},"content":{"rendered":"<h3>L\u2019\u00c9DIFICATION D\u2019UNE CULTURE MILITAIRE QUI FA\u00c7ONNE DES DIRIGEANTS \u00c9THIQUES<\/h3>\n<p>\u00c0 l\u2019occasion d\u2019un discours de remise de dipl\u00f4me aux \u00e9l\u00e8ves de l\u2019\u00c9cole de l\u2019arm\u00e9e de l\u2019air, Nosiviwe Mapisa-Nqakula, la ministre sud-africaine de la D\u00e9fense, a rappel\u00e9 aux jeunes dipl\u00f4m\u00e9s qu\u2019ils \u00e9taient sur le point d\u2019entamer une carri\u00e8re \u00e0 nulle autre pareille. \u00ab Vous avez r\u00e9pondu \u00e0 la forme la plus \u00e9lev\u00e9e de l\u2019appel du devoir \u00e0 laquelle tout citoyen puisse aspirer \u00bb, a-t-elle d\u00e9clar\u00e9 en juin 2015. \u00ab Au moment o\u00f9 vous achevez vos \u00e9tudes aujourd\u2019hui, vous rejoignez un groupe de Sud-Africains qui, au lieu de choisir un emploi normal, ont fait le choix de servir pour d\u00e9fendre votre pays, son peuple et ses ressources \u00bb.<\/p>\n<p>Elle a toutefois ajout\u00e9 que la v\u00e9ritable nature d\u2019un militaire professionnel ne peut \u00eatre r\u00e9v\u00e9l\u00e9e que lorsqu\u2019il est mis \u00e0 l\u2019\u00e9preuve, surmonte les difficult\u00e9s quotidiennes et satisfait aux exigences \u00e9thiques du service. \u00ab Vous avez \u00e9t\u00e9 impr\u00e9gn\u00e9s de ces valeurs d\u2019honneur, de discipline et de patriotisme \u00bb, a-t-elle d\u00e9clar\u00e9 aux dipl\u00f4m\u00e9s. \u00ab Mais que signifieront v\u00e9ritablement ces valeurs pour vous lorsque vous retournerez dans votre environnement, sur le terrain ? \u00bb<\/p>\n<p>Que signifie \u00eatre un professionnel ? Ce n\u2019est pas une question simple. Dans le civil, un professionnel est quelqu\u2019un qui est form\u00e9 dans un domaine et pay\u00e9 pour faire un travail sp\u00e9cifique. Un charpentier professionnel, par exemple, est diff\u00e9rent de quelqu\u2019un qui fait un peu de menuiserie chez lui.<\/p>\n<p>En revanche, le terme \u00ab militaire professionnel \u00bb a une signification plus vari\u00e9e. Le professionnalisme commence avec la formation et l\u2019expertise tactique, mais les soldats disent que cela va au-del\u00e0. Il exige \u00e9galement de la discipline et une aptitude \u00e0 subir de dures \u00e9preuves sans craquer. Certains mettent l\u2019accent sur un engagement en mati\u00e8re d\u2019\u00e9thique, et d\u2019autres font ressortir l\u2019honneur, les capacit\u00e9s \u00e0 diriger et un d\u00e9sir constant de s\u2019am\u00e9liorer. Ces attributs et bien d\u2019autres font partie de ce riche ensemble de qualit\u00e9s qui font un soldat professionnel.<\/p>\n<p>Il n\u2019y a pas de formule simple pour modeler un militaire professionnel, mais en parcourant les publications portant sur la formation militaire et en observant \u00e0 travers le monde quelques-unes des forces combattantes les plus globalement respect\u00e9es, certains points communs se profilent.<\/p>\n<figure id=\"attachment_4991\" aria-describedby=\"caption-attachment-4991\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4991\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits.jpg\" alt=\"Des officiers maliens venant de recevoir leur dipl\u00f4me prennent part \u00e0 une c\u00e9r\u00e9monie \u00e0 Koulikoro. REUTERS \" width=\"1080\" height=\"1087\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits-150x150.jpg 150w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits-300x302.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits-768x773.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/TanOutfits-1017x1024.jpg 1017w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption id=\"caption-attachment-4991\" class=\"wp-caption-text\">Des officiers maliens venant de recevoir leur dipl\u00f4me prennent part \u00e0 une c\u00e9r\u00e9monie \u00e0 Koulikoro. REUTERS<\/figcaption><\/figure>\n<p><b>UN PROCESSUS DE S\u00c9LECTION SUP\u00c9RIEUR<\/b><br \/>\nDans leur essai intitul\u00e9 \u00ab Military Leadership Development: A Model for the South African National Defence Force \u00bb (D\u00e9veloppement des capacit\u00e9s de commandement : un mod\u00e8le pour les Forces de d\u00e9fense nationale sud-africaines), Willem Erasmus et Frederik Uys, de l\u2019Universit\u00e9 Stellenbosch, font valoir que pour produire de grands leaders, leur pays doit commencer par mettre r\u00e9solument l\u2019accent sur la s\u00e9lection des candidats \u00e0 la fonction d\u2019officier. Les chercheurs font remarquer que les candidats \u00e0 l\u2019Acad\u00e9mie Royale Militaire de Sandhurst au Royaume-Uni passent au moins huit jours \u00e0 subir une s\u00e9rie de tests psychologiques, d\u2019aptitudes et d\u2019endurance pour d\u00e9cider s\u2019ils vont \u00eatre accept\u00e9s. Le Royaume-Uni a une organisation d\u00e9di\u00e9e, le Conseil de s\u00e9lection des officiers de l\u2019arm\u00e9e, dont la mission essentielle est de trouver les candidats les mieux qualifi\u00e9s \u00e0 partir d\u2019un large pool de candidatures. Comme les taux d\u2019abandon ou d\u2019expulsion sont faibles dans les \u00e9coles militaires, il est d\u2019importance cruciale de mettre en place un processus de s\u00e9lection efficace d\u00e8s le d\u00e9but.<\/p>\n<p>\u00ab Le processus vise \u00e0 ne s\u00e9lectionner que les candidats dont l\u2019intellect satisfait aux normes exig\u00e9es, et, plus important encore, dont le comportement et les aptitudes \u00e0 la prise de d\u00e9cision r\u00e9sistent aux conditions de stress \u00bb, expliquent ces chercheurs.<\/p>\n<figure id=\"attachment_4955\" aria-describedby=\"caption-attachment-4955\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-4955\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/PrettyBlueBarrets.jpg\" alt=\"Des soldats participent \u00e0 un d\u00e9fil\u00e9 c\u00e9l\u00e9brant le 54e Jour de l\u2019Ind\u00e9pendance de la C\u00f4te d\u2019Ivoire en 2014. REUTERS\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/PrettyBlueBarrets.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/PrettyBlueBarrets-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/PrettyBlueBarrets-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/PrettyBlueBarrets-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption id=\"caption-attachment-4955\" class=\"wp-caption-text\">Des soldats participent \u00e0 un d\u00e9fil\u00e9 c\u00e9l\u00e9brant le 54e Jour de l\u2019Ind\u00e9pendance de la C\u00f4te d\u2019Ivoire en 2014. REUTERS<\/figcaption><\/figure>\n<p><b>MENTORAT<\/b><br \/>\nUne partie du perfectionnement professionnel consiste \u00e0 suivre l\u2019exemple des autres. Dans le cadre d\u2019une enqu\u00eate portant sur des officiers am\u00e9ricains de haut rang, r\u00e9alis\u00e9e par le Center for Creative Leadership, le tout premier facteur de perfectionnement \u00e9tait le fait d\u2019avoir \u00ab des exemples \u00e0 suivre positifs \u00bb, mentionn\u00e9 par 37 pour cent des sond\u00e9s.<\/p>\n<p>Le<i> U.S. Army Leadership Handbook<\/i> (Guide du commandement dans l\u2019arm\u00e9e am\u00e9ricaine) insiste sur l\u2019importance de forger des relations de mentorat. Ce guide explique qu\u2019il n\u2019est pas n\u00e9cessaire que ce soit des relations de sup\u00e9rieur \u00e0 subordonn\u00e9, et que le mentorat se d\u00e9veloppe souvent entre homologues ou entre sous-officiers sup\u00e9rieurs et officiers subalternes. Le guide encourage les jeunes soldats \u00e0 rechercher des mentors et \u00e0 cultiver cette relation tout au long de leur carri\u00e8re.<\/p>\n<p>\u00ab Pour les soldats, la pratique consistant \u00e0 rechercher des retours d\u2019information dans le but de bien orienter leur perfectionnement, conjugu\u00e9e \u00e0 la recherche de mentors d\u00e9vou\u00e9s et bien inform\u00e9s, sera le socle permettant d\u2019int\u00e9grer les concepts d\u2019un apprentissage permanent, du d\u00e9veloppement personnel et de l\u2019adaptabilit\u00e9 \u00e0 la culture de l\u2019arm\u00e9e \u00bb, indique le guide.<\/p>\n<p><b>FORMATION CONTINUE EN MATI\u00c8RE D\u2019\u00c9THIQUE<\/b><br \/>\nLa formation au professionnalisme et \u00e0 l\u2019\u00e9thique assur\u00e9e en salle de classe trouve n\u00e9cessairement ses limites. Les commandants d\u2019unit\u00e9s ont estim\u00e9 qu\u2019il \u00e9tait important de reproduire le stress des sc\u00e9narios du monde r\u00e9el lorsqu\u2019ils pr\u00e9parent les soldats \u00e0 rencontrer des difficult\u00e9s d\u2019ordre \u00e9thique.<\/p>\n<p>Dans son essai intitul\u00e9 \u00ab L\u2019\u00e9tude de l\u2019\u00e9thique militaire : de la th\u00e9orie \u00e0 la pratique \u00bb, le g\u00e9n\u00e9ral fran\u00e7ais Beno\u00eet Royal affirme qu\u2019il ne doit pas exister un seul exercice de terrain sans qu\u2019au moins un cas pratique \u00e9thique soit ins\u00e9r\u00e9 dans l\u2019exercice. \u00ab Il s\u2019agit ainsi d\u2019habituer les soldats \u00e0 int\u00e9grer en permanence ces r\u00e9flexions \u00e0 l\u2019ex\u00e9cution des actes tactiques de terrain, dans la difficult\u00e9, sous la pression du temps, de la m\u00e9t\u00e9o et dans un vrai niveau de stress \u00bb, explique-t-il. \u00ab Il faut faire comprendre que le comportement d\u2019un soldat au combat doit \u00eatre en permanence irrigu\u00e9 par l\u2019esprit et les valeurs enseign\u00e9es \u00bb.<\/p>\n<p>Reconnaissant cela, les instructeurs de la Mission de formation de l\u2019Union europ\u00e9enne au Mali en 2015 ont insist\u00e9 sur la n\u00e9cessit\u00e9 de reproduire les sc\u00e9narios \u00e9thiques et humanitaires du monde r\u00e9el lors de la formation des soldats maliens. Ceci comportait des simulations de postes de contr\u00f4le, des d\u00e9cisions de commandement sur la protection des \u00e9coles et des h\u00f4pitaux, ainsi que des exercices d\u2019intervention en cas de violences \u00e0 l\u2019\u00e9gard des femmes. Cette insistance \u00e9tait une r\u00e9ponse aux critiques selon lesquelles l\u2019insuffisance de formation \u00e9thique au sein des Forces arm\u00e9es maliennes avait conduit \u00e0 un effondrement de la discipline pendant la crise de 2012 au Mali.<\/p>\n<p>La formation ne peut pas \u00eatre achev\u00e9e avec la remise des dipl\u00f4mes par une \u00e9cole militaire ou apr\u00e8s une formation de base. Il est largement reconnu que les comp\u00e9tences se d\u00e9gradent \u00e0 la longue si elles ne sont pas renforc\u00e9es et actualis\u00e9es. Selon l\u2019Institut de recherche de l\u2019Arm\u00e9e am\u00e9ricaine pour les sciences comportementales et sociales, les soldats perdent environ 60 pour cent de leur ma\u00eetrise des comp\u00e9tences apr\u00e8s seulement 180 jours sans pratique ou formation renouvel\u00e9e. \u00ab La formation militaire est un processus permanent qui inclut non seulement l\u2019apprentissage ou l\u2019acquisition des comp\u00e9tences initiales\u2026 mais aussi des r\u00e9p\u00e9titions et une pratique fr\u00e9quentes \u00bb, observe Abel Esterhuyse de l\u2019Universit\u00e9 Stellenbosch. \u00ab La vie quotidienne des soldats, aviateurs et marins est elle-m\u00eame un processus de formation dans lequel ils accomplissent leurs t\u00e2ches tout en poursuivant leur apprentissage pour am\u00e9liorer leur performance \u00bb.<\/p>\n<figure id=\"attachment_4855\" aria-describedby=\"caption-attachment-4855\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-4855\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/DialogueReplacement.jpg\" alt=\"Des officiers saluent au cours d\u2019un d\u00e9fil\u00e9 comm\u00e9morant le 150e anniversaire de l\u2019Arm\u00e9e nig\u00e9riane. REUTERS \" width=\"1080\" height=\"670\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/DialogueReplacement.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/DialogueReplacement-300x186.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/DialogueReplacement-768x476.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/DialogueReplacement-1024x635.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption id=\"caption-attachment-4855\" class=\"wp-caption-text\">Des officiers saluent au cours d\u2019un d\u00e9fil\u00e9 comm\u00e9morant le 150e anniversaire de l\u2019Arm\u00e9e nig\u00e9riane. \u00a0REUTERS<\/figcaption><\/figure>\n<p><b>PARTAGE DES CONNAISSANCES<\/b><br \/>\nQuel que soit le terrain, les professionnels ont la possibilit\u00e9 de faire b\u00e9n\u00e9ficier les autres de l\u2019apport de leurs propres connaissances. Ceci peut \u00eatre r\u00e9alis\u00e9 en organisant des sessions d\u2019\u00e9tudes pour les coll\u00e8gues, en \u00e9crivant des articles pour des revues professionnelles ou en enseignant dans une \u00e9cole d\u2019\u00e9tat-major ou dans un autre \u00e9tablissement. Cette \u00ab boucle de r\u00e9troaction \u00bb est une mani\u00e8re pour les membres de l\u2019encadrement de partager les meilleures pratiques apprises sur le terrain.<\/p>\n<p>Le Nigeria, par exemple, s\u2019est fix\u00e9 comme priorit\u00e9 d\u2019identifier les \u00e9l\u00e8ves exemplaires auxquels il est demand\u00e9 de retourner \u00e0 leur \u00e9cole de commandement ou d\u2019\u00e9tat-major \u00e0 titre d\u2019instructeur ou de \u00ab personnel d\u2019encadrement \u00bb. Les candidats sont \u00e9valu\u00e9s sur la base de leurs notes, caract\u00e8re, charisme et force mentale et physique. Le g\u00e9n\u00e9ral de division a\u00e9rienne John Ifemeje, de l\u2019arm\u00e9e de l\u2019air nig\u00e9riane, estime que ce processus rigoureux est la meilleure fa\u00e7on pour le syst\u00e8me de se r\u00e9g\u00e9n\u00e9rer et de modeler de futurs leaders.<\/p>\n<p><b>SURVEILLANCE<\/b><br \/>\nPour garantir la responsabilisation, de nombreuses arm\u00e9es cr\u00e9ent une fonction de surveillance exerc\u00e9e par un m\u00e9diateur militaire. Cette personne, ext\u00e9rieure \u00e0 la cha\u00eene de commandement, est charg\u00e9e d\u2019enqu\u00eater sur des probl\u00e8mes institutionnels ou individuels survenant au sein des forces arm\u00e9es et de proposer des solutions. Des civils ou des soldats peuvent d\u00e9poser des plaintes aupr\u00e8s du m\u00e9diateur sans crainte de repr\u00e9sailles.<\/p>\n<p>En 2012, l\u2019Afrique du Sud a cr\u00e9\u00e9 le bureau du m\u00e9diateur pour les Forces de d\u00e9fense nationale sud-africaines (SANDF), lequel a trait\u00e9 500 plaintes dans ses deux premi\u00e8res ann\u00e9es de fonctionnement. \u00ab Mon bureau est un observateur critique ind\u00e9pendant et impartial demandant des comptes aux SANDF, d\u2019une mani\u00e8re tr\u00e8s semblable au r\u00f4le que jouent les m\u00e9dias aupr\u00e8s des gouvernements \u00bb, explique le m\u00e9diateur Temba Matanzima, un g\u00e9n\u00e9ral de corps d\u2019arm\u00e9e \u00e0 la retraite. \u00ab C\u2019est un tiers ind\u00e9pendant et impartial qui m\u00e8ne l\u2019enqu\u00eate d\u2019une mani\u00e8re \u00e9quitable et objective pour veiller \u00e0 la responsabilisation et \u00e0 la transparence des pouvoirs publics \u00bb.<\/p>\n<p>Le colonel \u00e0 la retraite \u00c9mile Ouedraogo, du Burkina Faso, un expert du professionnalisme militaire, observe que le meilleur type de surveillance est toujours celui d\u2019un commandant d\u2019unit\u00e9 envers ses troupes. Lorsque les commandants sont s\u00e9par\u00e9s par la distance ou ne supervisent pas \u00e9troitement leurs subordonn\u00e9s, cela m\u00e8ne \u00e0 un effondrement de la discipline. On appelle ce ph\u00e9nom\u00e8ne une \u00ab lacune dans la cha\u00eene de commandement \u00bb.<\/p>\n<p>\u00ab Une cha\u00eene de commandement fonctionnelle est une condition pr\u00e9alable \u00e0 toute institution militaire \u00bb, explique le colonel Ouedraogo. \u00ab Elle refl\u00e8te un bon exercice de l\u2019autorit\u00e9 et une bonne discipline, et elle favorise la responsabilisation \u00bb.<\/p>\n<p><b>PROMOTION BAS\u00c9E SUR LE M\u00c9RITE<\/b><br \/>\nAu sein de certaines arm\u00e9es, les crit\u00e8res d\u2019attribution des promotions font r\u00e9guli\u00e8rement l\u2019objet de plaintes, du fait que celle-ci peut \u00eatre fond\u00e9e sur des liens du sang et sur des alliances personnelles plut\u00f4t que sur le m\u00e9rite. Il y a de tr\u00e8s nombreux exemples, mais \u00c9mile Ouedraogo observe que plusieurs arm\u00e9es africaines de premier plan comptent en leur sein de nombreux membres d\u2019un seul groupe ethnique, ou d\u2019une seule religion ou affiliation r\u00e9gionale.<\/p>\n<p>\u00ab Les officiers plac\u00e9s sous une telle cha\u00eene de commandement sont plus loyaux \u00e0 l\u2019\u00e9gard du pr\u00e9sident que de la constitution \u00bb, pr\u00e9cise-t-il. \u00ab Cette pratique compromet les normes professionnelles des forces arm\u00e9es tout en les dressant les unes contre les autres en fonction de l\u2019ethnicit\u00e9 \u00bb.<\/p>\n<p>Toutefois, le probl\u00e8me ne se limite pas \u00e0 un parti pris ethnique. Dans de nombreuses arm\u00e9es du monde entier, la promotion est fond\u00e9e sur l\u2019anciennet\u00e9 plut\u00f4t que sur les accomplissements. Ceci \u00e9limine l\u2019incitation \u00e0 exceller et peut effectivement conduire certains officiers tr\u00e8s performants \u00e0 d\u00e9missionner par frustration de ne pas \u00eatre reconnus \u00e0 leur juste valeur.<\/p>\n<p>Les arm\u00e9es professionnelles ont tendance \u00e0 pr\u00e9coniser des directives claires pr\u00e9sentant les crit\u00e8res de promotion et les r\u00e8gles concernant les soldes, les plans de carri\u00e8re et les affectations de ressources, selon Natasha Ezrow et Erica Frantz, auteurs de l\u2019ouvrage <i>Failed States and Institutional Decay <\/i>(\u00c9tats en d\u00e9route et d\u00e9litement des institutions). Ces normes contribuent \u00e0 \u00e9tablir les liens de confiance entre les soldats eux-m\u00eames et entre les soldats et l\u2019institution militaire.<\/p>\n<p><b>DOCUMENTS \u00c9THIQUES\u00a0<\/b><br \/>\nLes arm\u00e9es professionnelles s\u2019appuient g\u00e9n\u00e9ralement sur un socle solide de th\u00e9orie \u00e9thique consacr\u00e9e par des documents pr\u00e9conisant aux soldats les meilleurs modes de comportement. \u00c0 titre d\u2019exemple, citons le Military Covenant (Engagement militaire) dans les Forces arm\u00e9es britanniques et le Innere Fuhrung (Auto-dirig\u00e9) en Allemagne. Pour les simples soldats, le g\u00e9n\u00e9ral Royal estime qu\u2019il est utile de disposer d\u2019un code d\u2019honneur facile \u00e0 se rappeler et pouvant faire la synth\u00e8se de messages plus complexes. Par exemple, le \u00ab Soldier\u2019s Creed \u00bb (Convictions du soldat) de l\u2019Arm\u00e9e am\u00e9ricaine ne comporte que 121 mots, mais il inclut des r\u00e9f\u00e9rences au professionnalisme et \u00e0 la loyaut\u00e9 \u00e0 l\u2019\u00e9gard du pays et des compagnons d\u2019armes. La r\u00e9p\u00e9tition de telles convictions peut renforcer l\u2019importance des valeurs fondamentales dans l\u2019esprit d\u2019un soldat.<\/p>\n<p>\u00ab Cette approche consistant \u00e0 inculquer des valeurs morales est souvent rituelle, mais aussi directement compr\u00e9hensible au plus bas \u00e9chelon, par des soldats qui, sur le terrain, sont confront\u00e9s \u00e0 la complexit\u00e9 de l\u2019action au combat \u00bb, explique Beno\u00eet Royal. Les convictions permettent \u00e0 une \u00ab organisation militaire de mettre en exergue ce qui est consid\u00e9r\u00e9 comme une \u00ab v\u00e9rit\u00e9 du terrain \u00bb essentielle \u00bb.<\/p>\n<p>De nombreuses arm\u00e9es, y compris les SANDF, font obligation aux officiers de signer un code de conduite dans lequel ils font serment de rejeter la corruption, de demeurer loyaux envers leur pays et d\u2019\u00e9viter r\u00e9solument de faire de la politique.<\/p>\n<p><b>UNE R\u00c9MUN\u00c9RATION \u00c9QUITABLE<\/b><br \/>\nCela peut para\u00eetre \u00e9vident, mais, pour les soldats, l\u2019une des principales incitations \u00e0 la corruption et au comportement non professionnel est l\u2019insuffisance de la solde et son versement irr\u00e9gulier. Les soldats qui ne peuvent pas subvenir \u00e0 leurs besoins avec leur solde ou qui constatent que les hauts grad\u00e9s s\u2019enrichissent sont davantage susceptibles de recourir \u00e0 des comportements non \u00e9thiques.<\/p>\n<p>Dan Henk, un chercheur dans le domaine militaire, qui a \u00e9tudi\u00e9 la Force de d\u00e9fense du Botswana (BDF), a not\u00e9 que les pratiques de r\u00e9mun\u00e9ration \u00e9quitable en vigueur au sein de la BDF incitent peu les soldats \u00e0 violer les r\u00e8gles. \u00ab Les membres du personnel de la BDF sont bien et r\u00e9guli\u00e8rement pay\u00e9s, ce qui assure aux officiers un niveau de vie de classe moyenne et un confort relatif dans les rangs subalternes \u00bb, explique Dan Henk. \u00ab Les membres du personnel de la BDF peuvent prendre leur retraite apr\u00e8s vingt ans de service en touchant une retraite raisonnable. La r\u00e9gularit\u00e9 et le caract\u00e8re ad\u00e9quat de la r\u00e9mun\u00e9ration r\u00e9duisent sensiblement l\u2019incitation au trafic d\u2019influence qui a s\u00e9vi dans de nombreuses autres arm\u00e9es africaines \u00bb.<\/p>\n<p><b>AUTORIT\u00c9 CIVILE<\/b><br \/>\nUne des caract\u00e9ristiques d\u2019une arm\u00e9e professionnelle est le refus de la politisation. En Afrique, la tradition de l\u2019ing\u00e9rence de l\u2019arm\u00e9e dans la politique est \u00e9tablie de longue date et est pr\u00e9judiciable. D\u2019apr\u00e8s \u00c9mile Ouedraogo, 65 pour cent des pays subsahariens ont v\u00e9cu un coup d\u2019\u00c9tat. Pire encore, une fois que le premier coup d\u2019\u00c9tat se produit, il y a de plus fortes chances qu\u2019il soit suivi par un deuxi\u00e8me voire un troisi\u00e8me coup d\u2019\u00c9tat.<\/p>\n<p>Non seulement les coups d\u2019\u00c9tat compromettent la gouvernance et le processus d\u00e9mocratique dans ces pays, mais ils sont \u00e9galement dommageables \u00e0 l\u2019\u00e9conomie. Les pays connaissant des coups d\u2019\u00c9tat militaires ont un taux de croissance du produit int\u00e9rieur brut (PIB) inf\u00e9rieur \u00e0 celui des autres pays. Par exemple, la Guin\u00e9e, le Mali, la Mauritanie et le Nigeria ont chacun vu leur PIB r\u00e9el diminuer de 4,5 pour cent ou davantage \u00e0 la suite de coups d\u2019\u00c9tat.<\/p>\n<p>\u00ab La gouvernance sous la direction de l\u2019arm\u00e9e a de fortes chances d\u2019\u00eatre ruineuse pour l\u2019\u00e9conomie d\u2019un pays \u00bb, observe \u00c9mile Ouedraogo. \u00ab L\u2019instabilit\u00e9 dissuade les investisseurs et nuit au d\u00e9veloppement. Au contraire, les \u00c9tats non riches en ressources qui ont atteint les plus hauts niveaux de croissance durable sont presque uniform\u00e9ment ceux qui n\u2019ont connu que peu de coups d\u2019\u00c9tat voire aucun \u00bb.<\/p>\n<p>Le politologue Samuel Huntington a \u00e9crit que le professionnalisme est le facteur principal emp\u00eachant l\u2019arm\u00e9e d\u2019intervenir dans la politique. Dans son ouvrage <i>The Soldier<\/i> <i>and the State<\/i> (Le soldat et l\u2019\u00c9tat), il fait valoir qu\u2019une arm\u00e9e fonctionnant bien doit \u00eatre autoris\u00e9e \u00e0 d\u00e9velopper une expertise exempte d\u2019ing\u00e9rences ext\u00e9rieures ou de consid\u00e9rations politiques. D\u2019apr\u00e8s lui, ceci entra\u00eenera une plus grande autonomie, une soumission plus nette au pouvoir civil et un professionnalisme affirm\u00e9.<\/p>\n<p>Abel Esterhuyse estime qu\u2019une force combattante professionnelle ne devrait jamais s\u2019impliquer dans la politique, quelle que soit la tentation de le faire. \u00ab Les forces arm\u00e9es sont souvent consid\u00e9r\u00e9es, et se consid\u00e8rent elles-m\u00eames, comme \u00e9tant au-dessus de la politique \u2014 apolitiques de nature \u2014 \u00e9tant donn\u00e9 qu\u2019elles sont le d\u00e9positaire de l\u2019int\u00e9r\u00eat national \u00bb, note-t-il. \u00ab Elles garantissent la s\u00e9curit\u00e9 et l\u2019int\u00e9grit\u00e9 de l\u2019\u00c9tat, pas celles du gouvernement du moment \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00c9DIFICATION D\u2019UNE CULTURE MILITAIRE QUI FA\u00c7ONNE DES DIRIGEANTS \u00c9THIQUES \u00c0 l\u2019occasion d\u2019un discours de remise de dipl\u00f4me aux \u00e9l\u00e8ves de l\u2019\u00c9cole de l\u2019arm\u00e9e de l\u2019air, Nosiviwe Mapisa-Nqakula, la ministre sud-africaine de la D\u00e9fense, a rappel\u00e9 aux jeunes dipl\u00f4m\u00e9s qu\u2019ils \u00e9taient sur le point d\u2019entamer une carri\u00e8re \u00e0 nulle autre pareille. \u00ab Vous avez r\u00e9pondu \u00e0<\/p>\n","protected":false},"author":1,"featured_media":4964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[],"class_list":{"0":"post-5328","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articles"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Profession des Armes - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Profession des Armes - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00c9DIFICATION D\u2019UNE CULTURE MILITAIRE QUI FA\u00c7ONNE DES DIRIGEANTS \u00c9THIQUES \u00c0 l\u2019occasion d\u2019un discours de remise de dipl\u00f4me aux \u00e9l\u00e8ves de l\u2019\u00c9cole de l\u2019arm\u00e9e de l\u2019air, Nosiviwe Mapisa-Nqakula, la ministre sud-africaine de la D\u00e9fense, a rappel\u00e9 aux jeunes dipl\u00f4m\u00e9s qu\u2019ils \u00e9taient sur le point d\u2019entamer une carri\u00e8re \u00e0 nulle autre pareille. \u00ab Vous avez r\u00e9pondu \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-21T16:45:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-20T17:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"La Profession des Armes\",\"datePublished\":\"2015-12-21T16:45:36+00:00\",\"dateModified\":\"2016-01-20T17:50:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/\"},\"wordCount\":3017,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/RTR4HR8I.jpg\",\"articleSection\":[\"articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/\",\"name\":\"La Profession des Armes - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/RTR4HR8I.jpg\",\"datePublished\":\"2015-12-21T16:45:36+00:00\",\"dateModified\":\"2016-01-20T17:50:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/RTR4HR8I.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/RTR4HR8I.jpg\",\"width\":1080,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2015\\\/12\\\/the-profession-of-arms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Profession des Armes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Profession des Armes - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/","og_locale":"fr_FR","og_type":"article","og_title":"La Profession des Armes - Africa Defense Forum","og_description":"L\u2019\u00c9DIFICATION D\u2019UNE CULTURE MILITAIRE QUI FA\u00c7ONNE DES DIRIGEANTS \u00c9THIQUES \u00c0 l\u2019occasion d\u2019un discours de remise de dipl\u00f4me aux \u00e9l\u00e8ves de l\u2019\u00c9cole de l\u2019arm\u00e9e de l\u2019air, Nosiviwe Mapisa-Nqakula, la ministre sud-africaine de la D\u00e9fense, a rappel\u00e9 aux jeunes dipl\u00f4m\u00e9s qu\u2019ils \u00e9taient sur le point d\u2019entamer une carri\u00e8re \u00e0 nulle autre pareille. \u00ab Vous avez r\u00e9pondu \u00e0","og_url":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2015-12-21T16:45:36+00:00","article_modified_time":"2016-01-20T17:50:47+00:00","og_image":[{"width":1080,"height":776,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"La Profession des Armes","datePublished":"2015-12-21T16:45:36+00:00","dateModified":"2016-01-20T17:50:47+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/"},"wordCount":3017,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg","articleSection":["articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/","url":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/","name":"La Profession des Armes - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg","datePublished":"2015-12-21T16:45:36+00:00","dateModified":"2016-01-20T17:50:47+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2015\/12\/RTR4HR8I.jpg","width":1080,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2015\/12\/the-profession-of-arms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"La Profession des Armes"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/5328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/5328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/4964"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=5328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}