{"id":1816,"date":"2014-09-05T18:37:50","date_gmt":"2014-09-05T18:37:50","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=1816"},"modified":"2014-09-30T19:24:42","modified_gmt":"2014-09-30T19:24:42","slug":"la-lumiere-du-continent-ne-faiblira-pas","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2014\/09\/la-lumiere-du-continent-ne-faiblira-pas\/","title":{"rendered":"La Lumi\u00e8re Du Continent Ne Faiblira Pas"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-1323 size-medium\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/181919871-300x195.jpg\" alt=\"181919871\" width=\"300\" height=\"195\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/181919871-300x195.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/181919871.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p><em><strong>Le pr\u00e9sident ghan\u00e9en John Dramani Mahama s\u2019est adress\u00e9 \u00e0 la 68e Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, le 26 septembre 2013, \u00e0 New York, quelques jours apr\u00e8s l\u2019attaque terroriste du centre commercial Westgate \u00e0 Nairobi, au Kenya. Voici une version abr\u00e9g\u00e9e de ses propos.<\/strong><\/em><\/p>\n<p class=\"p1\"><span class=\"s1\">A<\/span>vant de quitter le Ghana pour me rendre \u00e0 cette assembl\u00e9e, j\u2019ai appris la nouvelle de l\u2019attentat terroriste qui a eu lieu \u00e0 Nairobi, au Kenya. J\u2019ai \u00e9t\u00e9 choqu\u00e9 et profond\u00e9ment attrist\u00e9 par la perte des nombreuses vies due \u00e0 ces actes insens\u00e9s de violence et de l\u00e2chet\u00e9.<\/p>\n<p class=\"p3\">Alors que le nombre des victimes augmentait, ma tristesse n\u2019en devenait que plus grande, sachant que chaque chiffre suppl\u00e9mentaire repr\u00e9sentait une autre vie humaine. Ces chiffres symbolisaient des personnes que ni vous ni moi ne connaissions, mais qui avaient une importance primordiale pour ceux qui les aimaient, c\u2019est-\u00e0-dire leurs parents, leurs enfants, leur mari, leur femme, leur amis ou encore leurs coll\u00e8gues.<\/p>\n<p class=\"p3\"><span class=\"s2\">Au moment de l\u2019ind\u00e9pendance, alors que nos possibilit\u00e9s nous semblaient infinies, le monde a pu voir \u00e0 quel point l\u2019Afrique pouvait rayonner. Ensuite, pendant des d\u00e9cennies, la lumi\u00e8re s\u2019est affaiblie. Il y a eu une \u00e9poque o\u00f9, en Afrique, les meurtres \u00e9taient presque monnaie courante. Aujourd\u2019hui encore, beaucoup de tombes sont rest\u00e9es anonymes. Il y a eu un temps o\u00f9 la cruaut\u00e9 des dictateurs semblait \u00eatre \u00e0 l\u2019ordre du jour. Pendant des d\u00e9cennies, la corruption, la cupidit\u00e9 et la d\u00e9pravation de certains ont fait souffrir tout un continent.<\/span><\/p>\n<p class=\"p3\">Nous aurions pu facilement succomber aux guerres, \u00e0 la pauvret\u00e9 et aux maladies. Or, nous avons tenu bon. Nous avons poursuivi notre chemin tant bien que mal, et nous avons finalement r\u00e9ussi. Nous avons surv\u00e9cu.<\/p>\n<p class=\"p3\">Il n\u2019y a plus de place aujourd\u2019hui pour la haine, l\u2019intol\u00e9rance et le meurtre d\u2019innocents en Afrique. Nous ne voulons plus jamais vivre \u00e7a. Alors, nous pleurerons nos morts, et nous nous consolerons mutuellement. Cependant, nous ne pouvons pas nous laisser vaincre par la terreur. C\u2019est ce qui doit affermir notre d\u00e9termination.<\/p>\n<p class=\"p3\"><span class=\"s1\">Le Ghana a toujours assur\u00e9 ses voisins de sa coop\u00e9ration, pour maintenir la s\u00e9curit\u00e9 des pays connaissant la stabilit\u00e9 et pour restaurer la s\u00e9curit\u00e9 dans ceux qui sont r\u00e9cemment sortis du chaos, comme la C\u00f4te d\u2019Ivoire et le Mali. \u00a0<\/span><\/p>\n<p class=\"p3\">Nous voulons faire savoir comment le monde est devenu un village global, en particulier au niveau des technologies, de la culture et des voyages. Or, ce village global est aussi \u00e0 la port\u00e9e des chefs de guerre et des groupes terroristes. Ils s\u2019en servent pour recruter de nouveaux membres, \u00e9tendre leurs cellules, cr\u00e9er des r\u00e9seaux intercontinentaux et acqu\u00e9rir des armes, tout en dissimulant leur identit\u00e9 et l\u2019endroit o\u00f9 ils se trouvent.<\/p>\n<p class=\"p3\">Nous devons riposter, et surtout coop\u00e9rer. Les pays du monde industrialis\u00e9 doivent s\u2019aligner sur les pays du monde en d\u00e9veloppement. Nous devons former des partenariats et travailler ensemble.<\/p>\n<p class=\"p3\">Les jeunes d\u00e9mocraties sont g\u00e9n\u00e9ralement fragiles ; leurs limites sont encore mises \u00e0 l\u2019\u00e9preuve et leurs caract\u00e9ristiques sont encore \u00e0 d\u00e9finir. La d\u00e9mocratie n\u2019est pas une entreprise \u00e0 taille unique ni un \u00e9v\u00e9nement ponctuel. C\u2019est un syst\u00e8me dont la construction dure des ann\u00e9es et un processus qui vous pousse vers une perfection inatteignable \u00e0 laquelle vous devez n\u00e9anmoins aspirer.<\/p>\n<p class=\"p3\">Le but de notre r\u00e9union aujourd\u2019hui est de trouver des voies et des moyens de cr\u00e9er un monde meilleur, plus pacifique et prosp\u00e8re.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident ghan\u00e9en John Dramani Mahama s\u2019est adress\u00e9 \u00e0 la 68e Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, le 26 septembre 2013, \u00e0 New York, quelques jours apr\u00e8s l\u2019attaque terroriste du centre commercial Westgate \u00e0 Nairobi, au Kenya. Voici une version abr\u00e9g\u00e9e de ses propos. Avant de quitter le Ghana pour me rendre \u00e0 cette assembl\u00e9e, j\u2019ai<\/p>\n","protected":false},"author":1,"featured_media":1332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[70,40],"tags":[],"class_list":{"0":"post-1816","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-perspective-africaine","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident ghan\u00e9en John Dramani Mahama s\u2019est adress\u00e9 \u00e0 la 68e Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, le 26 septembre 2013, \u00e0 New York, quelques jours apr\u00e8s l\u2019attaque terroriste du centre commercial Westgate \u00e0 Nairobi, au Kenya. Voici une version abr\u00e9g\u00e9e de ses propos. Avant de quitter le Ghana pour me rendre \u00e0 cette assembl\u00e9e, j\u2019ai\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-05T18:37:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-09-30T19:24:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1401\" \/>\n\t<meta property=\"og:image:height\" content=\"889\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"La Lumi\u00e8re Du Continent Ne Faiblira Pas\",\"datePublished\":\"2014-09-05T18:37:50+00:00\",\"dateModified\":\"2014-09-30T19:24:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/\"},\"wordCount\":615,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/AP740208253425.jpg\",\"articleSection\":[\"Perspective africaine\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/\",\"name\":\"La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/AP740208253425.jpg\",\"datePublished\":\"2014-09-05T18:37:50+00:00\",\"dateModified\":\"2014-09-30T19:24:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/AP740208253425.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/AP740208253425.jpg\",\"width\":1401,\"height\":889},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2014\\\/09\\\/continents-light-will-not-be-dimmed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Lumi\u00e8re Du Continent Ne Faiblira Pas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/","og_locale":"fr_FR","og_type":"article","og_title":"La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum","og_description":"Le pr\u00e9sident ghan\u00e9en John Dramani Mahama s\u2019est adress\u00e9 \u00e0 la 68e Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, le 26 septembre 2013, \u00e0 New York, quelques jours apr\u00e8s l\u2019attaque terroriste du centre commercial Westgate \u00e0 Nairobi, au Kenya. Voici une version abr\u00e9g\u00e9e de ses propos. Avant de quitter le Ghana pour me rendre \u00e0 cette assembl\u00e9e, j\u2019ai","og_url":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2014-09-05T18:37:50+00:00","article_modified_time":"2014-09-30T19:24:42+00:00","og_image":[{"width":1401,"height":889,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"La Lumi\u00e8re Du Continent Ne Faiblira Pas","datePublished":"2014-09-05T18:37:50+00:00","dateModified":"2014-09-30T19:24:42+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/"},"wordCount":615,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg","articleSection":["Perspective africaine","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/","url":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/","name":"La Lumi\u00e8re Du Continent Ne Faiblira Pas - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg","datePublished":"2014-09-05T18:37:50+00:00","dateModified":"2014-09-30T19:24:42+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2014\/08\/AP740208253425.jpg","width":1401,"height":889},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2014\/09\/continents-light-will-not-be-dimmed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"La Lumi\u00e8re Du Continent Ne Faiblira Pas"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/1816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=1816"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/1816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/1332"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=1816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=1816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=1816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}