{"id":132671,"date":"2025-11-25T11:59:00","date_gmt":"2025-11-25T16:59:00","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=132671"},"modified":"2025-11-25T11:59:00","modified_gmt":"2025-11-25T16:59:00","slug":"la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/","title":{"rendered":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre"},"content":{"rendered":"<p>Apr\u00e8s un si\u00e8ge de 18\u00a0mois, le groupe paramilitaire des Forces de soutien rapide (FSR) a fini par vaincre les troupes gouvernementales soudanaises \u00e0 El Fasher, en prenant le contr\u00f4le de la derni\u00e8re enclave militaire au Darfour et provoquant la mort, la famine et les d\u00e9placements.<\/p>\n<p>El Fasher, qui avait auparavant plus d\u2019un million d\u2019habitants, est tomb\u00e9e entre les mains des FSR le 26 octobre 2025. L\u2019Organisation internationale pour les migrations estime que plus de 70.000\u00a0personnes ont quitt\u00e9 la ville depuis la conqu\u00eate par les FSR. Toutefois, un camp pour personnes d\u00e9plac\u00e9es \u00e0 Tawila, \u00e0 environ 70\u00a0km \u00e0 l\u2019Ouest d\u2019El Fasher, a re\u00e7u beaucoup moins de gens que le nombre qui \u00e9tait anticip\u00e9, selon Al Jazeera.<\/p>\n<p>Le laboratoire de recherche humanitaire de l\u2019universit\u00e9 de Yale a examin\u00e9 les images satellitaires depuis la capture de la ville et not\u00e9 31 sites au moins qui sembleraient contenir des cadavres. Lorsque les FSR ont attaqu\u00e9 le camp pour personnes d\u00e9plac\u00e9es de Zamzam en avril, les 500.000\u00a0r\u00e9sidents se sont enfuis \u00e0 pied ou sur des charrettes tir\u00e9es par des \u00e2nes.<\/p>\n<p>Un tel exode n\u2019a pas \u00e9t\u00e9 constat\u00e9 apr\u00e8s la chute d\u2019El Fasher, selon Al Jazeera. Les chercheurs de Yale en ont conclu que \u00ab\u00a0la majorit\u00e9 des civils sont morts ou captur\u00e9s, ou bien ils se cachent\u00a0\u00bb. La pr\u00e9sidente du Comit\u00e9 international de la Croix-Rouge Mirjana Spoljaric a dit au service de presse que des dizaines de milliers de personnes pourraient \u00eatre prises au pi\u00e8ge sans nourriture, sans eau et sans soins de sant\u00e9.<\/p>\n<p>Fatima Yahya qui a r\u00e9ussi \u00e0 venir au camp de Tawila d\u00e9clare \u00e0 Al Jazeera\u00a0: \u00ab\u00a0Les morts \u00e9taient partout\u00a0: dans les rues, \u00e0 l\u2019int\u00e9rieur des maisons, sur le perron d\u2019un grand nombre de maisons. O\u00f9 que vous alliez \u00e0 El Fasher, vous verrez des cadavres \u00e9parpill\u00e9s.\u00a0\u00bb<\/p>\n<p>Les conditions au camp de Tawila sont \u00e9galement effroyables. Plus de 650.000\u00a0personnes y vivent et les ressources sont insuffisantes pour satisfaire aux besoins de tous. Certains abris de fortune sont seulement drap\u00e9s de v\u00eatements. Les tentes d\u2019abri des Nations unies sont en quantit\u00e9 limit\u00e9e.<\/p>\n<p>\u00ab\u00a0Nous n\u00e9cessitons de l\u2019eau de toute urgence\u00a0; c\u2019est la chose la plus importante en ce moment\u00a0\u00bb, a d\u00e9clar\u00e9 Sohaiba Omar, femme d\u00e9plac\u00e9e provenant d\u2019El Fasher, \u00e0 Africanews par l\u2019interm\u00e9diaire d\u2019un interpr\u00e8te.<\/p>\n<p>Les rapports qui ont accompagn\u00e9 la capture d\u2019El Fasher par les FSR mentionnent des atrocit\u00e9s telles que le pillage, les assassinats et la violence sexuelle. Aujourd\u2019hui, alors que les FSR contr\u00f4lent fermement l\u2019Ouest du pays, les combats se tournent vers l\u2019Est dans la r\u00e9gion du Kordofan du Sud, \u00c9tat p\u00e9trolier principalement contr\u00f4l\u00e9 par les Forces arm\u00e9es soudanaises (FAS).<\/p>\n<p>Le 6 novembre, les attaques des FSR contre un h\u00f4pital de Dilling ont fait cinq morts et cinq bless\u00e9s, selon les rapports publi\u00e9s. Ces attaques font craindre que d\u2019autres atrocit\u00e9s ne suivent, dans une guerre civile qui dure depuis deux ans et s\u2019accompagne de d\u00e9sespoir et d\u2019effusion de sang.<\/p>\n<p>Les combattants des FSR, dirig\u00e9s par un g\u00e9n\u00e9ral connu sous le nom de Hemeti, se battent depuis avril 2023 contre les FAS conduites par le g\u00e9n\u00e9ral Abdel Fattah al-Burhan, dans ce qui est devenu la pire crise humanitaire du monde. Certaines estimations indiquent 150.000\u00a0morts et 12\u00a0millions forc\u00e9s de partir de chez eux.<\/p>\n<p>Les efforts internationaux visant \u00e0 mettre fin aux combats ont capot\u00e9. L\u2019Arabie saoudite, l\u2019\u00c9gypte, les \u00c9mirats arabes unis et les \u00c9tats-Unis (le groupe appel\u00e9 le \u00ab\u00a0quad\u00a0\u00bb) ont propos\u00e9 un plan de paix qui fait appel \u00e0 une tr\u00eave humanitaire de trois mois suivie par un cessez-le-feu permanent. Ensuite, un gouvernement dirig\u00e9 par les civils serait form\u00e9 durant une p\u00e9riode de transition de neuf mois.<\/p>\n<p>Les repr\u00e9sentants du quad se sont r\u00e9unis s\u00e9par\u00e9ment avec les bellig\u00e9rants \u00e0 Washington, D.C., le 24 octobre, deux jours avant la chute d\u2019El Fasher, pour promouvoir le plan de paix. Le 6 novembre, les FSR ont signal\u00e9 leur soutien \u00e0 la tr\u00eave humanitaire mais les FAS ont \u00e9tabli des conditions auxquelles les FSR ne satisferont probablement pas, par exemple pour qu\u2019elles se retirent des villes qu\u2019elles occupent ou qu\u2019elles d\u00e9posent les armes.<\/p>\n<p>Lors d\u2019une conf\u00e9rence de presse le 7 novembre, Osman Abufatima Adam Mohammed, ambassadeur du Soudan en Afrique du Sud, a d\u00e9clar\u00e9 qu\u2019il \u00e9tait trop t\u00f4t pour que le gouvernement accepte le plan de paix. \u00ab\u00a0Notre exp\u00e9rience indique que nous avions eu de nombreuses tr\u00eaves au d\u00e9but de la guerre, mais \u00e0 chaque fois elles n\u2019\u00e9taient pas respect\u00e9es [par les FSR], a-t-il dit selon la BBC. Ils utilisent ces tr\u00eaves pour avancer dans de nouvelles zones et agir contre le gouvernement.\u00a0\u00bb<\/p>\n<p>Un jour apr\u00e8s avoir accept\u00e9 la tr\u00eave, les FSR ont attaqu\u00e9 la capitale de Khartoum avec des drones. Les r\u00e9sidents disent \u00e0 la BBC que des explosifs semblent avoir \u00e9clat\u00e9 pr\u00e8s d\u2019une base militaire et d\u2019une centrale \u00e9lectrique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un si\u00e8ge de 18\u00a0mois, le groupe paramilitaire des Forces de soutien rapide (FSR) a fini par vaincre les troupes gouvernementales soudanaises \u00e0 El Fasher, en prenant le contr\u00f4le de la derni\u00e8re enclave militaire au Darfour et provoquant la mort, la famine et les d\u00e9placements. El Fasher, qui avait auparavant plus d\u2019un million d\u2019habitants, est<\/p>\n","protected":false},"author":1,"featured_media":132646,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[1295,1181,485,1627],"class_list":{"0":"post-132671","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-civil-war-fr","9":"tag-sudan-fr","10":"tag-tchad","11":"tag-tchad-fr"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s un si\u00e8ge de 18\u00a0mois, le groupe paramilitaire des Forces de soutien rapide (FSR) a fini par vaincre les troupes gouvernementales soudanaises \u00e0 El Fasher, en prenant le contr\u00f4le de la derni\u00e8re enclave militaire au Darfour et provoquant la mort, la famine et les d\u00e9placements. El Fasher, qui avait auparavant plus d\u2019un million d\u2019habitants, est\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T16:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre\",\"datePublished\":\"2025-11-25T16:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/\"},\"wordCount\":879,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GettyImages-2245595257.jpg\",\"keywords\":[\"civil war\",\"Sudan\",\"Tchad\",\"Tchad\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/\",\"name\":\"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GettyImages-2245595257.jpg\",\"datePublished\":\"2025-11-25T16:59:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GettyImages-2245595257.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GettyImages-2245595257.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Des r\u00e9fugi\u00e9s soudanais remplissent des conteneurs d\u2019eau dans le camp de transit de Tine au Tchad, \u00e0 plus de 300 km d\u2019El Fasher (Soudan), le 10 novembre 2025. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2025\\\/11\\\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/","og_locale":"fr_FR","og_type":"article","og_title":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum","og_description":"Apr\u00e8s un si\u00e8ge de 18\u00a0mois, le groupe paramilitaire des Forces de soutien rapide (FSR) a fini par vaincre les troupes gouvernementales soudanaises \u00e0 El Fasher, en prenant le contr\u00f4le de la derni\u00e8re enclave militaire au Darfour et provoquant la mort, la famine et les d\u00e9placements. El Fasher, qui avait auparavant plus d\u2019un million d\u2019habitants, est","og_url":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-11-25T16:59:00+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre","datePublished":"2025-11-25T16:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/"},"wordCount":879,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg","keywords":["civil war","Sudan","Tchad","Tchad"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/","url":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/","name":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg","datePublished":"2025-11-25T16:59:00+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/11\/GettyImages-2245595257.jpg","width":1024,"height":683,"caption":"Des r\u00e9fugi\u00e9s soudanais remplissent des conteneurs d\u2019eau dans le camp de transit de Tine au Tchad, \u00e0 plus de 300 km d\u2019El Fasher (Soudan), le 10 novembre 2025. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2025\/11\/la-chute-del-fasher-aggrave-le-desespoir-et-revele-des-crimes-de-guerre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"La chute d\u2019El Fasher aggrave le d\u00e9sespoir et r\u00e9v\u00e8le des crimes de guerre"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/132671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=132671"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/132671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/132646"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=132671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=132671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=132671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}