{"id":131351,"date":"2025-10-21T14:33:09","date_gmt":"2025-10-21T18:33:09","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=131351"},"modified":"2025-10-21T14:33:28","modified_gmt":"2025-10-21T18:33:28","slug":"les-attaques-dans-le-bassin-du-lac-tchad-montrent-que-boko-haram-est-a-nouveau-en-expansion","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2025\/10\/les-attaques-dans-le-bassin-du-lac-tchad-montrent-que-boko-haram-est-a-nouveau-en-expansion\/","title":{"rendered":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion"},"content":{"rendered":"<p style=\"font-weight: 400;\">En ao\u00fbt dernier, les autorit\u00e9s du Niger ont affirm\u00e9 avoir tu\u00e9 Bakura Doro, chef de Boko Haram, dans une frappe de drone contre son quartier g\u00e9n\u00e9ral, situ\u00e9 dans une \u00eele du lac Tchad. Boko Haram a rejet\u00e9 l\u2019affirmation du Niger.<\/p>\n<p style=\"font-weight: 400;\">L\u2019attaque du quartier g\u00e9n\u00e9ral de M.\u00a0Doro s\u2019est produite au moment o\u00f9 le plus ancien groupe terroriste du Nigeria semble r\u00e9appara\u00eetre apr\u00e8s plusieurs ann\u00e9es de d\u00e9clin, \u00e0 la suite d\u2019affrontements territoriaux avec sa rivale r\u00e9gionale, la Province d\u2019Afrique de l\u2019Ouest de l\u2019\u00c9tat islamique (PAOEI). Ces combats avaient r\u00e9duit consid\u00e9rablement la pr\u00e9sence de Boko Haram dans la r\u00e9gion. Mais au cours des derniers mois, les terroristes de Boko Haram ont conduit des attaques meurtri\u00e8res contre des localit\u00e9s du Nord-Est du Nigeria et de l\u2019extr\u00eame Nord du Cameroun. L\u2019analyste Michael Nwankpa du Hudson Institute d\u00e9signe la pr\u00e9sence renouvel\u00e9e de Boko Haram comme \u00ab\u00a0Boko Haram 2.0\u00a0\u00bb.<\/p>\n<p style=\"font-weight: 400;\">En mai, les combattants de Boko Haram ont tu\u00e9 100\u00a0personnes dans deux localit\u00e9s de l\u2019\u00c9tat nig\u00e9rian de Borno, parce qu\u2019ils disaient qu\u2019elles avaient pris parti pour la PAOEI. En ao\u00fbt, les combattants de Boko Haram ont enlev\u00e9 50\u00a0passagers d\u2019un autobus camerounais voyageant dans le Diamar\u00e9, un d\u00e9partement de la r\u00e9gion de l\u2019Extr\u00eame-Nord. Les passagers ont \u00e9t\u00e9 d\u00e9tenus contre ran\u00e7on et finalement lib\u00e9r\u00e9s. Quelques semaines plus tard au d\u00e9but septembre, Boko Haram a tu\u00e9 60\u00a0personnes dans le village nig\u00e9rian de Darul Jamal, \u00c9tat de Borno. Les r\u00e9sidents ont d\u00e9clar\u00e9 aux chercheurs de l\u2019Institut pour les \u00e9tudes de s\u00e9curit\u00e9 que les tueurs soup\u00e7onnaient que leurs victimes fournissaient des informations \u00e0 l\u2019arm\u00e9e nig\u00e9riane.<\/p>\n<p style=\"font-weight: 400;\">Les experts signalent que la r\u00e9cente campagne des forces nig\u00e9rianes contre Boko Haram a chass\u00e9 les terroristes de l\u2019autre c\u00f4t\u00e9 de la fronti\u00e8re poreuse avec le Cameroun\u00a0; le nombre d\u2019attaques dans les localit\u00e9s de Mayo-Moskota et Kolofata, r\u00e9gion de l\u2019Extr\u00eame-Nord, est en hausse. Une \u00e9valuation r\u00e9cente par Silving Bo\u2019es Guistei, chercheur de l\u2019institut, a recens\u00e9 dans la r\u00e9gion en septembre 54\u00a0attaques terroristes attribu\u00e9es \u00e0 Boko Haram, sur un total de 95.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0La situation s\u00e9curitaire dans l\u2019Extr\u00eame-Nord du Cameroun est toujours pr\u00e9occupante\u00a0\u00bb, \u00e9crit-il dans un article sur LinkedIn accompagnant son rapport.<\/p>\n<p style=\"font-weight: 400;\">L\u2019analyste Saheed Babajide Owonikoko du Centre pour les \u00e9tudes de paix et de s\u00e9curit\u00e9 \u00e0 l\u2019universit\u00e9 de technologie Modibbo Adama du Nigeria, a \u00e9crit r\u00e9cemment dans The Conversation que le retour au premier plan de Boko Haram \u00e9tait d\u00fb selon lui \u00e0 plusieurs facteurs, notamment la focalisation intense des agences de contre-terrorisme sur la PAOEI dominante.<\/p>\n<p style=\"font-weight: 400;\">Le profil bas de M.\u00a0Doro en tant que chef de Boko Haram apr\u00e8s la mort d\u2019Abubakar Shekau a aussi aid\u00e9 \u00e0 r\u00e9tablir silencieusement Boko Haram autour du bassin du lac Tchad, \u00e9crit-il. M.\u00a0Doro \u00e9tait le chef de Boko Haram dans la r\u00e9gion du lac avant de prendre le contr\u00f4le de l\u2019organisation au sens large en 2022.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Il a aussi \u00e9vit\u00e9 la propagande des m\u00e9dias, ce qui a fait d\u00e9tourner de Boko Haram l\u2019attention du public et a permis au groupe de se d\u00e9velopper sans \u00eatre remarqu\u00e9\u00a0\u00bb, \u00e9crit-il.<\/p>\n<p style=\"font-weight: 400;\">Les quatre pays riverains du lac (Cameroun, Niger, Nigeria, Tchad) ont cr\u00e9\u00e9 la Force multinationale mixte (FMM) pour combattre le terrorisme dans la r\u00e9gion. Le B\u00e9nin fait aussi partie de la FMM bien qu\u2019il ne soit pas en bordure du lac.<\/p>\n<p style=\"font-weight: 400;\">La FMM a \u00e9t\u00e9 affaiblie lorsque le Tchad a retir\u00e9 ses troupes en janvier, en r\u00e9ponse \u00e0 une attaque meurtri\u00e8re de Boko Haram contre ses soldats dans l\u2019\u00eele de Barkaram en 2024. La junte nig\u00e9rienne au pouvoir s\u2019en est retir\u00e9e en avril. Les relations entre le Cameroun et le Nigeria sont tendues \u00e0 cause de la violence qui se propage \u00e0 travers leur fronti\u00e8re commune.<\/p>\n<p style=\"font-weight: 400;\">Les experts craignent que le regain d\u2019importance de Boko Haram n\u2019attire quelques-uns des combattants qui avaient pr\u00e9c\u00e9demment accept\u00e9 une amnistie et particip\u00e9 \u00e0 des programmes de r\u00e9int\u00e9grations organis\u00e9s par le gouvernement f\u00e9d\u00e9ral du Nigeria et le gouvernement de l\u2019\u00c9tat de Borno. Certains de ces ex-combattants ont \u00e9t\u00e9 recrut\u00e9s pour se battre contre leurs anciens coll\u00e8gues de Boko Haram au nom du gouvernement.<\/p>\n<p style=\"font-weight: 400;\">Vaincre Boko Haram exigera que les gouvernements r\u00e9gionaux r\u00e9\u00e9valuent leur approche en affrontant les conditions sous-jacentes du terrorisme, notamment le manque d\u2019autorit\u00e9 d\u2019\u00e9tat ou locale et le manque d\u2019investissements \u00e9conomiques, selon le Dr\u00a0Nwankpa.<\/p>\n<p style=\"font-weight: 400;\">Dans de nombreuses r\u00e9gions du bassin du Tchad, les groupes terroristes assument les responsabilit\u00e9s administratives habituelles d\u2019un gouvernement, \u00e9crit-il.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Boko Haram et ses factions prosp\u00e8rent dans ces conditions. Le gouvernement peut acc\u00e9l\u00e9rer la chute de Boko Haram en lui refusant un soutien populaire, en particulier en am\u00e9liorant les conditions environnementales et mat\u00e9rielles des r\u00e9sidents tout en assurant aussi la s\u00e9curit\u00e9, effort qui n\u00e9cessitera un r\u00f4le militaire dans un avenir proche.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ao\u00fbt dernier, les autorit\u00e9s du Niger ont affirm\u00e9 avoir tu\u00e9 Bakura Doro, chef de Boko Haram, dans une frappe de drone contre son quartier g\u00e9n\u00e9ral, situ\u00e9 dans une \u00eele du lac Tchad. Boko Haram a rejet\u00e9 l\u2019affirmation du Niger. L\u2019attaque du quartier g\u00e9n\u00e9ral de M.\u00a0Doro s\u2019est produite au moment o\u00f9 le plus ancien groupe<\/p>\n","protected":false},"author":1,"featured_media":131346,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[1220,426,993,1310,488,435,1256,485],"class_list":{"0":"post-131351","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-boko-haram-fr","9":"tag-cameroun","10":"tag-lac-tchad","11":"tag-mnjtf-fr","12":"tag-niger-fr","13":"tag-nigeria-fr","14":"tag-paoei","15":"tag-tchad"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/ar\/?p=131353\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"En ao\u00fbt dernier, les autorit\u00e9s du Niger ont affirm\u00e9 avoir tu\u00e9 Bakura Doro, chef de Boko Haram, dans une frappe de drone contre son quartier g\u00e9n\u00e9ral, situ\u00e9 dans une \u00eele du lac Tchad. Boko Haram a rejet\u00e9 l\u2019affirmation du Niger. L\u2019attaque du quartier g\u00e9n\u00e9ral de M.\u00a0Doro s\u2019est produite au moment o\u00f9 le plus ancien groupe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/ar\/?p=131353\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T18:33:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T18:33:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion\",\"datePublished\":\"2025-10-21T18:33:09+00:00\",\"dateModified\":\"2025-10-21T18:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353\"},\"wordCount\":890,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GettyImages-1258291745.jpg\",\"keywords\":[\"Boko Haram\",\"Cameroun\",\"Lac Tchad\",\"MNJTF\",\"Niger\",\"Nigeria\",\"PAOEI\",\"Tchad\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353\",\"name\":\"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GettyImages-1258291745.jpg\",\"datePublished\":\"2025-10-21T18:33:09+00:00\",\"dateModified\":\"2025-10-21T18:33:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GettyImages-1258291745.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GettyImages-1258291745.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Un regain de violence de Boko Haram dans le bassin du lac Tchad fait craindre que le groupe terroriste n\u2019attire certains des ex-combattants qui l\u2019avaient quitt\u00e9 il y a quelques ann\u00e9es. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/ar\\\/?p=131353#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/ar\/?p=131353","og_locale":"fr_FR","og_type":"article","og_title":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum","og_description":"En ao\u00fbt dernier, les autorit\u00e9s du Niger ont affirm\u00e9 avoir tu\u00e9 Bakura Doro, chef de Boko Haram, dans une frappe de drone contre son quartier g\u00e9n\u00e9ral, situ\u00e9 dans une \u00eele du lac Tchad. Boko Haram a rejet\u00e9 l\u2019affirmation du Niger. L\u2019attaque du quartier g\u00e9n\u00e9ral de M.\u00a0Doro s\u2019est produite au moment o\u00f9 le plus ancien groupe","og_url":"https:\/\/adf-magazine.com\/ar\/?p=131353","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2025-10-21T18:33:09+00:00","article_modified_time":"2025-10-21T18:33:28+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion","datePublished":"2025-10-21T18:33:09+00:00","dateModified":"2025-10-21T18:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353"},"wordCount":890,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg","keywords":["Boko Haram","Cameroun","Lac Tchad","MNJTF","Niger","Nigeria","PAOEI","Tchad"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/ar\/?p=131353#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/ar\/?p=131353","url":"https:\/\/adf-magazine.com\/ar\/?p=131353","name":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg","datePublished":"2025-10-21T18:33:09+00:00","dateModified":"2025-10-21T18:33:28+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/ar\/?p=131353"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2025\/10\/GettyImages-1258291745.jpg","width":1024,"height":683,"caption":"Un regain de violence de Boko Haram dans le bassin du lac Tchad fait craindre que le groupe terroriste n\u2019attire certains des ex-combattants qui l\u2019avaient quitt\u00e9 il y a quelques ann\u00e9es. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/ar\/?p=131353#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Les attaques dans le bassin du lac Tchad montrent que Boko Haram est \u00e0 nouveau en expansion"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/131351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=131351"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/131351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/131346"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=131351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=131351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=131351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}