{"id":13046,"date":"2019-08-06T17:43:42","date_gmt":"2019-08-06T17:43:42","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=13046"},"modified":"2019-08-21T15:10:25","modified_gmt":"2019-08-21T15:10:25","slug":"lafrique-cherche-a-developper-son-tourisme","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2019\/08\/lafrique-cherche-a-developper-son-tourisme\/","title":{"rendered":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME"},"content":{"rendered":"<p>AGENCE FRANCE-PRESSE<\/p>\n<p>5 %\u00a0seulement des touristes mondiaux se rendent en Afrique, malgr\u00e9 sa promotion des attractions allant des grandes pyramides et des chutes Victoria jusqu\u2019aux safaris d\u2019animaux sauvages et aux \u00e9tendues sans fin de plages immacul\u00e9es.<\/p>\n<p>Mais l\u2019\u00e9norme potentiel du continent peut \u00eatre r\u00e9alis\u00e9 gr\u00e2ce \u00e0 l\u2019\u00e9co-<br \/>\ntourisme, aux exp\u00e9riences culturelles, aux voyages nationaux et \u00e1 la stabilit\u00e9 politique, d\u00e9clarent les experts lors d\u2019une conf\u00e9rence sur le tourisme africain au Cap (Afrique du Sud).<\/p>\n<p>\u00ab Lorsque vous consid\u00e9rez les histoires \u00e0 succ\u00e8s, ce sont celles des pays qui adoptent les tendances \u00bb, d\u00e9clare Naledi Khabo, directeur g\u00e9n\u00e9ral de l\u2019Association du tourisme africain. \u00ab Lorsque vous consid\u00e9rez les pays qui se sont concentr\u00e9s sur la durabilit\u00e9, comme la Tanzanie ou le Rwanda, ceux-ci sont tr\u00e8s attrayants pour certains voyageurs. \u00bb<\/p>\n<p>Les safaris \u00e9cologiques et l\u2019h\u00e9bergement neutre en carbone attirent de plus en plus de touristes d\u2019Europe et d\u2019Am\u00e9rique du Nord. Le nombre de touristes qui visitent la Tanzanie a plus que doubl\u00e9 depuis 2006 pour atteindre plus de 1 million, ce qui correspond \u00e0 une contribution de 14 % au produit national brut, selon le site Internet Tanzania Invest.<\/p>\n<p>L\u2019Afrique du Sud a enregistr\u00e9 un boom de tours bas\u00e9s sur les exp\u00e9riences alternatives, qui permettent aux voyageurs de s\u00e9journer dans les municipalit\u00e9s d\u00e9favoris\u00e9es et les communaut\u00e9s rurales, ainsi que dans les exploitations viticoles et les pavillons de chasse.<\/p>\n<p>Le tourisme est un employeur majeur pour les Sud-Africains pauvres avec pr\u00e8s de 700.000 emplois, succ\u00e8s rare dans un pays dont le taux de ch\u00f4mage atteint pr\u00e8s de 27 %.<\/p>\n<p>Bien que de nombreuses destinations africaines aient sollicit\u00e9 les devises fortes des visiteurs \u00e9trangers, le Kenya a investi intens\u00e9ment dans la promotion des \u00ab vacances \u00e0 la maison \u00bb. Le pays s\u2019est engag\u00e9 \u00e0 promouvoir les voyages nationaux lorsque les arriv\u00e9es internationales ont baiss\u00e9 \u00e0 la suite des r\u00e9cents troubles violents et des attaques criminelles.<\/p>\n<p>\u00ab Nous avons r\u00e9ussi \u00e0 d\u00e9velopper le march\u00e9 national \u00bb, d\u00e9clare Najib Balala, ministre k\u00e9nyan du Tourisme. \u00ab Le march\u00e9 national contribue 21 % au taux d\u2019occupation d\u2019Airbnb. Il nous b\u00e9n\u00e9ficie. \u00bb<\/p>\n<p>Le tourisme, qui est maintenant le deuxi\u00e8me facteur principal de la croissance du Kenya, repr\u00e9sentait un chiffre d\u2019affaires de 1,2 milliard de dollars en 2017.<\/p>\n<p>Un grand nombre de pays du continent ont eu des difficult\u00e9s pour attirer les visiteurs \u00e9trangers qui craignaient l\u2019instabilit\u00e9 politique et la violence. Le Rwanda est un pays qui a r\u00e9ussi \u00e0 transformer son image mondiale. Cette petite nation d\u2019Afrique de l\u2019Est, d\u00e9chir\u00e9e par le g\u00e9nocide de 1994, s\u2019est depuis positionn\u00e9e comme une destination haut de gamme.<\/p>\n<p>\u00ab Le tourisme est le secteur qui gagne le plus de devises \u00e9trang\u00e8res, ce qui est \u00e9tonnant de voir dans un pays comme le Rwanda \u00bb, d\u00e9clare Rosette Rugamba, qui dirigeait Rwanda Tourism de 2003 \u00e0 2010. \u00ab Il contribue \u00e9norm\u00e9ment \u00e0 la promotion de l\u2019image de notre pays. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AGENCE FRANCE-PRESSE 5 %\u00a0seulement des touristes mondiaux se rendent en Afrique, malgr\u00e9 sa promotion des attractions allant des grandes pyramides et des chutes Victoria jusqu\u2019aux safaris d\u2019animaux sauvages et aux \u00e9tendues sans fin de plages immacul\u00e9es. Mais l\u2019\u00e9norme potentiel du continent peut \u00eatre r\u00e9alis\u00e9 gr\u00e2ce \u00e0 l\u2019\u00e9co- tourisme, aux exp\u00e9riences culturelles, aux voyages nationaux et<\/p>\n","protected":false},"author":1,"featured_media":13042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[44,40],"tags":[],"class_list":{"0":"post-13046","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-croissance-et-progres","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"AGENCE FRANCE-PRESSE 5 %\u00a0seulement des touristes mondiaux se rendent en Afrique, malgr\u00e9 sa promotion des attractions allant des grandes pyramides et des chutes Victoria jusqu\u2019aux safaris d\u2019animaux sauvages et aux \u00e9tendues sans fin de plages immacul\u00e9es. Mais l\u2019\u00e9norme potentiel du continent peut \u00eatre r\u00e9alis\u00e9 gr\u00e2ce \u00e0 l\u2019\u00e9co- tourisme, aux exp\u00e9riences culturelles, aux voyages nationaux et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T17:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-21T15:10:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME\",\"datePublished\":\"2019-08-06T17:43:42+00:00\",\"dateModified\":\"2019-08-21T15:10:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/\"},\"wordCount\":509,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/growth-fleurs-1.jpg\",\"articleSection\":[\"Croissance et progr\u00e8s\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/\",\"name\":\"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/growth-fleurs-1.jpg\",\"datePublished\":\"2019-08-06T17:43:42+00:00\",\"dateModified\":\"2019-08-21T15:10:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/growth-fleurs-1.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/growth-fleurs-1.jpg\",\"width\":1080,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/08\\\/africa-looks-to-boost-tourism\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum","og_description":"AGENCE FRANCE-PRESSE 5 %\u00a0seulement des touristes mondiaux se rendent en Afrique, malgr\u00e9 sa promotion des attractions allant des grandes pyramides et des chutes Victoria jusqu\u2019aux safaris d\u2019animaux sauvages et aux \u00e9tendues sans fin de plages immacul\u00e9es. Mais l\u2019\u00e9norme potentiel du continent peut \u00eatre r\u00e9alis\u00e9 gr\u00e2ce \u00e0 l\u2019\u00e9co- tourisme, aux exp\u00e9riences culturelles, aux voyages nationaux et","og_url":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2019-08-06T17:43:42+00:00","article_modified_time":"2019-08-21T15:10:25+00:00","og_image":[{"width":1080,"height":664,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME","datePublished":"2019-08-06T17:43:42+00:00","dateModified":"2019-08-21T15:10:25+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/"},"wordCount":509,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg","articleSection":["Croissance et progr\u00e8s","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/","url":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/","name":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg","datePublished":"2019-08-06T17:43:42+00:00","dateModified":"2019-08-21T15:10:25+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/06\/growth-fleurs-1.jpg","width":1080,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2019\/08\/africa-looks-to-boost-tourism\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"L\u2019AFRIQUE CHERCHE \u00c0 D\u00c9VELOPPER SON TOURISME"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/13046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=13046"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/13046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/13042"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=13046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=13046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=13046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}