{"id":12464,"date":"2019-05-06T18:20:11","date_gmt":"2019-05-06T18:20:11","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=12464"},"modified":"2019-05-15T18:10:04","modified_gmt":"2019-05-15T18:10:04","slug":"les-regions-doivent-adopter-une-approche-holistique-de-la-securite","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2019\/05\/les-regions-doivent-adopter-une-approche-holistique-de-la-securite\/","title":{"rendered":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9"},"content":{"rendered":"<p><b><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Mahamat_RTX4YLGV.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-12110 size-thumbnail\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Mahamat_RTX4YLGV-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Moussa Faki Mahamat est l\u2019ancien ministre des Affaires \u00e9trang\u00e8res du Tchad et le pr\u00e9sident de la commission de l\u2019Union africaine.<\/b><\/p>\n<p><i>Il a prononc\u00e9 une allocution lors du Sommet conjoint sur la paix, la s\u00e9curit\u00e9, le terrorisme et l\u2019extr\u00e9misme violent de la Communaut\u00e9 \u00e9conomique des \u00e9tats d\u2019Afrique de l\u2019Ouest (CEDEAO) et la Communaut\u00e9 \u00e9conomique des \u00c9tats de l\u2019Afrique centrale (CEEAC) le 30 juillet 2018 \u00e0 Lom\u00e9 (Togo). Ses remarques ont \u00e9t\u00e9 modifi\u00e9es pour les adapter \u00e0 ce format.<\/i><\/p>\n<hr \/>\n<p>Les d\u00e9fis s\u00e9curitaires auxquels les r\u00e9gions d\u2019Afrique centrale et occidentale font face sont bien connus. Qu\u2019il s\u2019agisse du terrorisme, si pr\u00e9valent dans le Sahel et le bassin du Lac Tchad, de rebellions arm\u00e9es et autres formes de violence qui s\u00e9vissent dans certains pays de la r\u00e9gion, de la piraterie dans le Golfe de Guin\u00e9e, de la persistance de trafics en tous genres ou d\u2019affrontements li\u00e9s au ph\u00e9nom\u00e8ne de la transhumance, la situation est une source de profonde pr\u00e9occupation.<\/p>\n<p>Un certain nombre de facteurs cr\u00e9ent un terrain fertile \u00e0 la persistance de cette ins\u00e9curit\u00e9. Ils portent sur le changement climatique, dont le r\u00e9tr\u00e9cissement du lac Tchad et l\u2019ensablement du fleuve Niger sont des exemples ; l\u2019absence d\u2019opportunit\u00e9s pour la jeunesse ; le sentiment de marginalisation, voire d\u2019exclusion pure et simple, qui habite des pans entiers de nos soci\u00e9t\u00e9s ; et les d\u00e9fis rencontr\u00e9s en mati\u00e8re de gouvernance.<\/p>\n<p>Je salue les initiatives prises par la CEDEAO et la CEEAC ces derni\u00e8res ann\u00e9es pour faire face \u00e0 cette situation. La cr\u00e9ation de la Force multinationale mixte charg\u00e9e de combattre le groupe terroriste Boko Haram et de la Force conjointe du G5 Sahel, ainsi que l\u2019action conduite s\u2019agissant de la lutte contre la piraterie maritime sont, entre autres exemples, l\u2019expression d\u2019une forte volont\u00e9 politique.<\/p>\n<p>Ces initiatives ont, toutes, permis de poser les jalons d\u2019une approche africaine face aux menaces asym\u00e9triques. Le Sommet conjoint de ce jour traduit la reconnaissance par tous que les efforts d\u00e9ploy\u00e9s jusqu\u2019ici, aussi importants soient-ils, ne sont pas suffisants. Il importe de faire davantage. Le statu quo est clairement intenable.<\/p>\n<p>Il importe que nous adoptions une approche holistique qui prenne en charge non seulement les aspects s\u00e9curitaires, mais aussi les causes sous-jacentes des probl\u00e8mes qui se posent.<\/p>\n<p>Autant la lutte contre les groupes terroristes et criminels doit \u00eatre implacable, autant le dialogue doit pr\u00e9valoir pour r\u00e9pondre aux pr\u00e9occupations l\u00e9gitimes de populations qui ont quelquefois le sentiment que leurs probl\u00e8mes ne sont pas suffisamment pris en charge.<\/p>\n<p>Nous nous devons de mobiliser tout le soutien n\u00e9cessaire pour l\u2019aboutissement de l\u2019Initiative africaine pour la paix et la r\u00e9conciliation en R\u00e9publique centrafricaine ; d\u2019aider \u00e0 la tenue, dans les conditions requises de transparence et d\u2019inclusion, des \u00e9lections pr\u00e9vues en d\u00e9cembre prochain en R\u00e9publique d\u00e9mocratique du Congo ; et de d\u00e9ployer des efforts renouvel\u00e9s pour h\u00e2ter le r\u00e8glement de la crise libyenne.<\/p>\n<p>Il est tout aussi important d\u2019\u0153uvrer plus r\u00e9solument en faveur d\u2019un d\u00e9veloppement inclusif et de l\u2019\u00e9radication de la pauvret\u00e9. \u00c0 cet \u00e9gard, des projets de nature \u00e0 am\u00e9liorer le quotidien des populations doivent \u00eatre convenus et men\u00e9s \u00e0 bien.<\/p>\n<p>Il est, enfin, essentiel que les actions envisag\u00e9es s\u2019inscrivent dans une dynamique d\u2019ensemble de renforcement continu de la gouvernance.<\/p>\n<p>Nous entendons, dans la p\u00e9riode \u00e0 venir, articuler nos efforts autour des axes ci-apr\u00e8s :<\/p>\n<p>Aider \u00e0 une meilleure synergie inter-r\u00e9gionale \u00e0 travers la mise en place d\u2019arrangements de coop\u00e9ration s\u00e9curitaires flexibles ou leur \u00e9largissement l\u00e0 o\u00f9 ils existent.<\/p>\n<p>Mobiliser un appui plus substantiel en faveur des initiatives r\u00e9gionales par le biais des structures comp\u00e9tentes de l\u2019Union africaine, notamment le Centre africain d\u2019\u00e9tude et de recherche sur le terrorisme, le M\u00e9canisme africain de coop\u00e9ration polici\u00e8re et le Comit\u00e9 des services de renseignements et de s\u00e9curit\u00e9 d\u2019Afrique.<\/p>\n<p>Promouvoir une meilleure articulation entre les efforts de la CEDEAO et de la CEEAC, d\u2019une part, et ceux de l\u2019Union africaine, d\u2019autre part, dont les instruments doivent servir de cadre global \u00e0 l\u2019action de lutte contre le terrorisme.<\/p>\n<p>Mener une action de plaidoyer plus soutenue au niveau international pour mobiliser un appui plus important pour le financement des op\u00e9rations de soutien \u00e0 la paix conduites par les pays des deux r\u00e9gions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moussa Faki Mahamat est l\u2019ancien ministre des Affaires \u00e9trang\u00e8res du Tchad et le pr\u00e9sident de la commission de l\u2019Union africaine. Il a prononc\u00e9 une allocution lors du Sommet conjoint sur la paix, la s\u00e9curit\u00e9, le terrorisme et l\u2019extr\u00e9misme violent de la Communaut\u00e9 \u00e9conomique des \u00e9tats d\u2019Afrique de l\u2019Ouest (CEDEAO) et la Communaut\u00e9 \u00e9conomique des \u00c9tats<\/p>\n","protected":false},"author":1,"featured_media":12107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[70,40],"tags":[],"class_list":{"0":"post-12464","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-perspective-africaine","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Moussa Faki Mahamat est l\u2019ancien ministre des Affaires \u00e9trang\u00e8res du Tchad et le pr\u00e9sident de la commission de l\u2019Union africaine. Il a prononc\u00e9 une allocution lors du Sommet conjoint sur la paix, la s\u00e9curit\u00e9, le terrorisme et l\u2019extr\u00e9misme violent de la Communaut\u00e9 \u00e9conomique des \u00e9tats d\u2019Afrique de l\u2019Ouest (CEDEAO) et la Communaut\u00e9 \u00e9conomique des \u00c9tats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T18:20:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T18:10:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9\",\"datePublished\":\"2019-05-06T18:20:11+00:00\",\"dateModified\":\"2019-05-15T18:10:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/\"},\"wordCount\":778,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Perspective_Guard_963680176_Toned.jpg\",\"articleSection\":[\"Perspective africaine\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/\",\"name\":\"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Perspective_Guard_963680176_Toned.jpg\",\"datePublished\":\"2019-05-06T18:20:11+00:00\",\"dateModified\":\"2019-05-15T18:10:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Perspective_Guard_963680176_Toned.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Perspective_Guard_963680176_Toned.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/regions-must-take-holistic-approach-to-security\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/","og_locale":"fr_FR","og_type":"article","og_title":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum","og_description":"Moussa Faki Mahamat est l\u2019ancien ministre des Affaires \u00e9trang\u00e8res du Tchad et le pr\u00e9sident de la commission de l\u2019Union africaine. Il a prononc\u00e9 une allocution lors du Sommet conjoint sur la paix, la s\u00e9curit\u00e9, le terrorisme et l\u2019extr\u00e9misme violent de la Communaut\u00e9 \u00e9conomique des \u00e9tats d\u2019Afrique de l\u2019Ouest (CEDEAO) et la Communaut\u00e9 \u00e9conomique des \u00c9tats","og_url":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2019-05-06T18:20:11+00:00","article_modified_time":"2019-05-15T18:10:04+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9","datePublished":"2019-05-06T18:20:11+00:00","dateModified":"2019-05-15T18:10:04+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/"},"wordCount":778,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg","articleSection":["Perspective africaine","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/","url":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/","name":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9 - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg","datePublished":"2019-05-06T18:20:11+00:00","dateModified":"2019-05-15T18:10:04+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/Perspective_Guard_963680176_Toned.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2019\/05\/regions-must-take-holistic-approach-to-security\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"LES R\u00c9GIONS DOIVENT ADOPTER UNE APPROCHE HOLISTIQUE DE LA S\u00c9CURIT\u00c9"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/12464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=12464"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/12464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/12107"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=12464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=12464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=12464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}