{"id":12406,"date":"2019-05-06T14:53:03","date_gmt":"2019-05-06T14:53:03","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=12406"},"modified":"2019-05-15T18:10:26","modified_gmt":"2019-05-15T18:10:26","slug":"la-reconquete-du-numerique","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2019\/05\/la-reconquete-du-numerique\/","title":{"rendered":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE"},"content":{"rendered":"<h3>Les groupes extr\u00e9mistes ont prosp\u00e9r\u00e9 en ligne.\u00a0Ils ne peuvent pas \u00eatre r\u00e9duits au silence, mais ils peuvent \u00eatre vaincus.<\/h3>\n<p>PERSONNEL D\u2019<i>ADF<\/i><\/p>\n<p>Photos par Reuters<\/p>\n<p>Pour ce qui est du recrutement radical, le v\u00e9hicule a pu changer au cours des ann\u00e9es mais les strat\u00e9gies et le message restent les m\u00eames.<\/p>\n<p>Depuis longtemps, les extr\u00e9mistes islamistes travaillent dans l\u2019ombre et utilisent tous les moyens possibles pour diffuser leur propagande. \u00c0 partir des ann\u00e9es soixante-dix, les pr\u00e9dicateurs radicaux ont pendant 20 ans utilis\u00e9 des audiocassettes et des prospectus transmis d\u2019une personne \u00e0 l\u2019autre pour influencer les gens.<\/p>\n<p>Lorsque les vid\u00e9os sont apparues, les recruteurs ont souvent utilis\u00e9 des vid\u00e9ocassettes. Ibrahim al-Afghani, l\u2019un des fondateurs d\u2019al-Shebab, s\u2019est fait conna\u00eetre en distribuant des vid\u00e9os des insurg\u00e9s luttant contre l\u2019Union sovi\u00e9tique en Afghanistan. Dans les ann\u00e9es quatre-vingt-dix, ces vid\u00e9os se sont propag\u00e9es en Somalie comme un virus et ont \u00e9t\u00e9 visionn\u00e9es dans les foyers et les petits th\u00e9\u00e2tres.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab Les bandes vid\u00e9o \u00e9taient primitives compar\u00e9 aux montages \u00e9labor\u00e9s, \u00e0 haute d\u00e9finition, produits plus tard par les groupes islamistes radicaux \u00bb, \u00e9crivent Dan Joseph et Harun Maruf dans leur livre : <i>Inside Al-Shabaab<\/i> [Au sein d\u2019Al-Shebab]. \u00ab Mais elles pr\u00e9sentaient tr\u00e8s bien la guerre comme la r\u00e9sistance la plus h\u00e9ro\u00efque que tout groupe musulman ait jamais entrepris contre une puissance moderne. \u00bb<\/p>\n<p>M. Al-Afghani a utilis\u00e9 ces vid\u00e9os pour b\u00e9n\u00e9ficier du soutien d\u2019al-Qa\u00efda et recruter des milliers de gens pour sa cause radicale.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-12113\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds.jpg\" alt=\"\" width=\"1080\" height=\"706\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds-300x196.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds-768x502.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-3ds-1024x669.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a>\u00c9tant donn\u00e9 ces ant\u00e9c\u00e9dents, il n\u2019est pas surprenant que les extr\u00e9mistes adoptent l\u2019Internet et y prolif\u00e8rent. Une analyse de 2015 par la Brookings Institution a recens\u00e9 plus de 45.000 comptes de r\u00e9seaux sociaux contr\u00f4l\u00e9s par les sympathisants de l\u2019EIIL. Le groupe est affili\u00e9 \u00e0 une agence de presse et cr\u00e9e des vid\u00e9os de haute qualit\u00e9 et d\u2019autres productions en anglais, arabe, russe, mandarin et h\u00e9breux, ainsi qu\u2019en langue des signes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab L\u2019acc\u00e8s des islamistes au cyberespace \u00e9tait in\u00e9vitable \u00bb, \u00e9crit Haroon Ullah dans le livre : <i>Digital World War<\/i> [Guerre mondiale du num\u00e9rique]. \u00ab D\u2019un certain c\u00f4t\u00e9, ce n\u2019\u00e9tait rien de nouveau : les islamistes avaient utilis\u00e9 adroitement depuis longtemps les derni\u00e8res technologies pour s\u2019adresser au public lorsque de nouvelles interfaces de r\u00e9seaux sociaux ont fait surface. \u00bb<\/p>\n<p>Bien que le recrutement par le num\u00e9rique s\u2019inscrive dans le cadre d\u2019une ancienne strat\u00e9gie, l\u2019Internet a chang\u00e9 la donne. Il permet aux extr\u00e9mistes de faire appel \u00e0 des gens qu\u2019ils n\u2019auraient pas pu auparavant rencontrer face \u00e0 face, notamment les femmes et les enfants. Il acc\u00e9l\u00e8re aussi le processus de radicalisation en permettant aux gens de communiquer dans les forums de discussion avec une communaut\u00e9 d\u2019id\u00e9ologues au lieu de simplement lire ou visionner tout seuls des pr\u00e9sentations.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Puisque l\u2019Internet sert de caisse de r\u00e9sonance o\u00f9 les recrues potentielles peuvent \u00eatre encadr\u00e9es par des personnes qui partagent les m\u00eames points de vue, il est devenu un espace concurrentiel pour conqu\u00e9rir les c\u0153urs et les esprits. Dans le livre <i>LikeWar: The Weaponization of Social Media<\/i> [Guerre du \u00ab j\u2019aime \u00bb : la militarisation des r\u00e9seaux sociaux], les auteurs Peter Warren Singer et Emerson Brooking soutiennent qu\u2019il existe d\u00e9sormais une lutte pour le \u00ab j\u2019aime \u00bb, c\u2019est-\u00e0-dire pour l\u2019influence.<\/p>\n<p>\u00ab Si la guerre cybern\u00e9tique concerne le piratage des r\u00e9seaux, la guerre du \u201cj\u2019aime\u201d concerne le piratage des abonn\u00e9s des r\u00e9seaux en propageant les id\u00e9es \u00bb, a d\u00e9clar\u00e9 M. Singer lors d\u2019un \u00e9v\u00e9nement organis\u00e9 par le Centre pour les \u00e9tudes strat\u00e9giques et internationales. \u00ab Vous avez des arm\u00e9es en ligne qui utilisent les m\u00eames tactiques pour atteindre leurs objectifs dans le monde r\u00e9el. \u00bb<\/p>\n<p>S\u2019il s\u2019agit vraiment d\u2019un nouveau type de guerre, les forces de s\u00e9curit\u00e9 doivent se poser la question suivante : \u00ab Comment allons-nous gagner ? \u00bb<\/p>\n<p><strong>Il est difficile de les r\u00e9duire au silence<\/strong><\/p>\n<p>Il existe une simple strat\u00e9gie pour emp\u00eacher les extr\u00e9mistes de diffuser leur propagande sur les r\u00e9seaux sociaux : fermer leurs comptes et les emp\u00eacher de revenir. Mais c\u2019est plus facile \u00e0 dire qu\u2019\u00e0 faire.<\/p>\n<p>Dans un rapport de 2018, la plateforme de r\u00e9seaux sociaux Twitter signale qu\u2019elle a bloqu\u00e9 1,2 million de comptes terroristes pr\u00e9sum\u00e9s sur une p\u00e9riode de deux ans, dont 275.000 comptes seulement au deuxi\u00e8me semestre 2017. La soci\u00e9t\u00e9 d\u00e9clare qu\u2019elle s\u2019appuie sur les rapports des personnes, des organisations et des gouvernements, ainsi que sur la technologie qui peut identifier un compte extr\u00e9miste et le bloquer avant qu\u2019il n\u2019\u00e9mette son premier tweet.<\/p>\n<p><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-12119 size-full\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi.jpg\" alt=\"\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-saudi-1024x683.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/p>\n<p>Elle d\u00e9clare qu\u2019elle a fait de Twitter un \u00ab lieu d\u00e9favorable \u00bb pour les gens propageant une id\u00e9ologie extr\u00e9miste et elle s\u2019est r\u00e9jouie de voir que certains groupes s\u2019\u00e9loignaient de son site.<\/p>\n<p>Mais ce succ\u00e8s est \u00e9ph\u00e9m\u00e8re. L\u2019exp\u00e9rience montre que plusieurs comptes sont cr\u00e9\u00e9s pour remplacer un compte qui est \u00e9limin\u00e9. Aswarti Media, utilisateur de Twitter associ\u00e9 \u00e0 l\u2019EIIL, s\u2019est vant\u00e9 du nombre de fois que Twitter avait cl\u00f4tur\u00e9 son compte : plus de 600 fois. En outre, lorsque les sites tels que Twitter deviennent moins conviviaux, les extr\u00e9mistes passent simplement \u00e0 d\u2019autres plateformes. Ils utilisent des services chiffr\u00e9s tels que WhatsApp ou Telegram, et des services de partage de fichier gr\u00e2ce auxquels ils peuvent \u00e9changer de simples fichiers PDF tels que ceux de <i>Rumiyah<\/i>, le magazine de l\u2019EIIL.<\/p>\n<p>\u00ab Il se trouve que la haine se propage plus rapidement que la justice de la Silicon Valley \u00bb, \u00e9crit le <i>New York Times<\/i> dans un article sur les efforts pour r\u00e9duire au silence les extr\u00e9mistes en ligne.<\/p>\n<p>De m\u00eame, un grand nombre de personnes pr\u00f4nant des messages extr\u00e9mistes sont pass\u00e9es ma\u00eetres dans l\u2019art de respecter les r\u00e8gles des r\u00e9seaux sociaux. Muhammad Al-Arifi, l\u2019un des pr\u00e9dicateurs islamistes les plus populaires du monde, a 21 millions d\u2019abonn\u00e9s sur Twitter. Il a inspir\u00e9 beaucoup de jeunes hommes \u00e0 rejoindre l\u2019EIIL et il produit des programmes qu\u2019il appelle \u00ab Fatwas Snap \u00bb sur Snapchat. Toutefois, puisqu\u2019il fait attention de ne pas faire explicitement appel \u00e0 la violence, il n\u2019enfreint pas les conditions d\u2019utilisation de ces plateformes.<\/p>\n<p>\u00ab Ils ne peuvent pas par exemple l\u2019emp\u00eacher de d\u00e9noncer la tyrannie de Bachar el-Assad alors qu\u2019il parle favorablement des lois religieuses et des gouvernements islamiques \u00bb, \u00e9crit M. Ullah dans un \u00e9ditorial publi\u00e9 par <i>The Guardian<\/i>. \u00ab Mais si vous juxtaposez ces deux id\u00e9es et ajoutez un contexte dangereux, vous obtenez quelque chose de mauvais. \u00bb<\/p>\n<p><strong>Combattre le feu par le feu<span class=\"Apple-converted-space\">\u00a0<\/span><\/strong><\/p>\n<p>Les groupes qui luttent contre le recrutement radical en ligne, tels que le groupe Jigsaw associ\u00e9 \u00e0 Google, pensent que la meilleure strat\u00e9gie consiste \u00e0 battre les terroristes \u00e0 leur propre jeu. En association avec un groupe appel\u00e9 Moonshot CVE, Jigsaw a lanc\u00e9 ce qu\u2019il appelle la m\u00e9thode de la redirection.<\/p>\n<p>Cette strat\u00e9gie est bas\u00e9e sur un principe simple : la plupart de ceux qui deviennent radicalis\u00e9s en ligne commencent par chercher des r\u00e9ponses \u00e0 des questions importantes, puis sont plus tard s\u00e9duits par la voie de l\u2019extr\u00e9misme. S\u2019ils peuvent obtenir des r\u00e9ponses diff\u00e9rentes au d\u00e9but de leur p\u00e9riple, ils pourront \u00eatre sauv\u00e9s.<\/p>\n<p>\u00ab Selon mes entretiens avec d\u2019anciens sympathisants ou des ex-recrues de l\u2019EIIL, ou avec d\u2019anciens extr\u00e9mistes, il s\u2019agit surtout de gens qui se posaient des questions quasi-l\u00e9gitimes, mais qui ont pris la mauvaise route \u00bb, d\u00e9clare Yasmin Green, directrice de la recherche et de la technologie chez Jigsaw. \u00ab Davantage d\u2019informations ou des informations meilleures, obtenues plus t\u00f4t sur ce parcours, auraient pu les orienter vers une direction diff\u00e9rente. \u00bb<\/p>\n<p><figure id=\"attachment_12116\" aria-describedby=\"caption-attachment-12116\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds.jpg\"><img decoding=\"async\" class=\"size-full wp-image-12116\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds.jpg\" alt=\"\" width=\"1080\" height=\"687\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds-300x191.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds-768x489.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds-1024x651.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-dvds-110x70.jpg 110w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-12116\" class=\"wp-caption-text\">Un client regarde un DVD intitul\u00e9 Westgate Attack [Attaque de Westgate] dans un march\u00e9 de plein air \u00e0 Nairobi (Kenya).<\/figcaption><\/figure>Le programme utilise le pouvoir de la publicit\u00e9 en ligne pour d\u00e9celer les gens qui recherchent des informations sur les groupes extr\u00e9mistes. Ensuite, le programme montre \u00e0 ces personnes une publicit\u00e9 pour une vid\u00e9o de YouTube qui pr\u00e9sente un pr\u00e9dicateur ou un d\u00e9serteur d\u2019une organisation extr\u00e9miste.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Le timing est essentiel dans cet effort. Les recherches montrent que, lorsque les jeunes gens entrent en contact avec un groupe extr\u00e9miste et deviennent entour\u00e9s d\u2019extr\u00e9mistes en ligne appartenant \u00e0 une \u00ab microcommunaut\u00e9 \u00bb qui partage le m\u00eame point de vue, il est plus difficile de les atteindre. Une fois que les recrues se pr\u00e9parent \u00e0 voyager vers une zone de guerre ou \u00e0 lancer une attaque, il est probablement trop tard pour les en dissuader.<\/p>\n<p>\u00ab On ne peut pas r\u00e9pondre oui ou non \u00e0 la radicalisation, d\u00e9clare Mme Green. C\u2019est un processus dans lequel les gens se posent des questions concernant l\u2019id\u00e9ologie, la religion, le cadre de vie, et ils acc\u00e8dent \u00e0 l\u2019Internet pour trouver des r\u00e9ponses. Cela pr\u00e9sente une opportunit\u00e9 pour les contacter. \u2026 Le but consiste \u00e0 leur donner la chance d\u2019entendre quelqu\u2019un qui a suivi cette route et qui en est revenu. \u00bb<\/p>\n<p><strong>La v\u00e9rit\u00e9 divulgu\u00e9e<span class=\"Apple-converted-space\">\u00a0<\/span><\/strong><\/p>\n<p>Les vid\u00e9os de propagande de l\u2019EIIL ont quelques th\u00e8mes coh\u00e9rents. Elles montrent que la zone contr\u00f4l\u00e9e par le groupe est prosp\u00e8re et bien gouvern\u00e9e, elles d\u00e9montrent sa puissance militaire, elles encouragent l\u2019endoctrinement religieux et elles soulignent la d\u00e9tresse des Musulmans dans le monde.<\/p>\n<p>Les responsables qui se sont entretenus avec des jeunes gens arr\u00eat\u00e9s alors qu\u2019ils essayaient de voyager pour rejoindre un groupe extr\u00e9miste d\u00e9clarent que les recrues qui se sont plong\u00e9es dans ces vid\u00e9os ont une vision pervertie et id\u00e9alis\u00e9e de l\u2019univers auquel elles veulent acc\u00e9der.<\/p>\n<p>Mme Green raconte l\u2019entretien qu\u2019elle avait eu avec une jeune fille de 13 ans qui pr\u00e9voyait de voyager jusqu\u2019en Syrie, mais qui avait \u00e9t\u00e9 d\u00e9barqu\u00e9e d\u2019un avion \u00e0 Londres. La jeune fille avait d\u00e9crit aux autorit\u00e9s une image de ce qu\u2019elle pensait rejoindre, y compris les centres commerciaux, le mariage avec un djihadiste et la vie heureuse jusqu\u2019\u00e0 la fin des temps. \u00ab Je pensais que j\u2019allais vivre dans un Disney World islamique \u00bb, a-t-elle d\u00e9clar\u00e9 aux autorit\u00e9s.<\/p>\n<p>\u00ab L\u2019EIIL comprend ce qui motive les gens et pr\u00e9pare avec soin ses messages en fonction de chaque audience \u00bb, d\u00e9clare Mme Green.<\/p>\n<p>Les groupes anti-extr\u00e9mistes cherchent \u00e0 r\u00e9futer cette fiction avec des vid\u00e9os qui montrent \u00e0 quoi ressemble vraiment la vie dans le territoire occup\u00e9 par les extr\u00e9mistes. Ils montrent les gens qui font la queue pour obtenir du pain dans le territoire contr\u00f4l\u00e9 par l\u2019EIIL, les combattants islamiques qui punissent brutalement les civils et les dommages collat\u00e9raux sanglants des attaques terroristes contre les innocents.<\/p>\n<p>Bien qu\u2019un grand nombre de ces efforts soient entrepris par des soci\u00e9t\u00e9s priv\u00e9es, les efforts des forces arm\u00e9es et des gouvernements peuvent \u00eatre particuli\u00e8rement utiles puisqu\u2019ils sont en premi\u00e8re ligne dans la lutte contre les extr\u00e9mistes. Ils sont bien plac\u00e9s pour filmer la r\u00e9alit\u00e9 et interroger les transfuges.<\/p>\n<p><strong>Des le\u00e7ons apprises<\/strong><\/p>\n<p>Bien que les groupes extr\u00e9mistes tirent parti de la disponibilit\u00e9 de l\u2019Internet, ils sont aussi expos\u00e9s \u00e0 la surveillance ou \u00e0 l\u2019interruption de leurs activit\u00e9s.<\/p>\n<p>Le recrutement en ligne passe en g\u00e9n\u00e9ral par plusieurs phases : la d\u00e9couverte, au cours de laquelle une recrue entreprend les premiers contacts ; la cr\u00e9ation d\u2019une microcommunaut\u00e9, au sein de laquelle la recrue est encadr\u00e9e par des gens qui partagent les m\u00eames id\u00e9es ; l\u2019isolement, pendant lequel elle est encourag\u00e9e \u00e0 couper les contacts avec les amis et la famille ; finalement, l\u2019intervention.<\/p>\n<p>Les responsables de la lutte contre le terrorisme peuvent obtenir de pr\u00e9cieuses informations \u00e0 chaque \u00e9tape. Ils peuvent recueillir les noms d\u2019utilisateur et autres donn\u00e9es des recruteurs habituels, suivre les r\u00e9p\u00e9titions des th\u00e8mes et des tactiques utilis\u00e9s pour influencer les gens, et dans certains cas intervenir avant qu\u2019une recrue ne devienne la proie d\u2019un groupe extr\u00e9miste.<\/p>\n<p>\u00ab L\u2019un des points positifs des r\u00e9seaux sociaux est le fait qu\u2019ils poussent les interactions humaines vers une structure relativement limit\u00e9e, ce qui nous permet de diagnostiquer le processus de ces interactions et de le reconna\u00eetre lorsqu\u2019il se r\u00e9p\u00e8te \u00bb, \u00e9crit J.M. Berger, ancien expert sur l\u2019extr\u00e9misme \u00e0 la Brookings Institution, qui a \u00e9tudi\u00e9 les activit\u00e9s en ligne de l\u2019EIIL. \u00ab Nous pouvons contrer l\u2019EIIL sur les r\u00e9seaux sociaux de fa\u00e7on plus judicieuse et plus efficace en \u00e9liminant les all\u00e9gories et en nous concentrant sur le m\u00e9canisme. \u00bb<span class=\"Apple-converted-space\">\u00a0\u00a0<\/span><\/p>\n<hr \/>\n<p><strong>Les \u00e9tapes du recrutement en ligne de l&rsquo;EIIL<\/strong><\/p>\n<p><b>La d\u00e9couverte :<\/b> les recruteurs de l\u2019EIIL surveillent attentivement les communaut\u00e9s en ligne auxquelles ils pensent que des personnes favorablement dispos\u00e9es peuvent appartenir. Ils se mettent \u00e0 la disposition des gens pour r\u00e9pondre aux questions et fournir des informations \u00e0 ceux qui semblent \u00eatre curieux.<\/p>\n<p><b>La cr\u00e9ation d\u2019une microcommunaut\u00e9 : <\/b>lorsqu\u2019une recrue potentielle est identifi\u00e9e, les sympathisants de l\u2019EIIL la prennent en charge pour renforcer ses nouvelles croyances. \u00ab Les recruteurs sont disponibles pour transmettre \u00e0 haut d\u00e9bit afin d\u2019interfacer avec leurs cibles, en publiant souvent 50 ou 60 tweets par jour. Certains utilisateurs prolifiques en enregistrent plus de 250, selon le jour \u00bb, \u00e9crit M. Berger dans un article pour le Centre de lutte contre le terrorisme \u00e0 West Point.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>L\u2019isolement :<\/b> les recrues potentielles sont exhort\u00e9es \u00e0 couper les liens avec leur famille, leurs amis et leur communaut\u00e9 religieuse locale. Cet isolement permet \u00e0 l\u2019EIIL de r\u00e9duire au silence les voix dissidentes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>Le passage aux communications priv\u00e9es :<\/b> les sympathisants de l\u2019EIIL encouragent les cibles \u00e0 amener les conversations en ligne sur des plateformes de messagerie priv\u00e9es ou chiffr\u00e9es.<\/p>\n<p><b>L\u2019encouragement \u00e0 l\u2019intervention :<\/b> les recruteurs de l\u2019EIIL d\u00e9terminent le type d\u2019intervention que la cible souhaite entreprendre. Il pourrait s\u2019agir d\u2019un voyage pour rejoindre l\u2019EIIL ou d\u2019une attaque terroriste dans le pays de la cible. Lorsque cela a \u00e9t\u00e9 d\u00e9termin\u00e9, les recruteurs encouragent la recrue \u00e0 agir.<\/p>\n<p>Source : J.M. Berger, \u00ab Interventions en ligne personnalis\u00e9es : la strat\u00e9gie de recrutement de l\u2019\u00c9tat islamique \u00bb<\/p>\n<hr \/>\n<p><strong>Les cinq r\u00e9cits courants de recrutement et comment ils peuvent \u00eatre discr\u00e9dit\u00e9s<\/strong><\/p>\n<p><strong>Bonne gouvernance :<\/strong> les groupes extr\u00e9mistes essaient de montrer \u00e0 leurs cibles que les communaut\u00e9s sous leur contr\u00f4le sont pacifiques, bien gouvern\u00e9es et religieusement pures.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>R\u00e9futation :<\/strong> le r\u00e9cit est contr\u00e9 en montrant la r\u00e9alit\u00e9 des zones contr\u00f4l\u00e9es par les terroristes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Les vid\u00e9os montrant les ch\u00e2timents cruels, la violence, la pauvret\u00e9 et le d\u00e9sespoir pr\u00e9sents dans<span class=\"Apple-converted-space\">\u00a0<\/span>ces r\u00e9gions peuvent offrir un moyen efficace de dissuader les gens de rejoindre les extr\u00e9mistes.<\/p>\n<p><strong>Puissance militaire :<\/strong> les groupes extr\u00e9mistes se vantent souvent de leurs victoires sur les champs de bataille et de leur mat\u00e9riel militaire. L\u2019EIIL montre par exemple des d\u00e9fil\u00e9s de chars d\u2019assaut dans les rues d\u2019une ville.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>R\u00e9futation :<\/strong> cet argument est contr\u00e9 par les cartes montrant la petite r\u00e9gion contr\u00f4l\u00e9e par<span class=\"Apple-converted-space\">\u00a0<\/span>un groupe et le manque de nourriture et d\u2019\u00e9quipement de ses combattants.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>L\u00e9gitimit\u00e9 religieuse :<\/strong> les groupes extr\u00e9mistes se targuent de leur interpr\u00e9tation \u00e9troite et d\u00e9form\u00e9e de l\u2019Islam, repr\u00e9sentant soi-disant la seule version authentique de cette foi.<\/p>\n<p><strong>R\u00e9futation :<\/strong> les imams et autres chefs religieux peuvent contredire ces interpr\u00e9tations<span class=\"Apple-converted-space\">\u00a0<\/span>en montrant qu\u2019elles ne sont pas ancr\u00e9es dans le Coran ou dans la tradition islamique.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>Appel au djihad :<\/strong> ces vid\u00e9os pr\u00e9tendent que les Musulmans pieux ont le devoir d\u2019immigrer au \u00ab califat \u00bb et de lancer des attaques terroristes dans le cadre d\u2019un djihad violent. Elles montrent des combattants du groupe extr\u00e9miste dont la vie est pleine d\u2019aventure, de camaraderie et de gloire.<\/p>\n<p><strong>R\u00e9futation :<\/strong> les entretiens avec les d\u00e9serteurs et les anciens combattants montrent que la<span class=\"Apple-converted-space\">\u00a0<\/span>r\u00e9alit\u00e9 est toute autre. Leurs histoires r\u00e9v\u00e8lent les luttes internes, la peur et les conditions<span class=\"Apple-converted-space\">\u00a0<\/span>de vie inhumaines.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>La condition de victime des Musulmans dans le monde :<\/strong> ces vid\u00e9os soulignent le mauvais traitement de la communaut\u00e9 mondiale des Musulmans, appel\u00e9e oumma. Elles exhortent les spectateurs \u00e0 intervenir pour mettre fin \u00e0 l\u2019asservissement des coreligionnaires musulmans aux mains des infid\u00e8les.<\/p>\n<p><strong>R\u00e9futation :<\/strong> la grande majorit\u00e9 des victimes des attaques commises par les extr\u00e9mistes<span class=\"Apple-converted-space\">\u00a0<\/span>islamistes sont des Musulmans. En montrant cela, la fiction selon laquelle un groupe terroriste<span class=\"Apple-converted-space\">\u00a0<\/span>peut d\u00e9fendre les Musulmans innocents du monde est r\u00e9fut\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les groupes extr\u00e9mistes ont prosp\u00e9r\u00e9 en ligne.\u00a0Ils ne peuvent pas \u00eatre r\u00e9duits au silence, mais ils peuvent \u00eatre vaincus. PERSONNEL D\u2019ADF Photos par Reuters Pour ce qui est du recrutement radical, le v\u00e9hicule a pu changer au cours des ann\u00e9es mais les strat\u00e9gies et le message restent les m\u00eames. Depuis longtemps, les extr\u00e9mistes islamistes travaillent<\/p>\n","protected":false},"author":1,"featured_media":12404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[],"class_list":{"0":"post-12406","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articles"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Les groupes extr\u00e9mistes ont prosp\u00e9r\u00e9 en ligne.\u00a0Ils ne peuvent pas \u00eatre r\u00e9duits au silence, mais ils peuvent \u00eatre vaincus. PERSONNEL D\u2019ADF Photos par Reuters Pour ce qui est du recrutement radical, le v\u00e9hicule a pu changer au cours des ann\u00e9es mais les strat\u00e9gies et le message restent les m\u00eames. Depuis longtemps, les extr\u00e9mistes islamistes travaillent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T14:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T18:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"LA RECONQU\u00caTE DU NUM\u00c9RIQUE\",\"datePublished\":\"2019-05-06T14:53:03+00:00\",\"dateModified\":\"2019-05-15T18:10:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/\"},\"wordCount\":2877,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/recruit-skull-1.jpg\",\"articleSection\":[\"articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/\",\"name\":\"LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/recruit-skull-1.jpg\",\"datePublished\":\"2019-05-06T14:53:03+00:00\",\"dateModified\":\"2019-05-15T18:10:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/recruit-skull-1.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/recruit-skull-1.jpg\",\"width\":1080,\"height\":806},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/05\\\/reclaiming-the-digital-terrain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA RECONQU\u00caTE DU NUM\u00c9RIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/","og_locale":"fr_FR","og_type":"article","og_title":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum","og_description":"Les groupes extr\u00e9mistes ont prosp\u00e9r\u00e9 en ligne.\u00a0Ils ne peuvent pas \u00eatre r\u00e9duits au silence, mais ils peuvent \u00eatre vaincus. PERSONNEL D\u2019ADF Photos par Reuters Pour ce qui est du recrutement radical, le v\u00e9hicule a pu changer au cours des ann\u00e9es mais les strat\u00e9gies et le message restent les m\u00eames. Depuis longtemps, les extr\u00e9mistes islamistes travaillent","og_url":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2019-05-06T14:53:03+00:00","article_modified_time":"2019-05-15T18:10:26+00:00","og_image":[{"width":1080,"height":806,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE","datePublished":"2019-05-06T14:53:03+00:00","dateModified":"2019-05-15T18:10:26+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/"},"wordCount":2877,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg","articleSection":["articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/","url":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/","name":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg","datePublished":"2019-05-06T14:53:03+00:00","dateModified":"2019-05-15T18:10:26+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/05\/recruit-skull-1.jpg","width":1080,"height":806},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2019\/05\/reclaiming-the-digital-terrain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"LA RECONQU\u00caTE DU NUM\u00c9RIQUE"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/12406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=12406"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/12406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/12404"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=12406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=12406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=12406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}