{"id":119874,"date":"2024-10-29T15:52:06","date_gmt":"2024-10-29T19:52:06","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=119874"},"modified":"2024-10-31T15:53:13","modified_gmt":"2024-10-31T19:53:13","slug":"le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/","title":{"rendered":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes"},"content":{"rendered":"<div><span lang=\"FR\">PERSONNEL D\u2019ADF<\/span><\/div>\n<div><span lang=\"FR\">\u00a0<\/span><\/div>\n<div><span lang=\"FR\">\u00a0<\/span><\/div>\n<div>\n<p><span lang=\"FR\">En septembre dernier, la Marine du Ghana a r\u00e9ceptionn\u00e9 deux navires patrouilleurs du type Defender, qui am\u00e9lioreront sa capacit\u00e9 de lutte contre la p\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e (INN), le trafic de drogue, la contrebande des armes, la piraterie, le vol \u00e0 main arm\u00e9e en mer et autres crimes maritimes.<\/span><\/p>\n<p>Le gouvernement des \u00c9tats-Unis a donn\u00e9 les navires et a aussi fourni une installation d\u2019entreposage. Le don a une valeur de plus de 24\u00a0millions de cedis ghan\u00e9ens (1,5\u00a0million de dollars). Les \u00c9tats-Unis avaient aussi fait don de deux navires Defender au Ghana l\u2019an dernier.<\/p>\n<p>Lors d\u2019une c\u00e9r\u00e9monie de transfert au Commandement de la formation navale (NAVTRAC) dans la r\u00e9gion ghan\u00e9enne de la Volta, le contre-amiral Issah Adam Yakubu, chef d\u2019\u00e9tat-major de la Marine du Ghana, a remerci\u00e9 les \u00c9tats-Unis pour avoir fourni ces quatre navires de 11,6\u00a0m ainsi que des outils de communication, des armes et des munitions, et un \u00e9quipement de visite, abordage, fouille et saisie.<\/p>\n<p>Le commodore Solomon Asiedu-Larbi, officier g\u00e9n\u00e9ral commandant NAVTRAC, a aussi exprim\u00e9 ses remerciements pour les membres de la Marine et du Corps des fusiliers marins des \u00c9tats-Unis qui ont aid\u00e9 \u00e0 construire l\u2019installation d\u2019entreposage.<\/p>\n<p>Virginia Palmer, ambassadrice des \u00c9tats-Unis au Ghana, a d\u00e9clar\u00e9 qu\u2019elle \u00e9tait fi\u00e8re du partenariat de longue date entre les pays, en disant qu\u2019il est bas\u00e9 sur des engagements mutuels envers la s\u00e9curit\u00e9, la d\u00e9mocratie et la prosp\u00e9rit\u00e9.<\/p>\n<p>Elle a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Cette c\u00e9r\u00e9monie est plus qu\u2019un simple transfert. Elle symbolise nos efforts conjoints pour assurer que la Marine du Ghana soit bien \u00e9quip\u00e9e afin de s\u00e9curiser les eaux du pays.\u00a0\u00bb<\/p>\n<p>La p\u00eache ill\u00e9gale, surtout pratiqu\u00e9e par les chalutiers industriels chinois, tourmente le Ghana et d\u2019autres pays d\u2019Afrique de l\u2019Ouest depuis des dizaines d\u2019ann\u00e9es. Cette pratique d\u00e9cime les stocks de poissons et fait monter le prix des fruits de mer. Au Ghana, les stocks de petits poissons p\u00e9lagiques tels que la sardinelle ont chut\u00e9 de 80\u00a0% au cours des vingt derni\u00e8res ann\u00e9es, selon l\u2019Environmental Justice Foundation. Les stocks de l\u2019esp\u00e8ce appel\u00e9e sardinella aurita se sont compl\u00e8tement effondr\u00e9s.<\/p>\n<p>Kofi Tawia, p\u00eacheur artisanal de 40\u00a0ans bas\u00e9 au port de Cape Coast, a d\u00e9clar\u00e9 au journal The Guardian que la prise avait baiss\u00e9e dramatiquement. Il est l\u2019un des plus de 100.000\u00a0p\u00eacheurs actifs dans le pays, pour lesquels les revenus annuels moyens ont baiss\u00e9 jusqu\u2019\u00e0 40\u00a0% par pirogue artisanale au cours des quinze derni\u00e8res ann\u00e9es environ, selon la fondation. La d\u00e9cimation des stocks de poissons fait grimper les prix et provoque l\u2019ins\u00e9curit\u00e9 alimentaire.<\/p>\n<p>M.\u00a0Tawia d\u00e9clare qu\u2019il y a si peu de poissons que les n\u00e9gociations sur le partage de la prise quotidienne peuvent facilement conduire \u00e0 des affrontements physiques. La situation est similaire dans toute l\u2019Afrique de l\u2019Ouest, aujourd\u2019hui consid\u00e9r\u00e9e comme l\u2019\u00e9picentre mondial de la p\u00eache ill\u00e9gale, o\u00f9 les gouvernements locaux perdent des sommes annuelles estim\u00e9es \u00e0 10\u00a0milliards de dollars, selon un rapport de septembre 2023 par le Stimson Center.<\/p>\n<p>La piraterie en Afrique de l\u2019Ouest est aussi en hausse. Au cours de l\u2019an dernier, les pirates, les voleurs arm\u00e9s et les groupes pratiquant l\u2019enl\u00e8vement contre ran\u00e7on ont \u00e9t\u00e9 actifs au large des c\u00f4tes du Cameroun, du Ghana, de la Guin\u00e9e \u00e9quatoriale, du Nigeria et du Togo. Ils prennent pour cible un \u00e9ventail de navires, notamment les p\u00e9troliers, les navires porte-conteneurs, les cargos en g\u00e9n\u00e9ral et les navires de passager, selon le minist\u00e8re des Transports des \u00c9tats-Unis. Ces criminels ont attaqu\u00e9 et abord\u00e9 des navires \u00e0 des distances jusqu\u2019\u00e0 300\u00a0milles marins du littoral, et ils sont bien connus pour faire feu sur les navires pendant les abordages ou les tentatives d\u2019abordage.<\/p>\n<p>Il y a eu 22\u00a0attaques de pirate dans le golfe de Guin\u00e9e en 2023, chiffre l\u00e9g\u00e8rement sup\u00e9rieur aux 19 attaques de 2022, mais inf\u00e9rieur aux 35 attaques de 2021 et aux 81 de 2020, selon le Bureau maritime international. Les responsables ont signal\u00e9 six incidents de piraterie au cours du premier trimestre 2024, compar\u00e9 \u00e0 cinq pendant la m\u00eame p\u00e9riode de 2023.<\/p>\n<p>Ces menaces pesant sur l\u2019\u00e9conomie des oc\u00e9ans du Ghana ont conduit \u00e0 la cr\u00e9ation de sa Strat\u00e9gie nationale maritime int\u00e9gr\u00e9e, qui vise \u00e0 assurer la s\u00e9curit\u00e9 du domaine maritime du Ghana \u00e0 partir de 2040.<\/p>\n<p>Son but est de renforcer le cadre de gouvernance maritime du Ghana, d\u2019assurer la s\u00e9curit\u00e9 de son domaine maritime, de prot\u00e9ger l\u2019environnement marin, de promouvoir la recherche, la sensibilisation et le partage des connaissances, et de d\u00e9velopper la coop\u00e9ration r\u00e9gionale et internationale, selon un reportage de Ghana Web.<\/p>\n<p>Godred Sowah Khartey, associ\u00e9 de l\u2019organisation CEMLAWS Africa qui encourage la s\u00e9curit\u00e9 maritime, d\u00e9clare qu\u2019il pense que la strat\u00e9gie affrontera efficacement les crimes maritimes et aidera \u00e0 am\u00e9liorer les moyens de subsistance des communaut\u00e9s c\u00f4ti\u00e8res du Ghana.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF \u00a0 \u00a0 En septembre dernier, la Marine du Ghana a r\u00e9ceptionn\u00e9 deux navires patrouilleurs du type Defender, qui am\u00e9lioreront sa capacit\u00e9 de lutte contre la p\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e (INN), le trafic de drogue, la contrebande des armes, la piraterie, le vol \u00e0 main arm\u00e9e en mer et autres crimes<\/p>\n","protected":false},"author":1,"featured_media":119871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[433,969,554,1028],"class_list":{"0":"post-119874","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-ghana-fr","9":"tag-marine","10":"tag-maritime-fr","11":"tag-piraterie"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF \u00a0 \u00a0 En septembre dernier, la Marine du Ghana a r\u00e9ceptionn\u00e9 deux navires patrouilleurs du type Defender, qui am\u00e9lioreront sa capacit\u00e9 de lutte contre la p\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e (INN), le trafic de drogue, la contrebande des armes, la piraterie, le vol \u00e0 main arm\u00e9e en mer et autres crimes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-29T19:52:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T19:53:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes\",\"datePublished\":\"2024-10-29T19:52:06+00:00\",\"dateModified\":\"2024-10-31T19:53:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/\"},\"wordCount\":883,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/DEFENDER-BOATS-ONE.jpg\",\"keywords\":[\"Ghana\",\"Marine\",\"maritime\",\"piraterie\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/\",\"name\":\"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/DEFENDER-BOATS-ONE.jpg\",\"datePublished\":\"2024-10-29T19:52:06+00:00\",\"dateModified\":\"2024-10-31T19:53:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/DEFENDER-BOATS-ONE.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/DEFENDER-BOATS-ONE.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Le contre-amiral Issah Adam Yakubu, chef d\u2019\u00e9tat-major de la Marine ghan\u00e9enne, s\u2019exprime lors de la livraison de deux navires patrouilleurs Defender par le gouvernement des \u00c9tats-Unis. FORCES ARM\u00c9ES DU GHANA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/10\\\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF \u00a0 \u00a0 En septembre dernier, la Marine du Ghana a r\u00e9ceptionn\u00e9 deux navires patrouilleurs du type Defender, qui am\u00e9lioreront sa capacit\u00e9 de lutte contre la p\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e (INN), le trafic de drogue, la contrebande des armes, la piraterie, le vol \u00e0 main arm\u00e9e en mer et autres crimes","og_url":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-10-29T19:52:06+00:00","article_modified_time":"2024-10-31T19:53:13+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes","datePublished":"2024-10-29T19:52:06+00:00","dateModified":"2024-10-31T19:53:13+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/"},"wordCount":883,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg","keywords":["Ghana","Marine","maritime","piraterie"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/","url":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/","name":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg","datePublished":"2024-10-29T19:52:06+00:00","dateModified":"2024-10-31T19:53:13+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/10\/DEFENDER-BOATS-ONE.jpg","width":1080,"height":720,"caption":"Le contre-amiral Issah Adam Yakubu, chef d\u2019\u00e9tat-major de la Marine ghan\u00e9enne, s\u2019exprime lors de la livraison de deux navires patrouilleurs Defender par le gouvernement des \u00c9tats-Unis. FORCES ARM\u00c9ES DU GHANA"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2024\/10\/le-ghana-receptionne-deux-navires-patrouilleurs-defender-pour-faire-face-aux-menaces-maritimes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Le Ghana r\u00e9ceptionne deux navires patrouilleurs Defender pour faire face aux menaces maritimes"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/119874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=119874"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/119874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/119871"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=119874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=119874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=119874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}