{"id":11751,"date":"2019-01-17T21:17:12","date_gmt":"2019-01-17T21:17:12","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=11751"},"modified":"2019-02-07T17:08:24","modified_gmt":"2019-02-07T17:08:24","slug":"la-cdaa-presente-un-front-commun-dans-la-lutte-contre-le-braconnage","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2019\/01\/la-cdaa-presente-un-front-commun-dans-la-lutte-contre-le-braconnage\/","title":{"rendered":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN  DANS LA LUTTE CONTRE LE BRACONNAGE"},"content":{"rendered":"<p>DEFENCEWEB<\/p>\n<p>Six \u00e9tats de la Communaut\u00e9 de d\u00e9veloppement d\u2019Afrique australe (CDAA) ont convenu de renforcer leur coop\u00e9ration pour combattre le fl\u00e9au du braconnage, notamment celui des rhinoc\u00e9ros et des \u00e9l\u00e9phants.<\/p>\n<p>Ces pays \u2013 l\u2019Afrique du Sud, le Botswana, le Mozambique, la Namibie et le Zimbabwe \u2013 se sont r\u00e9unis \u00e0 Mpumalanga (Afrique du Sud) pour la quatri\u00e8me r\u00e9union multilat\u00e9rale des chefs de la d\u00e9fense et de la s\u00e9curit\u00e9 sur la lutte contre le braconnage. Lors de la r\u00e9union, le g\u00e9n\u00e9ral Solly Shoke, chef de la Force nationale de d\u00e9fense d\u2019Afrique du Sud (SANDF), a d\u00e9clar\u00e9 qu\u2019ils \u00e9taient \u00ab des \u00e9tats membres tr\u00e8s unis \u00bb et qu\u2019ils devaient adresser collectivement le braconnage pour trouver une solution commune \u00e0 long terme.<\/p>\n<p>Apr\u00e8s plusieurs ann\u00e9es d\u2019augmentation, l\u2019Afrique du Sud a enregistr\u00e9 une l\u00e9g\u00e8re baisse du nombre de rhinoc\u00e9ros victimes du braconnage en 2017, de 1.054 \u00e0 1.028. Mais cela correspond toujours \u00e0 trois rhinoc\u00e9ros tu\u00e9s chaque jour.<\/p>\n<p>La ministre sud-africaine des Affaires environnementales Edna Molewa a d\u00e9clar\u00e9 aux chefs r\u00e9unis du bloc r\u00e9gional que la collaboration en mati\u00e8re de conservation de la faune sauvage et de mise en application des lois est cruciale.<\/p>\n<p>\u00ab La r\u00e9gion de la CDAA est unique et pourvue d\u2019une faune sauvage abondante, a-t-elle d\u00e9clar\u00e9. Cela la rend sujette \u00e0 des menaces quotidiennes de braconnage. En cons\u00e9quence, la collaboration et la coordination des efforts de mise en application des lois sont cruciales pour pr\u00e9server l\u2019int\u00e9grit\u00e9 \u00e9cologique de la r\u00e9gion. \u00bb<\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<\/span>Elle a ajout\u00e9 que la coop\u00e9ration transnationale inclurait le partage de la technologie, la formation, les op\u00e9rations conjointes et les centres op\u00e9rationnels conjoints, le partage des informations et les syst\u00e8mes de communication communs.<\/p>\n<p>Mme Molewa a d\u00e9clar\u00e9 qu\u2019il \u00e9tait important que \u00ab des mesures judiciaires soient trouv\u00e9es pour assurer la standardisation des punitions inflig\u00e9es aux braconniers condamn\u00e9s de la r\u00e9gion \u00bb.<\/p>\n<p>La CDAA \u00e9tudie la poursuite des braconniers \u00e0 travers les fronti\u00e8res et les op\u00e9rations conjointes pour arr\u00eater les braconniers et confisquer les armes.<\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<\/span>Avant la r\u00e9union, le lieutenant-g\u00e9n\u00e9ral Barney Hlatshwayo, chef de la division des op\u00e9rations conjointes des SANDF, a d\u00e9clar\u00e9 que les criminels trouveront des points faibles en Afrique australe si la poursuite des crimes contre la faune sauvage n\u2019est pas uniforme.<\/p>\n<p>\u00ab Cela est d\u00fb au fait que les animaux franchissent les fronti\u00e8res. Ils ne connaissent pas les d\u00e9marcations cr\u00e9\u00e9es par les humains. De m\u00eame, les criminels qui attaquent la faune sauvage franchiront les fronti\u00e8res en sachant que, s\u2019ils sont arr\u00eat\u00e9s, il leur sera possible d\u2019obtenir une condamnation moins s\u00e9v\u00e8re dans certains pays \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DEFENCEWEB Six \u00e9tats de la Communaut\u00e9 de d\u00e9veloppement d\u2019Afrique australe (CDAA) ont convenu de renforcer leur coop\u00e9ration pour combattre le fl\u00e9au du braconnage, notamment celui des rhinoc\u00e9ros et des \u00e9l\u00e9phants. Ces pays \u2013 l\u2019Afrique du Sud, le Botswana, le Mozambique, la Namibie et le Zimbabwe \u2013 se sont r\u00e9unis \u00e0 Mpumalanga (Afrique du Sud) pour<\/p>\n","protected":false},"author":1,"featured_media":11612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[51,40],"tags":[],"class_list":{"0":"post-11751","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-defense-et-securite","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"DEFENCEWEB Six \u00e9tats de la Communaut\u00e9 de d\u00e9veloppement d\u2019Afrique australe (CDAA) ont convenu de renforcer leur coop\u00e9ration pour combattre le fl\u00e9au du braconnage, notamment celui des rhinoc\u00e9ros et des \u00e9l\u00e9phants. Ces pays \u2013 l\u2019Afrique du Sud, le Botswana, le Mozambique, la Namibie et le Zimbabwe \u2013 se sont r\u00e9unis \u00e0 Mpumalanga (Afrique du Sud) pour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T21:17:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-07T17:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE\",\"datePublished\":\"2019-01-17T21:17:12+00:00\",\"dateModified\":\"2019-02-07T17:08:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/\"},\"wordCount\":488,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/RTS1CVWQ.jpg\",\"articleSection\":[\"D\u00e9fense et s\u00e9curit\u00e9\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/\",\"name\":\"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/RTS1CVWQ.jpg\",\"datePublished\":\"2019-01-17T21:17:12+00:00\",\"dateModified\":\"2019-02-07T17:08:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/RTS1CVWQ.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/RTS1CVWQ.jpg\",\"width\":1080,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/2019\\\/01\\\/sadc-shows-united-front-in-poaching-fight\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/","og_locale":"fr_FR","og_type":"article","og_title":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum","og_description":"DEFENCEWEB Six \u00e9tats de la Communaut\u00e9 de d\u00e9veloppement d\u2019Afrique australe (CDAA) ont convenu de renforcer leur coop\u00e9ration pour combattre le fl\u00e9au du braconnage, notamment celui des rhinoc\u00e9ros et des \u00e9l\u00e9phants. Ces pays \u2013 l\u2019Afrique du Sud, le Botswana, le Mozambique, la Namibie et le Zimbabwe \u2013 se sont r\u00e9unis \u00e0 Mpumalanga (Afrique du Sud) pour","og_url":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2019-01-17T21:17:12+00:00","article_modified_time":"2019-02-07T17:08:24+00:00","og_image":[{"width":1080,"height":705,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE","datePublished":"2019-01-17T21:17:12+00:00","dateModified":"2019-02-07T17:08:24+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/"},"wordCount":488,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg","articleSection":["D\u00e9fense et s\u00e9curit\u00e9","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/","url":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/","name":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg","datePublished":"2019-01-17T21:17:12+00:00","dateModified":"2019-02-07T17:08:24+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2019\/01\/RTS1CVWQ.jpg","width":1080,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/2019\/01\/sadc-shows-united-front-in-poaching-fight\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/"},{"@type":"ListItem","position":2,"name":"LA CDAA PR\u00c9SENTE UN FRONT COMMUN DANS LA LUTTE CONTRE LE BRACONNAGE"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/11751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=11751"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/11751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/11612"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=11751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=11751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=11751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}