{"id":115030,"date":"2024-06-04T14:12:58","date_gmt":"2024-06-04T18:12:58","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=115030"},"modified":"2024-06-04T14:13:17","modified_gmt":"2024-06-04T18:13:17","slug":"le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/","title":{"rendered":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">PERSONNEL D\u2019ADF<br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\nSouleymane Faye, p\u00eacheur s\u00e9n\u00e9galais \u00e0 la retraite, observait avec consternation un groupe de p\u00eacheurs artisanaux \u00e9puis\u00e9s par leur travail qui amenaient leurs pirogues aux couleurs vives vers le rivage de Bargny, \u00e0 environ 15\u00a0km \u00e0 l\u2019Est de Dakar.<\/span><\/p>\n<p>\u00ab\u00a0Regardez, ils viennent d\u2019arriver\u00a0\u00bb, a dit M.\u00a0Faye \u00e0 Reuters en mars dernier. En examinant l\u2019int\u00e9rieur des bo\u00eetes utilis\u00e9es pour transporter la prise, il a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Il n\u2019y a rien.\u00a0\u00bb<\/p>\n<p>Les r\u00e9sidents locaux bl\u00e2ment depuis longtemps les chalutiers industriels \u00e9trangers, pour la plupart chinois, pour d\u00e9cimer les stocks de poissons en utilisant des pratiques de p\u00eache ill\u00e9gales, non signal\u00e9es et non r\u00e9glement\u00e9es (INN). Selon l\u2019Environmental Justice Foundation (EJF), le S\u00e9n\u00e9gal perd plus de 270\u00a0millions de dollars de revenu chaque ann\u00e9e \u00e0 cause de la p\u00eache ill\u00e9gale.<\/p>\n<p>Malick Seck, p\u00eacheur de Fass Boye, d\u00e9clare \u00e0 l\u2019EJF\u00a0: \u00ab\u00a0L\u2019abondance qui existait jadis est en diminution. \u00c0 cette allure, nous ne pourrons pas survivre.\u00a0\u00bb<\/p>\n<p>Apr\u00e8s plusieurs ann\u00e9es de critiques sur la gouvernance m\u00e9diocre de son secteur de la p\u00eache, le gouvernement du S\u00e9n\u00e9gal sous son nouveau pr\u00e9sident, Bassirou Diomaye\u00a0<span style=\"font-weight: 400;\"><a href=\"https:\/\/www.aljazeera.com\/news\/2024\/3\/25\/senegal-election-results-who-is-diomaye-faye-tipped-to-be-next-president\">Faye<\/a><\/span><span style=\"font-weight: 400;\">, a introduit en mai une s\u00e9rie de mesures pour r\u00e9duire la p\u00eache INN, en commen\u00e7ant par la publication d\u2019une liste de navires autoris\u00e9s \u00e0 p\u00eacher dans les eaux territoriales<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>Cette liste comporte 132\u00a0chalutiers nationaux et 19\u00a0\u00e9trangers. Le registre, qui vise \u00e0 am\u00e9liorer la transparence sur la gestion des ressources naturelles, comporte les noms des navires, leur propri\u00e9taire, leur capacit\u00e9, le type de p\u00eache qu\u2019ils sont autoris\u00e9s \u00e0 pratiquer et la taille des filets qu\u2019ils peuvent utiliser, selon le Maritime Executive.<\/p>\n<p>La mesure \u00ab\u00a0refl\u00e8te le principe de la transparence dans la gestion des ressources nationales, qui sont un h\u00e9ritage national\u00a0\u00bb, a d\u00e9clar\u00e9 Fatou Diouf, ministre des P\u00eaches, des Infrastructures maritimes et portuaires, dans un rapport publi\u00e9 par la Conf\u00e9d\u00e9ration africaine des organisations de p\u00eache artisanale (CAOPA).<\/p>\n<p>En plus de la publication de la liste des navires approuv\u00e9s, le Conseil des ministres du S\u00e9n\u00e9gal pr\u00e9sid\u00e9 par M.\u00a0Faye a fait appel au renforcement du Code de la p\u00eache maritime du pays. Le pr\u00e9sident a aussi demand\u00e9 un inventaire et une \u00e9valuation de l\u2019intervention de l\u2019\u00c9tat, des subsides et du financement du secteur de la p\u00eache, selon le Maritime Executive.<\/p>\n<p>Aliou Ba, gestionnaire de la campagne des oc\u00e9ans pour Greenpeace, a applaudi les mesures.<\/p>\n<p>\u00ab\u00a0Donc nous exhortons maintenant l\u2019\u00e9tat \u00e0 v\u00e9rifier cette liste et \u00e0 examiner la question des pavillons s\u00e9n\u00e9galais pour que nous puissions comprendre comment ces navires ont \u00e9t\u00e9 capables d\u2019acqu\u00e9rir des permis de p\u00eache et comment ils ont pu pr\u00e9tendre \u00eatre des navires s\u00e9n\u00e9galais et pratiquer leurs activit\u00e9s dans les zones s\u00e9n\u00e9galaises\u00a0\u00bb, d\u00e9clare M. Ba sur France 24.<\/p>\n<p>Les chalutiers chinois sont bien connus pour \u00ab\u00a0emprunter\u00a0\u00bb le pavillon d\u2019un pays africain, ce qui veut dire qu\u2019ils utilisent les r\u00e8gles locales et les abusent pour inscrire un vaisseau de p\u00eache appartenant et g\u00e9r\u00e9 par une soci\u00e9t\u00e9 \u00e9trang\u00e8re sur un registre africain afin de p\u00eacher dans les eaux locales. Cette pratique indique fr\u00e9quemment que les navires s\u2019engagent dans la p\u00eache ill\u00e9gale.<\/p>\n<p>La Chine est le pire contrevenant mondial de la p\u00eache INN, selon l\u2019Indice de p\u00eache INN. Parmi les dix premi\u00e8res soci\u00e9t\u00e9s pratiquant la p\u00eache ill\u00e9gale dans le monde, huit sont chinoises.<\/p>\n<p>La surexploitation des p\u00eaches par la Chine et d\u2019autres pays est catastrophique pour le S\u00e9n\u00e9gal et l\u2019Afrique de l\u2019Ouest. Environ 20\u00a0% des poissons attrap\u00e9s ill\u00e9galement proviennent des eaux c\u00f4ti\u00e8res de Gambie, Guin\u00e9e, Guin\u00e9e-Bissau, Mauritanie, S\u00e9n\u00e9gal et Sierra Leone, selon un reportage de l\u2019organisation de presse Investigative Journalism Reportika.<\/p>\n<p>\u00c0 cause de la p\u00eache ill\u00e9gale, les p\u00eacheurs artisanaux du S\u00e9n\u00e9gal d\u00e9clarent que leur prise a chut\u00e9 de 58\u00a0% entre 2012 et 2019, selon un rapport de l\u2019EJF publi\u00e9 en 2023. 78\u00a0% des p\u00eacheurs et des traiteurs de poissons interview\u00e9s par l\u2019EJF d\u00e9clarent qu\u2019il leur est de plus en plus difficile de nourrir leur famille.<\/p>\n<p>Arona Boye, p\u00eacheur de Fass Boye, d\u00e9clare \u00e0 l\u2019EJF\u00a0: \u00ab\u00a0Dans chaque tente de p\u00eacheur o\u00f9 vous allez, le sujet de discussion est la p\u00e9nurie de poisson. Les navires attrapent tout ce que nous sommes cens\u00e9s attraper. Vous allez p\u00eacher, vous lancez vos filets et vous n\u2019attrapez rien.\u00a0\u00bb<\/p>\n<p>En plus de l\u2019emprunt de pavillon, l\u2019emploi des filets interdits, la p\u00eache aux explosifs et la p\u00eache dans les zones interdites, les chalutiers chinois au S\u00e9n\u00e9gal pratiquent aussi couramment le chalut de fond, qui ramasse sans discrimination toutes les esp\u00e8ces de faune marine.<\/p>\n<p>Sell\u00e9 Mbengue, directeur de la gestion et l\u2019exploitation de haute mer pour le minist\u00e8re s\u00e9n\u00e9galais de la P\u00eache, d\u00e9clare \u00e0 l\u2019EJF\u00a0: \u00ab\u00a0Le chalut de fond est un activit\u00e9 que les gestionnaires des fonds marins veulent changer. Non seulement il d\u00e9truit les habitats, mais il nuit aussi \u00e0 l\u2019\u00e9cosyst\u00e8me des fonds marins, et nous n\u00e9cessitons un \u00e9cosyst\u00e8me des fonds marins avec ses habitats et toute sa richesse naturelle.\u00a0\u00bb<\/p>\n<p>En 2023, pr\u00e8s de 100\u00a0navires de p\u00eache pratiquaient le chalut de fond au S\u00e9n\u00e9gal, selon la fondation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF Souleymane Faye, p\u00eacheur s\u00e9n\u00e9galais \u00e0 la retraite, observait avec consternation un groupe de p\u00eacheurs artisanaux \u00e9puis\u00e9s par leur travail qui amenaient leurs pirogues aux couleurs vives vers le rivage de Bargny, \u00e0 environ 15\u00a0km \u00e0 l\u2019Est de Dakar. \u00ab\u00a0Regardez, ils viennent d\u2019arriver\u00a0\u00bb, a dit M.\u00a0Faye \u00e0 Reuters en mars dernier. En examinant l\u2019int\u00e9rieur<\/p>\n","protected":false},"author":1,"featured_media":115024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[1780,1786,1713],"class_list":{"0":"post-115030","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-afrique-de-louest-fr","9":"tag-chine-fr","10":"tag-senegal-fr-2"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF Souleymane Faye, p\u00eacheur s\u00e9n\u00e9galais \u00e0 la retraite, observait avec consternation un groupe de p\u00eacheurs artisanaux \u00e9puis\u00e9s par leur travail qui amenaient leurs pirogues aux couleurs vives vers le rivage de Bargny, \u00e0 environ 15\u00a0km \u00e0 l\u2019Est de Dakar. \u00ab\u00a0Regardez, ils viennent d\u2019arriver\u00a0\u00bb, a dit M.\u00a0Faye \u00e0 Reuters en mars dernier. En examinant l\u2019int\u00e9rieur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T18:12:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T18:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN\",\"datePublished\":\"2024-06-04T18:12:58+00:00\",\"dateModified\":\"2024-06-04T18:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/\"},\"wordCount\":957,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GettyImages-2152628113.jpg\",\"keywords\":[\"Afrique de l\u2019Ouest\",\"Chine\",\"S\u00e9n\u00e9gal\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/\",\"name\":\"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GettyImages-2152628113.jpg\",\"datePublished\":\"2024-06-04T18:12:58+00:00\",\"dateModified\":\"2024-06-04T18:13:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GettyImages-2152628113.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/GettyImages-2152628113.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Des porteurs s\u00e9n\u00e9galais attendent l\u2019arriv\u00e9e des p\u00eacheurs locaux \u00e0 Cap Skirring. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/06\\\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/","og_locale":"fr_FR","og_type":"article","og_title":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF Souleymane Faye, p\u00eacheur s\u00e9n\u00e9galais \u00e0 la retraite, observait avec consternation un groupe de p\u00eacheurs artisanaux \u00e9puis\u00e9s par leur travail qui amenaient leurs pirogues aux couleurs vives vers le rivage de Bargny, \u00e0 environ 15\u00a0km \u00e0 l\u2019Est de Dakar. \u00ab\u00a0Regardez, ils viennent d\u2019arriver\u00a0\u00bb, a dit M.\u00a0Faye \u00e0 Reuters en mars dernier. En examinant l\u2019int\u00e9rieur","og_url":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-06-04T18:12:58+00:00","article_modified_time":"2024-06-04T18:13:17+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN","datePublished":"2024-06-04T18:12:58+00:00","dateModified":"2024-06-04T18:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/"},"wordCount":957,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg","keywords":["Afrique de l\u2019Ouest","Chine","S\u00e9n\u00e9gal"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/","url":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/","name":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg","datePublished":"2024-06-04T18:12:58+00:00","dateModified":"2024-06-04T18:13:17+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/06\/GettyImages-2152628113.jpg","width":1024,"height":683,"caption":"Des porteurs s\u00e9n\u00e9galais attendent l\u2019arriv\u00e9e des p\u00eacheurs locaux \u00e0 Cap Skirring. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2024\/06\/le-senegal-publie-une-liste-de-navires-autorises-pour-stopper-la-peche-inn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Le S\u00e9n\u00e9gal publie une liste de navires autoris\u00e9s pour stopper la p\u00eache INN"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/115030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=115030"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/115030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/115024"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=115030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=115030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=115030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}