{"id":112216,"date":"2024-01-30T13:57:29","date_gmt":"2024-01-30T18:57:29","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=112216"},"modified":"2024-01-30T13:58:02","modified_gmt":"2024-01-30T18:58:02","slug":"le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/","title":{"rendered":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques"},"content":{"rendered":"<p style=\"font-weight: 400;\">PERSONNEL D\u2019ADF<\/p>\n<p style=\"font-weight: 400;\">Le soutien des \u00c9mirats arabes unis aux Forces de soutien rapide (RSF) dans la guerre civile du Soudan suscite des critiques de la part des observateurs qui disent qu\u2019il attise les flammes de la violence.<\/p>\n<p style=\"font-weight: 400;\">Le soutien des \u00c9mirats pour le g\u00e9n\u00e9ral Mohamed Hamdan Dogolo alias Hemeti, chef des RSF, a jou\u00e9 un r\u00f4le cl\u00e9 dans ses succ\u00e8s sur le champ de bataille, selon Giorgio Cafiero, PDG de la firme de consulting de risque Gulf State Analytics.<\/p>\n<p style=\"font-weight: 400;\">Vers la mi-d\u00e9cembre 2023, les combattants des RSF ont saisi Wad Madani, capitale de l\u2019\u00c9tat d\u2019Al-Jazirah, au c\u0153ur de la r\u00e9gion agricole du Soudan. Les Forces arm\u00e9es soudanaises (SAF) ont offert peu de r\u00e9sistance. Cette ville au Sud-Ouest de Khartoum \u00e9tait devenue un refuge pour les gens et les entreprises, telles que celles du secteur bancaire, qui fuyaient la violence dans la r\u00e9gion de la capitale.<\/p>\n<p style=\"font-weight: 400;\">Le g\u00e9n\u00e9ral Abdel Fattah al-Burhan, commandant des SAF, a adopt\u00e9 une position dure contre les EAU, en expulsant quinze diplomates \u00e9miriens en d\u00e9cembre \u00e0 cause du soutien continu accord\u00e9 aux RSF par le pays.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Jusqu\u2019\u00e0 r\u00e9cemment, le camp de Burhan se comportait avec prudence et diplomatie, en \u00e9vitant les confrontations verbales directes contre les acteurs cl\u00e9s tels que [le mar\u00e9chal Khalifa] Haftar de Libye, la Russie et Abou Dabi\u00a0\u00bb, d\u00e9clare Jalel Harchaoui, chercheur associ\u00e9 du Royal United Services Institute (RUSI), \u00e0 l\u2019Agence France-Presse.<\/p>\n<p style=\"font-weight: 400;\">Le mar\u00e9chal Haftar, les mercenaires du groupe Wagner de Russie et les \u00c9mirats ont tous des liens avec les RSF, et avec Hemeti personnellement. Le mar\u00e9chal et la Wagner ont fourni des armes aux RSF d\u00e8s le d\u00e9but du conflit en utilisant les a\u00e9ronefs de Wagner bas\u00e9s dans le Sud de la Libye. La Wagner, r\u00e9cemment rebaptis\u00e9e du nom d\u2019Africa Corps, et les EAU ont aussi une relation de longue date avec Hemeti gr\u00e2ce \u00e0 l\u2019extraction et la contrebande de l\u2019or provenant des mines Jebel Amer du Darfour, contr\u00f4l\u00e9es par Hemeti. La majeure partie de cet or aboutit aux \u00c9mirats o\u00f9 il entre sur le march\u00e9 international.<\/p>\n<p style=\"font-weight: 400;\">Hemeti maintient ses finances, et celles des RSF, dans les EAU, o\u00f9 sont aussi h\u00e9berg\u00e9s les r\u00e9seaux sociaux de propagande des RSF. En 2019, quatre ans avant le d\u00e9but du conflit avec les SAF, Hemeti avait achet\u00e9 1.000\u00a0v\u00e9hicules aupr\u00e8s des \u00c9mirats qui pouvaient \u00eatre transform\u00e9s en \u00ab\u00a0technicals\u00a0\u00bb \u00e9quip\u00e9s de mitrailleuse. La soci\u00e9t\u00e9 de la famille Dogolo qui avait achet\u00e9 ces v\u00e9hicules, Tradive General Trading, est aussi bas\u00e9e aux EAU.<\/p>\n<p style=\"font-weight: 400;\">Aujourd\u2019hui, d\u00e9clarent les leaders du Soudan, les \u00c9mirats envoient aux RSF plus que des transports terrestres.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Selon des renseignements provenant de l\u2019agence de renseignements, de celle des renseignements militaires et du circuit diplomatique, les EAU envoient des avions pour soutenir les Janjawids [RSF]\u00a0\u00bb, a d\u00e9clar\u00e9 M.\u00a0Al-Atta lors d\u2019un discours devant les membres du service g\u00e9n\u00e9ral des renseignements \u00e0 Omdourman en novembre 2023.<\/p>\n<p style=\"font-weight: 400;\">Selon le chercheur Mohamed Suliman, les accusations r\u00e9centes du Soudan co\u00efncident avec les liens entre les \u00c9mirats et les RSF.<\/p>\n<p>Suliman, qui \u00e9tudie les tactiques des RSF, a r\u00e9cemment \u00e9crit sur le site web Politics Today\u00a0: \u00ab\u00a0Le soutien des EAU pour la milice [RSF] prend des formes vari\u00e9es, depuis le financement direct jusqu\u2019\u00e0 la logistique et l\u2019\u00e9quipement militaire. Ce soutien militaire a fourni aux milices les outils n\u00e9cessaires pour commettre des crimes innombrables.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">L\u2019analyste Nasim Ahmed \u00e9crit pour le Middle East Monitor que les actions des \u00c9mirats aident \u00e0 faire avancer leurs propres int\u00e9r\u00eats au Soudan en leur assurant un acc\u00e8s \u00e0 l\u2019or et aux autres ressources naturelles de ce pays. Le soutien des RSF donne aussi aux EAU une influence contre les pays tels que l\u2019\u00c9gypte et l\u2019Arabie saoudite, lesquels soutiennent les SAF, selon M.\u00a0Ahmed.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Plut\u00f4t que de promouvoir la stabilit\u00e9 et la s\u00e9curit\u00e9, les actions des EAU contribuent \u00e0 la rupture des n\u00e9gociations et la mont\u00e9e des acteurs non \u00e9tatiques violents.\u00a0\u00bb.<\/p>\n<p style=\"font-weight: 400;\">Alors que le conflit entre les SAF et les RSF continue lentement, le soutien des agents ext\u00e9rieurs, et particuli\u00e8rement des \u00c9mirats, est devenu extr\u00eamement important alors que la communaut\u00e9 internationale r\u00e9clame un cessez-le-feu, selon Alex de Waal, directeur de la World Peace Foundation.<\/p>\n<p style=\"font-weight: 400;\">Ce dernier d\u00e9clare \u00e0 Al-Jazeera\u00a0: \u00ab\u00a0Ce que les efforts de paix n\u2019ont pas r\u00e9ussi \u00e0 faire pour le moment, c\u2019est d\u2019amener ces puissances ext\u00e9rieures de soutien, en particulier les EAU, \u00e0 la table des n\u00e9gociations d\u2019une mani\u00e8re ou d\u2019une autre. Tant que cela ne se produit pas, il est tr\u00e8s improbable que la guerre puisse \u00eatre r\u00e9solue.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF Le soutien des \u00c9mirats arabes unis aux Forces de soutien rapide (RSF) dans la guerre civile du Soudan suscite des critiques de la part des observateurs qui disent qu\u2019il attise les flammes de la violence. Le soutien des \u00c9mirats pour le g\u00e9n\u00e9ral Mohamed Hamdan Dogolo alias Hemeti, chef des RSF, a jou\u00e9 un<\/p>\n","protected":false},"author":1,"featured_media":112209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[1295,1182,1181],"class_list":{"0":"post-112216","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-civil-war-fr","9":"tag-coups-fr","10":"tag-sudan-fr"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF Le soutien des \u00c9mirats arabes unis aux Forces de soutien rapide (RSF) dans la guerre civile du Soudan suscite des critiques de la part des observateurs qui disent qu\u2019il attise les flammes de la violence. Le soutien des \u00c9mirats pour le g\u00e9n\u00e9ral Mohamed Hamdan Dogolo alias Hemeti, chef des RSF, a jou\u00e9 un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T18:57:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T18:58:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques\",\"datePublished\":\"2024-01-30T18:57:29+00:00\",\"dateModified\":\"2024-01-30T18:58:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/\"},\"wordCount\":819,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg\",\"keywords\":[\"civil war\",\"coups\",\"Sudan\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/\",\"name\":\"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg\",\"datePublished\":\"2024-01-30T18:57:29+00:00\",\"dateModified\":\"2024-01-30T18:58:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg\",\"width\":1080,\"height\":708,\"caption\":\"Combattants des Forces de soutien rapide du Soudan, sur des \u00ab technicals \u00bb achet\u00e9s aupr\u00e8s des \u00c9mirats arabes unis en 2019. Selon les observateurs, ceci indique les liens profonds entre les RSF et les EAU dans leur conflit avec les Forces arm\u00e9es soudanaises. REUTERS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2024\\\/01\\\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF Le soutien des \u00c9mirats arabes unis aux Forces de soutien rapide (RSF) dans la guerre civile du Soudan suscite des critiques de la part des observateurs qui disent qu\u2019il attise les flammes de la violence. Le soutien des \u00c9mirats pour le g\u00e9n\u00e9ral Mohamed Hamdan Dogolo alias Hemeti, chef des RSF, a jou\u00e9 un","og_url":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2024-01-30T18:57:29+00:00","article_modified_time":"2024-01-30T18:58:02+00:00","og_image":[{"width":1080,"height":708,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques","datePublished":"2024-01-30T18:57:29+00:00","dateModified":"2024-01-30T18:58:02+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/"},"wordCount":819,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg","keywords":["civil war","coups","Sudan"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/","url":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/","name":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg","datePublished":"2024-01-30T18:57:29+00:00","dateModified":"2024-01-30T18:58:02+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2024\/01\/2019-09-25T175844Z_216133569_RC1549D684E0_RTRMADP_3_SUDAN-IMMIGRATION.jpg","width":1080,"height":708,"caption":"Combattants des Forces de soutien rapide du Soudan, sur des \u00ab technicals \u00bb achet\u00e9s aupr\u00e8s des \u00c9mirats arabes unis en 2019. Selon les observateurs, ceci indique les liens profonds entre les RSF et les EAU dans leur conflit avec les Forces arm\u00e9es soudanaises. REUTERS"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2024\/01\/le-role-des-eau-dans-la-guerre-civile-du-soudan-suscite-des-critiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Le r\u00f4le des EAU dans la guerre civile du Soudan suscite des critiques"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/112216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=112216"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/112216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/112209"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=112216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=112216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=112216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}