{"id":111739,"date":"2023-12-21T09:19:09","date_gmt":"2023-12-21T14:19:09","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=111739"},"modified":"2024-01-01T08:40:46","modified_gmt":"2024-01-01T13:40:46","slug":"point-de-vue-37","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/","title":{"rendered":"Point De Vue"},"content":{"rendered":"<p>Personnel de l\u2019\u00e9tat-major unifi\u00e9 des \u00c9tats-Unis pour l\u2019Afrique<\/p>\n<p>Lorsque les relations civilo-militaires sont d\u00e9s\u00e9quilibr\u00e9es, une nation enti\u00e8re peut sombrer dans le chaos.<\/p>\n<p>Au cours des derni\u00e8res ann\u00e9es, l\u2019Afrique a \u00e9t\u00e9 affect\u00e9e par une s\u00e9rie de coups d\u2019\u00c9tat militaires. Le Burkina Faso, le Gabon, la Guin\u00e9e, le Mali, le Niger et le Soudan ont tous subi un transfert de pouvoir non d\u00e9mocratique. Les d\u00e9tails sont diff\u00e9rents pour chaque pays mais le mod\u00e8le est le m\u00eame. Les putschistes justifient leurs actions en accusant les gouvernements d\u2019\u00eatre inefficaces, corrompus et autoritaires. Les chefs civils destitu\u00e9s bl\u00e2ment les soldats assoiff\u00e9s de pouvoir. Le coup d\u2019\u00c9tat laisse le pays avec moins de s\u00e9curit\u00e9 et un isolement diplomatique.<\/p>\n<p>Les experts d\u00e9clarent que les coups d\u2019\u00c9tat sont le sympt\u00f4me d\u2019un plus grand dysfonctionnement dans la dynamique civilo-militaire. Lorsqu\u2019elle fonctionne correctement, la relation est une aubaine pour les citoyens, les \u00e9lus et les forces arm\u00e9es. Ils ont tous un r\u00f4le important \u00e0 jouer et ils peuvent tous b\u00e9n\u00e9ficier.<\/p>\n<p>Dans les arm\u00e9es efficaces, les membres des services sont form\u00e9s pour \u00eatre loyaux \u00e0 la constitution et pour rester apolitiques. La soumission \u00e0 l\u2019autorit\u00e9 civile est enseign\u00e9e pendant la formation de base et renforc\u00e9e dans toute la carri\u00e8re militaire. Les civils, \u00e0 leur tour, effectuent la supervision par l\u2019interm\u00e9diaire de m\u00e9canismes tels que les comit\u00e9s parlementaires, le secteur judiciaire, les groupes de la soci\u00e9t\u00e9 civile et les m\u00e9dias.<\/p>\n<p>Un grand nombre de pays africains ont fait de grands progr\u00e8s dans l\u2019institutionnalisation des relations civilo-militaires depuis les premi\u00e8res ann\u00e9es de leur ind\u00e9pendance, lorsque les dictatures militaires \u00e9taient courantes. Les pays investissent dans l\u2019\u00e9ducation militaire professionnelle. Ils s\u2019assurent que le secteur de la s\u00e9curit\u00e9 travaille pour le public gr\u00e2ce \u00e0 des efforts centr\u00e9s sur les civils, tels que la r\u00e9ponse aux catastrophes, la construction de l\u2019infrastructure et les projets humanitaires. Les organisations r\u00e9gionales \u0153uvrent pour solidifier les normes d\u00e9mocratiques et arbitrer en cas de dispute civilo-militaire.<\/p>\n<p>Mais il y a fort \u00e0 faire. Il existe toujours de nombreux cas dans lesquels les forces arm\u00e9es sont politis\u00e9es et agissent contrairement \u00e0 leurs obligations constitutionnelles. Les soldats qui sont souvent frustr\u00e9s par la corruption ou les pertes dans le combat contre l\u2019extr\u00e9misme violent consid\u00e8rent les coups d\u2019\u00c9tat comme une solution rapide.<\/p>\n<p>Le r\u00e9\u00e9quilibrage de cette relation est une t\u00e2che pansoci\u00e9tale mais les membres des forces arm\u00e9es restent la derni\u00e8re ligne de d\u00e9fense. Ils doivent renforcer leur professionnalisme et leur responsabilisation au sein de leurs rangs et r\u00e9sister \u00e0 toute tentation de saisir le pouvoir \u00e0 la pointe d\u2019un fusil. Lorsqu\u2019ils r\u00e9ussissent, les avantages se font sentir pour les g\u00e9n\u00e9rations \u00e0 venir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personnel de l\u2019\u00e9tat-major unifi\u00e9 des \u00c9tats-Unis pour l\u2019Afrique Lorsque les relations civilo-militaires sont d\u00e9s\u00e9quilibr\u00e9es, une nation enti\u00e8re peut sombrer dans le chaos. Au cours des derni\u00e8res ann\u00e9es, l\u2019Afrique a \u00e9t\u00e9 affect\u00e9e par une s\u00e9rie de coups d\u2019\u00c9tat militaires. Le Burkina Faso, le Gabon, la Guin\u00e9e, le Mali, le Niger et le Soudan ont tous subi<\/p>\n","protected":false},"author":1,"featured_media":111321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[61,40],"tags":[],"class_list":{"0":"post-111739","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-point-de-vue","8":"category-rubriques"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Point De Vue - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Point De Vue - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"Personnel de l\u2019\u00e9tat-major unifi\u00e9 des \u00c9tats-Unis pour l\u2019Afrique Lorsque les relations civilo-militaires sont d\u00e9s\u00e9quilibr\u00e9es, une nation enti\u00e8re peut sombrer dans le chaos. Au cours des derni\u00e8res ann\u00e9es, l\u2019Afrique a \u00e9t\u00e9 affect\u00e9e par une s\u00e9rie de coups d\u2019\u00c9tat militaires. Le Burkina Faso, le Gabon, la Guin\u00e9e, le Mali, le Niger et le Soudan ont tous subi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T14:19:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-01T13:40:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Point De Vue\",\"datePublished\":\"2023-12-21T14:19:09+00:00\",\"dateModified\":\"2024-01-01T13:40:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/\"},\"wordCount\":498,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Viewpoint_7960821_CMYK.jpg\",\"articleSection\":[\"Point de vue\",\"rubriques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/\",\"name\":\"Point De Vue - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Viewpoint_7960821_CMYK.jpg\",\"datePublished\":\"2023-12-21T14:19:09+00:00\",\"dateModified\":\"2024-01-01T13:40:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Viewpoint_7960821_CMYK.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Viewpoint_7960821_CMYK.jpg\",\"width\":1080,\"height\":718,\"caption\":\"U.S. Africa Command Staff\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/12\\\/point-de-vue-37\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Point De Vue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Point De Vue - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/","og_locale":"fr_FR","og_type":"article","og_title":"Point De Vue - Africa Defense Forum","og_description":"Personnel de l\u2019\u00e9tat-major unifi\u00e9 des \u00c9tats-Unis pour l\u2019Afrique Lorsque les relations civilo-militaires sont d\u00e9s\u00e9quilibr\u00e9es, une nation enti\u00e8re peut sombrer dans le chaos. Au cours des derni\u00e8res ann\u00e9es, l\u2019Afrique a \u00e9t\u00e9 affect\u00e9e par une s\u00e9rie de coups d\u2019\u00c9tat militaires. Le Burkina Faso, le Gabon, la Guin\u00e9e, le Mali, le Niger et le Soudan ont tous subi","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-12-21T14:19:09+00:00","article_modified_time":"2024-01-01T13:40:46+00:00","og_image":[{"width":1080,"height":718,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Point De Vue","datePublished":"2023-12-21T14:19:09+00:00","dateModified":"2024-01-01T13:40:46+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/"},"wordCount":498,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg","articleSection":["Point de vue","rubriques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/","name":"Point De Vue - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg","datePublished":"2023-12-21T14:19:09+00:00","dateModified":"2024-01-01T13:40:46+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/12\/Viewpoint_7960821_CMYK.jpg","width":1080,"height":718,"caption":"U.S. Africa Command Staff"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/12\/point-de-vue-37\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Point De Vue"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/111739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=111739"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/111739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/111321"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=111739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=111739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=111739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}