{"id":109705,"date":"2023-09-26T10:09:00","date_gmt":"2023-09-26T14:09:00","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=109705"},"modified":"2023-09-27T08:40:27","modified_gmt":"2023-09-27T12:40:27","slug":"les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/","title":{"rendered":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique"},"content":{"rendered":"<p style=\"font-weight: 400;\">PERSONNEL D\u2019ADF<\/p>\n<p style=\"font-weight: 400;\">L\u2019annonce par le pr\u00e9sident s\u00e9n\u00e9galais Macky Sall en juillet dernier selon laquelle il ne briguerait pas un troisi\u00e8me mandat a \u00e9t\u00e9 accueillie avec un m\u00e9lange de soulagement et d\u2019orgueil dans le pays, c\u00e9l\u00e8bre pour ses traditions d\u00e9mocratiques.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Une bombe \u00e0 retardement a \u00e9t\u00e9 d\u00e9samorc\u00e9e\u00a0\u00bb, a d\u00e9clar\u00e9 Alioune Tine, d\u00e9fenseur s\u00e9n\u00e9galais pro\u00e9minent des droits de l\u2019homme, au New York Times. \u00ab\u00a0C\u2019est un grand soulagement pour le S\u00e9n\u00e9gal et le continent africain.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">Le S\u00e9n\u00e9gal, seul pays d\u2019Afrique de l\u2019Ouest \u00e0 n\u2019avoir jamais subi de coup d\u2019\u00c9tat ou d\u2019attaque terroriste importante, est depuis longtemps un pilier de la stabilit\u00e9 r\u00e9gionale. Mais il existe des fissures qui commencent \u00e0 appara\u00eetre dans ce pilier.<\/p>\n<p style=\"font-weight: 400;\">Les tensions sont en hausse r\u00e9guli\u00e8re depuis quelques ann\u00e9es, notamment les manifestations contre le co\u00fbt \u00e9lev\u00e9 de la vie et les accusations de corruption gouvernementale syst\u00e9mique. Le S\u00e9n\u00e9gal est devenu une cible de choix pour l\u2019expansion des organisations extr\u00e9mistes violentes dans la r\u00e9gion du Sahel.<\/p>\n<p style=\"font-weight: 400;\">Ces m\u00eames conditions, notamment l\u2019instabilit\u00e9 et le m\u00e9contentement concernant le gouvernement, ont contribu\u00e9 \u00e0 une s\u00e9rie de coups d\u2019\u00c9tat r\u00e9cents qui ont tourment\u00e9 le Sahel et l\u2019Afrique de l\u2019Ouest.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0[Le S\u00e9n\u00e9gal] a toujours \u00e9t\u00e9 consid\u00e9r\u00e9 comme une \u201cexception africaine\u201d, un \u201cmod\u00e8le de d\u00e9mocratie\u201d, une nation unie qui peut s\u2019appuyer sur un \u00e9tat et des institutions en bon ordre\u00a0\u00bb, d\u00e9clare le sociologue Aly Baba Faye au magazine Focus on Africa. \u00ab\u00a0Toutefois, il semble faire aujourd\u2019hui l\u2019objet de d\u00e9bats sur une stabilit\u00e9 qui risque de s\u2019effondrer.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">La pand\u00e9mie de Covid-19 a aggrav\u00e9 l\u2019inflation, l\u2019endettement et le ch\u00f4mage. L\u2019invasion de l\u2019Ukraine par la Russie a provoqu\u00e9 des carences alimentaires, des hausses de prix de l\u2019essence et de l\u2019\u00e9lectricit\u00e9, et un m\u00e9contentement encore plus grand \u00e0 l\u2019\u00e9gard de M.\u00a0Sall et son gouvernement.<\/p>\n<p style=\"font-weight: 400;\">En 2022, le taux de pauvret\u00e9 au S\u00e9n\u00e9gal \u00e9tait de 36,3\u00a0%, selon la Banque mondiale. Le gouvernement a essay\u00e9 de faire plafonner les prix de certaines denr\u00e9es, les frais de scolarit\u00e9 et les loyers, mais les critiques sont rest\u00e9s indiff\u00e9rents.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0L\u2019\u00e9norme ch\u00f4mage des jeunes et la lassitude li\u00e9e aux scandales de corruption de Sall ont fait pencher la bascule vers l\u2019hostilit\u00e9 contre le leadership politique du pays\u00a0\u00bb, \u00e9crit la journaliste \u00c9lodie Toto pour le magazine Foreign Policy.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0La col\u00e8re est tangible. Il suffirait d\u2019une \u00e9tincelle pour que ce baril de poudre s\u2019enflamme et offre une opportunit\u00e9 aux terroristes.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">Le Sahel enregistre 43\u00a0% des d\u00e9c\u00e8s mondiaux dus au terrorisme, et le nombre de victimes a augment\u00e9 de plus de 2.000\u00a0% au cours des quinze derni\u00e8res ann\u00e9es, selon l\u2019Indice mondial du terrorisme 2023.<\/p>\n<p style=\"font-weight: 400;\">Le Mali, voisin \u00e0 l\u2019Est du S\u00e9n\u00e9gal, est class\u00e9 quatri\u00e8me sur la liste mondiale des pays les plus affect\u00e9s, selon l\u2019indice. Le Burkina Faso est class\u00e9 second.<\/p>\n<p style=\"font-weight: 400;\">Les experts d\u00e9clarent que les d\u00e9fis complexes du pays le rendent vuln\u00e9rable face aux groupes terroristes qui peuvent profiter du m\u00e9contentement et l\u2019amplifier en radicalisant les jeunes gens insatisfaits.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Les frustrations en hausse au S\u00e9n\u00e9gal, notamment la d\u00e9sillusion \u00e9conomique, la violence polici\u00e8re et les accusations de corruption, sont les conditions dont profitent les groupes terroristes dans toute la r\u00e9gion\u00a0\u00bb, a \u00e9crit le Soufan Center, organisme de recherche ind\u00e9pendant sans but lucratif, dans un briefing au mois de juin.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Le Jamaat Nosrat al-Islam wal-Mouslimin affili\u00e9 \u00e0 al-Qa\u00efda et l\u2019\u00c9tat islamique dans le Grand Sahara ont tir\u00e9 profit des fronti\u00e8res poreuses, de la corruption, de la faiblesse de l\u2019\u00e9tat de droit et d\u2019autres d\u00e9fis r\u00e9gionaux multidimensionnels tels que la d\u00e9t\u00e9rioration de l\u2019environnement, l\u2019ins\u00e9curit\u00e9 alimentaire, les migrations et l\u2019instabilit\u00e9 \u00e9conomique.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">Les tensions politiques et la violence sont aussi en hausse. On craint que le gouvernement ne disqualifie Ousmane Sonko, chef de l\u2019opposition qui \u00e9tait en t\u00eate des sondages de l\u2019\u00e9lection pr\u00e9sidentielle de 2024 avant d\u2019\u00eatre accus\u00e9 de provoquer une insurrection le 31 juillet.<\/p>\n<p style=\"font-weight: 400;\">Une r\u00e9pression violente contre les sympathisants de M.\u00a0Sonko en juin a conduit \u00e0 23 d\u00e9c\u00e8s, des centaines d\u2019arrestation et la destruction des biens publics et priv\u00e9s, y compris des banques, des autobus et des trains.<\/p>\n<p style=\"font-weight: 400;\">Le gouvernement a aussi bloqu\u00e9 les applis des r\u00e9seaux sociaux et des messageries, puis il a coup\u00e9 l\u2019Internet mobile dans tout le pays, ce qui a provoqu\u00e9 de lourdes pertes \u00e9conomiques.<\/p>\n<p style=\"font-weight: 400;\">Le Dr\u00a0Faye pense que ces facteurs se combinent pour cr\u00e9er une \u00ab\u00a0temp\u00eate parfaite\u00a0\u00bb des tensions au S\u00e9n\u00e9gal.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Il est crucial que le gouvernement et les responsables politiques affrontent s\u00e9rieusement ces probl\u00e8mes et engagent des dialogues substantiels avec toutes les parties prenantes, dit-il. Cela inclut la mise en \u0153uvre de politiques qui ciblent le ch\u00f4mage des jeunes, la promotion de la transparence et de la prise de responsabilit\u00e9 concernant la gouvernance, et l\u2019assurance d\u2019un acc\u00e8s \u00e9gal aux opportunit\u00e9s pour tous les citoyens s\u00e9n\u00e9galais.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0C\u2019est seulement avec des efforts authentiques pour relever ces d\u00e9fis structurels que le S\u00e9n\u00e9gal pourra retrouver sa stabilit\u00e9 et satisfaire aux id\u00e9aux de son mod\u00e8le s\u00e9n\u00e9galais r\u00e9v\u00e9r\u00e9.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF L\u2019annonce par le pr\u00e9sident s\u00e9n\u00e9galais Macky Sall en juillet dernier selon laquelle il ne briguerait pas un troisi\u00e8me mandat a \u00e9t\u00e9 accueillie avec un m\u00e9lange de soulagement et d\u2019orgueil dans le pays, c\u00e9l\u00e8bre pour ses traditions d\u00e9mocratiques. \u00ab\u00a0Une bombe \u00e0 retardement a \u00e9t\u00e9 d\u00e9samorc\u00e9e\u00a0\u00bb, a d\u00e9clar\u00e9 Alioune Tine, d\u00e9fenseur s\u00e9n\u00e9galais pro\u00e9minent des droits<\/p>\n","protected":false},"author":1,"featured_media":109659,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[565,1284,489,679,1182,1000,699,1242,484,1247,434,487,413,1282],"class_list":{"0":"post-109705","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-afrique-de-louest","9":"tag-al-qaida","10":"tag-burkina-faso-fr","11":"tag-corruption-fr","12":"tag-coups-fr","13":"tag-democratie","14":"tag-elections-fr","15":"tag-etat-islamique","16":"tag-extremisme","17":"tag-gouvernance","18":"tag-mali-fr","19":"tag-sahel-fr","20":"tag-senegal-fr","21":"tag-terrorism-fr"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF L\u2019annonce par le pr\u00e9sident s\u00e9n\u00e9galais Macky Sall en juillet dernier selon laquelle il ne briguerait pas un troisi\u00e8me mandat a \u00e9t\u00e9 accueillie avec un m\u00e9lange de soulagement et d\u2019orgueil dans le pays, c\u00e9l\u00e8bre pour ses traditions d\u00e9mocratiques. \u00ab\u00a0Une bombe \u00e0 retardement a \u00e9t\u00e9 d\u00e9samorc\u00e9e\u00a0\u00bb, a d\u00e9clar\u00e9 Alioune Tine, d\u00e9fenseur s\u00e9n\u00e9galais pro\u00e9minent des droits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T14:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T12:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique\",\"datePublished\":\"2023-09-26T14:09:00+00:00\",\"dateModified\":\"2023-09-27T12:40:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/\"},\"wordCount\":942,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1258352504.jpg\",\"keywords\":[\"Afrique de l\u2019Ouest\",\"Al-Qa\u00efda\",\"Burkina Faso\",\"corruption\",\"coups\",\"d\u00e9mocratie\",\"elections\",\"\u00c9tat islamique\",\"extr\u00e9misme\",\"gouvernance\",\"Mali\",\"Sahel\",\"Senegal\",\"Terrorism\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/\",\"name\":\"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1258352504.jpg\",\"datePublished\":\"2023-09-26T14:09:00+00:00\",\"dateModified\":\"2023-09-27T12:40:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1258352504.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1258352504.jpg\",\"width\":1024,\"height\":682,\"caption\":\"La police s\u00e9n\u00e9galaise essaie de r\u00e9primer une manifestation en lan\u00e7ant des grenades lacrymog\u00e8nes \u00e0 Dakar le 1er juin 2023. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF L\u2019annonce par le pr\u00e9sident s\u00e9n\u00e9galais Macky Sall en juillet dernier selon laquelle il ne briguerait pas un troisi\u00e8me mandat a \u00e9t\u00e9 accueillie avec un m\u00e9lange de soulagement et d\u2019orgueil dans le pays, c\u00e9l\u00e8bre pour ses traditions d\u00e9mocratiques. \u00ab\u00a0Une bombe \u00e0 retardement a \u00e9t\u00e9 d\u00e9samorc\u00e9e\u00a0\u00bb, a d\u00e9clar\u00e9 Alioune Tine, d\u00e9fenseur s\u00e9n\u00e9galais pro\u00e9minent des droits","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-09-26T14:09:00+00:00","article_modified_time":"2023-09-27T12:40:27+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique","datePublished":"2023-09-26T14:09:00+00:00","dateModified":"2023-09-27T12:40:27+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/"},"wordCount":942,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg","keywords":["Afrique de l\u2019Ouest","Al-Qa\u00efda","Burkina Faso","corruption","coups","d\u00e9mocratie","elections","\u00c9tat islamique","extr\u00e9misme","gouvernance","Mali","Sahel","Senegal","Terrorism"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/","name":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg","datePublished":"2023-09-26T14:09:00+00:00","dateModified":"2023-09-27T12:40:27+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1258352504.jpg","width":1024,"height":682,"caption":"La police s\u00e9n\u00e9galaise essaie de r\u00e9primer une manifestation en lan\u00e7ant des grenades lacrymog\u00e8nes \u00e0 Dakar le 1er juin 2023. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/les-tensions-sont-en-hausse-au-senegal-pilier-de-la-democratie-en-afrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Les tensions sont en hausse au S\u00e9n\u00e9gal, pilier de la d\u00e9mocratie en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/109705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=109705"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/109705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/109659"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=109705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=109705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=109705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}