{"id":109323,"date":"2023-09-15T10:26:48","date_gmt":"2023-09-15T14:26:48","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=109323"},"modified":"2023-09-22T13:17:26","modified_gmt":"2023-09-22T17:17:26","slug":"leger-versatile-economique","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/","title":{"rendered":"L\u00e9ger Versatile \u00c9conomique"},"content":{"rendered":"<p>PERSONNEL D\u2019ADF<\/p>\n<p>Les jets de combat modernes sont des merveilles de puissance et de complexit\u00e9. Arm\u00e9s de missiles air-air, ils peuvent atteindre des vitesses de 1.600 km\/h. Ils sont aussi incroyablement on\u00e9reux. La g\u00e9n\u00e9ration actuelle de chasseurs a un prix de base d\u2019environ 100 millions de dollars l\u2019unit\u00e9. On estime que chaque jet co\u00fbte 1 milliard de dollars sous forme de d\u00e9penses op\u00e9rationnelles et de maintenance pendant sa dur\u00e9e de service optimale.<\/p>\n<p>La question de leur utilit\u00e9 se pose aussi. Pour tout ce qui ne concerne pas les combats a\u00e9riens et les frappes de missile, un avion de chasse est exag\u00e9r\u00e9. Depuis la fin de la guerre froide, les Arm\u00e9es de l\u2019air conduisent rarement des missions dans les espaces a\u00e9riens fortement disput\u00e9s et les affrontements avec des rivaux militaires avanc\u00e9s dot\u00e9s de syst\u00e8mes de d\u00e9fense et d\u2019\u00e9quipements avioniques sophistiqu\u00e9s sont extr\u00eamement rares.<\/p>\n<p>Aujourd\u2019hui, les guerres sont en grande mesure asym\u00e9triques, contre des insurg\u00e9s ou des terroristes. Ceci est en particulier le cas dans plusieurs r\u00e9gions d\u2019Afrique : les combats a\u00e9riens ne se produisent pas. Pour ce type de guerre, des a\u00e9ronefs plus petits et man\u0153uvrables sont n\u00e9cessaires. Ces a\u00e9ronefs de contre-insurrection, ou COIN, sont souvent con\u00e7us pour former les pilotes. Ils co\u00fbtent seulement une fraction du prix des chasseurs et sont beaucoup plus faciles et moins chers \u00e0 maintenir. Ils peuvent \u00eatre adapt\u00e9s \u00e0 de nouveaux emplois dans les missions d\u2019attaque l\u00e9g\u00e8re et de reconnaissance, et comme \u00ab pick-ups volants de travail \u00bb.<\/p>\n<figure id=\"attachment_109302\" aria-describedby=\"caption-attachment-109302\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-109302\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit.jpg\" alt=\"\" width=\"1080\" height=\"788\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit-300x219.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit-1024x747.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit-768x560.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-91631400_edit-86x64.jpg 86w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-109302\" class=\"wp-caption-text\">Le Westland Lynx, introduit en 1978, a \u00e9t\u00e9 utilis\u00e9 dans le monde entier, notamment au Nigeria et en Afrique du Sud. Certains pourraient toujours \u00eatre en service. Celui-ci appartient \u00e0 la Marine sud-africaine.<\/figcaption><\/figure>\n<p>Le site web d\u2019aviation Key Aero note que les a\u00e9ronefs d\u2019attaque l\u00e9gers sont une \u00ab source bon march\u00e9 et disponible de puissance a\u00e9rienne \u00bb pour les pays sensibles aux co\u00fbts et affrontant une insurrection. Les frais op\u00e9rationnels de ces a\u00e9ronefs sont en g\u00e9n\u00e9ral d\u2019environ 2.000 dollars l\u2019heure, soit entre 2 et 4 % du co\u00fbt des chasseurs avanc\u00e9s. Le co\u00fbt initial est aussi moindre, selon Key Aero : un chasseur de base pour la COIN peut co\u00fbter au d\u00e9part environ 10 millions de dollars.<\/p>\n<p>Le Nigeria, qui poss\u00e8de l\u2019une des plus grandes Arm\u00e9es de l\u2019air de l\u2019Afrique subsaharienne, a \u00e9t\u00e9 l\u2019un des premiers \u00e0 reconna\u00eetre l\u2019utilit\u00e9 de ces avions plus petits.<\/p>\n<p>\u00ab Avec sa vaste exp\u00e9rience de combat, d\u2019abord au Liberia dans le cadre de la force de maintien de la paix du groupe de surveillance de la Communaut\u00e9 \u00e9conomique des \u00c9tats d\u2019Afrique de l\u2019Ouest, puis pendant la longue guerre contre Boko Haram, l\u2019Arm\u00e9e de l\u2019air nig\u00e9riane a d\u00e9couvert rapidement que ses chasseurs rapides de premi\u00e8re ligne \u00e9taient beaucoup moins utiles pour le soutien a\u00e9rien rapproch\u00e9, compar\u00e9 \u00e0 ses avions d\u2019entra\u00eenement Aero L-39 et Dassault Alpha Jet \u00bb, selon un reportage du site d\u2019actualit\u00e9 Times Aerospace. \u00ab Ces derniers ont form\u00e9 l\u2019ossature de la campagne a\u00e9rienne du Nigeria contre le groupe d\u2019insurg\u00e9s islamistes, et ont aussi \u00e9t\u00e9 employ\u00e9s dans des op\u00e9rations au Cameroun, en \u00c9gypte, au Maroc et au Togo. \u00bb<\/p>\n<p>Alec Smith, analyste des renseignements et de la d\u00e9fense pour Grey Dynamics, note des rapports qui indiquent que les \u00c9tats-Unis ont consid\u00e9r\u00e9 des r\u00e9ductions dans leur programme de drones en vue d\u2019employer des a\u00e9ronefs COIN avec \u00e9quipage.<\/p>\n<p>\u00ab \u00c0 mesure que le nombre de guerres entre \u00e9tats-nations diminue, et que les insurrections localis\u00e9es deviennent plus probl\u00e9matiques et difficiles \u00e0 g\u00e9rer, les a\u00e9ronefs COIN joueront un r\u00f4le plus important pour att\u00e9nuer et limiter la port\u00e9e des op\u00e9rations des insurg\u00e9s \u00e0 l\u2019avenir \u00bb, \u00e9crit-il.<\/p>\n<p>Ces avions COIN ne sont pas toujours bas\u00e9s sur des entra\u00eeneurs. L\u2019Arm\u00e9e de l\u2019air des \u00c9tats-Unis a annonc\u00e9 en 2022 qu\u2019elle avait choisi l\u2019AT-802U Sky Warden produit par L3Harris Technologies et le fabricant d\u2019a\u00e9ronefs agricoles Air Tractor pour sa mission Armed Overwatch, afin de conduire des op\u00e9rations de contre-terrorisme et de guerre irr\u00e9guli\u00e8re dans les lieux tels que l\u2019Afrique. Le magazine Forbes signale que le Sky Warden est bas\u00e9 sur un avion d\u2019\u00e9pandage \u00e0 h\u00e9lice simple.<\/p>\n<p>Le Sky Warden a \u00e9t\u00e9 choisi pour sa grande charge utile, sa capacit\u00e9 de tir de missiles, de drones et de petites munitions, et sa capacit\u00e9 de transport de capteurs multiples et d\u2019un maximum de sept faisceaux hertziens avec ou sans ligne de vision, selon Forbes.<\/p>\n<p>Les a\u00e9ronefs COIN ne sont pas seulement des avions avec \u00e9quipage et \u00e0 voilure fixe ; les drones et les h\u00e9licopt\u00e8res ont aussi \u00e9t\u00e9 utilis\u00e9s dans la guerre asym\u00e9trique. Toutefois, les h\u00e9licopt\u00e8res ont des vuln\u00e9rabilit\u00e9s \u00e9videntes face aux tirs anti-a\u00e9riens et les drones ont tendance \u00e0 \u00eatre limit\u00e9s par les probl\u00e8mes de ligne de vis\u00e9e.<\/p>\n<p>M. Smith note que les h\u00e9licopt\u00e8res ont \u00e9t\u00e9 fortement employ\u00e9s comme a\u00e9ronefs COIN mais qu\u2019ils ont des limitations.<\/p>\n<p>\u00ab Malgr\u00e9 les apparences, les rotors sont en fait incroyablement friables \u00bb, d\u00e9clare-t-il \u00e0 ADF dans un e-mail. \u00ab Les tirs d\u2019arme de petit calibre peuvent s\u2019av\u00e9rer fatals pour les h\u00e9licopt\u00e8res, et puisque ceux-ci ont tendance \u00e0 survoler \u00e0 une altitude et une vitesse plus basses que celles des a\u00e9ronefs \u00e0 voilure fixe, ils sont plus expos\u00e9s \u00e0 ces tirs anti-a\u00e9riens potentiellement fatals. Il est certain que les h\u00e9licopt\u00e8res jouent un r\u00f4le important dans les op\u00e9rations COIN, par exemple pour am\u00e9liorer la mobilit\u00e9 a\u00e9rienne et \u00e9vacuer les victimes, mais ils sont seulement utiles en fonction des circonstances. \u00bb<\/p>\n<figure id=\"attachment_109306\" aria-describedby=\"caption-attachment-109306\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit.jpg\"><img decoding=\"async\" class=\"size-full wp-image-109306\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit.jpg\" alt=\"\" width=\"1080\" height=\"720\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit-300x200.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit-1024x683.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit-768x512.jpg 768w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-182723631_edit-272x182.jpg 272w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-109306\" class=\"wp-caption-text\">La guerre du Vi\u00eat-Nam a suscit\u00e9 un besoin pour le d\u00e9veloppement d\u2019un meilleur a\u00e9ronef COIN. Le Cessna A-37 Dragonfly a \u00e9t\u00e9 utilis\u00e9 dans le monde entier. On signale que certains \u00e9taient encore en service aussi r\u00e9cemment qu\u2019en 2016.<\/figcaption><\/figure>\n<p><b>LES D\u00c9BUTS DES A\u00c9RONEFS COIN<\/b><\/p>\n<p>L\u2019emploi des a\u00e9ronefs dans la contre-insurrection remonte presque \u00e0 l\u2019av\u00e8nement de l\u2019aviation. Mais les historiens d\u00e9clarent que les avions COIN modernes datent du d\u00e9but des ann\u00e9es 50 lorsque les \u00c9tats-Unis commenc\u00e8rent \u00e0 exp\u00e9rimenter avec les a\u00e9ronefs d\u2019entra\u00eenement en Cor\u00e9e et, quelques ann\u00e9es plus tard, au Vi\u00eat-Nam.<\/p>\n<p>\u00ab En Cor\u00e9e, les pilotes am\u00e9ricains employaient des versions arm\u00e9es des entra\u00eeneurs \u00e0 moteur \u00e0 piston de North American T-6 Texan appel\u00e9s \u201cMoustiques\u201d, principalement pour le rep\u00e9rage des pi\u00e8ces d\u2019artillerie et le contr\u00f4le a\u00e9rien avanc\u00e9 \u00bb, a \u00e9crit Robert Dorr pour The Year in Defense: Aerospace Edition en 2010.<\/p>\n<p>Au cours des ann\u00e9es, les experts militaires ont \u00e9num\u00e9r\u00e9 les normes accept\u00e9es des a\u00e9ronefs COIN performants, \u00e0 savoir :<\/p>\n<p>Les a\u00e9ronefs doivent \u00eatre durables et capables de longues p\u00e9riodes d\u2019utilisation sans maintenance du moteur ou de l\u2019avionique. Ils doivent \u00eatre \u00e9conomiques \u00e0 l\u2019achat et \u00e0 la maintenance.<\/p>\n<p>Ils doivent \u00eatre capables de d\u00e9coller rapidement en cas d\u2019urgence.<\/p>\n<p>Ils doivent \u00eatre suffisamment robustes pour survivre aux atterrissages ardus sur un terrain difficile et non pav\u00e9. De fa\u00e7on id\u00e9ale, ils devraient pouvoir d\u00e9coller et atterrir sur des pistes courtes de fortune.<\/p>\n<p>Leur pilotage doit \u00eatre simple. Les proc\u00e9dures op\u00e9rationnelles simples facilitent la formation des pilotes. La simplicit\u00e9 des op\u00e9rations facilite aussi l\u2019entretien des a\u00e9ronefs, point crucial pour assurer la performance op\u00e9rationnelle d\u2019une flotte a\u00e9rienne.<\/p>\n<p>De tels a\u00e9ronefs doivent avoir une capacit\u00e9 de basse vitesse leur permettant de \u00ab r\u00f4der \u00bb, combin\u00e9e \u00e0 une autonomie et une consommation de carburant excellentes.<\/p>\n<p>Ils doivent pouvoir acc\u00e9der rapidement \u00e0 des zones distantes tout en soutenant les troupes avec des renforts et des approvisionnements.<\/p>\n<p>Les programmes COIN sont devenus de plus en plus importants vers la fin du vingti\u00e8me si\u00e8cle lorsque la guerre asym\u00e9trique est devenue g\u00e9n\u00e9ralis\u00e9e. Certains experts affirment que les drones pourraient remplacer les a\u00e9ronefs COIN avec \u00e9quipage \u00e0 l\u2019avenir.<\/p>\n<p>Key Aero d\u00e9clare qu\u2019il est trop t\u00f4t pour assumer que les drones finiront pas remplacer les avions COIN : \u00ab En premier lieu, les drones ne sont pas n\u00e9cessairement \u201cl\u2019option la moins ch\u00e8re\u201d, comme on le suppose couramment. Un rapport r\u00e9cent du\u2026 Centre d\u2019\u00e9tudes strat\u00e9giques et internationales note que les drones peuvent co\u00fbter aussi cher que les a\u00e9ronefs avec \u00e9quipage \u00e0 la longue. Par exemple, les frais annuels de personnel pour un [drone] ISR MQ-9 Reaper s\u2019\u00e9l\u00e8vent \u00e0 environ 3 millions de dollars. \u00bb<\/p>\n<p>Doug Barrie de l\u2019Institut international pour les \u00e9tudes strat\u00e9giques d\u00e9clare \u00e0 Key Aero que les comparaisons de co\u00fbt entre les drones et les a\u00e9ronefs COIN avec \u00e9quipage peuvent \u00eatre trompeuses. Initialement, dit-il, un avion COIN avec \u00e9quipage co\u00fbtera plus cher. \u00ab Mais cela ne prend pas en compte la formation, les satellites qui doivent \u00eatre maintenus en orbite pour qu\u2019un [drone] puisse fonctionner, ou le soutien \u00e0 l\u2019arri\u00e8re pour l\u2019op\u00e9ration et l\u2019exploitation. \u00bb Et avec un drone, \u00ab si vous n\u2019avez pas de lien satellitaire, vous \u00eates limit\u00e9 \u00e0 une liaison de donn\u00e9es \u00e0 ligne de vis\u00e9e directe. Vous devez investir dans une capacit\u00e9 satellitaire ou demander \u00e0 quelqu\u2019un de le faire pour vous. \u00bb<\/p>\n<p><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/ADF_V16N3_FRN_Chart2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-109324\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/ADF_V16N3_FRN_Chart2.jpg\" alt=\"\" width=\"502\" height=\"928\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/ADF_V16N3_FRN_Chart2.jpg 502w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/ADF_V16N3_FRN_Chart2-300x555.jpg 300w\" sizes=\"(max-width: 502px) 100vw, 502px\" \/><\/a><\/p>\n<p>M. Smith a d\u00e9clar\u00e9 \u00e0 ADF qu\u2019il est \u00ab presque certain \u00bb que les drones domineront l\u2019espace a\u00e9rien des op\u00e9rations de contre-insurrection \u00e0 l\u2019avenir, mais qu\u2019il existe toujours un besoin pour les a\u00e9ronefs l\u00e9gers d\u2019attaque.<\/p>\n<p>\u00ab Ceci ne signifie pas n\u00e9cessairement que les a\u00e9ronefs l\u00e9gers avec \u00e9quipage n\u2019auront pas d\u2019emploi futur ; \u00e7a signifie tout simplement qu\u2019ils seront beaucoup moins pr\u00e9dominants, dit-il. Les a\u00e9ronefs avec \u00e9quipage seront toujours l\u2019outil principal pour les op\u00e9rations dans les espaces a\u00e9riens disput\u00e9s. Les a\u00e9ronefs avec \u00e9quipage sont utiles lorsqu\u2019un certain degr\u00e9 d\u2019intervention humaine instantan\u00e9e est n\u00e9cessaire dans le processus de prise de d\u00e9cision. Les a\u00e9ronefs avec \u00e9quipage ont tendance \u00e0 \u00eatre plus rapides ; si donc une r\u00e9ponse rapide est n\u00e9cessaire en cas de situation qui se d\u00e9veloppe, les drones ne sont pas vraiment la meilleure option. \u00bb<span class=\"Apple-converted-space\"> \u00a0<\/span><\/p>\n<hr \/>\n<p><b>Une Soci\u00e9t\u00e9 Sud-Africaine Fabrique <\/b><b>Un Nouvel A\u00e9ronef Coin<\/b><\/p>\n<p>PERSONNEL D\u2019ADF<\/p>\n<p>Le premier avion Mwari de surveillance et de frappe de pr\u00e9cision, appel\u00e9 initialement AHRLAC, a \u00e9t\u00e9 observ\u00e9 au Mozambique avec des marquages mozambicains.<\/p>\n<p>DefenceWeb a signal\u00e9 en mars 2023 que cet avion, qui peut \u00eatre employ\u00e9 dans les op\u00e9rations de contre-insurrection (COIN), avait \u00e9t\u00e9 observ\u00e9 dans la province du Cabo Delgado. Les donn\u00e9es de pistage de vol ont montr\u00e9 qu\u2019il survolait la r\u00e9gion de Nacala \u00e0 la fin janvier 2023.<\/p>\n<p>AHRLAC signifie \u00ab a\u00e9ronef l\u00e9ger avanc\u00e9 de haute performance pour la reconnaissance \u00bb. DefenceWeb signale qu\u2019il s\u2019agit du troisi\u00e8me AHRLAC produit apr\u00e8s deux prototypes, et qu\u2019il est l\u2019un de deux a\u00e9ronefs de pr\u00e9-production. Son premier vol a eu lieu en avril 2022.<\/p>\n<p>Les a\u00e9ronefs sont construits par Paramount Aerospace Industries d\u2019Afrique du Sud. En septembre 2022, Paramount a d\u00e9clar\u00e9 que quatre a\u00e9ronefs \u00e9taient en production \u00e0 l\u2019usine de l\u2019a\u00e9roport de Wonderboom pr\u00e8s de Pretoria, et que deux clients avaient pass\u00e9 commande pour neuf a\u00e9ronefs. Les a\u00e9ronefs sont con\u00e7us pour faire concurrence aux autres petits appareils \u00e0 h\u00e9lice, en particulier l\u2019Embraer A-29 Super Tucano fabriqu\u00e9 au Br\u00e9sil qui a enregistr\u00e9 de bons succ\u00e8s. Il y a plus de 260 Super Tucano utilis\u00e9s dans le monde, notamment en Mauritanie et au Nigeria.<\/p>\n<p>Le Mwari a \u00e9t\u00e9 en cours de d\u00e9veloppement pendant plus de dix ans. C\u2019est le premier a\u00e9ronef militaire nouvellement con\u00e7u en Afrique du Sud depuis la mise en service de l\u2019h\u00e9licopt\u00e8re d\u2019attaque Rooivalk en 1999. La production a \u00e9t\u00e9 retard\u00e9e en f\u00e9vrier 2019 \u00e0 la suite de probl\u00e8mes, notamment des contentieux \u00e0 propos des contrats, de la propri\u00e9t\u00e9 intellectuelle et du financement. Un plan de sauvetage a \u00e9t\u00e9 con\u00e7u et la production a repris en septembre 2022.<\/p>\n<figure id=\"attachment_109314\" aria-describedby=\"caption-attachment-109314\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-109314\" src=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit.jpg\" alt=\"\" width=\"1080\" height=\"741\" srcset=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit.jpg 1080w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit-300x206.jpg 300w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit-1024x703.jpg 1024w, https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Mwari-01_edit-768x527.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-109314\" class=\"wp-caption-text\">Le Mwari est un nouvel avion de surveillance et de frappe de pr\u00e9cision fabriqu\u00e9 en Afrique du Sud. PARAMOUNT GROUP<\/figcaption><\/figure>\n<p>Le Mwari est commercialis\u00e9 pour pr\u00e9senter une alternative relativement \u00e9conomique aux a\u00e9ronefs militaires de haut niveau dans les op\u00e9rations de surveillance, patrouille maritime et contre-insurrection. Il peut aussi \u00eatre utilis\u00e9 pour la formation. Il a un plafond de service de 9,5 km et une vitesse de croisi\u00e8re maximale de 460 km\/h, une autonomie de mission de plus de 1.000 km avec munitions, et un temps de vol total jusqu\u2019\u00e0 6,5 heures.<\/p>\n<p>Les responsables de la soci\u00e9t\u00e9 d\u00e9clarent que l\u2019a\u00e9ronef a aussi une capacit\u00e9 d\u2019atterrissage et de d\u00e9collage sur piste courte, avec un train d\u2019atterrissage r\u00e9tractable optimis\u00e9 pour les pistes ou les sites<br \/>\nnon pr\u00e9par\u00e9s ou semi-<br \/>\npr\u00e9par\u00e9s. L\u2019a\u00e9ronef pr\u00e9sente un moteur singulier bipoutre monopoussoir et une configuration \u00e0 angle de fl\u00e8che avanc\u00e9 \u00e0 montage en hauteur. La soci\u00e9t\u00e9 a annonc\u00e9 qu\u2019elle projetait de commercialiser ces avions \u00e0 un co\u00fbt d\u2019environ 10 millions de dollars l\u2019unit\u00e9, prix comparable aux avions COIN similaires vendus dans d\u2019autres r\u00e9gions du monde.<\/p>\n<p>Le site web The National Interest indique que le Mwari est commercialis\u00e9 sp\u00e9cifiquement pour les pays africains. Le site web mentionne la d\u00e9claration suivante de la soci\u00e9t\u00e9 : \u00ab Les types de menace auxquels les pays du monde entier font face ont chang\u00e9 consid\u00e9rablement au cours des derni\u00e8res ann\u00e9es. Beaucoup de menaces affront\u00e9es ne justifient pas les co\u00fbts op\u00e9rationnels des chasseurs rapides. \u00bb<\/p>\n<p>La soci\u00e9t\u00e9 pr\u00e9voit aussi de construire un deuxi\u00e8me avion, le Bronco II, con\u00e7u pour \u00eatre rapidement d\u00e9mont\u00e9, transport\u00e9 et remont\u00e9 sur le terrain par une petite \u00e9quipe. La soci\u00e9t\u00e9 projette de construire le Bronco II \u00e0 Crestview en Floride (\u00c9tats-Unis).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF Les jets de combat modernes sont des merveilles de puissance et de complexit\u00e9. Arm\u00e9s de missiles air-air, ils peuvent atteindre des vitesses de 1.600 km\/h. Ils sont aussi incroyablement on\u00e9reux. La g\u00e9n\u00e9ration actuelle de chasseurs a un prix de base d\u2019environ 100 millions de dollars l\u2019unit\u00e9. On estime que chaque jet co\u00fbte 1<\/p>\n","protected":false},"author":1,"featured_media":109298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[411,1725,585,1587],"class_list":{"0":"post-109323","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articles","8":"tag-afrique-du-sud","9":"tag-afrique-du-sud-fr","10":"tag-technologie","11":"tag-technologie-fr"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF Les jets de combat modernes sont des merveilles de puissance et de complexit\u00e9. Arm\u00e9s de missiles air-air, ils peuvent atteindre des vitesses de 1.600 km\/h. Ils sont aussi incroyablement on\u00e9reux. La g\u00e9n\u00e9ration actuelle de chasseurs a un prix de base d\u2019environ 100 millions de dollars l\u2019unit\u00e9. On estime que chaque jet co\u00fbte 1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T14:26:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-22T17:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-876306198_edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-876306198_edit.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"L\u00e9ger Versatile \u00c9conomique\",\"datePublished\":\"2023-09-15T14:26:48+00:00\",\"dateModified\":\"2023-09-22T17:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/\"},\"wordCount\":2411,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Light-Attack.jpg\",\"keywords\":[\"Afrique du Sud\",\"Afrique du Sud\",\"technologie\",\"technologie\"],\"articleSection\":[\"articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/\",\"name\":\"L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Light-Attack.jpg\",\"datePublished\":\"2023-09-15T14:26:48+00:00\",\"dateModified\":\"2023-09-22T17:17:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Light-Attack.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Light-Attack.jpg\",\"width\":1080,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/leger-versatile-economique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00e9ger Versatile \u00c9conomique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF Les jets de combat modernes sont des merveilles de puissance et de complexit\u00e9. Arm\u00e9s de missiles air-air, ils peuvent atteindre des vitesses de 1.600 km\/h. Ils sont aussi incroyablement on\u00e9reux. La g\u00e9n\u00e9ration actuelle de chasseurs a un prix de base d\u2019environ 100 millions de dollars l\u2019unit\u00e9. On estime que chaque jet co\u00fbte 1","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-09-15T14:26:48+00:00","article_modified_time":"2023-09-22T17:17:26+00:00","og_image":[{"width":864,"height":466,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-876306198_edit.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_image":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/iStock-876306198_edit.jpg","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"L\u00e9ger Versatile \u00c9conomique","datePublished":"2023-09-15T14:26:48+00:00","dateModified":"2023-09-22T17:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/"},"wordCount":2411,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Light-Attack.jpg","keywords":["Afrique du Sud","Afrique du Sud","technologie","technologie"],"articleSection":["articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/","name":"L\u00e9ger Versatile \u00c9conomique - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Light-Attack.jpg","datePublished":"2023-09-15T14:26:48+00:00","dateModified":"2023-09-22T17:17:26+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Light-Attack.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/Light-Attack.jpg","width":1080,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/leger-versatile-economique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"L\u00e9ger Versatile \u00c9conomique"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/109323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=109323"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/109323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/109298"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=109323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=109323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=109323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}