{"id":108798,"date":"2023-09-05T14:57:58","date_gmt":"2023-09-05T18:57:58","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=108798"},"modified":"2023-09-05T14:59:40","modified_gmt":"2023-09-05T18:59:40","slug":"en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/","title":{"rendered":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge"},"content":{"rendered":"<p style=\"font-weight: 400;\">PERSONNEL D\u2019ADF<\/p>\n<p style=\"font-weight: 400;\">L\u2019\u00c9rythr\u00e9e, appel\u00e9e parfois un royaume ermite, est l\u2019un des pays les plus diplomatiquement isol\u00e9s du monde. Ses ant\u00e9c\u00e9dents de r\u00e9pression, d\u2019abus des droits de l\u2019homme et de conflit avec les pays voisins l\u2019ont laiss\u00e9e avec peu d\u2019alli\u00e9s sur la sc\u00e8ne mondiale. Mais son littoral de 1.150\u00a0km sur la mer Rouge signifie qu\u2019elle continue \u00e0 attirer l\u2019int\u00e9r\u00eat des pays \u00e9trangers.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Asmara exerce une influence d\u00e9mesur\u00e9e du point de vue g\u00e9opolitique \u00e9tant donn\u00e9 son emplacement\u00a0\u00bb, \u00e9crit Joshua Meservey, a Senior Fellow qui \u00e9tudie l\u2019Afrique au Hudson Institute. \u00ab\u00a0Elle d\u00e9tient une position dominante sur le d\u00e9troit de Bab-el-Mandeb, point de passage mondial du transport maritime, et ses \u00eeles pars\u00e8ment l\u2019approche du d\u00e9troit dans la mer Rouge.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">Au cours de l\u2019an dernier, l\u2019\u00c9rythr\u00e9e a renforc\u00e9 ses liens \u00e9conomiques, diplomatiques et militaires avec la Chine et la Russie. Ces deux pays esp\u00e8rent d\u00e9velopper leur empreinte militaire dans la Corne de l\u2019Afrique et, malgr\u00e9 les d\u00e9mentis officiels, l\u2019\u00c9rythr\u00e9e semble ouverte \u00e0 l\u2019id\u00e9e d\u2019accueillir une base \u00e9trang\u00e8re.<\/p>\n<p style=\"font-weight: 400;\">Entre 2015 et 2021, l\u2019\u00c9rythr\u00e9e a autoris\u00e9 les a\u00e9ronefs des \u00c9mirats arabes unis \u00e0 utiliser un a\u00e9rodrome c\u00f4tier et mettre \u00e0 quai les navires au port de la ville d\u2019Assab pendant l\u2019engagement des EAU au Y\u00e9men. Elle pourrait souhaiter offrir des arrangements similaires \u00e0 la Chine ou la Russie.<\/p>\n<p>Meservey pense qu\u2019il \u00ab\u00a0faudrait sonner l\u2019alarme\u00a0\u00bb \u00e0 cause de la possibilit\u00e9 d\u2019un renforcement de la pr\u00e9sence militaire \u00e9trang\u00e8re sur la c\u00f4te, lequel pourrait menacer le commerce maritime. \u00ab\u00a0Si la Chine construit une base, ou peut-\u00eatre m\u00eame une infrastructure \u00e0 double emploi, \u00e0 Assab ou Massawa pour l\u2019ajouter \u00e0 sa base voisine de Djibouti, elle sera capable d\u2019effectuer un blocus du d\u00e9troit de Bab-el-Mandeb.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\"><strong>La s\u00e9duction chinoise<\/strong><\/p>\n<p style=\"font-weight: 400;\">En mai dernier, le pr\u00e9sident \u00e9rythr\u00e9en Isaias Afwerki s\u2019est rendu en Chine. Lors d\u2019un banquet au palais de l\u2019Assembl\u00e9e du peuple, le pr\u00e9sident Xi Jinping s\u2019est f\u00e9licit\u00e9 du \u00ab\u00a0lien profond d\u2019amiti\u00e9 [entre les deux pays] dans un monde incertain et instable\u00a0\u00bb.<\/p>\n<p style=\"font-weight: 400;\">Les liens de M.\u00a0Afwerki avec la Chine remontent \u00e0 1967, lorsqu\u2019il avait re\u00e7u une formation militaire dans le pays et avait appris les tactiques de gu\u00e9rilla employ\u00e9es par Mao Zedong.<\/p>\n<p style=\"font-weight: 400;\">En 2021, l\u2019\u00c9rythr\u00e9e a convenu de rejoindre l\u2019initiative chinoise de la Nouvelle route de la soie, et elle est cens\u00e9e enregistrer une forte augmentation du nombre de projets de construction chinois en 2023. Au cours des onze derni\u00e8res ann\u00e9es, les soci\u00e9t\u00e9s chinoises ont obtenu le contr\u00f4le des quatre projets de d\u00e9veloppement minier de l\u2019\u00c9rythr\u00e9e pour des minerais tels que le cuivre, le zinc et la potasse.<\/p>\n<p style=\"font-weight: 400;\">La Chine poss\u00e8de d\u00e9j\u00e0 sa premi\u00e8re base militaire d\u2019outre-mer dans le pays voisin de Djibouti, o\u00f9 elle a construit des abris souterrains, une infrastructure renforc\u00e9e et un quai capable de recevoir un porte-avions. Mais M.\u00a0Meservey d\u00e9clare que cela n\u2019\u00e9limine pas la possibilit\u00e9 d\u2019une expansion chinoise en \u00c9rythr\u00e9e.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0La perspective serait diff\u00e9rente, mais je pense que cela devrait \u00eatre suffisant pour leur donner une supr\u00e9matie dans le d\u00e9troit de Bab-el-Mandeb et ses approches, dit-il \u00e0 ADF. Parce que je ne vois pas la justification strat\u00e9gique de mettre quelque chose en \u00c9rythr\u00e9e si ce n\u2019est pas pour affirmer ou cr\u00e9er une pr\u00e9dominance dans ce point de passage.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\"><strong>Les liens russes<\/strong><\/p>\n<p>Afwerki s\u2019est rendu \u00e0 Moscou deux fois en 2023. Lors d\u2019un \u00e9v\u00e9nement de table ronde avec le pr\u00e9sident Vladimir Poutine, il a exhort\u00e9 la Russie \u00e0 montrer la voie pour cr\u00e9er ce qu\u2019il a appel\u00e9 un \u00ab\u00a0nouvel ordre mondial\u00a0\u00bb. L\u2019\u00c9rythr\u00e9e a soutenu fid\u00e8lement M.\u00a0Poutine et a \u00e9t\u00e9 le seul pays africain \u00e0 voter contre une r\u00e9solution de l\u2019ONU d\u00e9non\u00e7ant l\u2019invasion russe de l\u2019Ukraine en 2022.<\/p>\n<p style=\"font-weight: 400;\">La Russie souhaite depuis longtemps une pr\u00e9sence militaire permanente en mer Rouge et elle avait engag\u00e9 des pourparlers avec la junte du Soudan dans le but d\u2019\u00e9tablir une base \u00e0 Port-Soudan, avant que le Soudan ne devienne la proie d\u2019une guerre civile. Il y a des indications selon lesquelles elle pourrait tourner son attention vers l\u2019\u00c9rythr\u00e9e.<\/p>\n<p style=\"font-weight: 400;\">La ville portuaire \u00e9rythr\u00e9enne de Massawa a sign\u00e9 un protocole d\u2019accord avec la base navale russe de S\u00e9bastopol sur la mer Noire pour \u00e9tablir des liens plus \u00e9troits. Lors d\u2019une visite effectu\u00e9e en janvier par le ministre russe des Affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov, la premi\u00e8re de ce type, M.\u00a0Lavrov a lou\u00e9 le \u00ab\u00a0potentiel strat\u00e9gique\u00a0\u00bb du port et de l\u2019a\u00e9roport de Massawa.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Je pense que l\u2019\u00c9rythr\u00e9e serait un deuxi\u00e8me choix logique pour les Russes, d\u00e9clare M.\u00a0Meservey. Ils transf\u00e9reront potentiellement leur \u00e9nergie et leur focus \u00e0 l\u2019\u00c9rythr\u00e9e s\u2019il semble que Port-Soudan ne va pas leur servir. Il y a eu des engagements diplomatiques s\u00e9rieux de haut niveau.\u00a0\u00bb<\/p>\n<p style=\"font-weight: 400;\">La Russie a conclu plus de 24 accords de coop\u00e9ration en Afrique au cours des derni\u00e8res ann\u00e9es, hausse importante compar\u00e9 aux d\u00e9cennies ant\u00e9rieures, selon une analyse du Centre d\u2019\u00e9tudes strat\u00e9giques de l\u2019Afrique.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00ab\u00a0Un manipulateur rus\u00e9\u00a0\u00bb<\/strong><\/p>\n<p>Afwerki exerce le pouvoir d\u2019une main de fer depuis plus de trente ans, sans jamais se pr\u00e9senter \u00e0 des \u00e9lections ni affronter un d\u00e9fi s\u00e9rieux contre son r\u00e9gime. Dans un essai pour \u00ab\u00a0La d\u00e9mocratie en Afrique\u00a0\u00bb, les chercheurs Faisal Ali et Mohamed Kheir Omer s\u2019\u00e9tonnent de sa long\u00e9vit\u00e9 au cours des ann\u00e9es, alors qu\u2019il a fait la guerre contre ses voisins, envoy\u00e9 des armes aux groupes rebelles et r\u00e9duit au silence les dissidents.<\/p>\n<p style=\"font-weight: 400;\">Ils \u00e9crivent\u00a0: \u00ab\u00a0Afwerki est un manipulateur rus\u00e9 et un survivant d\u00e9termin\u00e9. Il est devenu le grand a\u00een\u00e9 de la politique d\u2019Afrique de l\u2019Est.\u00a0\u00bb<\/p>\n<p>Meservey d\u00e9clare que le resserrement des liens avec la Russie et la Chine sont une \u00ab\u00a0progression naturelle\u00a0\u00bb de la strat\u00e9gie et la perspective mondiale de M.\u00a0Afwerki, qui met l\u2019accent sur l\u2019autosuffisance et la d\u00e9fiance de l\u2019ordre mondial et des institutions internationales. Il pourrait penser que le moment est venu d\u2019accro\u00eetre son profil mondial. Toutefois, M.\u00a0Meservey avertit que la Chine et la Russie ont des ant\u00e9c\u00e9dents de renforcement et d\u2019encouragement des r\u00e9gimes parmi les plus oppressifs d\u2019Afrique.<\/p>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Ces deux pays ont de longs ant\u00e9c\u00e9dents de soutien aux r\u00e9gimes violents et autoritaires. Cela conduit \u00e0 une immense instabilit\u00e9 et aussi \u00e0 de graves violations des droits de l\u2019homme, dit-il. Alors que la Chine et la Russie d\u00e9veloppent leur influence dans des endroits tels que l\u2019\u00c9rythr\u00e9e, je pense donc que les r\u00e9gimes violents et autoritaires y gagnent, ce qui est regrettable.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF L\u2019\u00c9rythr\u00e9e, appel\u00e9e parfois un royaume ermite, est l\u2019un des pays les plus diplomatiquement isol\u00e9s du monde. Ses ant\u00e9c\u00e9dents de r\u00e9pression, d\u2019abus des droits de l\u2019homme et de conflit avec les pays voisins l\u2019ont laiss\u00e9e avec peu d\u2019alli\u00e9s sur la sc\u00e8ne mondiale. Mais son littoral de 1.150\u00a0km sur la mer Rouge signifie qu\u2019elle continue<\/p>\n","protected":false},"author":1,"featured_media":108793,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[553,1191,618],"class_list":{"0":"post-108798","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-chine","9":"tag-eritrea-fr","10":"tag-russie"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF L\u2019\u00c9rythr\u00e9e, appel\u00e9e parfois un royaume ermite, est l\u2019un des pays les plus diplomatiquement isol\u00e9s du monde. Ses ant\u00e9c\u00e9dents de r\u00e9pression, d\u2019abus des droits de l\u2019homme et de conflit avec les pays voisins l\u2019ont laiss\u00e9e avec peu d\u2019alli\u00e9s sur la sc\u00e8ne mondiale. Mais son littoral de 1.150\u00a0km sur la mer Rouge signifie qu\u2019elle continue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-05T18:57:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T18:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge\",\"datePublished\":\"2023-09-05T18:57:58+00:00\",\"dateModified\":\"2023-09-05T18:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/\"},\"wordCount\":1198,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1007692342.jpg\",\"keywords\":[\"Chine\",\"Eritrea\",\"Russie\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/\",\"name\":\"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1007692342.jpg\",\"datePublished\":\"2023-09-05T18:57:58+00:00\",\"dateModified\":\"2023-09-05T18:59:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1007692342.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/GettyImages-1007692342.jpg\",\"width\":1024,\"height\":685,\"caption\":\"Un bateau est amarr\u00e9 au quai de la ville portuaire de Massawa (\u00c9rythr\u00e9e). Le renforcement des liens entre la Russie, la Chine et l\u2019\u00c9rythr\u00e9e suscite des sp\u00e9culations selon lesquelles ce pays de la mer Rouge pourrait accueillir une base militaire \u00e9trang\u00e8re sur son littoral. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/09\\\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/","og_locale":"fr_FR","og_type":"article","og_title":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF L\u2019\u00c9rythr\u00e9e, appel\u00e9e parfois un royaume ermite, est l\u2019un des pays les plus diplomatiquement isol\u00e9s du monde. Ses ant\u00e9c\u00e9dents de r\u00e9pression, d\u2019abus des droits de l\u2019homme et de conflit avec les pays voisins l\u2019ont laiss\u00e9e avec peu d\u2019alli\u00e9s sur la sc\u00e8ne mondiale. Mais son littoral de 1.150\u00a0km sur la mer Rouge signifie qu\u2019elle continue","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-09-05T18:57:58+00:00","article_modified_time":"2023-09-05T18:59:40+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge","datePublished":"2023-09-05T18:57:58+00:00","dateModified":"2023-09-05T18:59:40+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/"},"wordCount":1198,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg","keywords":["Chine","Eritrea","Russie"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/","name":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg","datePublished":"2023-09-05T18:57:58+00:00","dateModified":"2023-09-05T18:59:40+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/09\/GettyImages-1007692342.jpg","width":1024,"height":685,"caption":"Un bateau est amarr\u00e9 au quai de la ville portuaire de Massawa (\u00c9rythr\u00e9e). Le renforcement des liens entre la Russie, la Chine et l\u2019\u00c9rythr\u00e9e suscite des sp\u00e9culations selon lesquelles ce pays de la mer Rouge pourrait accueillir une base militaire \u00e9trang\u00e8re sur son littoral. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/09\/en-erythree-la-chine-et-la-russie-cherchent-a-dominer-la-mer-rouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"En \u00c9rythr\u00e9e, la Chine et la Russie cherchent \u00e0 dominer la mer Rouge"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/108798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=108798"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/108798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/108793"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=108798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=108798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=108798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}