{"id":107092,"date":"2023-07-11T16:16:08","date_gmt":"2023-07-11T20:16:08","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=107092"},"modified":"2023-07-11T16:16:08","modified_gmt":"2023-07-11T20:16:08","slug":"la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/","title":{"rendered":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes"},"content":{"rendered":"<p>PERSONNEL D\u2019ADF<\/p>\n<p>Le gouvernement somalien a recrut\u00e9 20.000\u00a0soldats au cours de l\u2019ann\u00e9e pass\u00e9e pour relever les d\u00e9fis de s\u00e9curit\u00e9 dus principalement aux shebabs, alors que l\u2019Atmis (Mission de transition de l\u2019Union africaine en Somalie) retire ses troupes.<\/p>\n<p>L\u2019Atmis pr\u00e9voyait de retirer 2.000 soldats du pays avant le 30 juin\u00a0: c\u2019est le premier de trois retraits dans son plan de transition. L\u2019UA s\u2019est engag\u00e9e \u00e0 retirer les soldats graduellement et strat\u00e9giquement, secteur par secteur, dans le but de mettre un terme \u00e0 la mission le 31 d\u00e9cembre 2024. Le Burundi, Djibouti, l\u2019\u00c9thiopie, le Kenya et l\u2019Ouganda sont les pays qui fournissent des troupes \u00e0 la mission.<\/p>\n<p>Des milliers de recrues somaliennes ont \u00e9t\u00e9 envoy\u00e9es en \u00c9gypte, en \u00c9rythr\u00e9e, en \u00c9thiopie et en Ouganda pour leur formation.<\/p>\n<p>Certains observateurs pensent que le plan visant \u00e0 former 20.000 soldats pour d\u00e9fendre le pays contre les shebabs est ambitieux, mais le chef de l\u2019Atmis Mohamed El-Amine Souef a d\u00e9clar\u00e9 dans une conf\u00e9rence de presse au mois de juin qu\u2019il pensait que le gouvernement somalien avait recrut\u00e9 suffisamment de forces pour assumer les responsabilit\u00e9s de s\u00e9curit\u00e9 lorsque l\u2019Atmis partira.<\/p>\n<p>\u00ab\u00a0J\u2019ai pleinement confiance dans les capacit\u00e9s des Forces de s\u00e9curit\u00e9 somaliennes, a-t-il dit. Les SNA [Forces arm\u00e9es nationales somaliennes] d\u00e9montrent depuis un an une capacit\u00e9 croissante pour entreprendre des op\u00e9rations militaires contre le groupe de terroristes.\u00a0\u00bb<\/p>\n<p>Alors que les nouvelles recrues poursuivent leur formation, les responsables somaliens veulent que le Conseil de s\u00e9curit\u00e9 des Nations unies \u00e9limine l\u2019embargo sur les armes impos\u00e9 dans le pays en 1992, lorsque la situation s\u00e9curitaire \u00e9tait bien pire, selon eux.<\/p>\n<p>Au mois de juin, le pr\u00e9sident Mohamoud a d\u00e9clar\u00e9 au Conseil de s\u00e9curit\u00e9 que son gouvernement avait \u00e9tabli des mesures ad\u00e9quates pour combattre l\u2019afflux ill\u00e9gal des armes et cr\u00e9\u00e9 une l\u00e9gislation pour contr\u00f4ler la possession, la fabrication, l\u2019entreposage et l\u2019utilisation des armes \u00e0 feu.<\/p>\n<p>En levant l\u2019embargo, \u00ab\u00a0vous nous responsabiliserez afin que nous puissions affirmer notre souverainet\u00e9, combattre efficacement le terrorisme et construire un avenir pacifique et prosp\u00e8re pour notre pays\u00a0\u00bb, a-t-il dit dans un reportage de Voice of America (VOA).<\/p>\n<p>M.\u00a0Souef a fait \u00e9cho au pr\u00e9sident Mohamoud.<\/p>\n<p>\u00ab\u00a0Nous devons soutenir les responsables des SSF [Forces de s\u00e9curit\u00e9 somaliennes], conserver les zones lib\u00e9r\u00e9es et prendre en charge les FOB [bases op\u00e9rationnelles avanc\u00e9es], a-t-il d\u00e9clar\u00e9. Ces forces n\u00e9cessitent des ressources pour combattre les shebabs et stabiliser les zones nouvellement lib\u00e9r\u00e9es.\u00a0\u00bb<\/p>\n<p>Le 29 juin, les soldats burundais de l\u2019Atmis ont remis aux SNA la FOB de Cadale dans l\u2019\u00c9tat de Hirshabelle. C\u2019est jusqu\u2019\u00e0 pr\u00e9sent la quatri\u00e8me base transf\u00e9r\u00e9e dans le cadre de la transition.<\/p>\n<p>Le g\u00e9n\u00e9ral de brigade Jean Claude Niyiburana, commandant du contingent burundais, a offert des conseils au colonel Saney Abdulle, commandant de la brigade des SANA \u00e0 Cadale, lors de la c\u00e9r\u00e9monie de transfert.<\/p>\n<p>Il a dit dans un reportage du magazine African Business\u00a0: \u00ab\u00a0Vous connaissez mieux cette zone et les shebabs continuent \u00e0 prendre pour cible les forces de s\u00e9curit\u00e9 somaliennes et les troupes de l\u2019Atmis dans tous les secteurs. Restez vigilants parce que l\u2019ennemi ne se repose pas.\u00a0\u00bb<\/p>\n<p>Le colonel Saney a promis de \u00ab\u00a0maintenir le cap et de vaincre\u00a0\u00bb les shebabs.<\/p>\n<p>Bien que de nombreux experts pensent que les shebabs deviennent plus faibles, l\u2019analyste des affaires de la Corne de l\u2019Afrique Omar Yusuf Abdulle d\u00e9clare que le groupe continuera \u00e0 repr\u00e9senter une menace s\u00e9curitaire parce que son id\u00e9ologie \u00e0 elle seule est suffisante pour inspirer la violence.<\/p>\n<p>Il d\u00e9clare \u00e0 VOA\u00a0: Malgr\u00e9 leurs revers militaires r\u00e9cents, les shebabs \u00ab\u00a0peuvent toujours infliger des dommages parce que leurs chefs sont toujours pr\u00e9sents et contr\u00f4lent toujours un vaste territoire dans le Sud de la Somalie. En outre, les sympathisants fervents du groupe les \u00e9coutent toujours et il y en a probablement des milliers\u00a0; par cons\u00e9quent, la d\u00e9faite totale des shebabs d\u00e9pend de l\u2019\u00e9radication de l\u2019id\u00e9ologie qui inspire les terroristes\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF Le gouvernement somalien a recrut\u00e9 20.000\u00a0soldats au cours de l\u2019ann\u00e9e pass\u00e9e pour relever les d\u00e9fis de s\u00e9curit\u00e9 dus principalement aux shebabs, alors que l\u2019Atmis (Mission de transition de l\u2019Union africaine en Somalie) retire ses troupes. L\u2019Atmis pr\u00e9voyait de retirer 2.000 soldats du pays avant le 30 juin\u00a0: c\u2019est le premier de trois retraits<\/p>\n","protected":false},"author":1,"featured_media":107088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[1141,1266,538],"class_list":{"0":"post-107092","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-atmis-fr","9":"tag-shebabs","10":"tag-somalie"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF Le gouvernement somalien a recrut\u00e9 20.000\u00a0soldats au cours de l\u2019ann\u00e9e pass\u00e9e pour relever les d\u00e9fis de s\u00e9curit\u00e9 dus principalement aux shebabs, alors que l\u2019Atmis (Mission de transition de l\u2019Union africaine en Somalie) retire ses troupes. L\u2019Atmis pr\u00e9voyait de retirer 2.000 soldats du pays avant le 30 juin\u00a0: c\u2019est le premier de trois retraits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-11T20:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes\",\"datePublished\":\"2023-07-11T20:16:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/\"},\"wordCount\":715,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1447746004.jpg\",\"keywords\":[\"ATMIS\",\"Shebabs\",\"Somalie\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/\",\"name\":\"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1447746004.jpg\",\"datePublished\":\"2023-07-11T20:16:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1447746004.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1447746004.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Le major Mohamed Nur Madhere des Forces arm\u00e9es nationales somaliennes (SNA) accueille les soldats et les forces de s\u00e9curit\u00e9 des SNA \u00e0 leur arriv\u00e9e \u00e0 l\u2019a\u00e9roport de Baidoa. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/","og_locale":"fr_FR","og_type":"article","og_title":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF Le gouvernement somalien a recrut\u00e9 20.000\u00a0soldats au cours de l\u2019ann\u00e9e pass\u00e9e pour relever les d\u00e9fis de s\u00e9curit\u00e9 dus principalement aux shebabs, alors que l\u2019Atmis (Mission de transition de l\u2019Union africaine en Somalie) retire ses troupes. L\u2019Atmis pr\u00e9voyait de retirer 2.000 soldats du pays avant le 30 juin\u00a0: c\u2019est le premier de trois retraits","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-07-11T20:16:08+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes","datePublished":"2023-07-11T20:16:08+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/"},"wordCount":715,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg","keywords":["ATMIS","Shebabs","Somalie"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/","name":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg","datePublished":"2023-07-11T20:16:08+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1447746004.jpg","width":1024,"height":683,"caption":"Le major Mohamed Nur Madhere des Forces arm\u00e9es nationales somaliennes (SNA) accueille les soldats et les forces de s\u00e9curit\u00e9 des SNA \u00e0 leur arriv\u00e9e \u00e0 l\u2019a\u00e9roport de Baidoa. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/la-somalie-recrute-20-000-soldats-alors-que-latmis-commence-a-retirer-ses-troupes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"La Somalie recrute 20.000 soldats alors que l\u2019Atmis commence \u00e0 retirer ses troupes"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/107092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=107092"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/107092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/107088"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=107092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=107092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=107092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}