{"id":107065,"date":"2023-07-05T14:30:39","date_gmt":"2023-07-05T18:30:39","guid":{"rendered":"https:\/\/adf-magazine.com\/?p=107065"},"modified":"2023-07-05T14:31:00","modified_gmt":"2023-07-05T18:31:00","slug":"a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies","status":"publish","type":"post","link":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/","title":{"rendered":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies"},"content":{"rendered":"<p>PERSONNEL D\u2019ADF<\/p>\n<p>Des hommes arm\u00e9s ont chass\u00e9 Dawoud Adam Ishak de son foyer dans la r\u00e9gion soudanaise du Darfour.<\/p>\n<p>\u00ab\u00a0Ils sont venus pendant la nuit lorsque nous dormions, dit-il \u00e0 Voice of America. Nous nous sommes alors r\u00e9veill\u00e9s et nous nous sommes enfuis.\u00a0\u00bb<\/p>\n<p>Ishak a rejoint plus de 100.000 autres Soudanais qui ont franchi la fronti\u00e8re du Tchad depuis le d\u00e9but des combats le 15 avril entre les Forces arm\u00e9es du Soudan (SAF) et les Forces de soutien rapide (RSF) paramilitaires.<br \/>\nLes combats qui avaient \u00e9clat\u00e9 \u00e0 Khartoum se sont depuis lors propag\u00e9s vers la r\u00e9gion du Darfour o\u00f9 les RSF sont bas\u00e9es. Des attaques brutales dans le Darfour-Occidental et le Darfour du Nord ont provoqu\u00e9 l\u2019incendie des villages, le massacre de milliers de personnes et la fuite de milliers d\u2019autres pour \u00e9chapper \u00e0 la mort.<\/p>\n<p>La violence en cours fait \u00e9cho aux assauts g\u00e9nocidaires contre les groupes non arabes conduits il y a vingt ans par les Janjawids soutenus par le gouvernement, qui \u00e9taient les pr\u00e9curseurs des RSF. Cela fait poser une question \u00e0 certains experts\u00a0: les gardiens de la paix devraient-ils retourner au Darfour\u00a0?<\/p>\n<p>\u00ab\u00a0Oui\u00a0\u00bb, d\u00e9clare \u00e0 Voice of America l\u2019expert de la s\u00e9curit\u00e9 Alistair Edgar de l\u2019\u00c9cole Balsillie des affaires internationales. \u00ab\u00a0Je vous y r\u00e9pond imm\u00e9diatement.\u00a0\u00bb<\/p>\n<p>Le professeur Edgar d\u00e9clare que le renouvellement d\u2019une mission de maintien de la paix est n\u00e9cessaire \u00ab\u00a0\u00e0 cause du niveau de violence et aussi \u00e0 cause de la possibilit\u00e9 que cette violence se propage \u00e0 l\u2019ext\u00e9rieur, vers le Tchad et aussi en franchissant les fronti\u00e8res.\u00a0\u00bb<\/p>\n<p>Les efforts pr\u00e9c\u00e9dents de maintien de la paix au Darfour \u00e9taient centr\u00e9s sur la MINUAD, ou mission des Nations unies et de l\u2019Union africaine au Darfour. Elle a pris fin le 30 juin 2021 apr\u00e8s treize ann\u00e9es, sous la pression du Conseil de souverainet\u00e9 qui gouvernait le Soudan apr\u00e8s le renversement du dictateur Omar el-Beshir en 2019.<\/p>\n<p>Cette op\u00e9ration hybride de 19.000 personnes \u00e9taient critiqu\u00e9e pour son incapacit\u00e9 \u00e0 mettre fin aux assassinats de civils et aux attaques communautaires par les Janjawids et les forces gouvernementales contr\u00f4l\u00e9es \u00e0 l\u2019\u00e9poque par M.\u00a0el-Beshir. Dans certains cas, les critiques ont accus\u00e9 les gardiens de la paix de la MINUAD de passivit\u00e9 alors que les miliciens attaquaient les civils.<\/p>\n<p>Mohammed Amin et Phillip Kleinfeld \u00e9crivent pour The New Humanitarian\u00a0: \u00ab\u00a0La capacit\u00e9 de la MINUAD pour prot\u00e9ger les civils \u00e9tait souvent bloqu\u00e9e par le r\u00e9gime d\u2019el-Beshir, qui refusait les permissions de vol aux a\u00e9ronefs de la mission et rejetait d\u2019innombrables demandes de visa faites par les membres de la mission.\u00a0\u00bb<\/p>\n<p>Au moment o\u00f9 la mission a pris fin, ses bases ont \u00e9t\u00e9 attaqu\u00e9es et pill\u00e9es par les milices de la r\u00e9gion.<\/p>\n<p>Il n\u2019est pas certain qu\u2019une tentative de renouveler la MINUAD ou d\u2019autoriser une op\u00e9ration similaire puisse obtenir les votes n\u00e9cessaires au Conseil de s\u00e9curit\u00e9 de l\u2019ONU. Les RSF qui sont responsables pour une grande partie des massacres au Darfour sont des alli\u00e9s proches des mercenaires du groupe Wagner de Russie.<\/p>\n<p>Ant\u00e9rieurement, la Russie a utilis\u00e9 son droit de v\u00e9to au Conseil de s\u00e9curit\u00e9 pour bloquer les actions onusiennes en R\u00e9publique centrafricaine, o\u00f9 la Wagner est \u00e9troitement li\u00e9e au gouvernement et \u00e0 l\u2019extraction de l\u2019or et des diamants. En 2016, la Russie a bloqu\u00e9 la publication d\u2019un rapport de l\u2019ONU expliquant en d\u00e9tail la contrebande de l\u2019or par les milices du Darfour et une attaque contre les forces de la MINUAD par les Janjawids.<\/p>\n<p>L\u2019expert de la s\u00e9curit\u00e9 Walter Dorn du Coll\u00e8ge militaire royal du Canada a d\u00e9clar\u00e9 \u00e0 VOA qu\u2019un renouvellement de la mission de maintien de la paix de l\u2019ONU au Darfour est improbable \u00e0 court terme.<\/p>\n<p>\u00ab\u00a0Pour le moment, il ne semble pas exister de volont\u00e9 politique pour cr\u00e9er une force de maintien de la paix au Darfour, mais \u00e0 mesure que la situation empire, les demandes pour la cr\u00e9er s\u2019intensifieront.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERSONNEL D\u2019ADF Des hommes arm\u00e9s ont chass\u00e9 Dawoud Adam Ishak de son foyer dans la r\u00e9gion soudanaise du Darfour. \u00ab\u00a0Ils sont venus pendant la nuit lorsque nous dormions, dit-il \u00e0 Voice of America. Nous nous sommes alors r\u00e9veill\u00e9s et nous nous sommes enfuis.\u00a0\u00bb Ishak a rejoint plus de 100.000 autres Soudanais qui ont franchi la<\/p>\n","protected":false},"author":1,"featured_media":107062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[331],"tags":[801,739,617,618,643,485],"class_list":{"0":"post-107065","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dernieres-nouvelles","8":"tag-guerre-civile","9":"tag-maintien-de-la-paix","10":"tag-republique-centrafricaine","11":"tag-russie","12":"tag-soudan","13":"tag-tchad"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum\" \/>\n<meta property=\"og:description\" content=\"PERSONNEL D\u2019ADF Des hommes arm\u00e9s ont chass\u00e9 Dawoud Adam Ishak de son foyer dans la r\u00e9gion soudanaise du Darfour. \u00ab\u00a0Ils sont venus pendant la nuit lorsque nous dormions, dit-il \u00e0 Voice of America. Nous nous sommes alors r\u00e9veill\u00e9s et nous nous sommes enfuis.\u00a0\u00bb Ishak a rejoint plus de 100.000 autres Soudanais qui ont franchi la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa Defense Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADFmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-05T18:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T18:31:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:site\" content=\"@ADFmagazine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/\"},\"author\":{\"name\":\"ADF\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"headline\":\"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies\",\"datePublished\":\"2023-07-05T18:30:39+00:00\",\"dateModified\":\"2023-07-05T18:31:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/\"},\"wordCount\":707,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1231199786.jpg\",\"keywords\":[\"guerre civile\",\"Maintien de la paix\",\"R\u00e9publique centrafricaine\",\"Russie\",\"Soudan\",\"Tchad\"],\"articleSection\":[\"Actualit\u00e9s du Jour\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/\",\"name\":\"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1231199786.jpg\",\"datePublished\":\"2023-07-05T18:30:39+00:00\",\"dateModified\":\"2023-07-05T18:31:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1231199786.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/GettyImages-1231199786.jpg\",\"width\":1024,\"height\":580,\"caption\":\"La violence en hausse dans la r\u00e9gion soudanaise du Darfour incite certains experts internationaux \u00e0 demander le retour des casques bleus deux ans apr\u00e8s la fin de la mission conjointe pr\u00e9c\u00e9dente des Nations unies et de l\u2019Union africaine. AFP\\\/GETTY IMAGES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/2023\\\/07\\\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"page d\u2019accueil\",\"item\":\"https:\\\/\\\/adf-magazine.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/\",\"name\":\"Africa Defense Forum\",\"description\":\"Africa Defense Forum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adf-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/#\\\/schema\\\/person\\\/f266a6061389568b5a11465bb38bc025\",\"name\":\"ADF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"url\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"contentUrl\":\"https:\\\/\\\/adf-magazine.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-ADF_icon.jpg\",\"caption\":\"ADF\"},\"description\":\"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/ADFmagazine\"],\"url\":\"https:\\\/\\\/adf-magazine.com\\\/fr\\\/author\\\/adf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum","og_description":"PERSONNEL D\u2019ADF Des hommes arm\u00e9s ont chass\u00e9 Dawoud Adam Ishak de son foyer dans la r\u00e9gion soudanaise du Darfour. \u00ab\u00a0Ils sont venus pendant la nuit lorsque nous dormions, dit-il \u00e0 Voice of America. Nous nous sommes alors r\u00e9veill\u00e9s et nous nous sommes enfuis.\u00a0\u00bb Ishak a rejoint plus de 100.000 autres Soudanais qui ont franchi la","og_url":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/","og_site_name":"Africa Defense Forum","article_publisher":"https:\/\/www.facebook.com\/ADFmagazine\/","article_published_time":"2023-07-05T18:30:39+00:00","article_modified_time":"2023-07-05T18:31:00+00:00","og_image":[{"width":1024,"height":580,"url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg","type":"image\/jpeg"}],"author":"ADF","twitter_card":"summary_large_image","twitter_creator":"@ADFmagazine","twitter_site":"@ADFmagazine","twitter_misc":{"\u00c9crit par":"ADF","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#article","isPartOf":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/"},"author":{"name":"ADF","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"headline":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies","datePublished":"2023-07-05T18:30:39+00:00","dateModified":"2023-07-05T18:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/"},"wordCount":707,"commentCount":0,"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg","keywords":["guerre civile","Maintien de la paix","R\u00e9publique centrafricaine","Russie","Soudan","Tchad"],"articleSection":["Actualit\u00e9s du Jour"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/","url":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/","name":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies - Africa Defense Forum","isPartOf":{"@id":"https:\/\/adf-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#primaryimage"},"image":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#primaryimage"},"thumbnailUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg","datePublished":"2023-07-05T18:30:39+00:00","dateModified":"2023-07-05T18:31:00+00:00","author":{"@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025"},"breadcrumb":{"@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#primaryimage","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2023\/07\/GettyImages-1231199786.jpg","width":1024,"height":580,"caption":"La violence en hausse dans la r\u00e9gion soudanaise du Darfour incite certains experts internationaux \u00e0 demander le retour des casques bleus deux ans apr\u00e8s la fin de la mission conjointe pr\u00e9c\u00e9dente des Nations unies et de l\u2019Union africaine. AFP\/GETTY IMAGES"},{"@type":"BreadcrumbList","@id":"https:\/\/adf-magazine.com\/fr\/2023\/07\/a-cause-des-conditions-au-darfour-certains-experts-demandent-le-retour-des-gardiens-de-la-paix-des-nations-unies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"page d\u2019accueil","item":"https:\/\/adf-magazine.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"\u00c0 cause des conditions au Darfour, certains experts demandent le retour des gardiens de la paix des Nations unies"}]},{"@type":"WebSite","@id":"https:\/\/adf-magazine.com\/#website","url":"https:\/\/adf-magazine.com\/","name":"Africa Defense Forum","description":"Africa Defense Forum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adf-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/adf-magazine.com\/#\/schema\/person\/f266a6061389568b5a11465bb38bc025","name":"ADF","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","url":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","contentUrl":"https:\/\/adf-magazine.com\/wp-content\/uploads\/2020\/05\/cropped-ADF_icon.jpg","caption":"ADF"},"description":"ADF is a professional military magazine published quarterly by U.S. Africa Command to provide an international forum for African security professionals. ADF covers topics such as counter terrorism strategies, security and defense operations, transnational crime, and all other issues affecting peace, stability, and good governance on the African continent.","sameAs":["https:\/\/x.com\/ADFmagazine"],"url":"https:\/\/adf-magazine.com\/fr\/author\/adf\/"}]}},"_links":{"self":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/107065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/comments?post=107065"}],"version-history":[{"count":0,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/posts\/107065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media\/107062"}],"wp:attachment":[{"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/media?parent=107065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/categories?post=107065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adf-magazine.com\/fr\/wp-json\/wp\/v2\/tags?post=107065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}